{"id":13186,"date":"2014-10-29T12:22:56","date_gmt":"2014-10-29T15:22:56","guid":{"rendered":"http:\/\/blogdafeira.com.br\/home\/?p=13186"},"modified":"2014-10-29T12:22:56","modified_gmt":"2014-10-29T15:22:56","slug":"uefs-abre-na-proxima-semana-a-9a-feira-do-semiarido","status":"publish","type":"post","link":"https:\/\/blogdafeira.com.br\/home\/2014\/10\/29\/uefs-abre-na-proxima-semana-a-9a-feira-do-semiarido\/","title":{"rendered":"UEFS abre na pr\u00f3xima semana a 9\u00aa Feira do Semi\u00e1rido"},"content":{"rendered":"<div id=\"blogd-4112905327\" class=\"blogd-fim-do-post-mobile blogd-entity-placement\" style=\"margin-left: auto;margin-right: auto;text-align: center;\"><a href=\"https:\/\/www.feiradesantana.ba.gov.br\/servico.asp?s=a&#038;titulo=Alceu,-Paula-Fernandes,-Alcymar-Monteiro,-Fl%C3%A1vio-Jos%C3%A9-e-Ra%C3%A7a-Negra-animar%C3%A3o-o-Arrai%C3%A1-de%20Feira.html&#038;id=8&#038;link=secom\/noticias.asp&#038;idn=43073#noticias\" target=\"_blank\" aria-label=\"728&#215;90 (7)\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2026\/03\/728x90-7.gif\" alt=\"\"  class=\"no-lazyload\" width=\"728\" height=\"90\"  style=\"display: inline-block;\" \/><\/a><\/div><p>A Universidade Estadual de Feira de Santana (Uefs) realiza, de 4 a 7 de novembro, a IX Feira do Semi\u00e1rido, que este ano vai abordar o tema Diversidade Cultural e Pol\u00edticas P\u00fablicas para o Semi\u00e1rido.<\/p><div id=\"blogd-2580152145\" class=\"blogd-conteudo-2-mobile blogd-entity-placement\"><a href=\"https:\/\/feirenses.com.br\/\" target=\"_blank\" aria-label=\"feirenses\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2026\/04\/feirenses.png\" alt=\"\"  srcset=\"https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2026\/04\/feirenses.png 300w, https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2026\/04\/feirenses-170x45.png 170w, https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2026\/04\/feirenses-280x74.png 280w\" sizes=\"(max-width: 300px) 100vw, 300px\" class=\"no-lazyload\" width=\"300\" height=\"79\"  style=\"display: inline-block;\" \/><\/a><\/div>\n<p>Confira a programa\u00e7\u00e3o no portal\u00a0<a href=\"http:\/\/www.uefs.br\/\">www.uefs.br<\/a>.<\/p>\n<p>Est\u00e1 prevista a participa\u00e7\u00e3o de professores, pesquisadores e estudantes de diversas institui\u00e7\u00f5es de ensino do pa\u00eds. Ser\u00e3o realizadas atividades no campus universit\u00e1rio, inclusive em estandes, com a participa\u00e7\u00e3o de expositores de dezenas de munic\u00edpios baianos que mostrar\u00e3o os seus produtos.<\/p>\n<div id=\"blogd-3128805598\" class=\"blogd-final-post blogd-entity-placement\"><a href=\"https:\/\/www.feiradesantana.ba.leg.br\/\" target=\"_blank\" aria-label=\"BANNER-SITE-ENTREGADECHEQUE-CAMARADEFEIRA\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2026\/03\/BANNER-SITE-ENTREGADECHEQUE-CAMARADEFEIRA.gif\" alt=\"\"  class=\"no-lazyload\" width=\"728\" height=\"90\"   \/><\/a><\/div><p>Paralelo \u00e0 IX Feira do Semi\u00e1rido, ser\u00e1 realizada a I Semana Nacional de Agronomia, com o tema \u201cAgricultura Familiar: caminhos para uma produ\u00e7\u00e3o sustent\u00e1vel no semi\u00e1rido\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Universidade Estadual de Feira de Santana (Uefs) realiza, de 4 a 7 de novembro, a IX Feira do Semi\u00e1rido, que este ano vai abordar o tema Diversidade Cultural e Pol\u00edticas P\u00fablicas para o Semi\u00e1rido. Confira a programa\u00e7\u00e3o no portal\u00a0www.uefs.br. Est\u00e1 prevista a participa\u00e7\u00e3o de professores, pesquisadores e estudantes de diversas institui\u00e7\u00f5es de ensino do<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"cybocfi_hide_featured_image":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[1],"tags":[],"class_list":["post-13186","post","type-post","status-publish","format-standard","hentry","category-raiz"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p3niVf-3qG","jetpack_sharing_enabled":true,"jetpack-related-posts":[{"id":13280,"url":"https:\/\/blogdafeira.com.br\/home\/2014\/11\/04\/uefs-abre-hoje-a-noite-a-9a-feira-do-semiarido\/","url_meta":{"origin":13186,"position":0},"title":"UEFS abre hoje \u00e0 noite a 9\u00aa Feira do Semi\u00e1rido","author":"Blog da Feira","date":"04\/11\/2014","format":false,"excerpt":"A Universidade Estadual de Feira de Santana (Uefs) abre hoje \u00e0 noite, no campus central, a \u00a0IX Feira do Semi\u00e1rido, que este ano aborda o tema Diversidade Cultural e Pol\u00edticas P\u00fablicas para o Semi\u00e1rido. Confira a programa\u00e7\u00e3o no portal\u00a0www.uefs.br. Est\u00e1 prevista a participa\u00e7\u00e3o de professores, pesquisadores e estudantes de diversas\u2026","rel":"","context":"Em &quot;Home&quot;","block_context":{"text":"Home","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/raiz\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":11817,"url":"https:\/\/blogdafeira.com.br\/home\/2014\/08\/10\/estao-abertas-as-inscricoes-para-feira-do-semi-arido-na-uefs\/","url_meta":{"origin":13186,"position":1},"title":"Est\u00e3o abertas as inscri\u00e7\u00f5es para Feira do Semi \u00c1rido na UEFS","author":"Blog da Feira","date":"10\/08\/2014","format":false,"excerpt":"A Universidade Estadual de Feira de Santana (Uefs) inscreve at\u00e9 17 de agosto para submiss\u00e3o de trabalhos destinados \u00e0 participa\u00e7\u00e3o na 9\u00aa Feira do Semi\u00e1rido, evento que ser\u00e1 realizado de 4 a 7 de novembro de 2014 no campus universit\u00e1rio. Estudantes e profissionais de n\u00edvel superior, produtores agr\u00edcolas e interessados\u2026","rel":"","context":"Em &quot;Home&quot;","block_context":{"text":"Home","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/raiz\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":29204,"url":"https:\/\/blogdafeira.com.br\/home\/2018\/03\/09\/uefs-abre-na-proxima-semana-as-inscricoes-para-mais-uma-feira-do-semiarido\/","url_meta":{"origin":13186,"position":2},"title":"UEFS abre na pr\u00f3xima semana as inscri\u00e7\u00f5es para mais uma Feira do Semi\u00e1rido.","author":"Blog da Feira","date":"09\/03\/2018","format":false,"excerpt":"No per\u00edodo de 13 de mar\u00e7o a 2 de abril, a Universidade Estadual de Feira de Santana (Uefs) estar\u00e1 com inscri\u00e7\u00f5es abertas para 11\u00aa. Feira do Semi\u00e1rido que tem como eixo tem\u00e1tico \u201cPol\u00edticas p\u00fablicas e desenvolvimento territorial: temos sede de qu\u00ea?\u201d, que ser\u00e1 realizada de 23 a 25 de maio.\u2026","rel":"","context":"Em &quot;Home&quot;","block_context":{"text":"Home","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/raiz\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2018\/03\/Feira-do-Semi%C3%A1rido-DEF-725x1024.jpg?resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2018\/03\/Feira-do-Semi%C3%A1rido-DEF-725x1024.jpg?resize=350%2C200 1x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2018\/03\/Feira-do-Semi%C3%A1rido-DEF-725x1024.jpg?resize=525%2C300 1.5x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2018\/03\/Feira-do-Semi%C3%A1rido-DEF-725x1024.jpg?resize=700%2C400 2x"},"classes":[]},{"id":65,"url":"https:\/\/blogdafeira.com.br\/home\/2013\/04\/04\/diretor-do-instituto-nacional-do-semiarido-faz-palestra-na-uefs\/","url_meta":{"origin":13186,"position":3},"title":"Diretor do Instituto Nacional do Semi\u00e1rido faz palestra na UEFS","author":"Blog da Feira","date":"04\/04\/2013","format":false,"excerpt":"A Universidade Estadual de Feira de Santana (Uefs) realiza, segunda-feira (8), a partir das 14h, no pr\u00e9dio do\u00a0Labotec 2 \u2013 sala 20, a palestra \u201cA\u00e7\u00f5es de Ci\u00eancia, Tecnologia e Inova\u00e7\u00e3o no Semi\u00e1rido: o papel do Instituto Nacional do Semi\u00e1rido\u201d. O palestrante \u00e9 o professor doutor Salom\u00e3o de Souza Medeiros, pesquisador\u2026","rel":"","context":"Em &quot;Cidade&quot;","block_context":{"text":"Cidade","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/cidade\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":32531,"url":"https:\/\/blogdafeira.com.br\/home\/2019\/08\/28\/em-stand-na-expofeira-a-uefs-vai-mostrar-tecnologias-aplicadas-ao-semiarido\/","url_meta":{"origin":13186,"position":4},"title":"Em stand na ExpoFeira a UEFS vai mostrar tecnologias aplicadas ao semi\u00e1rido","author":"J\u00e2nio R\u00eago","date":"28\/08\/2019","format":false,"excerpt":"A Universidade Estadual de Feira de Santana (UEFS) estar\u00e1 presente na 44\u00aa Exposi\u00e7\u00e3o Agropecu\u00e1ria de Feira de Santana (Expofeira 2019), que acontece entre 1 e 8 de setembro. Ser\u00e1 montado no Parque de Exposi\u00e7\u00e3o Jo\u00e3o Martins da Silva o Espa\u00e7o Agro Saber, com o objetivo de divulgar os cursos ministrados\u2026","rel":"","context":"Em &quot;Home&quot;","block_context":{"text":"Home","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/raiz\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2019\/08\/2782019174632-346x216.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":2673,"url":"https:\/\/blogdafeira.com.br\/home\/2013\/06\/14\/presidenta-dilma-lanca-o-plano-safra-do-semiarido-em-salvador-dia-21\/","url_meta":{"origin":13186,"position":5},"title":"Presidenta Dilma lan\u00e7a o Plano Safra do Semi\u00e1rido em Salvador dia 21","author":"Blog da Feira","date":"14\/06\/2013","format":false,"excerpt":"A presidenta Dilma Rousseff cumprir\u00e1 agenda em Salvador na pr\u00f3xima sexta-feira (21), para fazer o lan\u00e7amento do Plano Safra do Semi\u00e1rido. A informa\u00e7\u00e3o partiu da assessoria do \u00a0senador Walter Pinheiro (PT-BA). Dilma tamb\u00e9m far\u00e1 a entrega de retroescavadeiras e motoniveladoras para 269 munic\u00edpios baianos., para a realiza\u00e7\u00e3o de obras para\u2026","rel":"","context":"Em &quot;Home&quot;","block_context":{"text":"Home","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/raiz\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"_links":{"self":[{"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/posts\/13186","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/comments?post=13186"}],"version-history":[{"count":1,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/posts\/13186\/revisions"}],"predecessor-version":[{"id":13187,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/posts\/13186\/revisions\/13187"}],"wp:attachment":[{"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/media?parent=13186"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/categories?post=13186"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/tags?post=13186"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}