{"id":24353,"date":"2016-11-17T00:47:59","date_gmt":"2016-11-17T03:47:59","guid":{"rendered":"http:\/\/blogdafeira.com.br\/home\/?p=24353"},"modified":"2020-09-02T23:45:49","modified_gmt":"2020-09-03T02:45:49","slug":"em-feira-de-santana-domingo-20-e-tambem-o-dia-municipal-do-samba-de-roda","status":"publish","type":"post","link":"https:\/\/blogdafeira.com.br\/home\/2016\/11\/17\/em-feira-de-santana-domingo-20-e-tambem-o-dia-municipal-do-samba-de-roda\/","title":{"rendered":"Em Feira de Santana domingo, 20, \u00e9 tamb\u00e9m o &#8216;Dia Municipal&#8217; do Samba-de-Roda"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-24354\" src=\"http:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2016\/11\/samba-de-roda-cartaz-quixabeira.jpg\" alt=\"samba-de-roda-cartaz-quixabeira\" width=\"685\" height=\"960\" srcset=\"https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2016\/11\/samba-de-roda-cartaz-quixabeira.jpg 685w, https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2016\/11\/samba-de-roda-cartaz-quixabeira-107x150.jpg 107w, https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2016\/11\/samba-de-roda-cartaz-quixabeira-214x300.jpg 214w\" sizes=\"auto, (max-width: 685px) 100vw, 685px\" \/><\/p>\n<div id=\"blogd-570383021\" class=\"blogd-fim-do-post-mobile blogd-entity-placement\" style=\"margin-left: auto;margin-right: auto;text-align: center;\"><a href=\"https:\/\/www.feiradesantana.ba.gov.br\/servico.asp?s=a&titulo=Prefeitura-de-Feira-lan%C3%A7a-programa-Rem%C3%A9dio-em-Casa-e-transforma-acesso-a-medicamentos-em-pol%C3%ADtica-p%C3%BAblica-de-cuidados.html&id=14&link=secom\/noticias.asp&idn=43684#noticias\" target=_blank><picture>\r\n  <source media=\"(min-width: 768px)\" srcset=\"https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2026\/03\/980x150.gif\">\r\n  \r\n  <img decoding=\"async\" src=\"https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2021\/01\/350x2002.gif\" alt=\"Publicidade\" style=\"width: 100%; max-width: 100%; height: auto; display: block; margin: 0 auto;\">\r\n\t<\/picture><\/a><\/div><p>O 1\u00ba Semin\u00e1rio sobre o Samba na Matinha \u00a0acontece no pr\u00f3ximo domingo, 20, na sede da &#8216;Quixabeira da Matinha&#8217;, a partir das 9h.<\/p>\n<p>Nacionalmente no dia 20 de novembro \u00e9 comemorado o &#8216;Dia da Consci\u00eancia Negra&#8217;. Aqui em Feira, por lei municipal, o dia 20 \u00e9 tamb\u00e9m o \u00a0Dia\u00a0 Municipal do Samba de Roda.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-24355\" src=\"http:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2016\/11\/quixabeira-346x260.jpg\" alt=\"quixabeira\" width=\"346\" height=\"260\" srcset=\"https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2016\/11\/quixabeira-346x260.jpg 346w, https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2016\/11\/quixabeira-170x128.jpg 170w, https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2016\/11\/quixabeira.jpg 400w\" sizes=\"auto, (max-width: 346px) 100vw, 346px\" \/>No Semin\u00e1rio promovido pela Quixabeira para marcar a data, ser\u00e3o realizadas rodas de palestras e apresenta\u00e7\u00f5es musicais. A entrada \u00e9 gratuita. O evento tem apoio da Prefeitura por meio da &#8216;Funda\u00e7\u00e3o Egberto Costa&#8217;, Governo do Estado, UEFS, e outras institui\u00e7\u00f5es.<\/p>\n<p>A sede da Quixabeira, no distrito rural de Matinha \u00e9 reconhecido oficialmente como \u00a0&#8220;Ponto de Cultura&#8217; da Bahia.<\/p>\n<p>O grupo de samba-de-roda Quixabeira da Matinha foi fundado pelo cantor e compositor <em>Coleirinho da Bahia<\/em>, incentivador da <em>variante mais tradicional do samba<\/em>.<\/p>\n<p>O samba-de-roda foi reconhecido pela Unesco, \u00f3rg\u00e3o da ONU para a cultura, como patrim\u00f4nio imaterial da humanidade em 2005, no mesmo ano em que Coleirinho morreu. A fam\u00edlia deu continuidade sob a lideran\u00e7a de Guda Moreno. (foto)<\/p>\n<div id=\"blogd-2849928654\" class=\"blogd-final-post blogd-entity-placement\"><a href=\"https:\/\/www.feiradesantana.ba.leg.br\/\" target=\"_blank\" aria-label=\"JUNHO-VERMELHO_CA\u0302MARA-DE-FEIRA\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2026\/03\/JUNHO-VERMELHO_CAMARA-DE-FEIRA.gif\" alt=\"\"  class=\"no-lazyload\" width=\"728\" height=\"90\"   \/><\/a><\/div><p>Chega-se \u00e0 sede da Quixabeira pela BR-116 Norte com entrada ap\u00f3s o bairro Novo Horizonte.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O 1\u00ba Semin\u00e1rio sobre o Samba na Matinha \u00a0acontece no pr\u00f3ximo domingo, 20, na sede da &#8216;Quixabeira da Matinha&#8217;, a partir das 9h. Nacionalmente no dia 20 de novembro \u00e9 comemorado o &#8216;Dia da Consci\u00eancia Negra&#8217;. Aqui em Feira, por lei municipal, o dia 20 \u00e9 tamb\u00e9m o \u00a0Dia\u00a0 Municipal do Samba de Roda. No<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"cybocfi_hide_featured_image":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[748,1],"tags":[368],"class_list":["post-24353","post","type-post","status-publish","format-standard","hentry","category-distritos","category-raiz","tag-distritos"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p3niVf-6kN","jetpack_sharing_enabled":true,"jetpack-related-posts":[{"id":24463,"url":"https:\/\/blogdafeira.com.br\/home\/2016\/11\/21\/palestra-cantada-homenageou-o-samba-de-roda-no-distrito-de-matinha-em-feira\/","url_meta":{"origin":24353,"position":0},"title":"&#8216;Palestra cantada&#8217; homenageou o samba-de-roda no distrito de Matinha em Feira","author":"Blog da Feira","date":"21\/11\/2016","format":false,"excerpt":"No Dia Municipal do Samba de Roda, ontem, 20, \u00a0esse g\u00eanero de m\u00fasica, dan\u00e7a e festa que \u00e9 patrim\u00f4nio imaterial da Bahia, ganhou for\u00e7a e resist\u00eancia na \"Casa de Samba Dona Chica do Pandeiro\", na sede do distrito de Matinha, onde ele\u00a0foi comemorado. Uma \"palestra cantada\" com as participa\u00e7\u00f5es de\u2026","rel":"","context":"Em &quot;Distritos&quot;","block_context":{"text":"Distritos","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/distritos\/"},"img":{"alt_text":"guda-moreno","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2016\/11\/GUDA-MORENO.jpg?resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2016\/11\/GUDA-MORENO.jpg?resize=350%2C200 1x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2016\/11\/GUDA-MORENO.jpg?resize=525%2C300 1.5x"},"classes":[]},{"id":6373,"url":"https:\/\/blogdafeira.com.br\/home\/2013\/11\/22\/samba-na-quixabeira-da-matinha-comemora-dia-do-samba-de-roda-em-feira\/","url_meta":{"origin":24353,"position":1},"title":"Quixabeira da Matinha comemora &#8216;Dia do Samba-de-Roda&#8217; em Feira","author":"Blog da Feira","date":"22\/11\/2013","format":false,"excerpt":"Neste domingo, dia 24, no distrito rural de Matinha, em Feira de Santana, o tradicional grupo de samba Quixabeira da Matinha comemora o 'Dia Municipal do Samba de Roda' que oficialmente \u00e9 no dia 25, segunda feira. Al\u00e9m do samba de roda no espa\u00e7o do grupo Quixabeira da Matinha, tamb\u00e9m\u2026","rel":"","context":"Em &quot;Home&quot;","block_context":{"text":"Home","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/raiz\/"},"img":{"alt_text":"quixambeira da matinha","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2013\/11\/quixambeira-da-matinha.jpg?resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2013\/11\/quixambeira-da-matinha.jpg?resize=350%2C200 1x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2013\/11\/quixambeira-da-matinha.jpg?resize=525%2C300 1.5x"},"classes":[]},{"id":3850,"url":"https:\/\/blogdafeira.com.br\/home\/2013\/07\/26\/samba-da-quixabeira-da-matinha-comeca-hoje-e-termina-domingo\/","url_meta":{"origin":24353,"position":2},"title":"Samba da &#8216;Quixabeira da Matinha&#8217; come\u00e7a hoje e termina domingo","author":"Blog da Feira","date":"26\/07\/2013","format":false,"excerpt":"O grupo de samba-de-roda 'Quixabeira da Matinha' promove a partir desta sexta-feira, \u00e0s 20 horas, \u00a03 dias de festa na sede do grupo, que fica no distrito rural de Matinha, em Feira de Santana. No s\u00e1bado o samba-de-roda recome\u00e7a \u00e0s 19 horas e no domingo \u00e0s 10 horas.\u00a0A entrada \u00e9\u2026","rel":"","context":"Em &quot;Home&quot;","block_context":{"text":"Home","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/raiz\/"},"img":{"alt_text":"GUDA","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2013\/07\/GUDA-346x213.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":3746,"url":"https:\/\/blogdafeira.com.br\/home\/2013\/07\/23\/festa-de-santannaquixabeira-faz-samba-de-roda-na-matinha\/","url_meta":{"origin":24353,"position":3},"title":"Festa de Sant&#8217;Anna:Quixabeira faz samba-de-roda na Matinha","author":"Blog da Feira","date":"23\/07\/2013","format":false,"excerpt":"O grupo de samba-de-roda Quixabeira da Matinha promove a partir de sexta-feira, 26, \u00e0 noite, 3 dias de festa na sede do grupo, naquele distrito rural de Feira de Santana. Na sexta-feira o samba-de-roda come\u00e7a \u00e0s 20 horas, no s\u00e1bado \u00e0s 19 e no domingo o batuque come\u00e7a pela manh\u00e3,\u2026","rel":"","context":"Em &quot;Home&quot;","block_context":{"text":"Home","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/raiz\/"},"img":{"alt_text":"quixabeira 02","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2013\/07\/quixabeira-02-170x127.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":55285,"url":"https:\/\/blogdafeira.com.br\/home\/2022\/11\/07\/quixabeira-da-matinha-participou-de-seminario-em-ribeirao-preto\/","url_meta":{"origin":24353,"position":4},"title":"Quixabeira da Matinha participou de semin\u00e1rio em Ribeir\u00e3o Preto","author":"Blog da Feira","date":"07\/11\/2022","format":false,"excerpt":"O grupo Quixabeira da Matinha participou no \u00faltimo final de semana de um semin\u00e1rio sobre o samba-de-roda promovido pelo \u00a0Instituto Plural de Educa\u00e7\u00e3o e Cidadania Vila Bela de Ribeir\u00e3o Preto, S\u00e3o Paulo. Semin\u00e1rio de Samba de Roda-Patrim\u00f4nio Imaterial. O Instituto Plural de Educa\u00e7\u00e3o e Cidadania Vila Bela,\u00a0 atua h\u00e1 20\u2026","rel":"","context":"Em &quot;Cultura&quot;","block_context":{"text":"Cultura","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/cultura\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2022\/11\/Screenshot_20221107-2200363.png?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2022\/11\/Screenshot_20221107-2200363.png?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2022\/11\/Screenshot_20221107-2200363.png?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2022\/11\/Screenshot_20221107-2200363.png?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":35121,"url":"https:\/\/blogdafeira.com.br\/home\/2020\/02\/06\/industria-de-arames-patrocina-em-feira-o-3-seminario-sobre-o-samba-de-roda\/","url_meta":{"origin":24353,"position":5},"title":"Ind\u00fastria de arames patrocina em Feira o 3\u00b0 Semin\u00e1rio sobre o Samba de Roda","author":"J\u00e2nio R\u00eago","date":"06\/02\/2020","format":false,"excerpt":"3\u00b0 Semin\u00e1rio sobre Samba de Roda. A\u00e7\u00f5es se iniciam (11\/02) com oficinas (percuss\u00e3o, cavaquinho e samba de roda), em escolas, al\u00e9m de rodas de conversa e shows de grupos de samba locais (16\/02). Todas as a\u00e7\u00f5es ser\u00e3o no distrito da Matinha, em Feira de Santana.Este o 3\u00b0 Semin\u00e1rio faz parte\u2026","rel":"","context":"Em &quot;Cultura&quot;","block_context":{"text":"Cultura","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/cultura\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2020\/02\/IMG-20200206-WA0021.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2020\/02\/IMG-20200206-WA0021.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2020\/02\/IMG-20200206-WA0021.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2020\/02\/IMG-20200206-WA0021.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/posts\/24353","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/comments?post=24353"}],"version-history":[{"count":1,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/posts\/24353\/revisions"}],"predecessor-version":[{"id":24356,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/posts\/24353\/revisions\/24356"}],"wp:attachment":[{"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/media?parent=24353"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/categories?post=24353"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/tags?post=24353"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}