{"id":2646,"date":"2013-06-13T18:05:40","date_gmt":"2013-06-13T21:05:40","guid":{"rendered":"http:\/\/blogdafeira.com.br\/home\/?p=2646"},"modified":"2021-12-08T01:18:44","modified_gmt":"2021-12-08T04:18:44","slug":"predio-da-casa-das-lampadas-foi-projetado-pelo-arquiteto-amelio-amorim","status":"publish","type":"post","link":"https:\/\/blogdafeira.com.br\/home\/2013\/06\/13\/predio-da-casa-das-lampadas-foi-projetado-pelo-arquiteto-amelio-amorim\/","title":{"rendered":"As marcas de Am\u00e9lio Amorim pela Feira de Santana: &#8216;Casa das L\u00e2mpadas&#8217;"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-2647\" src=\"http:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2013\/06\/DSC07071.jpg\" alt=\"DSC07071\" width=\"640\" height=\"480\" srcset=\"https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2013\/06\/DSC07071.jpg 640w, https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2013\/06\/DSC07071-170x127.jpg 170w, https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2013\/06\/DSC07071-346x259.jpg 346w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/p>\n<div id=\"blogd-962864883\" class=\"blogd-fim-do-post-mobile blogd-entity-placement\" style=\"margin-left: auto;margin-right: auto;text-align: center;\"><a href=\"https:\/\/www.feiradesantana.ba.gov.br\/servico.asp?s=a&titulo=Prefeitura-de-Feira-lan%C3%A7a-programa-Rem%C3%A9dio-em-Casa-e-transforma-acesso-a-medicamentos-em-pol%C3%ADtica-p%C3%BAblica-de-cuidados.html&id=14&link=secom\/noticias.asp&idn=43684#noticias\" target=_blank><picture>\r\n  <source media=\"(min-width: 768px)\" srcset=\"https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2026\/03\/980x150.gif\">\r\n  \r\n  <img decoding=\"async\" src=\"https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2021\/01\/350x2002.gif\" alt=\"Publicidade\" style=\"width: 100%; max-width: 100%; height: auto; display: block; margin: 0 auto;\">\r\n\t<\/picture><\/a><\/div><p>O arquiteto Am\u00e9lio Amorim al\u00e9m de nome do maior Centro Cultural de Feira de Santana no local onde funcionou um grande empreendimento tur\u00edstico dele, tem espalhado pela cidade v\u00e1rias marcas do seu g\u00eanio arquitet\u00f4nico considerado um dos mais ousados da sua \u00e9poca. Entre elas o pr\u00e9dio onde funcionou antigamente a &#8220;Casa das L\u00e2mpadas (foto), esquina da Get\u00falio Vargas com Conselheiro Franco, no centro. Quando foi constru\u00eddo, n\u00e3o existia a avenida continuidade da Get\u00falio, a Ol\u00edmpio Vital.<\/p>\n<p><em>S\u00edmbolo de arrojo e genialidade, o nome de Am\u00e9lio Amorim ficou conhecido em todo o pa\u00eds. O arquiteto realizou importantes projetos em v\u00e1rias cidades brasileiras, como \u00e9 o caso das 400 casas que planejou para a cidade de Ilha bela, no litoral paulista. Tamb\u00e9m \u00e9 de sua autoria uma imponente resid\u00eancia situada em Londrina, no Paran\u00e1, famosa pelo belo painel que ornamenta a sua fachada,\u00a0<\/em>informa <strong><a href=\"http:\/\/www.tribunafeirense.com.br\/noticias\/31845\/amelio-amorim-e-a-fantasia-concreta-que-remodelou-o-sertao.html\">a jornalista Isis Moraes em texto publicado no jornal Tribuna Feirense (clique)<\/a><\/strong><\/p>\n<p>Em Feira foi o Clube de Campo Cajueiro e o seu empreendimento Carro de Boi que o imortalizaram. Mas h\u00e1 muitos outros exemplos de sua arquitetura.<\/p>\n<p>Leia tamb\u00e9m:<\/p>\n<div id=\"blogd-2047522777\" class=\"blogd-final-post blogd-entity-placement\"><a href=\"https:\/\/www.feiradesantana.ba.leg.br\/\" target=\"_blank\" aria-label=\"JUNHO-VERMELHO_CA\u0302MARA-DE-FEIRA\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2026\/03\/JUNHO-VERMELHO_CAMARA-DE-FEIRA.gif\" alt=\"\"  class=\"no-lazyload\" width=\"728\" height=\"90\"   \/><\/a><\/div><p><strong><a href=\"http:\/\/blogdafeira.com.br\/home\/2013\/06\/13\/morreu-empresario-fundador-da-rede-de-farmacias-silva-em-feira\/\">Morreu o empres\u00e1rio L\u00edcio Silva<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O arquiteto Am\u00e9lio Amorim al\u00e9m de nome do maior Centro Cultural de Feira de Santana no local onde funcionou um grande empreendimento tur\u00edstico dele, tem espalhado pela cidade v\u00e1rias marcas do seu g\u00eanio arquitet\u00f4nico considerado um dos mais ousados da sua \u00e9poca. Entre elas o pr\u00e9dio onde funcionou antigamente a &#8220;Casa das L\u00e2mpadas (foto), esquina<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"cybocfi_hide_featured_image":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":true,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[3,4],"tags":[291,290,10,8,132],"class_list":["post-2646","post","type-post","status-publish","format-standard","hentry","category-cidade","category-cultura","tag-amelio-amorim","tag-arquitetura","tag-feira","tag-feira-de-santana","tag-urbanismo"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p3niVf-GG","jetpack_sharing_enabled":true,"jetpack-related-posts":[{"id":13553,"url":"https:\/\/blogdafeira.com.br\/home\/2014\/11\/18\/e-o-restaurante-carro-de-boi-do-amelio-amorim\/","url_meta":{"origin":2646,"position":0},"title":"E o Restaurante Carro de Boi do Am\u00e9lio Amorim?","author":"Blog da Feira","date":"18\/11\/2014","format":false,"excerpt":"Com as mudan\u00e7as urbanas de Feira de Santana na d\u00e9cada de 70, ou seja, a sa\u00edda da feira livre do centro da cidade e a industrializa\u00e7\u00e3o no sentido da BR-324, CIS, \u00a0uma urbaniza\u00e7\u00e3o requintada surgiu entre a\u00a0elite feirense, \u00a0formada ent\u00e3o por um misto de comerciantes bem sucedidos e fazendeiros em\u2026","rel":"","context":"Em &quot;Home&quot;","block_context":{"text":"Home","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/raiz\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1441,"url":"https:\/\/blogdafeira.com.br\/home\/2013\/05\/10\/amelio-amorim-foi-reformado-mas-o-jerimum-continua-em-ruinas\/","url_meta":{"origin":2646,"position":1},"title":"Am\u00e9lio Amorim foi reformado mas o \u2018Jerimum\u2019 continua em ru\u00ednas","author":"Blog da Feira","date":"10\/05\/2013","format":false,"excerpt":"A Secretaria de Cultura do Estado da Bahia (Secult) prepara uma celebra\u00e7\u00e3o \u2018em grande estilo\u2019 para comemorar a reabertura, pr\u00f3ximo dia 16, do Centro de Cultura Am\u00e9lio Amorim, de Feira de Santana, ap\u00f3s uma reforma no local. A Secult anuncia uma ampla programa\u00e7\u00e3o de 16 a 30 deste m\u00eas para\u2026","rel":"","context":"Em &quot;Cultura&quot;","block_context":{"text":"Cultura","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/cultura\/"},"img":{"alt_text":"a567","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2013\/05\/a567-170x126.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":2639,"url":"https:\/\/blogdafeira.com.br\/home\/2013\/06\/13\/morreu-empresario-fundador-da-rede-de-farmacias-silva-em-feira\/","url_meta":{"origin":2646,"position":2},"title":"Morreu o empres\u00e1rio L\u00edcio Silva em Feira de Santana","author":"Blog da Feira","date":"13\/06\/2013","format":false,"excerpt":"Aos 86 anos, faleceu\u00a0Licio Silva, empres\u00e1rio, fundador da tradicional empresa Casa das L\u00e2mpadas em Feira de Santana al\u00e9m de outros empreendimentos comerciais no centro da cidade. Por diversas vezes foi presidente do Clube de Campo Cajueiro.\u00a0Deixou tr\u00eas filhos, Lula, Carlos Henrique \u00a0e Licio Filho, sete netos e bisnetos e a\u2026","rel":"","context":"Em &quot;Home&quot;","block_context":{"text":"Home","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/raiz\/"},"img":{"alt_text":"foto (2)","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2013\/06\/foto-2-128x150.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":32852,"url":"https:\/\/blogdafeira.com.br\/home\/2019\/09\/13\/centro-de-cultura-amelio-amorim-em-feira-de-santana-comemora-27-anos-com-uma-ocupacao-artistica\/","url_meta":{"origin":2646,"position":3},"title":"Centro de Cultura Am\u00e9lio Amorim, em Feira de Santana, comemora 27 anos com uma ocupa\u00e7\u00e3o art\u00edstica","author":"J\u00e2nio R\u00eago","date":"13\/09\/2019","format":false,"excerpt":"Neste s\u00e1bado a arte tem um endere\u00e7o certo: Centro de Cultura Am\u00e9lio Amorim que completa 27 anos de funda\u00e7\u00e3o comemorada com uma ampla interven\u00e7\u00e3o art\u00edstica nas depend\u00eancias do CCAA. Mais de uma dezena de de artistas dos mais diversos segmentos confirmaram presen\u00e7a. A ocupa\u00e7\u00e3o faz refer\u00eancia ao 'Jerimum', antiga boate\u2026","rel":"","context":"Em &quot;Home&quot;","block_context":{"text":"Home","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/raiz\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2019\/09\/IMG-20190829-WA0031-975x1024.jpg?resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2019\/09\/IMG-20190829-WA0031-975x1024.jpg?resize=350%2C200 1x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2019\/09\/IMG-20190829-WA0031-975x1024.jpg?resize=525%2C300 1.5x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2019\/09\/IMG-20190829-WA0031-975x1024.jpg?resize=700%2C400 2x"},"classes":[]},{"id":26011,"url":"https:\/\/blogdafeira.com.br\/home\/2017\/03\/13\/a-cidade-da-rua-direita-abre-festival-de-teatro-no-amelio-amorim-em-feira\/","url_meta":{"origin":2646,"position":4},"title":"&#8216;A Cidade da Rua Direita&#8217; abre festival de teatro no Am\u00e9lio Amorim em Feira","author":"Blog da Feira","date":"13\/03\/2017","format":false,"excerpt":"No dia 15 de mar\u00e7o, \u00e0s 15h, o espet\u00e1culo \u201cA Cidade da Rua Direita\u201d abre as apresenta\u00e7\u00f5es do Festival de Teatro do Interior da Bahia em Feira de Santana, no Centro de Cultura Am\u00e9lio Amorim. A montagem traz uma hist\u00f3ria que se passa na cidade de Feira de Santana dos\u2026","rel":"","context":"Em &quot;Home&quot;","block_context":{"text":"Home","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/raiz\/"},"img":{"alt_text":"z-rua-direita","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2017\/03\/Z-RUA-DIREITA.jpg?resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2017\/03\/Z-RUA-DIREITA.jpg?resize=350%2C200 1x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2017\/03\/Z-RUA-DIREITA.jpg?resize=525%2C300 1.5x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2017\/03\/Z-RUA-DIREITA.jpg?resize=700%2C400 2x"},"classes":[]},{"id":1625,"url":"https:\/\/blogdafeira.com.br\/home\/2013\/05\/15\/sanfoneiros-e-filarmonica-de-irara-reabrem-o-amelio-amorim-em-feira\/","url_meta":{"origin":2646,"position":5},"title":"Sanfoneiros e Filarm\u00f4nica de Irar\u00e1 reabrem o Am\u00e9lio Amorim em Feira","author":"Blog da Feira","date":"15\/05\/2013","format":false,"excerpt":"A Filarm\u00f4nica de Irar\u00e1 e um \u00a0grupo de sanfoneiros liderados pelo cantor e compositor Carlos Pita se apresentam amanh\u00e3, a partir das 19 horas, na reabertura oficial do Centro de Cultura Am\u00e9lio Amorim, em Feira de Santana. Est\u00e1 confiramda tamb\u00e9m a presen\u00e7a do\u00a0secret\u00e1rio de cultura da Bahia, Albino Rubin, que\u2026","rel":"","context":"Em &quot;Home&quot;","block_context":{"text":"Home","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/raiz\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"_links":{"self":[{"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/posts\/2646","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/comments?post=2646"}],"version-history":[{"count":9,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/posts\/2646\/revisions"}],"predecessor-version":[{"id":49182,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/posts\/2646\/revisions\/49182"}],"wp:attachment":[{"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/media?parent=2646"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/categories?post=2646"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/tags?post=2646"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}