{"id":28585,"date":"2017-11-15T11:41:58","date_gmt":"2017-11-15T14:41:58","guid":{"rendered":"http:\/\/blogdafeira.com.br\/home\/?p=28585"},"modified":"2020-09-02T23:45:48","modified_gmt":"2020-09-03T02:45:48","slug":"colegio-em-bonfim-de-feira-realiza-evento-com-foco-em-saude-e-bem-estar","status":"publish","type":"post","link":"https:\/\/blogdafeira.com.br\/home\/2017\/11\/15\/colegio-em-bonfim-de-feira-realiza-evento-com-foco-em-saude-e-bem-estar\/","title":{"rendered":"Col\u00e9gio em Bonfim de Feira realiza evento com foco em sa\u00fade e bem estar"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-28587\" src=\"http:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2017\/11\/images-8.jpeg\" alt=\"images-8\" width=\"470\" height=\"313\" srcset=\"https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2017\/11\/images-8.jpeg 470w, https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2017\/11\/images-8-170x113.jpeg 170w, https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2017\/11\/images-8-346x230.jpeg 346w\" sizes=\"auto, (max-width: 470px) 100vw, 470px\" \/><\/p>\n<div id=\"blogd-3414797765\" class=\"blogd-fim-do-post-mobile blogd-entity-placement\" style=\"margin-left: auto;margin-right: auto;text-align: center;\"><a href=\"https:\/\/www.feiradesantana.ba.gov.br\/servico.asp?s=a&titulo=Prefeitura-de-Feira-lan%C3%A7a-programa-Rem%C3%A9dio-em-Casa-e-transforma-acesso-a-medicamentos-em-pol%C3%ADtica-p%C3%BAblica-de-cuidados.html&id=14&link=secom\/noticias.asp&idn=43684#noticias\" target=_blank><picture>\r\n  <source media=\"(min-width: 768px)\" srcset=\"https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2026\/03\/980x150.gif\">\r\n  \r\n  <img decoding=\"async\" src=\"https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2021\/01\/350x2002.gif\" alt=\"Publicidade\" style=\"width: 100%; max-width: 100%; height: auto; display: block; margin: 0 auto;\">\r\n\t<\/picture><\/a><\/div><p>O Col\u00e9gio Cupertino de Lacerda, no distrito de Bonfim de Feira, realiza nesta quinta-feira,16, a partir das 8h30h, o evento &#8216;Sa\u00fade em Foco&#8217;, com servi\u00e7os voltados para a sa\u00fade e bem estar da popula\u00e7\u00e3o.<\/p>\n<p>Entre servi\u00e7os oferecidos para o p\u00fablico em geral est\u00e3o: Aferi\u00e7\u00e3o de press\u00e3o;Teste de glicemia;Palestras sobre : Sa\u00fade da mulher e do homem, Sa\u00fadeMental,Palestra sobre Hipertens\u00e3o e Diabetes. Sustentabilidade.<\/p>\n<p>Ter\u00e1 tamb\u00e9m um *Bazar Solid\u00e1rio* para arrecadar fundos para o evento de encerramento do ano letivo, no col\u00e9gio estadual.<\/p>\n<div id=\"blogd-4098442386\" class=\"blogd-final-post blogd-entity-placement\"><a href=\"https:\/\/www.feiradesantana.ba.leg.br\/\" target=\"_blank\" aria-label=\"JUNHO-VERMELHO_CA\u0302MARA-DE-FEIRA\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2026\/03\/JUNHO-VERMELHO_CAMARA-DE-FEIRA.gif\" alt=\"\"  class=\"no-lazyload\" width=\"728\" height=\"90\"   \/><\/a><\/div><p>A diretora, Neide Rodrigues, os professores e alunos convidam toda a comunidade para participar do evento.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Col\u00e9gio Cupertino de Lacerda, no distrito de Bonfim de Feira, realiza nesta quinta-feira,16, a partir das 8h30h, o evento &#8216;Sa\u00fade em Foco&#8217;, com servi\u00e7os voltados para a sa\u00fade e bem estar da popula\u00e7\u00e3o. Entre servi\u00e7os oferecidos para o p\u00fablico em geral est\u00e3o: Aferi\u00e7\u00e3o de press\u00e3o;Teste de glicemia;Palestras sobre : Sa\u00fade da mulher e do<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"cybocfi_hide_featured_image":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[748,1],"tags":[368],"class_list":["post-28585","post","type-post","status-publish","format-standard","hentry","category-distritos","category-raiz","tag-distritos"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p3niVf-7r3","jetpack_sharing_enabled":true,"jetpack-related-posts":[{"id":9620,"url":"https:\/\/blogdafeira.com.br\/home\/2014\/03\/13\/audiencias-para-a-ldo-2015-comecam-na-segunda-em-feira\/","url_meta":{"origin":28585,"position":0},"title":"Audi\u00eancias para a LDO 2015 come\u00e7am na segunda em Feira","author":"Blog da Feira","date":"13\/03\/2014","format":false,"excerpt":"Come\u00e7am na segunda-feira, dia 17, as audi\u00eancias p\u00fablica para elabora\u00e7\u00e3o do Projeto de Lei das Diretrizes Or\u00e7ament\u00e1rias de Feira de Santana (LDO) para o exerc\u00edcio de 2015. A primeira reuni\u00e3o ser\u00e1 realizada \u00e0s 8h30 com Regi\u00f5es Administrativas I, II e III no Audit\u00f3rio da Secretaria Municipal de Sa\u00fade. \u00c0s 14h30,\u2026","rel":"","context":"Em &quot;Home&quot;","block_context":{"text":"Home","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/raiz\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":4087,"url":"https:\/\/blogdafeira.com.br\/home\/2013\/08\/02\/prefeito-de-feira-vai-participar-do-seminario-emancipa-humildes\/","url_meta":{"origin":28585,"position":1},"title":"Prefeito de Feira vai participar do semin\u00e1rio &#8216;Emancipa Humildes&#8217;","author":"Blog da Feira","date":"02\/08\/2013","format":false,"excerpt":"O prefeito de Feira, Jos\u00e9 Ronaldo, est\u00e1 na programa\u00e7\u00e3o \u00a0do Semin\u00e1rio Regional de Emancipa\u00e7\u00e3o, que acontecer\u00e1 em Humildes no pr\u00f3ximo dia 18. Ronaldo encerra o evento que tem um dia inteiro de palestras sobre o tema da cria\u00e7\u00e3o de novos munic\u00edpios com desmenbramentos de distritos como \u00e9 o caso de\u2026","rel":"","context":"Em &quot;Home&quot;","block_context":{"text":"Home","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/raiz\/"},"img":{"alt_text":"AAAAAAAAAAAAAAAA","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2013\/08\/AAAAAAAAAAAAAAAA.jpg?resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2013\/08\/AAAAAAAAAAAAAAAA.jpg?resize=350%2C200 1x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2013\/08\/AAAAAAAAAAAAAAAA.jpg?resize=525%2C300 1.5x"},"classes":[]},{"id":51853,"url":"https:\/\/blogdafeira.com.br\/home\/2022\/04\/18\/comecam-hoje-audiencias-publicas-para-ldo-2023\/","url_meta":{"origin":28585,"position":2},"title":"Come\u00e7am hoje audi\u00eancias p\u00fablicas para LDO 2023","author":"Blog da Feira","date":"18\/04\/2022","format":false,"excerpt":"Come\u00e7am hoje no audit\u00f3rio da Secretaria Municipal da Sa\u00fade as audi\u00eancias p\u00fablicas que visam\u00a0 ouvir a sociedade civil para a elabora\u00e7\u00e3o da Lei de Diretrizes Or\u00e7ament\u00e1rias de Feira de Santana para o ano 2023. A LDO deste ano foi o motivo do conflito entre o Poder Executivo e Legislativo.\u00a0 As\u2026","rel":"","context":"Em &quot;Cidade&quot;","block_context":{"text":"Cidade","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/cidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2022\/04\/Feira-de-Santana-BA.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2022\/04\/Feira-de-Santana-BA.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2022\/04\/Feira-de-Santana-BA.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2022\/04\/Feira-de-Santana-BA.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2022\/04\/Feira-de-Santana-BA.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":62288,"url":"https:\/\/blogdafeira.com.br\/home\/2024\/05\/28\/prefeitura-de-feira-promove-palestra-e-plantio-de-arvores-para-comemorar-odia-meio-ambiente\/","url_meta":{"origin":28585,"position":3},"title":"Prefeitura de Feira promove palestra e plantio de \u00e1rvores para comemorar o Dia do Meio Ambiente","author":"Blog da Feira","date":"28\/05\/2024","format":false,"excerpt":"No Dia Mundial do Meio Ambiente (5 de junho) ter\u00e1 programa\u00e7\u00e3o especial em Feira de Santana. As atividades alusivas a data come\u00e7am nesta quarta-feira (29) com a palestra \u201cPolui\u00e7\u00e3o Atmosf\u00e9rica Relacionada ao Uso de Produtos Qu\u00edmicos pelas Empresas Dedetizadoras\u201d, no audit\u00f3rio da Secretaria Municipal de Sa\u00fade, a partir das 8h.\u2026","rel":"","context":"Em &quot;Geral&quot;","block_context":{"text":"Geral","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/geral\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2024\/05\/Dia-da-Arvore-Plantio-de-Mudas-na-Noide-Cerqueira-foto-Jorge-Magalhaes-5-1.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2024\/05\/Dia-da-Arvore-Plantio-de-Mudas-na-Noide-Cerqueira-foto-Jorge-Magalhaes-5-1.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2024\/05\/Dia-da-Arvore-Plantio-de-Mudas-na-Noide-Cerqueira-foto-Jorge-Magalhaes-5-1.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2024\/05\/Dia-da-Arvore-Plantio-de-Mudas-na-Noide-Cerqueira-foto-Jorge-Magalhaes-5-1.jpeg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2024\/05\/Dia-da-Arvore-Plantio-de-Mudas-na-Noide-Cerqueira-foto-Jorge-Magalhaes-5-1.jpeg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":53158,"url":"https:\/\/blogdafeira.com.br\/home\/2022\/07\/04\/audiencias-para-orcamento-de-feira-nao-tem-estimulo-a-participacao-popular\/","url_meta":{"origin":28585,"position":4},"title":"Audi\u00eancias para Or\u00e7amento de Feira n\u00e3o t\u00eam est\u00edmulo \u00e0 participa\u00e7\u00e3o popular","author":"Blog da Feira","date":"04\/07\/2022","format":false,"excerpt":"O Governo de Feira de Santana come\u00e7a amanh\u00e3 (ter\u00e7a-feira,5) em Jaguara, o distrito rural mais distante da sede, as audi\u00eancias p\u00fablicas para elabora\u00e7\u00e3o do projeto da Lei Or\u00e7ament\u00e1ria Anual (LOA), exerc\u00edcio de 2023. Exigidas para legitimar o Or\u00e7amento, as audi\u00eancias na verdade cumprem apenas esse protocolo legal pois s\u00e3o invariavelmente\u2026","rel":"","context":"Em &quot;Geral&quot;","block_context":{"text":"Geral","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/geral\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2022\/07\/audiencia.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2022\/07\/audiencia.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2022\/07\/audiencia.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2022\/07\/audiencia.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2022\/07\/audiencia.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":25928,"url":"https:\/\/blogdafeira.com.br\/home\/2017\/03\/02\/comecam-pelos-distritos-rurais-as-audiencias-publicas-para-o-orcamento-de-feira-2018\/","url_meta":{"origin":28585,"position":5},"title":"Come\u00e7am pelos distritos rurais as audi\u00eancias p\u00fablicas para o Or\u00e7amento de Feira 2018","author":"Blog da Feira","date":"02\/03\/2017","format":false,"excerpt":"A Prefeitura de Feira de Santana come\u00e7a no pr\u00f3ximo dia 21, a realizar as audi\u00eancias p\u00fablicas obrigat\u00f3rias para a elabora\u00e7\u00e3o do Plano Plurianual e a Lei de Diretrizes Or\u00e7ament\u00e1rias para 2018. No calend\u00e1rio divulgado pela Prefeitura, as audi\u00eancias come\u00e7am pelos distritos. No dia 21 est\u00e3o marcadas duas audi\u00eancias: pela manh\u00e3\u2026","rel":"","context":"Em &quot;Distritos&quot;","block_context":{"text":"Distritos","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/distritos\/"},"img":{"alt_text":"BONFIM DE FEIRA - IGREJA","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2015\/10\/BONFIM-DE-FEIRA-IGREJA.jpg?resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2015\/10\/BONFIM-DE-FEIRA-IGREJA.jpg?resize=350%2C200 1x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2015\/10\/BONFIM-DE-FEIRA-IGREJA.jpg?resize=525%2C300 1.5x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/posts\/28585","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/comments?post=28585"}],"version-history":[{"count":2,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/posts\/28585\/revisions"}],"predecessor-version":[{"id":28588,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/posts\/28585\/revisions\/28588"}],"wp:attachment":[{"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/media?parent=28585"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/categories?post=28585"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/tags?post=28585"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}