{"id":32689,"date":"2019-09-03T17:29:13","date_gmt":"2019-09-03T20:29:13","guid":{"rendered":"http:\/\/blogdafeira.com.br\/home\/?p=32689"},"modified":"2019-09-03T17:07:23","modified_gmt":"2019-09-03T20:07:23","slug":"contrato-do-shopping-popular-com-a-prefeitura-de-feira-de-santana-legisla-ate-sobre-uso-do-poder-de-policia-no-municipio","status":"publish","type":"post","link":"https:\/\/blogdafeira.com.br\/home\/2019\/09\/03\/contrato-do-shopping-popular-com-a-prefeitura-de-feira-de-santana-legisla-ate-sobre-uso-do-poder-de-policia-no-municipio\/","title":{"rendered":"Contrato entre shopping popular e Prefeitura de Feira de Santana &#8216;legisla&#8217; at\u00e9 sobre o poder de pol\u00edcia no Munic\u00edpio"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-32683 size-full\" src=\"http:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2019\/09\/IMG-20190715-WA00292.jpg\" alt=\"\" width=\"502\" height=\"815\" srcset=\"https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2019\/09\/IMG-20190715-WA00292.jpg 502w, https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2019\/09\/IMG-20190715-WA00292-92x150.jpg 92w, https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2019\/09\/IMG-20190715-WA00292-185x300.jpg 185w\" sizes=\"auto, (max-width: 502px) 100vw, 502px\" \/><\/p>\n<div id=\"blogd-3216437837\" class=\"blogd-fim-do-post-mobile blogd-entity-placement\" style=\"margin-left: auto;margin-right: auto;text-align: center;\"><a href=\"https:\/\/www.feiradesantana.ba.gov.br\/servico.asp?s=a&titulo=Prefeitura-de-Feira-lan%C3%A7a-programa-Rem%C3%A9dio-em-Casa-e-transforma-acesso-a-medicamentos-em-pol%C3%ADtica-p%C3%BAblica-de-cuidados.html&id=14&link=secom\/noticias.asp&idn=43684#noticias\" target=_blank><picture>\r\n  <source media=\"(min-width: 768px)\" srcset=\"https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2026\/03\/980x150.gif\">\r\n  \r\n  <img decoding=\"async\" src=\"https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2021\/01\/350x2002.gif\" alt=\"Publicidade\" style=\"width: 100%; max-width: 100%; height: auto; display: block; margin: 0 auto;\">\r\n\t<\/picture><\/a><\/div><p>O contrato entre a Prefeitura de Feira de Santana (Concedente) e a S.A Feira Popular\u00a0 (Concession\u00e1ria) tem cl\u00e1usulas francamente desfavor\u00e1veis \u00e0 Municipalidade e que chegam a praticamente substituir o papel do\u00a0 Poder Legislativo.<\/p>\n<p>Um exemplo \u00e9 a que OBRIGA <strong>(foto<\/strong>) a Prefeitura de Feira a usar o <em>&#8216;poder de pol\u00edcia&#8217;<\/em> para impedir e reprimir,\u00a0 n\u00e3o apenas os cadastrados para ocupar o espa\u00e7o mas todo e qualquer <em>&#8220;empreendedor informal&#8217;<\/em>\u00a0 que esteja atuando <em>&#8220;no \u00e2mbito do Munic\u00edpio&#8221;<\/em>.<\/p>\n<blockquote>\n<div><em>\u00c9 obriga\u00e7\u00e3o do PODER CONCEDENTE impedir que os listados no CADASTRO MUNICIPAL ou quaisquer outros empreendedores informais atuem, direta ou indiretamente, no \u00e2mbito do Munic\u00edpio, cabendo-lhe implementar os esfor\u00e7os necess\u00e1rios para exercer seu poder de pol\u00edcia para o cumprimento desta obriga\u00e7\u00e3o.<\/em><\/div>\n<\/blockquote>\n<div><\/div>\n<div>Uma outra situa\u00e7\u00e3o de submiss\u00e3o do Poder P\u00fablico \u00e0 Concession\u00e1ria \u00e9 referente \u00e0 fiscaliza\u00e7\u00e3o relativa ao cumprimento do contrato quanto &#8220;\u00e0 opera\u00e7\u00e3o, manuten\u00e7\u00e3o e explora\u00e7\u00e3o econ\u00f4mica&#8221;.<\/div>\n<div><\/div>\n<div>Nesse caso compete \u00e0 pr\u00f3pria concession\u00e1ria escolher um &#8220;Verificador Independente&#8221; para fiscalizar a si pr\u00f3pria.<\/div>\n<div>\n<div>\n<div><\/div>\n<blockquote>\n<div><\/div>\n<div><em>A CONCESSION\u00c1RIA dever\u00e1 apresentar ao PODER <\/em><em>CONCEDENTE lista tr\u00edplice de entidades independentes de reputa\u00e7\u00e3o t\u00e9cnica no mercado, em at\u00e9 60 (sessenta) dias anteriores ao in\u00edcio da opera\u00e7\u00e3o do CENTRO DE COM\u00c9RCIO POPULAR, cujo termo inicial estar\u00e1 condicionado \u00e0 data do Termo de Recebimento Definitivo das OBRAS.<\/em><\/div>\n<\/blockquote>\n<div>LEIA TAMB\u00c9M:<\/div>\n<\/div>\n<\/div>\n<blockquote class=\"wp-embedded-content\" data-secret=\"nnD63rgkBR\"><p><a href=\"http:\/\/blogdafeira.com.br\/home\/2019\/08\/13\/shopping-popular-tem-ate-cinco-anos-para-absorver-os-camelos-cadastrados-pela-prefeitura-de-feira-de-santana\/\">Shopping Popular tem at\u00e9 cinco anos para absorver os camel\u00f4s cadastrados pela Prefeitura de Feira de Santana<\/a><\/p><\/blockquote>\n<p><iframe loading=\"lazy\" title=\"&#8220;Shopping Popular tem at\u00e9 cinco anos para absorver os camel\u00f4s cadastrados pela Prefeitura de Feira de Santana&#8221; &#8212; Blog da Feira\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; clip: rect(1px, 1px, 1px, 1px);\" src=\"http:\/\/blogdafeira.com.br\/home\/2019\/08\/13\/shopping-popular-tem-ate-cinco-anos-para-absorver-os-camelos-cadastrados-pela-prefeitura-de-feira-de-santana\/embed\/#?secret=nnD63rgkBR\" data-secret=\"nnD63rgkBR\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe><\/p>\n<div id=\"blogd-4057449366\" class=\"blogd-final-post blogd-entity-placement\"><a href=\"https:\/\/www.feiradesantana.ba.leg.br\/\" target=\"_blank\" aria-label=\"JUNHO-VERMELHO_CA\u0302MARA-DE-FEIRA\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2026\/03\/JUNHO-VERMELHO_CAMARA-DE-FEIRA.gif\" alt=\"\"  class=\"no-lazyload\" width=\"728\" height=\"90\"   \/><\/a><\/div><blockquote class=\"wp-embedded-content\" data-secret=\"T9aVsT9Gcs\"><p><a href=\"http:\/\/blogdafeira.com.br\/home\/2017\/05\/29\/alem-de-aluguel-e-condominio-boxes-no-shopping-uai-vao-pagar-a-propaganda\/\">Al\u00e9m de aluguel e condom\u00ednio, boxes no shopping popular em Feira v\u00e3o pagar taxa de propaganda<\/a><\/p><\/blockquote>\n<p><iframe loading=\"lazy\" title=\"&#8220;Al\u00e9m de aluguel e condom\u00ednio, boxes no shopping popular em Feira v\u00e3o pagar taxa de propaganda&#8221; &#8212; Blog da Feira\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; clip: rect(1px, 1px, 1px, 1px);\" src=\"http:\/\/blogdafeira.com.br\/home\/2017\/05\/29\/alem-de-aluguel-e-condominio-boxes-no-shopping-uai-vao-pagar-a-propaganda\/embed\/#?secret=T9aVsT9Gcs\" data-secret=\"T9aVsT9Gcs\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O contrato entre a Prefeitura de Feira de Santana (Concedente) e a S.A Feira Popular\u00a0 (Concession\u00e1ria) tem cl\u00e1usulas francamente desfavor\u00e1veis \u00e0 Municipalidade e que chegam a praticamente substituir o papel do\u00a0 Poder Legislativo. Um exemplo \u00e9 a que OBRIGA (foto) a Prefeitura de Feira a usar o &#8216;poder de pol\u00edcia&#8217; para impedir e reprimir,\u00a0 n\u00e3o<\/p>\n","protected":false},"author":8,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"cybocfi_hide_featured_image":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[1],"tags":[],"class_list":["post-32689","post","type-post","status-publish","format-standard","hentry","category-raiz"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p3niVf-8vf","jetpack_sharing_enabled":true,"jetpack-related-posts":[{"id":31769,"url":"https:\/\/blogdafeira.com.br\/home\/2019\/06\/25\/17-perguntas-sobre-o-shopping-popular-para-a-prefeitura-de-feira-de-santana-responder\/","url_meta":{"origin":32689,"position":0},"title":"17 perguntas sobre o shopping popular para a Prefeitura de Feira de Santana responder","author":"J\u00e2nio R\u00eago","date":"25\/06\/2019","format":false,"excerpt":"O advogado H\u00e9rcules Oliveira, representando a Associa\u00e7\u00e3o dos Pra\u00e7as, Policiais e Bombeiros Militares,usou a 'tribuna livre' da C\u00e2mara de Vereadores de Feira de Santana, hoje pela manh\u00e3, para oficializar em pronunciamento,\u00a0 um documento com 17 perguntas sobre a Parceria P\u00fablico Privada entre a Prefeitura e um cons\u00f3rcio de empresas lideradas\u2026","rel":"","context":"Em &quot;Home&quot;","block_context":{"text":"Home","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/raiz\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2019\/06\/20190611_115850_HDR.jpg?resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2019\/06\/20190611_115850_HDR.jpg?resize=350%2C200 1x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2019\/06\/20190611_115850_HDR.jpg?resize=525%2C300 1.5x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2019\/06\/20190611_115850_HDR.jpg?resize=700%2C400 2x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2019\/06\/20190611_115850_HDR.jpg?resize=1050%2C600 3x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2019\/06\/20190611_115850_HDR.jpg?resize=1400%2C800 4x"},"classes":[]},{"id":70465,"url":"https:\/\/blogdafeira.com.br\/home\/2025\/12\/09\/comerciantes-do-shopping-popular-terao-recursos-do-crediamigo-do-bnb\/","url_meta":{"origin":32689,"position":1},"title":"Comerciantes do Shopping Popular ter\u00e3o recursos do Crediamigo do BNB","author":"Blog da Feira","date":"09\/12\/2025","format":false,"excerpt":"A Prefeitura Municipal de Feira de Santana e o Banco do Nordeste do Brasil (BNB) celebraram, nesta segunda-feira (08), um\u00a0 Acordo de Coopera\u00e7\u00e3o T\u00e9cnica, para\u00a0 principal objetivo \"impulsionar o fomento ao empreendedorismo na cidade, por meio da amplia\u00e7\u00e3o do programa de microcr\u00e9dito produtivo e orientado CrediAmigo.\" O acordo estabelece uma\u2026","rel":"","context":"Em &quot;Economia&quot;","block_context":{"text":"Economia","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/economia\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2025\/12\/Prefeito-Acordo-Banco-do-Nordeste-Fotos-Washington-Nery-08-12-25-6.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2025\/12\/Prefeito-Acordo-Banco-do-Nordeste-Fotos-Washington-Nery-08-12-25-6.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2025\/12\/Prefeito-Acordo-Banco-do-Nordeste-Fotos-Washington-Nery-08-12-25-6.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2025\/12\/Prefeito-Acordo-Banco-do-Nordeste-Fotos-Washington-Nery-08-12-25-6.jpeg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2025\/12\/Prefeito-Acordo-Banco-do-Nordeste-Fotos-Washington-Nery-08-12-25-6.jpeg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":32363,"url":"https:\/\/blogdafeira.com.br\/home\/2019\/08\/13\/shopping-popular-tem-ate-cinco-anos-para-absorver-os-camelos-cadastrados-pela-prefeitura-de-feira-de-santana\/","url_meta":{"origin":32689,"position":2},"title":"Shopping Popular tem at\u00e9 cinco anos para absorver os camel\u00f4s cadastrados pela Prefeitura de Feira de Santana","author":"J\u00e2nio R\u00eago","date":"13\/08\/2019","format":false,"excerpt":"Quem pensou que por ter sido cadastrado pela Prefeitura de Feira de Santana como camel\u00f4 da Sales Barbosa ou da Marechal tem garantida a ocupa\u00e7\u00e3o de um espa\u00e7o no Shopping Popular est\u00e1 enganado. A 'Concession\u00e1ria', ou seja, o Shopping Popular tem at\u00e9 cinco anos para arranjar uma coloca\u00e7\u00e3o para os\u2026","rel":"","context":"Em &quot;Home&quot;","block_context":{"text":"Home","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/raiz\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2019\/08\/IMG-20190715-WA00242-182x300.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":32862,"url":"https:\/\/blogdafeira.com.br\/home\/2019\/09\/16\/audiencia-publica-nesta-terca-sobre-o-shopping-popular-de-feira-de-santana\/","url_meta":{"origin":32689,"position":3},"title":"Audi\u00eancia p\u00fablica nesta ter\u00e7a sobre o shopping popular de Feira de Santana","author":"J\u00e2nio R\u00eago","date":"16\/09\/2019","format":false,"excerpt":"Acontece nesta ter\u00e7a-feira a audi\u00eancia p\u00fablica na Camara de Vereadores de Feira de Santana sobre o pol\u00eamico shopping popular em constru\u00e7ao no antigo Centro de Abastecimento. A audi\u00eancia foi marcada ap\u00f3s uma s\u00e9rie de protestos de feirantes e camel\u00f4s que ser\u00e3o relocados do centro da cidade para o shopping. \u00c9\u2026","rel":"","context":"Em &quot;Home&quot;","block_context":{"text":"Home","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/raiz\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2019\/09\/20190826_111532_HDR-576x1024.jpg?resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2019\/09\/20190826_111532_HDR-576x1024.jpg?resize=350%2C200 1x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2019\/09\/20190826_111532_HDR-576x1024.jpg?resize=525%2C300 1.5x"},"classes":[]},{"id":70853,"url":"https:\/\/blogdafeira.com.br\/home\/2026\/01\/11\/municipio-apura-contratos-de-organizacoes-sociais-na-saude-para-garantir-direitos-trabalhistas-e-qualidade-do-servico\/","url_meta":{"origin":32689,"position":4},"title":"Z\u00e9 Ronaldo autoriza portaria para apurar supostas irregularidades em Organiza\u00e7\u00f5es Sociais na Sa\u00fade","author":"Blog da Feira","date":"11\/01\/2026","format":false,"excerpt":"A Prefeitura de Feira de Santana instaurou um Processo Administrativo para apurar poss\u00edveis irregularidades na execu\u00e7\u00e3o de contratos de gest\u00e3o na \u00e1rea da Sa\u00fade. A medida foi oficializada por meio da Portaria n\u00ba 035\/2026, publicada no Di\u00e1rio Oficial do Munic\u00edpio, ontem, s\u00e1bado (10). A decis\u00e3o do prefeito Z\u00e9 Ronaldo atende\u2026","rel":"","context":"Em &quot;Cidade&quot;","block_context":{"text":"Cidade","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/cidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2026\/01\/10012026125719.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2026\/01\/10012026125719.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2026\/01\/10012026125719.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2026\/01\/10012026125719.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2026\/01\/10012026125719.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":46540,"url":"https:\/\/blogdafeira.com.br\/home\/2021\/07\/20\/emendas-a-ldo-de-feira-impedem-a-governabilidade-diz-vereador-pedro-americo\/","url_meta":{"origin":32689,"position":5},"title":"Emendas \u00e0 LDO de Feira impedem a governabilidade, diz vereador Pedro Am\u00e9rico","author":"Blog da Feira","date":"20\/07\/2021","format":false,"excerpt":"O vereador Pedro Am\u00e9rico (DEM) admitiu hoje pela manh\u00e3 em entrevista ao radialista Juarez Fernandes, no Suba\u00e9 Not\u00edcias, a possibilidade da Prefeitura de Feira de Santana recorrer \u00e0 Justi\u00e7a caso as emendas \u00e0 Lei de Diretrizes Or\u00e7ament\u00e1rias (LDO) sejam aprovadas da maneira como foram encaminhadas para discuss\u00e3o e vota\u00e7\u00e3o, ou\u2026","rel":"","context":"Em &quot;Home&quot;","block_context":{"text":"Home","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/raiz\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2021\/07\/15042021102322.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2021\/07\/15042021102322.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2021\/07\/15042021102322.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2021\/07\/15042021102322.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2021\/07\/15042021102322.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/posts\/32689","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/comments?post=32689"}],"version-history":[{"count":8,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/posts\/32689\/revisions"}],"predecessor-version":[{"id":32704,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/posts\/32689\/revisions\/32704"}],"wp:attachment":[{"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/media?parent=32689"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/categories?post=32689"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/tags?post=32689"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}