{"id":3441,"date":"2013-07-12T12:08:46","date_gmt":"2013-07-12T15:08:46","guid":{"rendered":"http:\/\/blogdafeira.com.br\/home\/?p=3441"},"modified":"2013-07-12T12:08:46","modified_gmt":"2013-07-12T15:08:46","slug":"wagner-em-feira-entrega-apartamentos-no-bairro-do-aeroporto","status":"publish","type":"post","link":"https:\/\/blogdafeira.com.br\/home\/2013\/07\/12\/wagner-em-feira-entrega-apartamentos-no-bairro-do-aeroporto\/","title":{"rendered":"Wagner em Feira entrega apartamentos no bairro do Aeroporto"},"content":{"rendered":"<div id=\"blogd-791803024\" class=\"blogd-fim-do-post-mobile blogd-entity-placement\" style=\"margin-left: auto;margin-right: auto;text-align: center;\"><a href=\"https:\/\/www.feiradesantana.ba.gov.br\/servico.asp?s=a&titulo=Prefeitura-de-Feira-lan%C3%A7a-programa-Rem%C3%A9dio-em-Casa-e-transforma-acesso-a-medicamentos-em-pol%C3%ADtica-p%C3%BAblica-de-cuidados.html&id=14&link=secom\/noticias.asp&idn=43684#noticias\" target=_blank><picture>\r\n  <source media=\"(min-width: 768px)\" srcset=\"https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2026\/03\/980x150.gif\">\r\n  \r\n  <img decoding=\"async\" src=\"https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2021\/01\/350x2002.gif\" alt=\"Publicidade\" style=\"width: 100%; max-width: 100%; height: auto; display: block; margin: 0 auto;\">\r\n\t<\/picture><\/a><\/div><p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-3442\" alt=\"120713MD 08copy\" src=\"http:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2013\/07\/120713MD-08copy.jpg\" width=\"640\" height=\"427\" srcset=\"https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2013\/07\/120713MD-08copy.jpg 640w, https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2013\/07\/120713MD-08copy-170x113.jpg 170w, https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2013\/07\/120713MD-08copy-346x230.jpg 346w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/>Com a presen\u00e7a do governador Jaques Wagner foram entregues hoje em Feira de Santana 1.000 apartamentos populares no bairro do Aeroporto.Os im\u00f3veis dos residenciais \u00a0Vida Nova Aeroporto I \u00a0e II t\u00eam \u00a0t\u00eam dois quartos, sala, cozinha, banheiro e \u00e1rea de servi\u00e7o e cerca de 40 metros quadrados.<\/p>\n<p>Com a entrega desta sexta em Feira de Santana, a Bahia segue como um dos estados que mais construiu unidades habitacionais no Minha Casa, Minha Vida. S\u00e3o mais de 120 mil im\u00f3veis.<\/p>\n<div id=\"blogd-1775058506\" class=\"blogd-final-post blogd-entity-placement\"><a href=\"https:\/\/www.feiradesantana.ba.leg.br\/\" target=\"_blank\" aria-label=\"JUNHO-VERMELHO_CA\u0302MARA-DE-FEIRA\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2026\/03\/JUNHO-VERMELHO_CAMARA-DE-FEIRA.gif\" alt=\"\"  class=\"no-lazyload\" width=\"728\" height=\"90\"   \/><\/a><\/div><p>Wagner tamb\u00e9m entregou viaturas para a Delegacia Especial de Atendimento \u00e0 Mulher (Deam) de Feira de Santana.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Com a presen\u00e7a do governador Jaques Wagner foram entregues hoje em Feira de Santana 1.000 apartamentos populares no bairro do Aeroporto.Os im\u00f3veis dos residenciais \u00a0Vida Nova Aeroporto I \u00a0e II t\u00eam \u00a0t\u00eam dois quartos, sala, cozinha, banheiro e \u00e1rea de servi\u00e7o e cerca de 40 metros quadrados. Com a entrega desta sexta em Feira de<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"cybocfi_hide_featured_image":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[1],"tags":[],"class_list":["post-3441","post","type-post","status-publish","format-standard","hentry","category-raiz"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p3niVf-Tv","jetpack_sharing_enabled":true,"jetpack-related-posts":[{"id":1969,"url":"https:\/\/blogdafeira.com.br\/home\/2013\/05\/27\/wagner-entrega-maquinas-no-derba-mas-suspende-visita-a-car\/","url_meta":{"origin":3441,"position":0},"title":"Wagner entrega m\u00e1quinas no Derba mas suspende visita \u00e0 CAR","author":"Blog da Feira","date":"27\/05\/2013","format":false,"excerpt":"O governador Jacques Wagner cumpriu pela metade a agenda programada para sua visita hoje a Feira de Santana. Wagner entregou m\u00e1quinas e equipamentos na sede do Derba, na avenida Transnordestina (BR-116 Norte) mas n\u00e3o foi \u00e0 inaugura\u00e7\u00e3o do novo escrit\u00f3rio da Companhia de Desenvolvimento e A\u00e7\u00e3o Regional, a CAR. A\u2026","rel":"","context":"Em &quot;Cidade&quot;","block_context":{"text":"Cidade","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/cidade\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":12300,"url":"https:\/\/blogdafeira.com.br\/home\/2014\/09\/11\/governo-wagner-tira-nome-de-joao-durval-do-aeroporto-de-feira\/","url_meta":{"origin":3441,"position":1},"title":"Governo Wagner tira nome de Jo\u00e3o Durval do Aeroporto de Feira","author":"Blog da Feira","date":"11\/09\/2014","format":false,"excerpt":"O nome do ex-governador Jo\u00e3o Durval Carneiro sumiu da placa oficial reinaugurada ontem no Aeroporto de Feira de Santana, pelo governador Jaques Wagner. Na placa (foto) tem apenas o nome Aeroporto de Feira de Santana e os do governador, secret\u00e1rio da Infra-Estrutura \u00a0e do executivo da Agerba. Al\u00e9m do Aeroporto,\u2026","rel":"","context":"Em &quot;Home&quot;","block_context":{"text":"Home","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/raiz\/"},"img":{"alt_text":"AEROPORTO","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2014\/09\/AEROPORTO.jpg?resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2014\/09\/AEROPORTO.jpg?resize=350%2C200 1x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2014\/09\/AEROPORTO.jpg?resize=525%2C300 1.5x"},"classes":[]},{"id":9396,"url":"https:\/\/blogdafeira.com.br\/home\/2014\/02\/28\/sem-holofotes-wagner-e-ronado-conversam\/","url_meta":{"origin":3441,"position":2},"title":"Sem holofotes, Wagner e Ronaldo conversam","author":"Blog da Feira","date":"28\/02\/2014","format":false,"excerpt":"Ap\u00f3s entrega de residenciais do programa \"Minha Casa, Minha Vida\", no bairro Avi\u00e1rio, na tarde de quinta-feira (27), Jaques Wagner e Jos\u00e9 Ronaldo \u00a0tiveram a oportunidade de consersar sem holofotes. No final do ato p\u00fablico, que contou com a cobertura da imprensa local, o governador convidou o prefeito de Feira\u2026","rel":"","context":"Em &quot;Home&quot;","block_context":{"text":"Home","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/raiz\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":7735,"url":"https:\/\/blogdafeira.com.br\/home\/2013\/12\/26\/minha-casa-minha-vida-wagner-mais-uma-vez-em-feira-com-ze-neto\/","url_meta":{"origin":3441,"position":3},"title":"&#8216;Minha Casa, Minha Vida&#8217;: Wagner mais uma vez em Feira com Z\u00e9 Neto","author":"Blog da Feira","date":"26\/12\/2013","format":false,"excerpt":"O governador Jacques Wagner vir\u00e1 a Feira, talvez pela \u00faltima vez este ano, na pr\u00f3xima sexta-feira, dia 27, para entrega de resid\u00eancias constru\u00eddas atrav\u00e9s do programa Minha Casa, Minha Vida. A entrega das unidades vai acontecer a partir das 9 horas. Em Feira mais uma vez o governador ter\u00e1 oportunidade,\u2026","rel":"","context":"Em &quot;Home&quot;","block_context":{"text":"Home","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/raiz\/"},"img":{"alt_text":"DSC02341","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2013\/12\/DSC02341.jpg?resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2013\/12\/DSC02341.jpg?resize=350%2C200 1x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2013\/12\/DSC02341.jpg?resize=525%2C300 1.5x"},"classes":[]},{"id":800,"url":"https:\/\/blogdafeira.com.br\/home\/2013\/04\/23\/wagner-em-feira-nesta-quinta-para-entregar-retroescavadeiras\/","url_meta":{"origin":3441,"position":4},"title":"Wagner em Feira nesta quinta para entregar retroescavadeiras","author":"Blog da Feira","date":"23\/04\/2013","format":false,"excerpt":"O governador da Bahia, Jacques Wagner vem a Feira de Santana nesta quinta-feira para distribuir \u00a020 retroescavadeiras a Prefeituras das regi\u00e3o. Os equipamentos est\u00e3o estocados no p\u00e1tio do Derba, na BR-116 norte. O governador anunciou sua visita a Feira, hoje, durante o programa radiof\u00f4nico 'Conversa com o Governador.","rel":"","context":"Em &quot;Home&quot;","block_context":{"text":"Home","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/raiz\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":7770,"url":"https:\/\/blogdafeira.com.br\/home\/2013\/12\/27\/clima-pode-ficar-tenso-hoje-entre-ronaldo-ze-neto-e-wagner\/","url_meta":{"origin":3441,"position":5},"title":"Clima pode ficar tenso hoje entre Ronaldo, Z\u00e9 Neto e Wagner","author":"Blog da Feira","date":"27\/12\/2013","format":false,"excerpt":"A entrega de mais unidades residenciais do programa Minha Casa Minha Vida em Feira de Santana vai provocar, logo mais a partir das 9 horas, um encontro do Prefeito de Feira, Jos\u00e9 Ronaldo, com o deputado Z\u00e9 Neto e o governador Jacques Wagner. O clima entre eles poder\u00e1 n\u00e3o ser\u2026","rel":"","context":"Em &quot;Home&quot;","block_context":{"text":"Home","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/raiz\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"_links":{"self":[{"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/posts\/3441","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/comments?post=3441"}],"version-history":[{"count":1,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/posts\/3441\/revisions"}],"predecessor-version":[{"id":3443,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/posts\/3441\/revisions\/3443"}],"wp:attachment":[{"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/media?parent=3441"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/categories?post=3441"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/tags?post=3441"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}