{"id":3452,"date":"2013-07-12T13:57:42","date_gmt":"2013-07-12T16:57:42","guid":{"rendered":"http:\/\/blogdafeira.com.br\/home\/?p=3452"},"modified":"2013-07-12T13:57:42","modified_gmt":"2013-07-12T16:57:42","slug":"uefs-e-prefeitura-vao-fazer-estudo-sobre-moradores-de-rua-em-feira","status":"publish","type":"post","link":"https:\/\/blogdafeira.com.br\/home\/2013\/07\/12\/uefs-e-prefeitura-vao-fazer-estudo-sobre-moradores-de-rua-em-feira\/","title":{"rendered":"UEFS e Prefeitura v\u00e3o fazer estudo sobre moradores de rua em Feira"},"content":{"rendered":"<div id=\"blogd-183833663\" class=\"blogd-fim-do-post-mobile blogd-entity-placement\" style=\"margin-left: auto;margin-right: auto;text-align: center;\"><a href=\"https:\/\/www.feiradesantana.ba.gov.br\/servico.asp?s=a&titulo=Prefeitura-de-Feira-lan%C3%A7a-programa-Rem%C3%A9dio-em-Casa-e-transforma-acesso-a-medicamentos-em-pol%C3%ADtica-p%C3%BAblica-de-cuidados.html&id=14&link=secom\/noticias.asp&idn=43684#noticias\" target=_blank><picture>\r\n  <source media=\"(min-width: 768px)\" srcset=\"https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2026\/03\/980x150.gif\">\r\n  \r\n  <img decoding=\"async\" src=\"https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2021\/01\/350x2002.gif\" alt=\"Publicidade\" style=\"width: 100%; max-width: 100%; height: auto; display: block; margin: 0 auto;\">\r\n\t<\/picture><\/a><\/div><p>A Secretaria Municipal de Desenvolvimento Social (Sedeso) e a Universidade Estadual de Feira de Santana (UEFS) firmar\u00e3o um conv\u00eanio para a realiza\u00e7\u00e3o de estudos voltados \u00e0 pol\u00edtica de desenvolvimento social do munic\u00edpio.<\/p>\n<p>A medida foi definida durante uma reuni\u00e3o entre o secret\u00e1rio Ildes Ferreira e o reitor Jos\u00e9 Carlos Barreto.<\/p>\n<div id=\"blogd-2826360311\" class=\"blogd-final-post blogd-entity-placement\"><a href=\"https:\/\/www.feiradesantana.ba.leg.br\/\" target=\"_blank\" aria-label=\"JUNHO-VERMELHO_CA\u0302MARA-DE-FEIRA\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2026\/03\/JUNHO-VERMELHO_CAMARA-DE-FEIRA.gif\" alt=\"\"  class=\"no-lazyload\" width=\"728\" height=\"90\"   \/><\/a><\/div><p>A partir do conv\u00eanio ser\u00e3o realizados estudos-diagn\u00f3sticos sobre o trabalho infantil no munic\u00edpio, moradores de rua e catadores de materiais recicl\u00e1veis.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Secretaria Municipal de Desenvolvimento Social (Sedeso) e a Universidade Estadual de Feira de Santana (UEFS) firmar\u00e3o um conv\u00eanio para a realiza\u00e7\u00e3o de estudos voltados \u00e0 pol\u00edtica de desenvolvimento social do munic\u00edpio. A medida foi definida durante uma reuni\u00e3o entre o secret\u00e1rio Ildes Ferreira e o reitor Jos\u00e9 Carlos Barreto. A partir do conv\u00eanio ser\u00e3o<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"cybocfi_hide_featured_image":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[1],"tags":[],"class_list":["post-3452","post","type-post","status-publish","format-standard","hentry","category-raiz"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p3niVf-TG","jetpack_sharing_enabled":true,"jetpack-related-posts":[{"id":41608,"url":"https:\/\/blogdafeira.com.br\/home\/2020\/11\/06\/estudantes-da-uefs-realizam-pesquisa-sobre-contas-publicas-de-municipios-baianos\/","url_meta":{"origin":3452,"position":0},"title":"Estudantes da Uefs realizam pesquisa sobre contas p\u00fablicas de munic\u00edpios baianos","author":"Blog da Feira","date":"06\/11\/2020","format":false,"excerpt":"Os estudantes do 4\u00ba semestre do curso de Administra\u00e7\u00e3o da Universidade Estadual de Feira de Santana (Uefs) realizaram por cerca de 3 meses uma pesquisa sobre a gest\u00e3o financeira de 7 cidades do estado da Bahia com popula\u00e7\u00e3o superior a 200 mil habitantes. A atividade produzida virtualmente \u00e9 da disciplina\u2026","rel":"","context":"Em &quot;Bahia&quot;","block_context":{"text":"Bahia","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/bahia\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2020\/07\/uefs-uefs.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2020\/07\/uefs-uefs.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2020\/07\/uefs-uefs.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":27422,"url":"https:\/\/blogdafeira.com.br\/home\/2017\/07\/12\/observatorio-da-cidade-vai-reunir-estudos-sobre-feira-produzidos-pela-uefs\/","url_meta":{"origin":3452,"position":1},"title":"&#8216;Observat\u00f3rio da Cidade&#8217; vai reunir estudos sobre Feira produzidos pela UEFS","author":"Blog da Feira","date":"12\/07\/2017","format":false,"excerpt":"At\u00e9 o final do ano o site \"Observat\u00f3rio da Cidade\" \u00a0estar\u00e1 no ar, reunindo e \u00a0disponibilizando para a comunidade conhecimentos e estudos sobre o Munic\u00edpio e Regi\u00e3o de Feira de Santana, produzidos, principalmente, pela Universidade Estadual de Feira de Santana (UEFS). \"As universidades devem atuar como institui\u00e7\u00f5es parceiras e dinamizadoras\u2026","rel":"","context":"Em &quot;Home&quot;","block_context":{"text":"Home","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/raiz\/"},"img":{"alt_text":"evandro-reitor","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2017\/07\/evandro-reitor-1024x685.jpg?resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2017\/07\/evandro-reitor-1024x685.jpg?resize=350%2C200 1x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2017\/07\/evandro-reitor-1024x685.jpg?resize=525%2C300 1.5x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2017\/07\/evandro-reitor-1024x685.jpg?resize=700%2C400 2x"},"classes":[]},{"id":28847,"url":"https:\/\/blogdafeira.com.br\/home\/2017\/12\/21\/uefs-assinou-convenio-com-universidade-peruana-na-area-de-ciencias-ambientais\/","url_meta":{"origin":3452,"position":2},"title":"UEFS assinou conv\u00eanio com universidade peruana na \u00e1rea de ci\u00eancias ambientais","author":"Blog da Feira","date":"21\/12\/2017","format":false,"excerpt":"A Universidade Estadual de Feira de Santana (Uefs) vai atuar em parceria com a Universidad Nacional de Moquegua (Unam), do Peru, para o desenvolvimento de projetos de pesquisa, ensino e difus\u00e3o do conhecimento, em especial da \u00e1rea de Ci\u00eancias Ambientais. Conv\u00eanio neste sentido foi assinado pelo reitor Evandro do Nascimento\u2026","rel":"","context":"Em &quot;Home&quot;","block_context":{"text":"Home","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/raiz\/"},"img":{"alt_text":"img_3128","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2017\/12\/IMG_3128-1024x658.jpg?resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2017\/12\/IMG_3128-1024x658.jpg?resize=350%2C200 1x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2017\/12\/IMG_3128-1024x658.jpg?resize=525%2C300 1.5x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2017\/12\/IMG_3128-1024x658.jpg?resize=700%2C400 2x"},"classes":[]},{"id":59219,"url":"https:\/\/blogdafeira.com.br\/home\/2023\/09\/03\/jeronimo-assina-convenios-e-autoriza-obras-em-saubara\/","url_meta":{"origin":3452,"position":3},"title":"Jer\u00f4nimo assina conv\u00eanios e autoriza obras em Saubara","author":"Blog da Feira","date":"03\/09\/2023","format":false,"excerpt":"Neste domingo (3), o governador Jer\u00f4nimo Rodrigues esteve no munic\u00edpio de Saubara, no Rec\u00f4ncavo Baiano, a 70km de Feira de Santana,\u00a0 para autorizar a realiza\u00e7\u00e3o de obras\u00a0 nas \u00e1reas de infraestrutura, desenvolvimento urbano, desenvolvimento rural e esporte. Ele assinou ordem de servi\u00e7o para a pavimenta\u00e7\u00e3o de trecho de estrada, celebra\u00e7\u00e3o\u2026","rel":"","context":"Em &quot;Home&quot;","block_context":{"text":"Home","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/raiz\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2023\/09\/Assinaturas-saubara-4-Foto-Feijao-Almeida_GOVBA.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2023\/09\/Assinaturas-saubara-4-Foto-Feijao-Almeida_GOVBA.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2023\/09\/Assinaturas-saubara-4-Foto-Feijao-Almeida_GOVBA.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2023\/09\/Assinaturas-saubara-4-Foto-Feijao-Almeida_GOVBA.jpeg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2023\/09\/Assinaturas-saubara-4-Foto-Feijao-Almeida_GOVBA.jpeg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2023\/09\/Assinaturas-saubara-4-Foto-Feijao-Almeida_GOVBA.jpeg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":57427,"url":"https:\/\/blogdafeira.com.br\/home\/2023\/05\/04\/eua-financia-500-mil-para-pesquisa-na-uefs-sobre-ayahuasca\/","url_meta":{"origin":3452,"position":4},"title":"EUA financia 500 mil para pesquisa na UEFS sobre ayahuasca","author":"J\u00e2nio R\u00eago","date":"04\/05\/2023","format":false,"excerpt":"O projeto de pesquisa da Universidade Estadual de Feira de Santana (Uefs) intitulado ''Efeitos persistentes, agudos e subagudos da ayahuasca: uma avalia\u00e7\u00e3o neuropsiqui\u00e1trica transcultural'' receber\u00e1 um financiamento de cerca de R$ 500.000,00, atrav\u00e9s de um conv\u00eanio firmado com o Federal Drug Administration (FDA), uma ag\u00eancia reguladora ligada ao departamento de\u2026","rel":"","context":"Em &quot;Geral&quot;","block_context":{"text":"Geral","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/geral\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2023\/05\/R-7.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2023\/05\/R-7.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2023\/05\/R-7.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2023\/05\/R-7.jpeg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":37850,"url":"https:\/\/blogdafeira.com.br\/home\/2020\/05\/17\/ibope-faz-pesquisa-em-feira-sobre-a-propagacao-do-coronavirus-no-brasil\/","url_meta":{"origin":3452,"position":5},"title":"Ibope faz pesquisa em Feira sobre a propaga\u00e7\u00e3o do coronav\u00edrus no Brasil","author":"Blog da Feira","date":"17\/05\/2020","format":false,"excerpt":"O IBOPE Intelig\u00eancia finaliza hoje, 17, a pesquisa em Feira de Santana e em todo o pa\u00eds sobre a preval\u00eancia do COVID-19 na popula\u00e7\u00e3o brasileira. A coordena\u00e7\u00e3o do estudo \u00e9 da Universidade Federal de Pelotas - UFPel, com financiamento do Minist\u00e9rio da Sa\u00fade. O objetivo dessa pesquisa \u00e9 medir o\u2026","rel":"","context":"Em &quot;Cidade&quot;","block_context":{"text":"Cidade","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/cidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2020\/05\/capa-25.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2020\/05\/capa-25.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2020\/05\/capa-25.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/posts\/3452","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/comments?post=3452"}],"version-history":[{"count":2,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/posts\/3452\/revisions"}],"predecessor-version":[{"id":3454,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/posts\/3452\/revisions\/3454"}],"wp:attachment":[{"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/media?parent=3452"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/categories?post=3452"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/tags?post=3452"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}