{"id":3468,"date":"2013-07-12T16:57:13","date_gmt":"2013-07-12T19:57:13","guid":{"rendered":"http:\/\/blogdafeira.com.br\/home\/?p=3468"},"modified":"2013-07-17T00:56:09","modified_gmt":"2013-07-17T03:56:09","slug":"debate-na-uefs-dia-18-sobre-as-manifestacoes-de-junho","status":"publish","type":"post","link":"https:\/\/blogdafeira.com.br\/home\/2013\/07\/12\/debate-na-uefs-dia-18-sobre-as-manifestacoes-de-junho\/","title":{"rendered":"Debate na UEFS, dia 18, sobre as &#8216;manifesta\u00e7\u00f5es de junho&#8217;"},"content":{"rendered":"<div id=\"blogd-1303663733\" class=\"blogd-fim-do-post-mobile blogd-entity-placement\" style=\"margin-left: auto;margin-right: auto;text-align: center;\"><a href=\"https:\/\/www.feiradesantana.ba.gov.br\/servico.asp?s=a&titulo=Prefeitura-de-Feira-lan%C3%A7a-programa-Rem%C3%A9dio-em-Casa-e-transforma-acesso-a-medicamentos-em-pol%C3%ADtica-p%C3%BAblica-de-cuidados.html&id=14&link=secom\/noticias.asp&idn=43684#noticias\" target=_blank><picture>\r\n  <source media=\"(min-width: 768px)\" srcset=\"https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2026\/03\/980x150.gif\">\r\n  \r\n  <img decoding=\"async\" src=\"https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2021\/01\/350x2002.gif\" alt=\"Publicidade\" style=\"width: 100%; max-width: 100%; height: auto; display: block; margin: 0 auto;\">\r\n\t<\/picture><\/a><\/div><p>Um debate \u00a0sobre &#8216;as manifesta\u00e7\u00f5es de junho&#8217;, vai acontecer no pr\u00f3ximo dia <img loading=\"lazy\" decoding=\"async\" class=\"alignright size-thumbnail wp-image-3469\" alt=\"UEFS\" src=\"http:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2013\/07\/UEFS-106x150.jpg\" width=\"106\" height=\"150\" srcset=\"https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2013\/07\/UEFS-106x150.jpg 106w, https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2013\/07\/UEFS-212x300.jpg 212w, https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2013\/07\/UEFS.jpg 453w\" sizes=\"auto, (max-width: 106px) 100vw, 106px\" \/>18, \u00e0s 18:30h, \u00a0no m\u00f3dulo 2 do campus da UEFS, em Feira de Santana.<\/p>\n<p>Na mesa de discuss\u00e3o v\u00e3o estar os professores\u00a0Malcom Rodrigues, \u00a0Z\u00f3zimo Trabuco, \u00a0<a href=\"http:\/\/www.bahianoticias.com.br\/2011\/imprime.php?tabela=principal_noticias&amp;cod=93422\" target=\"_blank\">Andr\u00e9 Uzeda<\/a> e \u00a0<a href=\"https:\/\/www.facebook.com\/jhonatas.monteiro.50?fref=ts\" target=\"_blank\">Jhonatas Monteiro<\/a>, tendo como mediador\u00a0\u00a0Charliston Pablo.<\/p>\n<div id=\"blogd-3073461192\" class=\"blogd-final-post blogd-entity-placement\"><a href=\"https:\/\/www.feiradesantana.ba.leg.br\/\" target=\"_blank\" aria-label=\"JUNHO-VERMELHO_CA\u0302MARA-DE-FEIRA\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2026\/03\/JUNHO-VERMELHO_CAMARA-DE-FEIRA.gif\" alt=\"\"  class=\"no-lazyload\" width=\"728\" height=\"90\"   \/><\/a><\/div><p>O evento \u00e9 aberto ao p\u00fablico.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Um debate \u00a0sobre &#8216;as manifesta\u00e7\u00f5es de junho&#8217;, vai acontecer no pr\u00f3ximo dia 18, \u00e0s 18:30h, \u00a0no m\u00f3dulo 2 do campus da UEFS, em Feira de Santana. Na mesa de discuss\u00e3o v\u00e3o estar os professores\u00a0Malcom Rodrigues, \u00a0Z\u00f3zimo Trabuco, \u00a0Andr\u00e9 Uzeda e \u00a0Jhonatas Monteiro, tendo como mediador\u00a0\u00a0Charliston Pablo. O evento \u00e9 aberto ao p\u00fablico.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"cybocfi_hide_featured_image":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[1],"tags":[],"class_list":["post-3468","post","type-post","status-publish","format-standard","hentry","category-raiz"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p3niVf-TW","jetpack_sharing_enabled":true,"jetpack-related-posts":[{"id":27123,"url":"https:\/\/blogdafeira.com.br\/home\/2017\/06\/14\/uefs-promove-debate-sobre-o-momento-politico-do-pais\/","url_meta":{"origin":3468,"position":0},"title":"UEFS promove debate sobre o momento pol\u00edtico do pa\u00eds","author":"Blog da Feira","date":"14\/06\/2017","format":false,"excerpt":"Ser\u00e1 realizada na Universidade Estadual de Feira de Santana (Uefs) a mesa redonda \"Conjuntura Pol\u00edtica Nacional e seus impactos nas Institui\u00e7\u00f5es P\u00fablicas de Feira de Santana\". O evento est\u00e1 programado\u00a0 para o pr\u00f3ximo dia\u00a021 de junho (quarta-feira), \u00e0s 9 h, no Anfiteatro do m\u00f3dulo 2 do campus universit\u00e1rio. Os palestrantes\u2026","rel":"","context":"Em &quot;Home&quot;","block_context":{"text":"Home","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/raiz\/"},"img":{"alt_text":"uefs uefs","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2016\/05\/uefs-uefs.jpg?resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2016\/05\/uefs-uefs.jpg?resize=350%2C200 1x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2016\/05\/uefs-uefs.jpg?resize=525%2C300 1.5x"},"classes":[]},{"id":14169,"url":"https:\/\/blogdafeira.com.br\/home\/2015\/03\/18\/evandro-e-normalucia-debatem-hoje-o-futuro-da-uefs\/","url_meta":{"origin":3468,"position":1},"title":"Evandro e Normal\u00facia debatem hoje o futuro da UEFS","author":"Blog da Feira","date":"18\/03\/2015","format":false,"excerpt":"Os professores Evandro Nascimento e NormaLucia Almeida, candidatos \u00fanicos \u00e0 Reitor e Vice da UEFS, promovem um debate com a comunidade, hoje \u00e0s 18 horas, no campus em Feira de Santana. A elei\u00e7\u00e3o acontecer\u00e1 no final deste m\u00eas.","rel":"","context":"Em &quot;Home&quot;","block_context":{"text":"Home","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/raiz\/"},"img":{"alt_text":"1_ELEI_ES","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2015\/03\/1_ELEI_ES.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":10604,"url":"https:\/\/blogdafeira.com.br\/home\/2014\/05\/27\/justica-comunicacao-e-etica-em-debate-quinta-feira-na-uefs\/","url_meta":{"origin":3468,"position":2},"title":"Justi\u00e7a, Comunica\u00e7\u00e3o e \u00c9tica em debate quinta-feira na UEFS","author":"Blog da Feira","date":"27\/05\/2014","format":false,"excerpt":"Temas como \u201cA mentira na pol\u00edtica\u201d, \u201cA imprensa no mensal\u00e3o\u201d e \u201cNa Filosofia Pol\u00edtica, o que faz esc\u00e2ndalo?\u201d ser\u00e3o abordados durante o 1\u00ba Semin\u00e1rio sobre genealogias do esc\u00e2ndalo pol\u00edtico no Brasil democr\u00e1tico, evento que \u00a0ocorrer\u00e1 no dia 29 de maio, na Universidade Estadual de Feira de Santana (Uefs). A Confer\u00eancia\u2026","rel":"","context":"Em &quot;Home&quot;","block_context":{"text":"Home","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/raiz\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":14763,"url":"https:\/\/blogdafeira.com.br\/home\/2015\/05\/05\/calourada-da-uefs-vai-debater-sobre-brt-de-feira-tu-acha-o-que\/","url_meta":{"origin":3468,"position":3},"title":"Calourada da UEFS vai debater sobre BRT de Feira: &#8216;tu acha o qu\u00ea?&#8217;","author":"Blog da Feira","date":"05\/05\/2015","format":false,"excerpt":"O Diret\u00f3rio Central dos estudantes da Universidade Estadual de Feira de Santana convidaram secret\u00e1rios do Governo Municipal para um debate sobre o BRT de Feira durante a 'Calourada'. Foram convidados os secret\u00e1rios de Transporte, Meio Ambiente e Servi\u00e7os p\u00fablicos. O debate est\u00e1 marcado para o dia 8, no campus da\u2026","rel":"","context":"Em &quot;Home&quot;","block_context":{"text":"Home","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/raiz\/"},"img":{"alt_text":"11159480_10152978813596185_2515197738288598518_n","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2015\/05\/11159480_10152978813596185_2515197738288598518_n.jpg?resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2015\/05\/11159480_10152978813596185_2515197738288598518_n.jpg?resize=350%2C200 1x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2015\/05\/11159480_10152978813596185_2515197738288598518_n.jpg?resize=525%2C300 1.5x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2015\/05\/11159480_10152978813596185_2515197738288598518_n.jpg?resize=700%2C400 2x"},"classes":[]},{"id":12540,"url":"https:\/\/blogdafeira.com.br\/home\/2014\/09\/24\/editora-da-uefs-tem-18-novos-lancamentos-no-stand-da-feira-do-livro\/","url_meta":{"origin":3468,"position":4},"title":"Editora da UEFS tem 18 lan\u00e7amentos no stand da Feira do Livro","author":"Blog da Feira","date":"24\/09\/2014","format":false,"excerpt":"S\u00e3o 18 novos livros em 'lan\u00e7amento' pela Editora da Universidade Estadual de Feira de Santana durante a 7\u00aa Feira do Livro promovida pela UEFS em parceria com o Munic\u00edpio e o Estado, al\u00e9m de dezenas de outras editoras e institui\u00e7\u00f5es culturais. A Feira do Livro ocupa a pra\u00e7a do F\u00f3rum\u2026","rel":"","context":"Em &quot;Home&quot;","block_context":{"text":"Home","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/raiz\/"},"img":{"alt_text":"DSC03340","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2014\/09\/DSC03340.jpg?resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2014\/09\/DSC03340.jpg?resize=350%2C200 1x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2014\/09\/DSC03340.jpg?resize=525%2C300 1.5x"},"classes":[]},{"id":19687,"url":"https:\/\/blogdafeira.com.br\/home\/2016\/02\/23\/semana-juridica-na-uefs-debate-o-projeto-de-brt-para-feira-de-santana\/","url_meta":{"origin":3468,"position":5},"title":"&#8216;Semana Jur\u00eddica&#8217;  na UEFS debate o projeto de BRT para Feira de Santana","author":"Blog da Feira","date":"23\/02\/2016","format":false,"excerpt":"\u00a0 O Diret\u00f3rio Acad\u00eamico \"Josaphat Marinho\", do Curso de Direito da Universidade Estadual de Feira de Santana, promove, desta hoje\u00a0\u00a0at\u00e9 sexta-feira (23 a 26), a 7\u00aa Semana Jur\u00eddica da Uefs, sobre o tema 'Direitos Humanos e a Cidade na Contemporaneidade'. O objetivo \u00e9 discutir assuntos de relev\u00e2ncia n\u00e3o apenas no\u2026","rel":"","context":"Em &quot;Home&quot;","block_context":{"text":"Home","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/raiz\/"},"img":{"alt_text":"CYXZS1vWYAQXssx","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2016\/01\/CYXZS1vWYAQXssx.jpg?resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2016\/01\/CYXZS1vWYAQXssx.jpg?resize=350%2C200 1x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2016\/01\/CYXZS1vWYAQXssx.jpg?resize=525%2C300 1.5x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/posts\/3468","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/comments?post=3468"}],"version-history":[{"count":5,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/posts\/3468\/revisions"}],"predecessor-version":[{"id":3601,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/posts\/3468\/revisions\/3601"}],"wp:attachment":[{"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/media?parent=3468"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/categories?post=3468"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/tags?post=3468"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}