{"id":3629,"date":"2013-07-18T11:27:56","date_gmt":"2013-07-18T14:27:56","guid":{"rendered":"http:\/\/blogdafeira.com.br\/home\/?p=3629"},"modified":"2013-07-19T14:15:50","modified_gmt":"2013-07-19T17:15:50","slug":"casa-cor-sera-instalada-no-estacionamento-do-boulevard","status":"publish","type":"post","link":"https:\/\/blogdafeira.com.br\/home\/2013\/07\/18\/casa-cor-sera-instalada-no-estacionamento-do-boulevard\/","title":{"rendered":"Casa Cor ser\u00e1 instalada em Feira no estacionamento do Boulevard"},"content":{"rendered":"<div id=\"blogd-3819689293\" class=\"blogd-fim-do-post-mobile blogd-entity-placement\" style=\"margin-left: auto;margin-right: auto;text-align: center;\"><a href=\"https:\/\/www.feiradesantana.ba.gov.br\/servico.asp?s=a&titulo=Prefeitura-de-Feira-lan%C3%A7a-programa-Rem%C3%A9dio-em-Casa-e-transforma-acesso-a-medicamentos-em-pol%C3%ADtica-p%C3%BAblica-de-cuidados.html&id=14&link=secom\/noticias.asp&idn=43684#noticias\" target=_blank><picture>\r\n  <source media=\"(min-width: 768px)\" srcset=\"https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2026\/03\/980x150.gif\">\r\n  \r\n  <img decoding=\"async\" src=\"https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2021\/01\/350x2002.gif\" alt=\"Publicidade\" style=\"width: 100%; max-width: 100%; height: auto; display: block; margin: 0 auto;\">\r\n\t<\/picture><\/a><\/div><p>A edi\u00e7\u00e3o feirense da Casa Cor Bahia ser\u00e1 instalada no estacionamento coberto do shopping Boulevard, durante um m\u00eas, de 3 de outubro a 3 de novembro. O Boulevard \u00e9 o principal patrocinador do evento.<\/p>\n<p>De acordo com o projeto desenvolvido pelo arquiteto Luiz Humberto Carvalho, ser\u00e3o 23 ambientes &#8216;de puro glamour, praticidade, inova\u00e7\u00e3o, tecnologia e muitas dicas que envolvem o tema do evento: Morar Bem&#8217;.<\/p>\n<div id=\"blogd-1656100397\" class=\"blogd-final-post blogd-entity-placement\"><a href=\"https:\/\/www.feiradesantana.ba.leg.br\/\" target=\"_blank\" aria-label=\"JUNHO-VERMELHO_CA\u0302MARA-DE-FEIRA\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2026\/03\/JUNHO-VERMELHO_CAMARA-DE-FEIRA.gif\" alt=\"\"  class=\"no-lazyload\" width=\"728\" height=\"90\"   \/><\/a><\/div><p>A apresenta\u00e7\u00e3o do evento foi feita em um encontro, ontem, com a presen\u00e7a da imprensa, profissionais, representantes do Boulevard e dos franqueados da Casa Cor e realizadores da exposi\u00e7\u00e3o em Salvador h\u00e1 19 anos: Luizinha, Chico e Alexandre Brand\u00e3o.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A edi\u00e7\u00e3o feirense da Casa Cor Bahia ser\u00e1 instalada no estacionamento coberto do shopping Boulevard, durante um m\u00eas, de 3 de outubro a 3 de novembro. O Boulevard \u00e9 o principal patrocinador do evento. De acordo com o projeto desenvolvido pelo arquiteto Luiz Humberto Carvalho, ser\u00e3o 23 ambientes &#8216;de puro glamour, praticidade, inova\u00e7\u00e3o, tecnologia e<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"cybocfi_hide_featured_image":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[1],"tags":[],"class_list":["post-3629","post","type-post","status-publish","format-standard","hentry","category-raiz"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p3niVf-Wx","jetpack_sharing_enabled":true,"jetpack-related-posts":[{"id":5256,"url":"https:\/\/blogdafeira.com.br\/home\/2013\/09\/25\/casa-cor-comeca-a-ser-montada-no-boulevard-para-abrir-no-dia-3\/","url_meta":{"origin":3629,"position":0},"title":"Casa Cor come\u00e7a a ser montada no Boulevard para abrir no dia 3","author":"Blog da Feira","date":"25\/09\/2013","format":false,"excerpt":"Uma edi\u00e7\u00e3o especial da \u00a0maior mostra de decora\u00e7\u00e3o do pa\u00eds, a Casa Cor, em sua 19\u00aa edi\u00e7\u00e3o na Bahia, vai acontecer de 3 de outubro a 3 de novembro, em uma \u00a0\u00e1rea de 1.600m\u00b2\u00a0, no shopping Boulevard em Feira de Santana. \u00c9 a primeira vez que a Casa Cor acontece\u2026","rel":"","context":"Em &quot;Home&quot;","block_context":{"text":"Home","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/raiz\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":12931,"url":"https:\/\/blogdafeira.com.br\/home\/2014\/10\/15\/casa-cor-bahia-este-ano-trocou-o-mercado-de-feira-por-itabuna\/","url_meta":{"origin":3629,"position":1},"title":"Casa Cor Bahia este ano trocou o mercado de Feira por Itabuna","author":"Blog da Feira","date":"15\/10\/2014","format":false,"excerpt":"Este ano o maior evento de decora\u00e7\u00e3o do Brasil, a Casa Cor, 'desistiu' do mercado de Feira de Santana e como fez nesta cidade no ano passado, implantou em Itabuna uma 'Casa Cor Especial'. Uma empresa do Grupo Abril, Casa Cor \u00e9 hoje reconhecida como a mais completa mostra de\u2026","rel":"","context":"Em &quot;Home&quot;","block_context":{"text":"Home","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/raiz\/"},"img":{"alt_text":"CASA COR","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2014\/10\/CASA-COR.jpg?resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2014\/10\/CASA-COR.jpg?resize=350%2C200 1x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2014\/10\/CASA-COR.jpg?resize=525%2C300 1.5x"},"classes":[]},{"id":9625,"url":"https:\/\/blogdafeira.com.br\/home\/2014\/03\/13\/ibametro-movel-fica-em-feira-ate-amanha-no-estacionamento-do-boulevard\/","url_meta":{"origin":3629,"position":2},"title":"&#8216;Ibametro M\u00f3vel&#8217; fica em Feira at\u00e9 amanh\u00e3 no estacionamento do Boulevard","author":"Blog da Feira","date":"13\/03\/2014","format":false,"excerpt":"O \u201cIbametro M\u00f3vel\u2019, do \u00a0Instituto Baiano de Metrologia e Qualidade (Ibametro) est\u00e1 instalado no estacionamento do shopping Boulevard em Feira de Santana, desde ontem, dia 12, quando foi lan\u00e7ado o \u2018Projeto Ibametro M\u00f3vel na Estrada\u2019 que faz parte do \"Programa Educa\u00e7\u00e3o para o Consumo\". O objetivo \u00e9 divulgar conhecimentos da\u2026","rel":"","context":"Em &quot;Home&quot;","block_context":{"text":"Home","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/raiz\/"},"img":{"alt_text":"Diretor-geral do Ibametro_Osny Bomfim_no evento","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2014\/03\/Diretor-geral-do-Ibametro_Osny-Bomfim_no-evento.jpg?resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2014\/03\/Diretor-geral-do-Ibametro_Osny-Bomfim_no-evento.jpg?resize=350%2C200 1x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2014\/03\/Diretor-geral-do-Ibametro_Osny-Bomfim_no-evento.jpg?resize=525%2C300 1.5x"},"classes":[]},{"id":65210,"url":"https:\/\/blogdafeira.com.br\/home\/2025\/01\/15\/parque-tematico-leva-criancas-a-um-mundo-jurassico-no-shopping-boulevard\/","url_meta":{"origin":3629,"position":3},"title":"Parque tem\u00e1tico leva crian\u00e7as a um &#8220;mundo jur\u00e1ssico&#8221; no Shopping Boulevard","author":"Blog da Feira","date":"15\/01\/2025","format":false,"excerpt":"O Boulevard Shopping se transforma em um verdadeiro mundo jur\u00e1ssico com a chegada da exposi\u00e7\u00e3o Dino World. Com um cen\u00e1rio cuidadosamente elaborado, o espa\u00e7o, montado na pra\u00e7a de eventos, oferece um circuito repleto de brincadeiras interativas e surpresas, transportando os participantes para a era dos dinossauros.A atra\u00e7\u00e3o ficar\u00e1 dispon\u00edvel at\u00e9\u2026","rel":"","context":"Em &quot;Cidade&quot;","block_context":{"text":"Cidade","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/cidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2025\/01\/Screenshot_20250115-2157382.png?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2025\/01\/Screenshot_20250115-2157382.png?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2025\/01\/Screenshot_20250115-2157382.png?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2025\/01\/Screenshot_20250115-2157382.png?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":17212,"url":"https:\/\/blogdafeira.com.br\/home\/2015\/10\/20\/tabela-de-precos-do-estacionamento-do-shopping-boulevard-feira\/","url_meta":{"origin":3629,"position":4},"title":"Tabela de pre\u00e7os do estacionamento do shopping Boulevard Feira","author":"Blog da Feira","date":"20\/10\/2015","format":false,"excerpt":"O Shopping Boulevard Feira de Santana divulgou a tabela com pre\u00e7os das vagas nos estacionamentos. S\u00e3o 1.700 vagas, segundo a Assessoria do Shopping e come\u00e7ar\u00e3o a ser cobrados na pr\u00f3xima segunda-feira. CARRO 4 primeiras horas \u2013 R$ 4,00 (quatro reais) Por cada hora subsequente ou por fra\u00e7\u00e3o de hora \u2013\u2026","rel":"","context":"Em &quot;Home&quot;","block_context":{"text":"Home","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/raiz\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":17364,"url":"https:\/\/blogdafeira.com.br\/home\/2015\/10\/28\/shopping-boulevard-feira-comeca-hoje-a-cobrar-estacionamento\/","url_meta":{"origin":3629,"position":5},"title":"Shopping Boulevard Feira come\u00e7a hoje a cobrar estacionamento","author":"Blog da Feira","date":"28\/10\/2015","format":false,"excerpt":"Autorizado pela Justi\u00e7a da Bahia, o shopping Boulevard Feira come\u00e7a hoje a cobran\u00e7a de vagas no estacionamento do empreendimento que fica localizado na avenida Jo\u00e3o Durval, em Feira de Sant'Anna. A C\u00e2mara de Vereadores de Feira de Sant'Anna e a Prefeitura de Feira tentaram uma manobra pol\u00edtico-administrativa para impedir a\u2026","rel":"","context":"Em &quot;Home&quot;","block_context":{"text":"Home","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/raiz\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"_links":{"self":[{"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/posts\/3629","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/comments?post=3629"}],"version-history":[{"count":8,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/posts\/3629\/revisions"}],"predecessor-version":[{"id":3686,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/posts\/3629\/revisions\/3686"}],"wp:attachment":[{"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/media?parent=3629"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/categories?post=3629"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/tags?post=3629"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}