{"id":3647,"date":"2013-07-18T13:59:46","date_gmt":"2013-07-18T16:59:46","guid":{"rendered":"http:\/\/blogdafeira.com.br\/home\/?p=3647"},"modified":"2013-07-18T14:04:37","modified_gmt":"2013-07-18T17:04:37","slug":"dengue-provocou-a-morte-do-jovem-matheus-do-bando-de-lucas","status":"publish","type":"post","link":"https:\/\/blogdafeira.com.br\/home\/2013\/07\/18\/dengue-provocou-a-morte-do-jovem-matheus-do-bando-de-lucas\/","title":{"rendered":"Dengue provocou a morte do jovem Matheus do &#8216;Bando de Lucas&#8217;"},"content":{"rendered":"<div id=\"blogd-3087936086\" class=\"blogd-fim-do-post-mobile blogd-entity-placement\" style=\"margin-left: auto;margin-right: auto;text-align: center;\"><a href=\"https:\/\/www.feiradesantana.ba.gov.br\/servico.asp?s=a&titulo=Prefeitura-de-Feira-lan%C3%A7a-programa-Rem%C3%A9dio-em-Casa-e-transforma-acesso-a-medicamentos-em-pol%C3%ADtica-p%C3%BAblica-de-cuidados.html&id=14&link=secom\/noticias.asp&idn=43684#noticias\" target=_blank><picture>\r\n  <source media=\"(min-width: 768px)\" srcset=\"https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2026\/03\/980x150.gif\">\r\n  \r\n  <img decoding=\"async\" src=\"https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2021\/01\/350x2002.gif\" alt=\"Publicidade\" style=\"width: 100%; max-width: 100%; height: auto; display: block; margin: 0 auto;\">\r\n\t<\/picture><\/a><\/div><p>Complica\u00e7\u00f5es decorrentes da dengue foram as causas da morte do jovem Matheus Wagner Pessoa, 32, falecido no \u00faltimo dio 24 de junho \u00a0no Hospital Cl\u00e9riston Andrade, em Feira de Santana.<\/p>\n<p>Matheus era estudante de veterin\u00e1ria e fundador do &#8216;Bando de Lucas&#8217; que sai todos os anos no &#8216;Bando Anunciador da Festa de Sant&#8217;Anna&#8217;.<\/p>\n<p>O primeiro diagn\u00f3stico emitido ap\u00f3s ser hospitalizado foi a de leptospirose, em seguida babesiose (provocada por carrapatos).<\/p>\n<p>O novo diagn\u00f3stico e causas do \u00f3bito foram confirmados pelo Laborat\u00f3rio Central de Sa\u00fade P\u00fablica e pela Funda\u00e7\u00e3o Oswaldo Cruz.<\/p>\n<p>Leia tamb\u00e9m:<\/p>\n<div id=\"blogd-705837502\" class=\"blogd-final-post blogd-entity-placement\"><a href=\"https:\/\/www.feiradesantana.ba.leg.br\/\" target=\"_blank\" aria-label=\"JUNHO-VERMELHO_CA\u0302MARA-DE-FEIRA\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2026\/03\/JUNHO-VERMELHO_CAMARA-DE-FEIRA.gif\" alt=\"\"  class=\"no-lazyload\" width=\"728\" height=\"90\"   \/><\/a><\/div><h1><a title=\"Permalink to Bando Anunciador sai este ano sem o grupo de Lucas da Feira\" href=\"http:\/\/blogdafeira.com.br\/home\/?p=3289\" rel=\"bookmark\">Bando Anunciador sai este ano sem o grupo de Lucas da Feira<\/a><\/h1>\n","protected":false},"excerpt":{"rendered":"<p>Complica\u00e7\u00f5es decorrentes da dengue foram as causas da morte do jovem Matheus Wagner Pessoa, 32, falecido no \u00faltimo dio 24 de junho \u00a0no Hospital Cl\u00e9riston Andrade, em Feira de Santana. Matheus era estudante de veterin\u00e1ria e fundador do &#8216;Bando de Lucas&#8217; que sai todos os anos no &#8216;Bando Anunciador da Festa de Sant&#8217;Anna&#8217;. O primeiro<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"cybocfi_hide_featured_image":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[1],"tags":[],"class_list":["post-3647","post","type-post","status-publish","format-standard","hentry","category-raiz"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p3niVf-WP","jetpack_sharing_enabled":true,"jetpack-related-posts":[{"id":31820,"url":"https:\/\/blogdafeira.com.br\/home\/2019\/07\/01\/bando-de-lucas-a-irreverencia-que-incomodou-os-primeiros-anos-do-bando-anunciador-em-feira-de-santana\/","url_meta":{"origin":3647,"position":0},"title":"&#8216;Bando de Lucas&#8217;, a irrever\u00eancia que incomodou os primeiros anos do Bando Anunciador em Feira de Santana","author":"J\u00e2nio R\u00eago","date":"01\/07\/2019","format":false,"excerpt":"O 'Bando de Lucas' foi praticamente 'banido' nos primeiros anos em que a UEFS retomou a festividade\u00a0 do Bando Anunciador. Formado quase todo por estudantes universit\u00e1rios que saiam \u00e0s ruas totalmente 'pintados' com carv\u00e3o e por isso mesmo 'sujando' todos a quem abra\u00e7avam ou cumprimentavam, o bando provocou a 'repulsa'\u2026","rel":"","context":"Em &quot;Home&quot;","block_context":{"text":"Home","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/raiz\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2019\/07\/bando-de-lucas.jpg?resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2019\/07\/bando-de-lucas.jpg?resize=350%2C200 1x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2019\/07\/bando-de-lucas.jpg?resize=525%2C300 1.5x"},"classes":[]},{"id":3289,"url":"https:\/\/blogdafeira.com.br\/home\/2013\/07\/05\/bando-anunciador-sai-este-ano-sem-o-grupo-de-lucas-da-feira-2\/","url_meta":{"origin":3647,"position":1},"title":"Bando Anunciador sai este ano sem o grupo de Lucas da Feira","author":"Blog da Feira","date":"05\/07\/2013","format":false,"excerpt":"O Bando Anunciador vai para as ruas no domingo com um pouco menos\u00a0de irrever\u00eancia e 'escracho', \u00a0caracter\u00edsticas principais do evento resgatado pela UEFS desde 2007. Este ano o \u00a0'Bando de Lucas', um grupo de universit\u00e1rios e universit\u00e1rias, pintados com carv\u00e3o por todo o corpo, n\u00e3o vai participar da festa porque\u2026","rel":"","context":"Em &quot;Cultura&quot;","block_context":{"text":"Cultura","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/cultura\/"},"img":{"alt_text":"RAINHA2","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2013\/07\/RAINHA21-239x300.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":3386,"url":"https:\/\/blogdafeira.com.br\/home\/2013\/07\/09\/morreu-estudante-de-veterinaria-fundador-do-bando-de-lucas\/","url_meta":{"origin":3647,"position":2},"title":"Morreu estudante de Veterin\u00e1ria fundador do &#8216;Bando de Lucas&#8217;","author":"Blog da Feira","date":"09\/07\/2013","format":false,"excerpt":"Estudante de Veterin\u00e1ria na Universidade Federal do Rec\u00f4ncavo da Bahia (UFRB), \u00a0Mateus Vagner Pessoa (foto), 32 anos, faleceu hoje no Hospital Cl\u00e9riston Andrade.\u00a0Ele foi acometido por uma leptospirose h\u00e1 alguns dias e n\u00e3o resistiu \u00e0 doen\u00e7a. Poeta e compositor, Mateus foi um dos fundadores do 'Bando de Lucas da Feira',\u2026","rel":"","context":"Em &quot;Home&quot;","block_context":{"text":"Home","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/raiz\/"},"img":{"alt_text":"Mateus","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2013\/07\/Mateus-192x300.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":11338,"url":"https:\/\/blogdafeira.com.br\/home\/2014\/07\/13\/bando-anunciador-da-festa-de-santanna-em-feira\/","url_meta":{"origin":3647,"position":3},"title":"Bando Anunciador da Festa de Sant&#8217;Anna em Feira","author":"Blog da Feira","date":"13\/07\/2014","format":false,"excerpt":"O Bando Anunciador da Festa de Senhora Sant'Anna, padroeira cat\u00f3lica de Feira de Santana, foi \u00e0s ruas pela 8\u00aa vez ap\u00f3s ser resgatado pela Universidade Estadual de Feira de Santana atrav\u00e9s do Centro Universit\u00e1rio de Cultura e Arte (Cuca). O 'Bando Anunciador' havia sido proibido pela Prefeitura de Feira, a\u2026","rel":"","context":"Em &quot;Home&quot;","block_context":{"text":"Home","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/raiz\/"},"img":{"alt_text":"bando de lucas","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2014\/07\/bando-de-lucas.jpg?resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2014\/07\/bando-de-lucas.jpg?resize=350%2C200 1x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2014\/07\/bando-de-lucas.jpg?resize=525%2C300 1.5x"},"classes":[]},{"id":72642,"url":"https:\/\/blogdafeira.com.br\/home\/2026\/05\/29\/quem-pariu-matheus-que-balance-neto-de-cesce-amorim-faz-show-hoje-na-cidade-da-cultura\/","url_meta":{"origin":3647,"position":4},"title":"&#8220;Quem pariu Matheus que balance&#8221;: neto de Cesc\u00e9 Amorim faz show hoje na Cidade da Cultura","author":"Blog da Feira","date":"29\/05\/2026","format":false,"excerpt":"O cantor e compositor Matheus Amorim se apresenta nesta sexta (29), a partir das 21 horas, no tradicional espa\u00e7o Cidade da Cultura, no Conjunto Jo\u00e3o Paulo II. O talentoso artista feirense ser\u00e1 acompanhado pelo baixista Danilo Vital e pelo baterista Robson Souza. O cantor Cesc\u00e9 Amorim, av\u00f4 de Matheus, tamb\u00e9m\u2026","rel":"","context":"Em &quot;Cultura&quot;","block_context":{"text":"Cultura","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/cultura\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2026\/05\/IMG-20260529-WA00501.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2026\/05\/IMG-20260529-WA00501.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2026\/05\/IMG-20260529-WA00501.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2026\/05\/IMG-20260529-WA00501.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2026\/05\/IMG-20260529-WA00501.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":46377,"url":"https:\/\/blogdafeira.com.br\/home\/2021\/07\/11\/morte-ressurreicao-e-covid19-do-bando-anunciador\/","url_meta":{"origin":3647,"position":5},"title":"Ressurrei\u00e7\u00e3o e morte do Bando Anunciador","author":"Blog da Feira","date":"11\/07\/2021","format":false,"excerpt":"A pandemia da Covid 19 provocou a segunda \"morte\" do Bando Anunciador, depois que foi \"ressuscitado\" por obra e gra\u00e7a da Universidade Estadual de Feira de Santana (UEFS) no primeiro mandato do reitorado de Jos\u00e9 Carlos Barreto. O desfile do Bando Anunciador \u00e9 o cortejo profano e irreverente que anuncia\u00a0\u2026","rel":"","context":"Em &quot;Cidade&quot;","block_context":{"text":"Cidade","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/cidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2021\/07\/Screenshot_20210711-0818563.png?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2021\/07\/Screenshot_20210711-0818563.png?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2021\/07\/Screenshot_20210711-0818563.png?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2021\/07\/Screenshot_20210711-0818563.png?resize=700%2C400&ssl=1 2x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/posts\/3647","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/comments?post=3647"}],"version-history":[{"count":4,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/posts\/3647\/revisions"}],"predecessor-version":[{"id":3649,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/posts\/3647\/revisions\/3649"}],"wp:attachment":[{"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/media?parent=3647"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/categories?post=3647"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/tags?post=3647"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}