{"id":3667,"date":"2013-07-19T01:35:54","date_gmt":"2013-07-19T04:35:54","guid":{"rendered":"http:\/\/blogdafeira.com.br\/home\/?p=3667"},"modified":"2013-07-19T01:37:09","modified_gmt":"2013-07-19T04:37:09","slug":"capoeira-esta-presente-em-657-dos-municipios-do-nordeste","status":"publish","type":"post","link":"https:\/\/blogdafeira.com.br\/home\/2013\/07\/19\/capoeira-esta-presente-em-657-dos-municipios-do-nordeste\/","title":{"rendered":"Capoeira est\u00e1 presente em 65,7% dos munic\u00edpios do Nordeste"},"content":{"rendered":"<div id=\"blogd-151847382\" class=\"blogd-fim-do-post-mobile blogd-entity-placement\" style=\"margin-left: auto;margin-right: auto;text-align: center;\"><a href=\"https:\/\/www.feiradesantana.ba.gov.br\/servico.asp?s=a&titulo=Prefeitura-de-Feira-lan%C3%A7a-programa-Rem%C3%A9dio-em-Casa-e-transforma-acesso-a-medicamentos-em-pol%C3%ADtica-p%C3%BAblica-de-cuidados.html&id=14&link=secom\/noticias.asp&idn=43684#noticias\" target=_blank><picture>\r\n  <source media=\"(min-width: 768px)\" srcset=\"https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2026\/03\/980x150.gif\">\r\n  \r\n  <img decoding=\"async\" src=\"https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2021\/01\/350x2002.gif\" alt=\"Publicidade\" style=\"width: 100%; max-width: 100%; height: auto; display: block; margin: 0 auto;\">\r\n\t<\/picture><\/a><\/div><p>A Capoeira, manifesta\u00e7\u00e3o cultural genuinamente brasileira, est\u00e1 presente em 53,7% dos munic\u00edpios do pa\u00eds e em 65,7% dos localizados no nordeste brasileiro.<img loading=\"lazy\" decoding=\"async\" class=\"alignright size-thumbnail wp-image-3668\" alt=\"Capoeira-Instruments\" src=\"http:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2013\/07\/Capoeira-Instruments-170x127.jpg\" width=\"170\" height=\"127\" srcset=\"https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2013\/07\/Capoeira-Instruments-170x127.jpg 170w, https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2013\/07\/Capoeira-Instruments.jpg 300w\" sizes=\"auto, (max-width: 170px) 100vw, 170px\" \/><\/p>\n<p>Na Bahia, 82,7% dos munic\u00edpios praticam a capoeira, que \u00e9 &#8216;um misto de dan\u00e7a, m\u00fasica e filosofia.&#8217;.<\/p>\n<div id=\"blogd-2321155718\" class=\"blogd-final-post blogd-entity-placement\"><a href=\"https:\/\/www.feiradesantana.ba.leg.br\/\" target=\"_blank\" aria-label=\"JUNHO-VERMELHO_CA\u0302MARA-DE-FEIRA\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2026\/03\/JUNHO-VERMELHO_CAMARA-DE-FEIRA.gif\" alt=\"\"  class=\"no-lazyload\" width=\"728\" height=\"90\"   \/><\/a><\/div><p>As informa\u00e7\u00f5es est\u00e3o na &#8220;<em>Pesquisa de Informa\u00e7\u00f5es B\u00e1sicas Municipais &#8211; Perfil dos Munic\u00edpios Brasileiros,2012&#8243;<\/em>, produzida e divulgada \u00a0pelo<strong><a href=\"http:\/\/www.ibge.gov.br\/home\/\" target=\"_blank\"> IBGE.<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Capoeira, manifesta\u00e7\u00e3o cultural genuinamente brasileira, est\u00e1 presente em 53,7% dos munic\u00edpios do pa\u00eds e em 65,7% dos localizados no nordeste brasileiro. Na Bahia, 82,7% dos munic\u00edpios praticam a capoeira, que \u00e9 &#8216;um misto de dan\u00e7a, m\u00fasica e filosofia.&#8217;. As informa\u00e7\u00f5es est\u00e3o na &#8220;Pesquisa de Informa\u00e7\u00f5es B\u00e1sicas Municipais &#8211; Perfil dos Munic\u00edpios Brasileiros,2012&#8243;, produzida e<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"cybocfi_hide_featured_image":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[1],"tags":[],"class_list":["post-3667","post","type-post","status-publish","format-standard","hentry","category-raiz"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p3niVf-X9","jetpack_sharing_enabled":true,"jetpack-related-posts":[{"id":23295,"url":"https:\/\/blogdafeira.com.br\/home\/2016\/08\/27\/no-map-de-feira-hoje-tem-maculele-capoeira-bumba-meu-boi-e-cantoria\/","url_meta":{"origin":3667,"position":0},"title":"No MAP de Feira hoje tem: maculel\u00ea, capoeira, bumba-meu-boi e cantoria","author":"Blog da Feira","date":"27\/08\/2016","format":false,"excerpt":"O Mercado de Arte Popular receber\u00e1 neste s\u00e1bado, 27, uma programa\u00e7\u00e3o cultural bastante rica, no pen\u00faltimo dia da Semana do Folclore. Capoeira, Maculel\u00ea, Bumba Meu Boi, apresenta\u00e7\u00e3o de quadrilha junina e samba animar\u00e3o o palco do MAP durante todo o dia. E \u00e0 noite tem Cantoria-de-Viola com a \u00a042\u00aa edi\u00e7\u00e3o\u2026","rel":"","context":"Em &quot;Distritos&quot;","block_context":{"text":"Distritos","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/distritos\/"},"img":{"alt_text":"mercado de arte popular de feira de santana","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2016\/08\/mercado-de-arte-popular-de-feira-de-santana.jpg?resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2016\/08\/mercado-de-arte-popular-de-feira-de-santana.jpg?resize=350%2C200 1x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2016\/08\/mercado-de-arte-popular-de-feira-de-santana.jpg?resize=525%2C300 1.5x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2016\/08\/mercado-de-arte-popular-de-feira-de-santana.jpg?resize=700%2C400 2x"},"classes":[]},{"id":19209,"url":"https:\/\/blogdafeira.com.br\/home\/2016\/01\/17\/salvador-sedia-encontro-internacional-de-capoeira-angola\/","url_meta":{"origin":3667,"position":1},"title":"Salvador sedia encontro internacional de Capoeira Angola","author":"Blog da Feira","date":"17\/01\/2016","format":false,"excerpt":"Quem assiste ao en\u00e9rgico senhor que atende por Mestre Curi\u00f3, em uma roda de capoeira, talvez n\u00e3o consiga imaginar que Jaime Martins dos Santos, nome escolhido pela m\u00e3e, j\u00e1 foi menino de rua e passou por pelo menos dez profiss\u00f5es diferentes at\u00e9 se tornar um dos mestres de Capoeira Angola\u2026","rel":"","context":"Em &quot;Home&quot;","block_context":{"text":"Home","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/raiz\/"},"img":{"alt_text":"Ronaldo_Silva_GOVBA_1","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2016\/01\/Ronaldo_Silva_GOVBA_1.jpg?resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2016\/01\/Ronaldo_Silva_GOVBA_1.jpg?resize=350%2C200 1x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2016\/01\/Ronaldo_Silva_GOVBA_1.jpg?resize=525%2C300 1.5x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2016\/01\/Ronaldo_Silva_GOVBA_1.jpg?resize=700%2C400 2x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2016\/01\/Ronaldo_Silva_GOVBA_1.jpg?resize=1050%2C600 3x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2016\/01\/Ronaldo_Silva_GOVBA_1.jpg?resize=1400%2C800 4x"},"classes":[]},{"id":46723,"url":"https:\/\/blogdafeira.com.br\/home\/2021\/07\/29\/tonho-materia-fala-sobre-capoeira-na-camara-dos-deputados\/","url_meta":{"origin":3667,"position":2},"title":"Tonho Mat\u00e9ria fala sobre Capoeira na C\u00e2mara dos Deputados","author":"Blog da Feira","date":"29\/07\/2021","format":false,"excerpt":"O cantor, compositor e mestre de capoeira Tonho Mat\u00e9ria est\u00e1 entre os convidados da Comiss\u00e3o de Cultura da C\u00e2mara dos Deputados para\u00a0 a audi\u00eancia p\u00fablica, no pr\u00f3ximo dia 6 de agosto, sobre pol\u00edticas p\u00fablicas para a capoeira. A reuni\u00e3o foi solicitada pela deputada Alice Portugal (PCdoB-BA). Est\u00e3o convidados tamb\u00e9m o\u2026","rel":"","context":"Em &quot;Cultura&quot;","block_context":{"text":"Cultura","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/cultura\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2021\/07\/Screenshot_20210729-0815252.png?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2021\/07\/Screenshot_20210729-0815252.png?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2021\/07\/Screenshot_20210729-0815252.png?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2021\/07\/Screenshot_20210729-0815252.png?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":10348,"url":"https:\/\/blogdafeira.com.br\/home\/2014\/04\/22\/capoeirista-diz-na-camara-de-feira-que-vereadors-viram-as-costas-para-a-arte\/","url_meta":{"origin":3667,"position":3},"title":"Capoeirista diz na C\u00e2mara de Feira que vereadores &#8216;viram as costas&#8217; para a arte","author":"Blog da Feira","date":"22\/04\/2014","format":false,"excerpt":"Dois mestres de capoeira ocuparam nesta manh\u00e3 a 'tribuna livre' da C\u00e3mara de Vereadores de Feira de Santana para falar sobre a atividade cultural ligada \u00e0 cultura afro-brasileira. Um deles provocou constrangimento aos vereadores : ele disse que quando \u00e9 \u00e9poca de campanha os vereadores procuram alguns grupos de capoeira,\u2026","rel":"","context":"Em &quot;Home&quot;","block_context":{"text":"Home","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/raiz\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":23864,"url":"https:\/\/blogdafeira.com.br\/home\/2016\/10\/14\/brinquedos-de-angola-evento-nacional-de-capoeira-acontece-em-feira-ate-sabado\/","url_meta":{"origin":3667,"position":4},"title":"&#8216;Brinquedos de Angola&#8217;, evento nacional de Capoeira, acontece em Feira at\u00e9 s\u00e1bado","author":"Blog da Feira","date":"14\/10\/2016","format":false,"excerpt":"O Brinquedo dos Angolas \u00e9 um Encontro realizado anualmente pelo Malungo Centro de Capoeira Angola, localizado em Feira de Santana, \u00a0o qual re\u00fane capoeiristas de v\u00e1rias partes da Bahia e de outros Estados brasileiros, a exemplo do Par\u00e1 e Rio de Janeiro. Sua primeira edi\u00e7\u00e3o ocorreu em Feira de Santana,\u2026","rel":"","context":"Em &quot;Home&quot;","block_context":{"text":"Home","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/raiz\/"},"img":{"alt_text":"fb_img_1476461037819","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2016\/10\/FB_IMG_1476461037819.jpg?resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2016\/10\/FB_IMG_1476461037819.jpg?resize=350%2C200 1x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2016\/10\/FB_IMG_1476461037819.jpg?resize=525%2C300 1.5x"},"classes":[]},{"id":32379,"url":"https:\/\/blogdafeira.com.br\/home\/2019\/08\/14\/capoeirista-e-historiador-bel-pires-e-mais-um-colunista-do-blog-da-feira\/","url_meta":{"origin":3667,"position":5},"title":"Capoeirista e historiador Bel Pires \u00e9 mais um colunista do Blog da Feira","author":"J\u00e2nio R\u00eago","date":"14\/08\/2019","format":false,"excerpt":"Bel Pires Natural de Central, cidade da Chapada Diamantina, vive em Feira de Santana desde os primeiros anos de vida. Pai de Kissa, Maisha e Mosi. Graduado em Historia pela UEFS, mestre e doutor pela UFBA. Mestre de capoeira, coordena o Malungo Centro de Capoeira Angola, entidade cultural que desenvolve\u2026","rel":"","context":"Em &quot;Home&quot;","block_context":{"text":"Home","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/raiz\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2019\/08\/IMG-20190814-WA0007-346x260.jpg?resize=350%2C200","width":350,"height":200},"classes":[]}],"_links":{"self":[{"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/posts\/3667","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/comments?post=3667"}],"version-history":[{"count":2,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/posts\/3667\/revisions"}],"predecessor-version":[{"id":3670,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/posts\/3667\/revisions\/3670"}],"wp:attachment":[{"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/media?parent=3667"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/categories?post=3667"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/tags?post=3667"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}