{"id":3752,"date":"2013-07-23T14:46:03","date_gmt":"2013-07-23T17:46:03","guid":{"rendered":"http:\/\/blogdafeira.com.br\/home\/?p=3752"},"modified":"2013-07-23T14:46:03","modified_gmt":"2013-07-23T17:46:03","slug":"carro-de-bombeiro-que-vem-para-feira-foi-feito-sob-encomenda","status":"publish","type":"post","link":"https:\/\/blogdafeira.com.br\/home\/2013\/07\/23\/carro-de-bombeiro-que-vem-para-feira-foi-feito-sob-encomenda\/","title":{"rendered":"Carro de Bombeiro que vem para Feira foi feito sob encomenda"},"content":{"rendered":"<div id=\"blogd-311523517\" class=\"blogd-fim-do-post-mobile blogd-entity-placement\" style=\"margin-left: auto;margin-right: auto;text-align: center;\"><a href=\"https:\/\/www.feiradesantana.ba.gov.br\/servico.asp?s=a&titulo=Prefeitura-de-Feira-lan%C3%A7a-programa-Rem%C3%A9dio-em-Casa-e-transforma-acesso-a-medicamentos-em-pol%C3%ADtica-p%C3%BAblica-de-cuidados.html&id=14&link=secom\/noticias.asp&idn=43684#noticias\" target=_blank><picture>\r\n  <source media=\"(min-width: 768px)\" srcset=\"https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2026\/03\/980x150.gif\">\r\n  \r\n  <img decoding=\"async\" src=\"https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2021\/01\/350x2002.gif\" alt=\"Publicidade\" style=\"width: 100%; max-width: 100%; height: auto; display: block; margin: 0 auto;\">\r\n\t<\/picture><\/a><\/div><p>O deputado estadual Z\u00e9 Neto (PT), l\u00edder do governo na Assembleia Legislativa da Bahia, anunciou e comemorou, na manh\u00e3 desta ter\u00e7a-feira (23), a entrega de um novo ve\u00edculo para o Corpo de Bombeiros de Feira de Santana.<\/p>\n<p>O novo ve\u00edculo, chamado de &#8216;Auto Bomba Tanque&#8217;, da Volvo, tem \u00a0capacidade para sete bombeiros e cinco mil litros de \u00e1gua e custou 300 mil ao Estado.<\/p>\n<p>Segundo o parlamentar, os carros s\u00e3o feitos por encomenda. O governo comprou 11 carros desse tipo para a Bahia.<\/p>\n<div id=\"blogd-245570584\" class=\"blogd-final-post blogd-entity-placement\"><a href=\"https:\/\/www.feiradesantana.ba.leg.br\/\" target=\"_blank\" aria-label=\"JUNHO-VERMELHO_CA\u0302MARA-DE-FEIRA\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2026\/03\/JUNHO-VERMELHO_CAMARA-DE-FEIRA.gif\" alt=\"\"  class=\"no-lazyload\" width=\"728\" height=\"90\"   \/><\/a><\/div><p>O deputado lembrou o caminh\u00e3o do tipo &#8216;Ataque Principal 2&#8217; para combate a inc\u00eandio que est\u00e1 no Aeroporto de Feira e 45 hidrantes que a Embasa j\u00e1 implantou em locais estrat\u00e9gicos da cidade.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O deputado estadual Z\u00e9 Neto (PT), l\u00edder do governo na Assembleia Legislativa da Bahia, anunciou e comemorou, na manh\u00e3 desta ter\u00e7a-feira (23), a entrega de um novo ve\u00edculo para o Corpo de Bombeiros de Feira de Santana. O novo ve\u00edculo, chamado de &#8216;Auto Bomba Tanque&#8217;, da Volvo, tem \u00a0capacidade para sete bombeiros e cinco mil<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"cybocfi_hide_featured_image":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[1],"tags":[],"class_list":["post-3752","post","type-post","status-publish","format-standard","hentry","category-raiz"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p3niVf-Yw","jetpack_sharing_enabled":true,"jetpack-related-posts":[{"id":65057,"url":"https:\/\/blogdafeira.com.br\/home\/2025\/01\/07\/em-tres-anos-de-mandato-deputado-ze-neto-destina-r-61-milhoes-para-feira-e-regiao\/","url_meta":{"origin":3752,"position":0},"title":"Em tr\u00eas anos de mandato, deputado Z\u00e9 Neto destina R$ 61 milh\u00f5es para Feira e regi\u00e3o","author":"Blog da Feira","date":"07\/01\/2025","format":false,"excerpt":"*Em tr\u00eas anos de Mandato, Z\u00e9 Neto destina R$ 61 milh\u00f5es para Feira de Santana e regi\u00e3o* \u00a0 O deputado federal Z\u00e9 Neto (PT), em seu terceiro ano de Mandato, consolidou-se como um dos principais articuladores de recursos para Feira de Santana e regi\u00e3o. Com a destina\u00e7\u00e3o de mais de\u2026","rel":"","context":"Em &quot;Economia&quot;","block_context":{"text":"Economia","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/economia\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2025\/01\/IMG-20250106-WA0074.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2025\/01\/IMG-20250106-WA0074.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2025\/01\/IMG-20250106-WA0074.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2025\/01\/IMG-20250106-WA0074.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2025\/01\/IMG-20250106-WA0074.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2025\/01\/IMG-20250106-WA0074.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":26393,"url":"https:\/\/blogdafeira.com.br\/home\/2017\/04\/03\/governador-rui-costa-vem-a-feira-inaugurar-sede-da-procuradoria-e-autorizar-obras\/","url_meta":{"origin":3752,"position":1},"title":"Governador Rui Costa vem a Feira inaugurar sede da Procuradoria e autorizar obras","author":"Blog da Feira","date":"03\/04\/2017","format":false,"excerpt":"O governador Rui Costa participa em Feira de Santana na manh\u00e3 desta ter\u00e7a-feira, 4, \u00a0da inaugura\u00e7\u00e3o da nova sede da Procuradoria Geral do Estado, na avenida presidente Dutra, \u00e0s 9 horas. Em seguida, no terreno onde ser\u00e1 constru\u00edda a Policl\u00ednica Regional, tamb\u00e9m na Avenida Presidente Dutra, o governador autoriza o\u2026","rel":"","context":"Em &quot;Home&quot;","block_context":{"text":"Home","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/raiz\/"},"img":{"alt_text":"ruiu-feira","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2017\/04\/ruiu-feira-346x257.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":41120,"url":"https:\/\/blogdafeira.com.br\/home\/2020\/10\/13\/mais-de-200-bombeiros-apagaram-os-incendios-na-chapada\/","url_meta":{"origin":3752,"position":2},"title":"Mais de 200 bombeiros apagaram os inc\u00eandios na Chapada","author":"Blog da Feira","date":"13\/10\/2020","format":false,"excerpt":"Os inc\u00eandios florestais na regi\u00e3o da Chapada Diamantina foram todos apagados. O combate aos inc\u00eandios na regi\u00e3o\u00a0 seis avi\u00f5es air track e um helic\u00f3ptero do Grupamento A\u00e9reo da Pol\u00edcia Militar de 37 bombeiros militares e mais de 200 brigadistas ligados a \u00f3rg\u00e3os ambientais e volunt\u00e1rios. As seis aeronaves lan\u00e7aram mais\u2026","rel":"","context":"Em &quot;Bahia&quot;","block_context":{"text":"Bahia","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/bahia\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2020\/10\/Foto-Paula-Froes_GOVBA-4.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2020\/10\/Foto-Paula-Froes_GOVBA-4.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2020\/10\/Foto-Paula-Froes_GOVBA-4.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2020\/10\/Foto-Paula-Froes_GOVBA-4.jpeg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2020\/10\/Foto-Paula-Froes_GOVBA-4.jpeg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":62079,"url":"https:\/\/blogdafeira.com.br\/home\/2024\/05\/10\/bombeiros-da-bahia-ja-resgataram-mais-de-200-pessoas-das-enche-todo-rs\/","url_meta":{"origin":3752,"position":3},"title":"Bombeiros da Bahia j\u00e1 resgataram mais de 200 pessoas das enchentes do RS","author":"Blog da Feira","date":"10\/05\/2024","format":false,"excerpt":"Uma semana ap\u00f3s chegarem no Rio Grande do Sul, a tropa do Corpo de Bombeiros Militar da Bahia (CBMBA) realizou a retirada de fios que estavam rompidos no rio Ca\u00ed, no munic\u00edpio de Caxias do Sul. Os bombeiros da Bahia tamb\u00e9m realizaram a desobstru\u00e7\u00e3o de algumas pistas. O objetivo foi\u2026","rel":"","context":"Em &quot;Geral&quot;","block_context":{"text":"Geral","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/geral\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2024\/05\/Screenshot_20240510-071406.png?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2024\/05\/Screenshot_20240510-071406.png?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2024\/05\/Screenshot_20240510-071406.png?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2024\/05\/Screenshot_20240510-071406.png?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2024\/05\/Screenshot_20240510-071406.png?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":62039,"url":"https:\/\/blogdafeira.com.br\/home\/2024\/05\/06\/jeronimo-faz-entrega-de-150-veiculos-para-reforcar-frota-da-saude-dos-municipios-baianos\/","url_meta":{"origin":3752,"position":4},"title":"Jer\u00f4nimo faz entrega de 150 ve\u00edculos para refor\u00e7ar frota da sa\u00fade dos munic\u00edpios baianos","author":"Blog da Feira","date":"06\/05\/2024","format":false,"excerpt":"Foram entregues, na manh\u00e3 desta segunda-feira (6), durante ato no Parque de Exposi\u00e7\u00f5es Agropecu\u00e1rias de Salvador, 150 ve\u00edculos que v\u00e3o refor\u00e7ar e renovar a frota de sa\u00fade dos munic\u00edpios baianos. S\u00e3o 64 ambul\u00e2ncias, 10 vans para Tratamento Fora de Domicilio (TFD), que beneficiam pacientes que far\u00e3o consultas, exames ou tratamentos\u2026","rel":"","context":"Em &quot;Bahia&quot;","block_context":{"text":"Bahia","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/bahia\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2024\/05\/Fotos-Joa-SouzaGOVBAApp-Image-2024-05-06-at-10.40.50-1-1068x712-1.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2024\/05\/Fotos-Joa-SouzaGOVBAApp-Image-2024-05-06-at-10.40.50-1-1068x712-1.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2024\/05\/Fotos-Joa-SouzaGOVBAApp-Image-2024-05-06-at-10.40.50-1-1068x712-1.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2024\/05\/Fotos-Joa-SouzaGOVBAApp-Image-2024-05-06-at-10.40.50-1-1068x712-1.jpeg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2024\/05\/Fotos-Joa-SouzaGOVBAApp-Image-2024-05-06-at-10.40.50-1-1068x712-1.jpeg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":64328,"url":"https:\/\/blogdafeira.com.br\/home\/2024\/10\/16\/os-carros-usados-mais-vendidos-em-feira-de-santana\/","url_meta":{"origin":3752,"position":5},"title":"Os carros usados mais vendidos em Feira de Santana","author":"Blog da Feira","date":"16\/10\/2024","format":false,"excerpt":"A cidade de Feira de Santana \u00e9 um nicho bem espec\u00edfico do territ\u00f3rio da Bahia e apresenta \u00f3timos n\u00fameros em rela\u00e7\u00e3o \u00e0s vendas de seminovos no estado O setor automotivo \u00e9 um dos principais do Brasil. Ao longo do ano, milhares de carros s\u00e3o comercializados no pa\u00eds e condutores trocam\u2026","rel":"","context":"Em &quot;Geral&quot;","block_context":{"text":"Geral","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/geral\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2024\/10\/pexels-perofelixg-19581626-2.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2024\/10\/pexels-perofelixg-19581626-2.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2024\/10\/pexels-perofelixg-19581626-2.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/posts\/3752","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/comments?post=3752"}],"version-history":[{"count":2,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/posts\/3752\/revisions"}],"predecessor-version":[{"id":3754,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/posts\/3752\/revisions\/3754"}],"wp:attachment":[{"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/media?parent=3752"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/categories?post=3752"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/tags?post=3752"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}