{"id":3825,"date":"2013-07-25T13:27:45","date_gmt":"2013-07-25T16:27:45","guid":{"rendered":"http:\/\/blogdafeira.com.br\/home\/?p=3825"},"modified":"2013-07-25T13:27:45","modified_gmt":"2013-07-25T16:27:45","slug":"imprensa-de-salvador-diz-que-ha-duelo-pela-coleta-do-lixo-em-feira","status":"publish","type":"post","link":"https:\/\/blogdafeira.com.br\/home\/2013\/07\/25\/imprensa-de-salvador-diz-que-ha-duelo-pela-coleta-do-lixo-em-feira\/","title":{"rendered":"Imprensa de Salvador diz que h\u00e1 &#8216;duelo&#8217; pela coleta do lixo em Feira"},"content":{"rendered":"<div id=\"blogd-2630254550\" class=\"blogd-fim-do-post-mobile blogd-entity-placement\" style=\"margin-left: auto;margin-right: auto;text-align: center;\"><a href=\"https:\/\/www.feiradesantana.ba.gov.br\/servico.asp?s=a&titulo=Prefeitura-de-Feira-lan%C3%A7a-programa-Rem%C3%A9dio-em-Casa-e-transforma-acesso-a-medicamentos-em-pol%C3%ADtica-p%C3%BAblica-de-cuidados.html&id=14&link=secom\/noticias.asp&idn=43684#noticias\" target=_blank><picture>\r\n  <source media=\"(min-width: 768px)\" srcset=\"https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2026\/03\/980x150.gif\">\r\n  \r\n  <img decoding=\"async\" src=\"https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2021\/01\/350x2002.gif\" alt=\"Publicidade\" style=\"width: 100%; max-width: 100%; height: auto; display: block; margin: 0 auto;\">\r\n\t<\/picture><\/a><\/div><p>&#8216;Duas empresas duelam para conseguir vencer licita\u00e7\u00e3o e administrar o lixo em Feira de Santana. A Viva Ambiental e a Sustentare vislumbram um contrato rent\u00e1vel, talvez o de maior valor na Prefeitura do munic\u00edpio&#8217;, \u00e9 o que diz o site Boc\u00e3oNews, de Salvador.<\/p>\n<p>A rep\u00f3rter Fab\u00edola Lima esteve em Feira e conversou com representantes das empresas, Prefeitura, empres\u00e1rios e pessoas da comunidade pr\u00f3xima ao aterro sanit\u00e1rio.<\/p>\n<div id=\"blogd-1682812819\" class=\"blogd-final-post blogd-entity-placement\"><a href=\"https:\/\/www.feiradesantana.ba.leg.br\/\" target=\"_blank\" aria-label=\"JUNHO-VERMELHO_CA\u0302MARA-DE-FEIRA\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2026\/03\/JUNHO-VERMELHO_CAMARA-DE-FEIRA.gif\" alt=\"\"  class=\"no-lazyload\" width=\"728\" height=\"90\"   \/><\/a><\/div><p>O ve\u00edculo relata toda briga judicial e den\u00fancias no Minist\u00e9rio P\u00fablico envolvendo as duas empresas. Atualmente, esse servi\u00e7o est\u00e1 sendo feito por uma empresa contratada emergencialmente.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8216;Duas empresas duelam para conseguir vencer licita\u00e7\u00e3o e administrar o lixo em Feira de Santana. A Viva Ambiental e a Sustentare vislumbram um contrato rent\u00e1vel, talvez o de maior valor na Prefeitura do munic\u00edpio&#8217;, \u00e9 o que diz o site Boc\u00e3oNews, de Salvador. A rep\u00f3rter Fab\u00edola Lima esteve em Feira e conversou com representantes das<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"cybocfi_hide_featured_image":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[1],"tags":[],"class_list":["post-3825","post","type-post","status-publish","format-standard","hentry","category-raiz"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p3niVf-ZH","jetpack_sharing_enabled":true,"jetpack-related-posts":[{"id":23242,"url":"https:\/\/blogdafeira.com.br\/home\/2016\/08\/25\/lixo-em-feira-prefeitura-vai-contratar-empresa-para-cuidar-do-chorume\/","url_meta":{"origin":3825,"position":0},"title":"Lixo em Feira: Prefeitura vai contratar empresa para cuidar do &#8216;chorume&#8217;","author":"Blog da Feira","date":"25\/08\/2016","format":false,"excerpt":"A \u00a0'coleta, transporte e destina\u00e7\u00e3o do chorume' \u00a0do aterro sanit\u00e1rio de Feira de Santana entra em um nova fase: a Prefeitura abriu uma licita\u00e7\u00e3o para contrata\u00e7\u00e3o de uma empresa para fazer esse servi\u00e7o. O problema do chorume no aterro sanit\u00e1rio de Feira \u00e9 constantemente motivo de pol\u00eamica e d\u00favidas da\u2026","rel":"","context":"Em &quot;Home&quot;","block_context":{"text":"Home","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/raiz\/"},"img":{"alt_text":"LIXAO","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2016\/08\/LIXAO.jpg?resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2016\/08\/LIXAO.jpg?resize=350%2C200 1x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2016\/08\/LIXAO.jpg?resize=525%2C300 1.5x"},"classes":[]},{"id":3827,"url":"https:\/\/blogdafeira.com.br\/home\/2013\/07\/25\/coleta-de-lixo-em-feira-contrato-emergencial-termina-em-agosto\/","url_meta":{"origin":3825,"position":1},"title":"Coleta de lixo em Feira: contrato emergencial termina em agosto","author":"Blog da Feira","date":"25\/07\/2013","format":false,"excerpt":"A JG Com\u00e9rcio e Engenharia Ltda, de Salvador, foi a empresa apresentou o menor pre\u00e7o na cota\u00e7\u00e3o realizada pela Secretaria Municipal de Administra\u00e7\u00e3o, e \u00a0que desde \u00a01\u00ba de mar\u00e7o \u00e9 respons\u00e1vel pela coleta de lixo domiciliar de Feira de Santana. O contrato foi em \u00a0car\u00e1ter emergencial e validade de seis\u2026","rel":"","context":"Em &quot;Home&quot;","block_context":{"text":"Home","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/raiz\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":9028,"url":"https:\/\/blogdafeira.com.br\/home\/2014\/02\/10\/tribunal-de-justica-da-bahia-suspende-licitacao-do-lixo-em-feira\/","url_meta":{"origin":3825,"position":2},"title":"Tribunal de Justi\u00e7a da Bahia suspende licita\u00e7\u00e3o do lixo em Feira","author":"Blog da Feira","date":"10\/02\/2014","format":false,"excerpt":"A \u2018briga\u2019 pelo lixo em Feira est\u00e1 acirrada na Justi\u00e7a. Por determina\u00e7\u00e3o do Tribunal de Justi\u00e7a da Bahia, a Prefeitura suspendeu a licita\u00e7\u00e3o que aconteceria nesta segunda-feira. No edital, a Prefeitura de Feira de Santana quer \u00a0contratar duas empresas para operar o aterro sanit\u00e1rio e fazer a limpeza e coleta\u2026","rel":"","context":"Em &quot;Home&quot;","block_context":{"text":"Home","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/raiz\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":42812,"url":"https:\/\/blogdafeira.com.br\/home\/2020\/12\/29\/sustentare-continua-coleta-de-lixo-em-feira-contrato-de-25-milhoes\/","url_meta":{"origin":3825,"position":3},"title":"Sustentare continua coleta de lixo em Feira; contrato de 25 milh\u00f5es","author":"Blog da Feira","date":"29\/12\/2020","format":false,"excerpt":"Como foi anunciado em junho deste ano, a\u00a0 Prefeitura de Feira de Santana\u00a0 contratou \"emergencialmente\"\u00a0 a morena Sustentare Saneamento S\/A, para continuar na limpeza e coleta de lixo urbano em Feira de Santana. A contrata\u00e7\u00e3o foi conforme publicada na edi\u00e7\u00e3o desta ter\u00e7a-feira (29), no Di\u00e1rio Oficial Eletr\u00f4nico, e segundo assegurou\u2026","rel":"","context":"Em &quot;Cidade&quot;","block_context":{"text":"Cidade","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/cidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2020\/12\/images-72.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2020\/12\/images-72.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2020\/12\/images-72.jpeg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":4448,"url":"https:\/\/blogdafeira.com.br\/home\/2013\/08\/20\/empresa-paulista-ganhou-licitacao-para-coleta-de-lixo-em-feira\/","url_meta":{"origin":3825,"position":4},"title":"Empresa paulista ganhou licita\u00e7\u00e3o para coleta de lixo em Feira","author":"Blog da Feira","date":"20\/08\/2013","format":false,"excerpt":"A empresa paulista Construrban Engenharia de Constru\u00e7\u00e3o Ltda, venceu a licita\u00e7\u00e3o realizada, na segunda-feira, 19, pela Prefeitura de Feira de Santana e vai ser a respons\u00e1vel pela coleta dos res\u00edduos s\u00f3lidos domiciliares, entre outros servi\u00e7os relacionados \u00e0 limpeza p\u00fablica, nos pr\u00f3ximos seis meses \u2013 o contrato \u00e9 emergencial. A Construrban\u2026","rel":"","context":"Em &quot;Home&quot;","block_context":{"text":"Home","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/raiz\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":2064,"url":"https:\/\/blogdafeira.com.br\/home\/2013\/05\/29\/vereador-governista-diz-que-tem-lixo-espalhado-por-toda-a-feira\/","url_meta":{"origin":3825,"position":5},"title":"Vereador governista diz que &#8216;tem lixo espalhado por toda a Feira&#8217;","author":"Blog da Feira","date":"29\/05\/2013","format":false,"excerpt":"O vereador governista Jos\u00e9 Carneiro surpreendeu na C\u00e2mara ao criticar com muita veem\u00eancia \u00a0a empresa respons\u00e1vel pela coleta de lixo em Feira de Santana. Carneiro chegou a dizer que 'o lixo est\u00e1 espalhado por toda a cidade'. Ao mesmo tempo 'blindou' o prefeito Jos\u00e9 Ronaldo, dando 'a pista' para o\u2026","rel":"","context":"Em &quot;Cidade&quot;","block_context":{"text":"Cidade","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/cidade\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"_links":{"self":[{"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/posts\/3825","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/comments?post=3825"}],"version-history":[{"count":2,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/posts\/3825\/revisions"}],"predecessor-version":[{"id":3829,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/posts\/3825\/revisions\/3829"}],"wp:attachment":[{"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/media?parent=3825"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/categories?post=3825"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/tags?post=3825"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}