{"id":38917,"date":"2020-07-11T15:37:12","date_gmt":"2020-07-11T18:37:12","guid":{"rendered":"https:\/\/blogdafeira.com.br\/home\/?p=38917"},"modified":"2020-09-02T23:45:44","modified_gmt":"2020-09-03T02:45:44","slug":"ex-vereador-do-pt-de-feira-oferece-sitio-na-matinha-para-lula-morar","status":"publish","type":"post","link":"https:\/\/blogdafeira.com.br\/home\/2020\/07\/11\/ex-vereador-do-pt-de-feira-oferece-sitio-na-matinha-para-lula-morar\/","title":{"rendered":"Ex-vereador do PT de Feira oferece s\u00edtio na Matinha para Lula morar"},"content":{"rendered":"<div id=\"blogd-3238694423\" class=\"blogd-fim-do-post-mobile blogd-entity-placement\" style=\"margin-left: auto;margin-right: auto;text-align: center;\"><a href=\"https:\/\/www.feiradesantana.ba.gov.br\/servico.asp?s=a&titulo=Prefeitura-de-Feira-lan%C3%A7a-programa-Rem%C3%A9dio-em-Casa-e-transforma-acesso-a-medicamentos-em-pol%C3%ADtica-p%C3%BAblica-de-cuidados.html&id=14&link=secom\/noticias.asp&idn=43684#noticias\" target=_blank><picture>\r\n  <source media=\"(min-width: 768px)\" srcset=\"https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2026\/03\/980x150.gif\">\r\n  \r\n  <img decoding=\"async\" src=\"https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2021\/01\/350x2002.gif\" alt=\"Publicidade\" style=\"width: 100%; max-width: 100%; height: auto; display: block; margin: 0 auto;\">\r\n\t<\/picture><\/a><\/div><p>O ex-vereador de Feira de Santana, Marialvo Barreto (PT) ofereceu um s\u00edtio que ele possui no distrito rural da Matinha para Lula e a namorada dele, Janja, residirem. O ex-presidente, <a href=\"https:\/\/www.bahianoticias.com.br\/noticia\/250644-lula-pretende-comprar-casa-em-salvador-apos-casar-com-namorada.html?utm_source=principal&amp;utm_medium=link&amp;utm_campaign=destaques\">conforme notici\u00e1rio nacional,<\/a> est\u00e1 \u00e0 procura de um lugar para morar em Salvador, na Bahia.<\/p>\n<p><em>&#8220;Estou franqueando minha ch\u00e1cara na Matinha para Lula morar. \u00c9 UM LUGAR ADOR\u00c1VEL, banhado pelas sadias \u00e1guas sertanejas do Riacho de S\u00e3o Jos\u00e9 das Itapororocas, com muitas fruteiras, todas plantadas por mim, ao longo de quase quatro d\u00e9cadas, onde Lula e sua esposa poder\u00e3o desfrutar de doces cajus vermelhos, manga rosa, sapotis, umbu, caj\u00e1, pinhas, assar um milho no fog\u00e3o de<span class=\"text_exposed_show\"> lenha &#8211; para lembrar de Garanhuns, preparar uma macaxeira com carne de sol, de boas castanhas torradas na hora,etc. Mas al\u00e9m disso, Lula e esposa ir\u00e3o residir em uma \u00e1rea Quilombola e desfrutar da boa amizade e da hospitalidade dos seus moradores, onde muitos s\u00e3o parentes da minha esposa&#8221;,\u00a0<\/span><\/em><span class=\"text_exposed_show\">escreveu, no facebook,\u00a0 Marialvo, que \u00e9\u00a0 ge\u00f3grafo e professor universit\u00e1rio.\u00a0<\/span><\/p>\n<p>Al\u00e9m dessas qualidades, o professor faz tamb\u00e9m uma refer\u00eancia ao s\u00edtio de Atibaia, pelo qual Lula sofreu condena\u00e7\u00e3o jur\u00eddica, e diz: &#8220;<em>N\u00e3o h\u00e1 risco de promotor inventar falsa propriedade deste s\u00edtio, pois gato e sapato sabem que ele me pertence, aqui na Princesa do Sert\u00e3o.&#8221;<\/em><\/p>\n<p>Marialvo diz que <em>&#8220;a casa \u00e9 muito simples e antiga, mas faremos uma reforma, para lhes dar mais conforto&#8221; <\/em>\u00a0e informa no s\u00edtio <em>&#8220;h\u00e1 espa\u00e7o para fazer um estacionamento para receber caravanas de correligion\u00e1rios e simpatizantes&#8221;<\/em><\/p>\n<p>E descreve o clima buc\u00f3lico e interiorano do local com a vantagem de ser\u00a0 &#8220;<em>perto da capital, pouco mais de 100 km de dist\u00e2ncia, mas \u00e9 lugar de se respirar o bom ar sertanejo e se tomar aquele caf\u00e9 da manh\u00e3 com coalhada, beiju e leite tiradinho n<span id=\"u_ps_jsonp_15_4_a\" class=\"_ezo\">a hora&#8221;<\/span><\/em><\/p>\n<p><em>&#8220;E mais Lula, voc\u00ea em Feira atrair\u00e1 mais desenvolvimento para o sert\u00e3o, pois daqui tudo se propaga com mais facilidade, pela sua excelente localiza\u00e7\u00e3o. Ser\u00e1 a senha para termos um din\u00e2mico aeroporto e quem sabe a t\u00e3o sonhada ferrovia de trem r\u00e1pido para passageiros e de trem de carga para o porto. \u00c9 PARA VALER LULA, AGUARDO SUA RESPOSTA&#8221;, <\/em>diz.<\/p>\n<div id=\"blogd-4072035416\" class=\"blogd-final-post blogd-entity-placement\"><a href=\"https:\/\/www.feiradesantana.ba.leg.br\/\" target=\"_blank\" aria-label=\"JUNHO-VERMELHO_CA\u0302MARA-DE-FEIRA\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2026\/03\/JUNHO-VERMELHO_CAMARA-DE-FEIRA.gif\" alt=\"\"  class=\"no-lazyload\" width=\"728\" height=\"90\"   \/><\/a><\/div><p><strong><a href=\"https:\/\/www.facebook.com\/profile.php?id=100011194266460\">Visite a p\u00e1gina de Marialvo no facebook, clique aqui<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O ex-vereador de Feira de Santana, Marialvo Barreto (PT) ofereceu um s\u00edtio que ele possui no distrito rural da Matinha para Lula e a namorada dele, Janja, residirem. O ex-presidente, conforme notici\u00e1rio nacional, est\u00e1 \u00e0 procura de um lugar para morar em Salvador, na Bahia. &#8220;Estou franqueando minha ch\u00e1cara na Matinha para Lula morar. \u00c9<\/p>\n","protected":false},"author":1,"featured_media":38918,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"cybocfi_hide_featured_image":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[748,1,631],"tags":[368],"class_list":["post-38917","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-distritos","category-raiz","category-politica","tag-distritos"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2020\/07\/marialvo.jpg","jetpack_shortlink":"https:\/\/wp.me\/p3niVf-a7H","jetpack_sharing_enabled":true,"jetpack-related-posts":[{"id":70243,"url":"https:\/\/blogdafeira.com.br\/home\/2025\/11\/16\/jaqueira-de-marialvo-na-matinha-bota-safra-com-mais-de-200-jacas\/","url_meta":{"origin":38917,"position":0},"title":"Jaqueira de Marialvo na Matinha tem safra com mais de 200 jacas","author":"Blog da Feira","date":"16\/11\/2025","format":false,"excerpt":"Ge\u00f3grafo, professor universit\u00e1rio aposentado, al\u00e9m de ex-vereador em Feira de Santana, Marialvo Barreto tem uma pequena propriedade no distrito da Matinha onde passa o seu tempo a cultivar plantas comest\u00edveis e n\u00e3o comest\u00edveis, inclusive produzindo mudas que oferta gratuitamente \u00e0s pessoas. A vida dele no s\u00edtio, esse trabalho de dedica\u00e7\u00e3o\u2026","rel":"","context":"Em &quot;Distritos&quot;","block_context":{"text":"Distritos","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/distritos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2025\/11\/Screenshot_20251116-201413.png?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2025\/11\/Screenshot_20251116-201413.png?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2025\/11\/Screenshot_20251116-201413.png?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2025\/11\/Screenshot_20251116-201413.png?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2025\/11\/Screenshot_20251116-201413.png?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":33868,"url":"https:\/\/blogdafeira.com.br\/home\/2019\/11\/11\/lula-e-a-arapuca-por-jolivaldo-freitas\/","url_meta":{"origin":38917,"position":1},"title":"&#8216;Lula e a arapuca&#8217;, por Jolivaldo Freitas","author":"Jolivaldo Freitas","date":"11\/11\/2019","format":false,"excerpt":"por Jolivaldo Freitas* Lula solto depois que o Supremo Tribunal Federal decidiu que um r\u00e9u condenado deve aguardar o fim dos recursos judiciais em liberdade, gera incertezas para ele, seus ac\u00f3litos e para o pr\u00f3prio PT que hoje encontra-se mais dividido que gomos de laranja dentro de uma mesma casca.\u2026","rel":"","context":"Em &quot;Colunistas&quot;","block_context":{"text":"Colunistas","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/colunistas\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2019\/11\/download-9.jpeg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":43904,"url":"https:\/\/blogdafeira.com.br\/home\/2021\/03\/08\/caso-lula-governador-da-bahia-diz-que-foi-vitoria-da-democracia\/","url_meta":{"origin":38917,"position":2},"title":"Caso Lula: Governador da Bahia diz que foi &#8220;vit\u00f3ria da democracia&#8221;","author":"Blog da Feira","date":"08\/03\/2021","format":false,"excerpt":"O governador da Bahia, Rui Costa (PT) escreveu que \u00e9 uma \"vit\u00f3ria da democracia\" a anula\u00e7\u00e3o das a\u00e7\u00f5es contra o ex-presidente Lula. \"A verdade come\u00e7a a ser restabelecida com a decis\u00e3o do ministro Fachin de anular todas as condena\u00e7\u00f5es do ex-presidente Lula pela Justi\u00e7a Federal no Paran\u00e1 relacionadas \u00e0s investiga\u00e7\u00f5es\u2026","rel":"","context":"Em &quot;Home&quot;","block_context":{"text":"Home","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/raiz\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2021\/03\/Screenshot_20210308-1804492.png?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2021\/03\/Screenshot_20210308-1804492.png?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2021\/03\/Screenshot_20210308-1804492.png?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2021\/03\/Screenshot_20210308-1804492.png?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":5625,"url":"https:\/\/blogdafeira.com.br\/home\/2013\/10\/19\/ex-presidente-da-petrobras-e-o-preferido-de-lula-para-governar-a-bahia\/","url_meta":{"origin":38917,"position":3},"title":"Ex-presidente da Petrobr\u00e1s \u00e9 o preferido de Lula para governar a Bahia","author":"Blog da Feira","date":"19\/10\/2013","format":false,"excerpt":"O ex-presidente da Petrobr\u00e1s e atual secret\u00e1rio de Planejamento da Bahia, Jos\u00e9 S\u00e9rgio Gabrielli foi lan\u00e7ado nesta s\u00e1bado como pr\u00e9-candidato a governador do Estado, com o apoio dos movimentos sociais, em especial, de dirigentes estaduais e nacionais da Central \u00danica dos Trabalhadores (CUT), bem como de setores ligados a Agricultura\u2026","rel":"","context":"Em &quot;Home&quot;","block_context":{"text":"Home","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/raiz\/"},"img":{"alt_text":"02","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2013\/10\/02.jpg?resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2013\/10\/02.jpg?resize=350%2C200 1x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2013\/10\/02.jpg?resize=525%2C300 1.5x"},"classes":[]},{"id":19905,"url":"https:\/\/blogdafeira.com.br\/home\/2016\/03\/04\/advogados-de-lula-dizem-que-acao-foi-violencia-juridica-sem-precedentes\/","url_meta":{"origin":38917,"position":4},"title":"Advogados de Lula dizem que a\u00e7\u00e3o foi &#8216;viol\u00eancia jur\u00eddica sem precedentes&#8217;","author":"Blog da Feira","date":"04\/03\/2016","format":false,"excerpt":"Em nota distribu\u00edda com a imprensa os advogados do ex-presidente Lula, \u00a0Roberto Teixeira e Cristiano Martins, dizem aguardar uma defini\u00e7\u00e3o das compet\u00eancias para continuidade das investiga\u00e7\u00f5es e que tomar\u00e3o medidas legais para \"impugnar as arbitrariedades hoje cometidas\". Leia a nota na \u00edntegra: Foi uma viol\u00eancia jur\u00eddica sem precedentes a condu\u00e7\u00e3o\u2026","rel":"","context":"Em &quot;Home&quot;","block_context":{"text":"Home","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/raiz\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":52515,"url":"https:\/\/blogdafeira.com.br\/home\/2022\/05\/23\/ze-neto-eleicao-mais-importante-da-historia-do-pais\/","url_meta":{"origin":38917,"position":5},"title":"Z\u00e9 Neto: &#8220;elei\u00e7\u00e3o mais importante da hist\u00f3ria do pa\u00eds&#8221;","author":"Blog da Feira","date":"23\/05\/2022","format":false,"excerpt":"Na luta pelo segundo Mandato de deputado federal, Z\u00e9 Neto (PT-BA) exaltou o legado dos governos \u00a0petistas na Bahia e no Brasil, e reafirmou que \u2018essa ser\u00e1 a elei\u00e7\u00e3o mais importante da hist\u00f3ria do pa\u00eds\u2019, ao oficializar sua pr\u00e9-candidatura \u00e0 reelei\u00e7\u00e3o no Ville Convention (Ville Goumert) em Feira de Santana,\u2026","rel":"","context":"Em &quot;Home&quot;","block_context":{"text":"Home","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/raiz\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2022\/05\/WhatsApp-Image-2022-05-23-at-13.43.34.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2022\/05\/WhatsApp-Image-2022-05-23-at-13.43.34.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2022\/05\/WhatsApp-Image-2022-05-23-at-13.43.34.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2022\/05\/WhatsApp-Image-2022-05-23-at-13.43.34.jpeg?resize=700%2C400&ssl=1 2x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/posts\/38917","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/comments?post=38917"}],"version-history":[{"count":2,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/posts\/38917\/revisions"}],"predecessor-version":[{"id":38920,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/posts\/38917\/revisions\/38920"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/media\/38918"}],"wp:attachment":[{"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/media?parent=38917"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/categories?post=38917"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/tags?post=38917"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}