{"id":3969,"date":"2013-07-31T09:43:15","date_gmt":"2013-07-31T12:43:15","guid":{"rendered":"http:\/\/blogdafeira.com.br\/home\/?p=3969"},"modified":"2013-07-31T09:46:23","modified_gmt":"2013-07-31T12:46:23","slug":"ronaldo-empossa-novos-conselheiros-de-cultura-de-feira-de-santana","status":"publish","type":"post","link":"https:\/\/blogdafeira.com.br\/home\/2013\/07\/31\/ronaldo-empossa-novos-conselheiros-de-cultura-de-feira-de-santana\/","title":{"rendered":"Ronaldo empossa novos conselheiros de Cultura de Feira de Santana"},"content":{"rendered":"<div id=\"blogd-929389983\" class=\"blogd-fim-do-post-mobile blogd-entity-placement\" style=\"margin-left: auto;margin-right: auto;text-align: center;\"><a href=\"https:\/\/www.feiradesantana.ba.gov.br\/servico.asp?s=a&#038;titulo=Alceu,-Paula-Fernandes,-Alcymar-Monteiro,-Fl%C3%A1vio-Jos%C3%A9-e-Ra%C3%A7a-Negra-animar%C3%A3o-o-Arrai%C3%A1-de%20Feira.html&#038;id=8&#038;link=secom\/noticias.asp&#038;idn=43073#noticias\" target=\"_blank\" aria-label=\"728&#215;90 (7)\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2026\/03\/728x90-7.gif\" alt=\"\"  class=\"no-lazyload\" width=\"728\" height=\"90\"  style=\"display: inline-block;\" \/><\/a><\/div><p>Numa solenidade r\u00e1pida \u00a0no Parque do Saber, hoje pela manh\u00e3,. foram empossados os novos membros do Conselho Municipal de Cultura de Feira de Santana.<\/p><div id=\"blogd-2020563219\" class=\"blogd-conteudo-2-mobile blogd-entity-placement\"><a href=\"https:\/\/feirenses.com.br\/\" target=\"_blank\" aria-label=\"feirenses\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2026\/04\/feirenses.png\" alt=\"\"  srcset=\"https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2026\/04\/feirenses.png 300w, https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2026\/04\/feirenses-170x45.png 170w, https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2026\/04\/feirenses-280x74.png 280w\" sizes=\"(max-width: 300px) 100vw, 300px\" class=\"no-lazyload\" width=\"300\" height=\"79\"  style=\"display: inline-block;\" \/><\/a><\/div>\n<p>O prefeito de Feira, Jos\u00e9 Ronaldo, presidiu a solenidade ao lado dos secret\u00e1rios de Cultura, Jailton Batista, e Educa\u00e7\u00e3o, Jaylza Ribeiro.<\/p>\n<p>Quase todos os conselheiros e suplentes compareceram. Ap\u00f3s a posse o presidente do Conselho, Jailton Batista, convocou a primeira reuni\u00e3o oficial que aconteceu no pr\u00f3prio Parque do Saber.<\/p>\n<div id=\"blogd-1327912530\" class=\"blogd-final-post blogd-entity-placement\"><a href=\"https:\/\/www.feiradesantana.ba.leg.br\/\" target=\"_blank\" aria-label=\"BANNER-SITE-ENTREGADECHEQUE-CAMARADEFEIRA\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2026\/03\/BANNER-SITE-ENTREGADECHEQUE-CAMARADEFEIRA.gif\" alt=\"\"  class=\"no-lazyload\" width=\"728\" height=\"90\"   \/><\/a><\/div><p>Saiba quem s\u00e3o os conselheiros: <strong><a href=\"http:\/\/blogdafeira.com.br\/home\/?p=3931\" target=\"_blank\">clique aqui<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Numa solenidade r\u00e1pida \u00a0no Parque do Saber, hoje pela manh\u00e3,. foram empossados os novos membros do Conselho Municipal de Cultura de Feira de Santana. O prefeito de Feira, Jos\u00e9 Ronaldo, presidiu a solenidade ao lado dos secret\u00e1rios de Cultura, Jailton Batista, e Educa\u00e7\u00e3o, Jaylza Ribeiro. Quase todos os conselheiros e suplentes compareceram. Ap\u00f3s a posse<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"cybocfi_hide_featured_image":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[1],"tags":[],"class_list":["post-3969","post","type-post","status-publish","format-standard","hentry","category-raiz"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p3niVf-121","jetpack_sharing_enabled":true,"jetpack-related-posts":[{"id":3931,"url":"https:\/\/blogdafeira.com.br\/home\/2013\/07\/30\/conselheiros-de-cultura-de-feira-tomam-posse-nesta-quarta-feira\/","url_meta":{"origin":3969,"position":0},"title":"Conselheiros de Cultura de Feira tomam posse nesta quarta-feira","author":"Blog da Feira","date":"30\/07\/2013","format":false,"excerpt":"O novo Conselho Municipal de Cultura de Feira de Santana ser\u00e1 empossado nesta quarta-feira, \u00e0s 8 horas, no Parque do Saber Dival Pitombo. Eles foram eleitos em assembleia durante o II F\u00f3rum Municipal de Cultura realizado no dia 12 de julho. O Conselho est\u00e1 assim composto:\u00a0representantes do poder p\u00fablico: Jailton\u2026","rel":"","context":"Em &quot;Cultura&quot;","block_context":{"text":"Cultura","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/cultura\/"},"img":{"alt_text":"1 ELSIMARIIIII","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2013\/07\/1-ELSIMARIIIII.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":8961,"url":"https:\/\/blogdafeira.com.br\/home\/2014\/02\/06\/ronaldo-e-ildes-empossam-o-conselho-de-seguranca-alimentar-de-feira\/","url_meta":{"origin":3969,"position":1},"title":"Ronaldo e Ildes empossam Conselho de Seguran\u00e7a Alimentar de Feira","author":"Blog da Feira","date":"06\/02\/2014","format":false,"excerpt":"O prefeito de Feira, Jos\u00e9 Ronaldo, e o secret\u00e1rio de Desenvolvimento Social, Ildes Ferreira, d\u00e3o posse nesta sexta-feira os membros do Conselho Municipal de Seguran\u00e7a Alimentar. A solenidade vai acontecer \u00e0s 14 horas, na sala de reuni\u00f5es do Gabinete do Prefeito, no Pa\u00e7o Municipal \u2018Maria Quit\u00e9ria\u2019. Ser\u00e3o empossados 42 membros\u2026","rel":"","context":"Em &quot;Home&quot;","block_context":{"text":"Home","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/raiz\/"},"img":{"alt_text":"tutelares","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2014\/01\/tutelares.jpg?resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2014\/01\/tutelares.jpg?resize=350%2C200 1x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2014\/01\/tutelares.jpg?resize=525%2C300 1.5x"},"classes":[]},{"id":380,"url":"https:\/\/blogdafeira.com.br\/home\/2013\/04\/11\/membros-do-conselho-de-cultura-voltam-a-defender-recebimento-de-cache\/","url_meta":{"origin":3969,"position":2},"title":"Membros do Conselho de Cultura voltam a defender  &#8216;cach\u00ea&#8217; pela atividade","author":"Blog da Feira","date":"11\/04\/2013","format":false,"excerpt":"Depois de um longu\u00edssimo per\u00edodo de inatividade, foram retomadas as reuni\u00f5es do Conselho de Cultura de Feira de Santana. At\u00e9 agora ocorreram dois encontros e, de forma surpreendente, um velho e pol\u00eamico tema foi ressuscitado, o pagamento de pr\u00f3 labore aos conselheiros. Segundo o Blog da Feira apurou, pelo menos\u2026","rel":"","context":"Em &quot;Cultura&quot;","block_context":{"text":"Cultura","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/cultura\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":3970,"url":"https:\/\/blogdafeira.com.br\/home\/2013\/07\/31\/feira-de-santana-aderiu-ao-sistema-nacional-de-cultura\/","url_meta":{"origin":3969,"position":3},"title":"Feira de Santana aderiu ao Sistema Nacional de Cultura","author":"Blog da Feira","date":"31\/07\/2013","format":false,"excerpt":"O secret\u00e1rio de Cultura de Feira, Jailton Batista, disse hoje pela manh\u00e3 durante a posse dos conselheiros de Cultura que o munic\u00edpio \u00a0j\u00e1 assinou o termo de ades\u00e3o ao Sistema Nacional de Cultura. O Sistema Nacional de Cultura (SNC) \u00e9 um modelo de gest\u00e3o criado pelo Minist\u00e9rio da Cultura (MinC)\u2026","rel":"","context":"Em &quot;Home&quot;","block_context":{"text":"Home","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/raiz\/"},"img":{"alt_text":"JAILTON","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2013\/07\/JAILTON-240x300.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":2031,"url":"https:\/\/blogdafeira.com.br\/home\/2013\/05\/28\/musica-e-humor-no-forum-de-conselheiros-e-dirigentes-culturais\/","url_meta":{"origin":3969,"position":4},"title":"M\u00fasica e humor no f\u00f3rum de conselheiros e dirigentes culturais","author":"Blog da Feira","date":"28\/05\/2013","format":false,"excerpt":"Um sexteto de m\u00fasicos da Orquestra Sinf\u00f4nica da Bahia realizou \u00a0um pequeno concerto de m\u00fasicas instrumentais ap\u00f3s um 'stand up' do humorista Pisit Mota (clique aqui), \u00a0durante os f\u00f3runs de dirigentes e conselheiros de cultura que acontece at\u00e9 hoje no Centro de Cultura Am\u00e9lio Amorim em Feira de Santana. Promovido\u2026","rel":"","context":"Em &quot;Home&quot;","block_context":{"text":"Home","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/raiz\/"},"img":{"alt_text":"CENTRO DE CULTURA AMELIO AMORIM. ALBINO RUBIN (2)","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2013\/05\/CENTRO-DE-CULTURA-AMELIO-AMORIM.-ALBINO-RUBIN-2.jpg?resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2013\/05\/CENTRO-DE-CULTURA-AMELIO-AMORIM.-ALBINO-RUBIN-2.jpg?resize=350%2C200 1x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2013\/05\/CENTRO-DE-CULTURA-AMELIO-AMORIM.-ALBINO-RUBIN-2.jpg?resize=525%2C300 1.5x"},"classes":[]},{"id":12155,"url":"https:\/\/blogdafeira.com.br\/home\/2014\/08\/26\/saida-de-jailton-poe-coelho-em-destaque-na-area-cultural-de-feira\/","url_meta":{"origin":3969,"position":5},"title":"Sa\u00edda de Jailton p\u00f5e Coelho em destaque na \u00e1rea cultural de Feira","author":"Blog da Feira","date":"26\/08\/2014","format":false,"excerpt":"A sa\u00edda de Jailton Batista da Secretaria de Cultura de Feira p\u00f5e em destaque nesta \u00e1rea a figura do ex-vereador Ant\u00f4nio Carlos Coelho (camisa listrada) , que preside a Funda\u00e7\u00e3o Cultural Egberto Costa. O ex-vereador come\u00e7ou esta semana anunciando medidas modernizadoras na Biblioteca Arnold Silva, com a implanta\u00e7\u00e3o de um\u2026","rel":"","context":"Em &quot;Home&quot;","block_context":{"text":"Home","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/raiz\/"},"img":{"alt_text":"COELHO","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2014\/08\/COELHO.jpg?resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2014\/08\/COELHO.jpg?resize=350%2C200 1x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2014\/08\/COELHO.jpg?resize=525%2C300 1.5x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2014\/08\/COELHO.jpg?resize=700%2C400 2x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/posts\/3969","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/comments?post=3969"}],"version-history":[{"count":3,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/posts\/3969\/revisions"}],"predecessor-version":[{"id":3974,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/posts\/3969\/revisions\/3974"}],"wp:attachment":[{"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/media?parent=3969"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/categories?post=3969"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/tags?post=3969"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}