{"id":42039,"date":"2020-11-23T16:53:42","date_gmt":"2020-11-23T19:53:42","guid":{"rendered":"https:\/\/blogdafeira.com.br\/home\/?p=42039"},"modified":"2020-11-24T00:44:43","modified_gmt":"2020-11-24T03:44:43","slug":"colbert-promete-reformar-50-mil-casas-nos-distritos-rurais-de-feira","status":"publish","type":"post","link":"https:\/\/blogdafeira.com.br\/home\/2020\/11\/23\/colbert-promete-reformar-50-mil-casas-nos-distritos-rurais-de-feira\/","title":{"rendered":"Colbert  promete reformar 50 mil casas nos distritos rurais de Feira"},"content":{"rendered":"<div id=\"blogd-4084737662\" class=\"blogd-fim-do-post-mobile blogd-entity-placement\" style=\"margin-left: auto;margin-right: auto;text-align: center;\"><a href=\"https:\/\/www.feiradesantana.ba.gov.br\/servico.asp?s=a&titulo=Prefeitura-de-Feira-lan%C3%A7a-programa-Rem%C3%A9dio-em-Casa-e-transforma-acesso-a-medicamentos-em-pol%C3%ADtica-p%C3%BAblica-de-cuidados.html&id=14&link=secom\/noticias.asp&idn=43684#noticias\" target=_blank><picture>\r\n  <source media=\"(min-width: 768px)\" srcset=\"https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2026\/03\/980x150.gif\">\r\n  \r\n  <img decoding=\"async\" src=\"https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2021\/01\/350x2002.gif\" alt=\"Publicidade\" style=\"width: 100%; max-width: 100%; height: auto; display: block; margin: 0 auto;\">\r\n\t<\/picture><\/a><\/div><p style=\"text-align: justify;\">A campanha de m\u00eddia do prefeito Colbert Filho, candidato \u00e0\u00a0 reelei\u00e7\u00e3o\u00a0 neste segundo turno, &#8216;escondeu&#8217; o ex-prefeito Jos\u00e9 Ronaldo de Carvalho que no primeiro turno praticamente apresentava os programas eleitorais de Colbert e nesta ter\u00e7a-feira, o segundo programa da propaganda eleitoral deste turno foi dedicado \u00e0 zona rural de Feira de Santana.<\/p>\n<p style=\"text-align: justify;\">Quem pontua o programa desta segunda-feira \u00e9 o prefeito de Salvador, ACM Neto. Primeiro com a promessa de Colbert de trazer para Feira o programa de reforma de moradias aplicados pela Prefeitura de Salvador.<\/p>\n<p style=\"text-align: justify;\"><strong><a href=\"https:\/\/www.youtube.com\/watch?v=iYcZAZqoEn4&amp;t=127s\"><em>&#8220;Ser\u00e3o 50 mil casas reformadas<\/em>&#8221; diz o prefeito depois de um filmete onde ele visita, e toma caf\u00e9, com uma dona-de-casa no distrito rural de Humildes<\/a><\/strong>.<\/p>\n<p style=\"text-align: justify;\">Na casa de Dona Rain\u00e9, onde explicou o &#8220;Morar Melhor&#8221;, de Salvador,\u00a0 Colbert admitiu a dist\u00e2ncia que existe entre o povo da zona rural e a Prefeitura.<\/p>\n<p style=\"text-align: justify;\"><em>&#8220;\u00c0s vezes morar afastado da cidade faz com que melhorias demorem para chegar, vou \u00a0diminuir esta dist\u00e2ncia entre as\u00a0 a\u00e7\u00f5es da Prefeitura e quem mora nos distritos<\/em>&#8220;, disse.<\/p>\n<p style=\"text-align: justify;\">No final do programa o prefeito de Salvador aparece e explica porque para ele o prefeito Colbert merece a reelei\u00e7\u00e3o.<\/p>\n<div id=\"blogd-2923417677\" class=\"blogd-final-post blogd-entity-placement\"><a href=\"https:\/\/www.feiradesantana.ba.leg.br\/\" target=\"_blank\" aria-label=\"JUNHO-VERMELHO_CA\u0302MARA-DE-FEIRA\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2026\/03\/JUNHO-VERMELHO_CAMARA-DE-FEIRA.gif\" alt=\"\"  class=\"no-lazyload\" width=\"728\" height=\"90\"   \/><\/a><\/div><p style=\"text-align: justify;\">Al\u00e9m das reformar, o prefeito Colberte prometeu implantar &#8220;Prefeituras-distrito&#8221; e mostrou o projeto &#8220;Novo Centro&#8221; com algumas &#8220;pitadas&#8217; de provoca\u00e7\u00f5es feitas por um ator ao candidato Z\u00e9 Neto: &#8220;deixe Colbert trabalhar&#8230;!!&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A campanha de m\u00eddia do prefeito Colbert Filho, candidato \u00e0\u00a0 reelei\u00e7\u00e3o\u00a0 neste segundo turno, &#8216;escondeu&#8217; o ex-prefeito Jos\u00e9 Ronaldo de Carvalho que no primeiro turno praticamente apresentava os programas eleitorais de Colbert e nesta ter\u00e7a-feira, o segundo programa da propaganda eleitoral deste turno foi dedicado \u00e0 zona rural de Feira de Santana. Quem pontua o<\/p>\n","protected":false},"author":1,"featured_media":42040,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"cybocfi_hide_featured_image":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[750,1],"tags":[],"class_list":["post-42039","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eleicoes-2020","category-raiz"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2020\/11\/Screenshot_20201123-1645492.png","jetpack_shortlink":"https:\/\/wp.me\/p3niVf-aW3","jetpack_sharing_enabled":true,"jetpack-related-posts":[{"id":55999,"url":"https:\/\/blogdafeira.com.br\/home\/2023\/01\/02\/minha-casa-minha-vida-e-a-promessa-de-colbert-para-a-zona-rural\/","url_meta":{"origin":42039,"position":0},"title":"&#8220;Minha Casa, Minha Vida&#8221; e a promessa de Colbert para a zona rural","author":"J\u00e2nio R\u00eago","date":"02\/01\/2023","format":false,"excerpt":"Est\u00e1\u00a0 no site da Prefeitura de Feira de Santana a \u00faltima lista de inscritos para o \"Minha Casa Minha Vida\", do ano de 2016... Foram\u00a0 tempos em que a cidade tornou-se uma das \"campe\u00e3s\" do pa\u00eds no combate ao d\u00e9ficit habitacional atrav\u00e9s desse programa governamental que o\u00a0 presidente Lula promete\u2026","rel":"","context":"Em &quot;Colunistas&quot;","block_context":{"text":"Colunistas","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/colunistas\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2023\/01\/IMG_20221029_173740_864-scaled.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2023\/01\/IMG_20221029_173740_864-scaled.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2023\/01\/IMG_20221029_173740_864-scaled.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2023\/01\/IMG_20221029_173740_864-scaled.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2023\/01\/IMG_20221029_173740_864-scaled.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2023\/01\/IMG_20221029_173740_864-scaled.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":22515,"url":"https:\/\/blogdafeira.com.br\/home\/2016\/07\/14\/colbert-como-vice-fez-crescer-o-clima-de-ja-ganhou-no-ronaldismo-em-feira\/","url_meta":{"origin":42039,"position":1},"title":"Ronaldo teme segundo turno e escolhe Colbert como candidato a vice Prefeito","author":"Blog da Feira","date":"14\/07\/2016","format":false,"excerpt":"O Prefeito de Feira, Colbert Filho e Luciano Ribeiro, no CDL: elei\u00e7\u00f5es 2016. O\u00a0ex-deputado federal Colbert Martins Filho \u00e9 o candidato \u00a0a vice prefeito de Jos\u00e9 Ronaldo na elei\u00e7\u00e3o deste ano. O an\u00fancio foi feito pelo Prefeito em clima de pr\u00e9 conven\u00e7\u00e3o eleitoral na\u00a0\u00a0C\u00e2mara de Diretores Lojistas de Feira de\u2026","rel":"","context":"Em &quot;Home&quot;","block_context":{"text":"Home","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/raiz\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":41800,"url":"https:\/\/blogdafeira.com.br\/home\/2020\/11\/17\/ha-24-anos-ze-neto-se-absteve-e-colbert-apoiou-falcao-no-segundo-turno\/","url_meta":{"origin":42039,"position":2},"title":"H\u00e1 24 anos: Z\u00e9 Neto absteve-se e Colbert apoiou Falc\u00e3o no segundo turno","author":"Blog da Feira","date":"17\/11\/2020","format":false,"excerpt":"H\u00e1\u00a0 24 anos (1996), quando terminou o primeiro turno da elei\u00e7\u00e3o para Prefeito de Feira de Santana,\u00a0 entre\u00a0 os candidatos derrotados\u00a0 estavam Colbert Filho\u00a0 e Z\u00e9 Neto. Em 1996 o segundo turno aconteceu entre o pastor presbiteriano e ex-reitor da UEFS Josu\u00e9 Melo , apoiado por ACM, e o advogado\u00a0\u2026","rel":"","context":"Em &quot;Elei\u00e7\u00f5es 2020&quot;","block_context":{"text":"Elei\u00e7\u00f5es 2020","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/eleicoes-2020\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2020\/11\/CANDIDATOS-A-PREFEITO-EM-1996eleicoes.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2020\/11\/CANDIDATOS-A-PREFEITO-EM-1996eleicoes.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2020\/11\/CANDIDATOS-A-PREFEITO-EM-1996eleicoes.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2020\/11\/CANDIDATOS-A-PREFEITO-EM-1996eleicoes.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":41901,"url":"https:\/\/blogdafeira.com.br\/home\/2020\/11\/18\/jose-de-arimateia-declara-apoio-a-colbert\/","url_meta":{"origin":42039,"position":3},"title":"Jos\u00e9 de Arimat\u00e9ia declara apoio a Colbert","author":"Blog da Feira","date":"18\/11\/2020","format":false,"excerpt":"O pastor Jos\u00e9 de Arimat\u00e9ia (Republicanos), deputado estadual\u00a0 e um dos candidatos a prefeito de Feira de Santana no primeiro turno, declarou apoio ao prefeito Colbert Martins(MDB) candidato \u00e0 reelei\u00e7\u00e3o e que disputa este segundo turno eleitoral com o candidato Z\u00e9 Neto(PT) O apoio tem o aval do Republicanos local\u2026","rel":"","context":"Em &quot;Elei\u00e7\u00f5es 2020&quot;","block_context":{"text":"Elei\u00e7\u00f5es 2020","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/eleicoes-2020\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2020\/11\/Screenshot_20201118-1946472.png?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2020\/11\/Screenshot_20201118-1946472.png?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2020\/11\/Screenshot_20201118-1946472.png?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2020\/11\/Screenshot_20201118-1946472.png?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":31788,"url":"https:\/\/blogdafeira.com.br\/home\/2019\/06\/27\/vereador-lulinha-encerra-semestre-com-balanco-de-acoes-do-mandato-em-feira-e-agradece-a-colbert-e-jose-ronaldo\/","url_meta":{"origin":42039,"position":4},"title":"Vereador Lulinha encerra semestre com balan\u00e7o de &#8216;a\u00e7\u00f5es do mandato&#8217; em Feira e  agradece a Colbert e Jos\u00e9 Ronaldo","author":"J\u00e2nio R\u00eago","date":"27\/06\/2019","format":false,"excerpt":"No encerramento das atividades legislativas deste primeiro semestre, quarta-feira,26,\u00a0 o vereador Luiz Augusto de Jesus \u2013 Lulinha (DEM) usou a tribuna na sess\u00e3o ordin\u00e1riana quarta-feira (26) para\u00a0 destacar \"a\u00e7\u00f5es do seu mandato\" e agradecer diretamente ao prefeito Colbert Martins e ao ex-prefeito Jos\u00e9 Ronaldo. Lulinha destacou diversas melhorias contempladas no\u2026","rel":"","context":"Em &quot;Distritos&quot;","block_context":{"text":"Distritos","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/distritos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2018\/03\/unnamed-1.jpg?resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2018\/03\/unnamed-1.jpg?resize=350%2C200 1x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2018\/03\/unnamed-1.jpg?resize=525%2C300 1.5x"},"classes":[]},{"id":35483,"url":"https:\/\/blogdafeira.com.br\/home\/2020\/02\/17\/lampadas-led-iluminam-o-bairro-da-queimadinha-colbert-fez-caminhada-no-bairro\/","url_meta":{"origin":42039,"position":5},"title":"L\u00e2mpadas led iluminam a Queimadinha; Colbert fez caminhada no bairro","author":"J\u00e2nio R\u00eago","date":"17\/02\/2020","format":false,"excerpt":"Dono de lanchonete na rua Intendente Abdon, principal via do bairro Queimadinha, Rodrigo Mota [foto abaixo], n\u00e3o vai mais\u00a0 fazer uso de um refletor instalado por ele em frente ao estabelecimento. \u00c9 que o novo sistema de ilumina\u00e7\u00e3o em Led, implantado pela Prefeitura de Feira de Santana, \u00e9 o suficiente\u2026","rel":"","context":"Em &quot;Cidade&quot;","block_context":{"text":"Cidade","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/cidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2020\/02\/ilumina3.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2020\/02\/ilumina3.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2020\/02\/ilumina3.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2020\/02\/ilumina3.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2020\/02\/ilumina3.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2020\/02\/ilumina3.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/posts\/42039","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/comments?post=42039"}],"version-history":[{"count":4,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/posts\/42039\/revisions"}],"predecessor-version":[{"id":42076,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/posts\/42039\/revisions\/42076"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/media\/42040"}],"wp:attachment":[{"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/media?parent=42039"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/categories?post=42039"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/tags?post=42039"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}