{"id":43212,"date":"2021-02-02T09:42:27","date_gmt":"2021-02-02T12:42:27","guid":{"rendered":"https:\/\/blogdafeira.com.br\/home\/?p=43212"},"modified":"2021-02-04T13:31:52","modified_gmt":"2021-02-04T16:31:52","slug":"nova-escultura-do-vaqueiro-da-feira-esta-pronta-para-ser-instalada","status":"publish","type":"post","link":"https:\/\/blogdafeira.com.br\/home\/2021\/02\/02\/nova-escultura-do-vaqueiro-da-feira-esta-pronta-para-ser-instalada\/","title":{"rendered":"Nova escultura do &#8216;Vaqueiro da Feira&#8217; est\u00e1 pronta para ser instalada"},"content":{"rendered":"<div id=\"blogd-439325461\" class=\"blogd-fim-do-post-mobile blogd-entity-placement\" style=\"margin-left: auto;margin-right: auto;text-align: center;\"><a href=\"https:\/\/www.feiradesantana.ba.gov.br\/servico.asp?s=a&titulo=Prefeitura-de-Feira-lan%C3%A7a-programa-Rem%C3%A9dio-em-Casa-e-transforma-acesso-a-medicamentos-em-pol%C3%ADtica-p%C3%BAblica-de-cuidados.html&id=14&link=secom\/noticias.asp&idn=43684#noticias\" target=_blank><picture>\r\n  <source media=\"(min-width: 768px)\" srcset=\"https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2026\/03\/980x150.gif\">\r\n  \r\n  <img decoding=\"async\" src=\"https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2021\/01\/350x2002.gif\" alt=\"Publicidade\" style=\"width: 100%; max-width: 100%; height: auto; display: block; margin: 0 auto;\">\r\n\t<\/picture><\/a><\/div><p style=\"text-align: justify;\">O a\u00e7o contorcido moldado pelas ferramentas do arquiteto Danilo Freitas deu forma a escultura do vaqueiro montado a cavalo que, ao ser observado em diferentes \u00e2ngulos, mostra estar em movimento. <strong><a href=\"https:\/\/blogdafeira.com.br\/home\/2017\/01\/16\/cade-o-vaqueiro-da-olimpio-vital\/\">A pe\u00e7a ser\u00e1 instalada na rua Ol\u00edmpio Vital, substituindo o antigo monumento<\/a> <\/strong>que se desgastou com o tempo.<\/p>\n<p style=\"text-align: justify;\">Vencedor do pr\u00eamio Cultura de Arte Popular, Danilo levou quase trinta dias para construir a escultura que tem dois metros de altura por tr\u00eas e meio de comprimento. Estima-se que pesa cerca de 500 kg. A montagem da obra come\u00e7ou pelos membros do cavalo, dando sustenta\u00e7\u00e3o para seguir com a montagem dos arreios e por \u00faltimo, o vaqueiro.\u00a0<img decoding=\"async\" src=\"http:\/\/feiradesantana.ba.gov.br\/fts_secom\/fts\/images\/Nova%20escutura%20do%20vaqueiro%20Danilo%20Freitas%2028-01-2021%20Foto%20Izinaldo%20Barreto%20(3).JPG\" alt=\"\" \/><\/p>\n<p style=\"text-align: justify;\">Segundo ele, a pe\u00e7a foi feita em a\u00e7o patin\u00e1vel, conhecido como corten, que cont\u00e9m elementos anticorrosivos e de alta dura\u00e7\u00e3o. \u201cEste material desenvolve naturalmente a p\u00e1tina protetora, uma esp\u00e9cie de ferrugem que proporciona maior durabilidade \u00e0 pe\u00e7a. Al\u00e9m disso, foram utilizados telha de zincalume (\u00e9 utilizada para servi\u00e7os de alta resist\u00eancia \u00e0 corros\u00e3o atmosf\u00e9rica) e chapa fina&#8221;.<\/p>\n<p style=\"text-align: justify;\"><img decoding=\"async\" src=\"http:\/\/feiradesantana.ba.gov.br\/fts_secom\/fts\/images\/Nova%20escutura%20do%20vaqueiro%20Danilo%20Freitas%2028-01-2021%20Foto%20Izinaldo%20Barreto%20(16).JPG\" alt=\"\" \/>Na constru\u00e7\u00e3o do monumento e para alcan\u00e7ar o tamanho desejado, Danilo utilizou algumas t\u00e9cnicas para calcular a propor\u00e7\u00e3o e ferramentas feitas por ele mesmo para moldar o ferro. Al\u00e9m disso, contou com o aux\u00edlio de dois ajudantes. &#8220;Algumas pe\u00e7as com menos mobilidade levamos a um serralheiro para adapt\u00e1-las&#8221;, acrescenta.<\/p>\n<p style=\"text-align: justify;\"><img decoding=\"async\" src=\"http:\/\/feiradesantana.ba.gov.br\/fts_secom\/fts\/images\/Nova%20escutura%20do%20vaqueiro%20Danilo%20Freitas%2028-01-2021%20Foto%20Izinaldo%20Barreto%20(11).JPG\" alt=\"\" \/>O arquiteto feirense conta que imaginou o vaqueiro em alta performance. Da\u00ed a ideia em participar do concurso. O prot\u00f3tipo foi feito em lat\u00e3o e chapas de lat\u00e3o, utilizando trena, martelo, alicate e cortador de chapa. &#8220;Entre quatro participantes, eu fui selecionado\u201d, comenta. A miniatura ser\u00e1 doada pelo artista ao Parque do Saber.<\/p>\n<p style=\"text-align: justify;\">A Secretaria de Cultura, Esporte e Lazer (Secel) \u00e9 a idealizadora do pr\u00eamio de Cultura e Arte e respons\u00e1vel pela escultura, que dever\u00e1 ser fixada na avenida Ol\u00edmpio Vital em comum acordo com as obras do projeto Novo Centro.<\/p>\n<p style=\"text-align: justify;\">Danilo ganhou no concurso R$ 15 mil. Ele \u00e9 formado pela Universidade Federal da Bahia (UFBA), em 2013. Sua primeira introdu\u00e7\u00e3o com artes pl\u00e1sticas foi no CUCA com um projeto de arte contempor\u00e2nea e a partir da\u00ed n\u00e3o parou mais, esteve sempre ligado a projetos que utilizam materiais sustent\u00e1veis ou menos invasivo a natureza, dando forma atrav\u00e9s do seu est\u00fadio D&#8217;ideia Arquitetura e Design de M\u00f3veis. <strong>Fotos: Izinaldo Barreto<\/strong><\/p>\n<p>Leia tamb\u00e9m:<\/p>\n<div id=\"blogd-3456676848\" class=\"blogd-final-post blogd-entity-placement\"><a href=\"https:\/\/www.feiradesantana.ba.leg.br\/\" target=\"_blank\" aria-label=\"JUNHO-VERMELHO_CA\u0302MARA-DE-FEIRA\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2026\/03\/JUNHO-VERMELHO_CAMARA-DE-FEIRA.gif\" alt=\"\"  class=\"no-lazyload\" width=\"728\" height=\"90\"   \/><\/a><\/div><blockquote class=\"wp-embedded-content\" data-secret=\"naohiQVMac\"><p><a href=\"https:\/\/blogdafeira.com.br\/home\/2018\/09\/27\/pedestal-vazio-vira-o-tumulo-do-vaqueiro-em-protesto-de-marcio-punk-no-centro-de-feira-de-santana\/\">Pedestal vazio vira o &#8216;T\u00famulo do Vaqueiro&#8217; em protesto de M\u00e1rcio Punk no centro de Feira<\/a><\/p><\/blockquote>\n<p><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; clip: rect(1px, 1px, 1px, 1px);\" title=\"&#8220;Pedestal vazio vira o &#8216;T\u00famulo do Vaqueiro&#8217; em protesto de M\u00e1rcio Punk no centro de Feira&#8221; &#8212; Blog da Feira\" src=\"https:\/\/blogdafeira.com.br\/home\/2018\/09\/27\/pedestal-vazio-vira-o-tumulo-do-vaqueiro-em-protesto-de-marcio-punk-no-centro-de-feira-de-santana\/embed\/#?secret=naohiQVMac\" data-secret=\"naohiQVMac\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O a\u00e7o contorcido moldado pelas ferramentas do arquiteto Danilo Freitas deu forma a escultura do vaqueiro montado a cavalo que, ao ser observado em diferentes \u00e2ngulos, mostra estar em movimento. A pe\u00e7a ser\u00e1 instalada na rua Ol\u00edmpio Vital, substituindo o antigo monumento que se desgastou com o tempo. Vencedor do pr\u00eamio Cultura de Arte Popular,<\/p>\n","protected":false},"author":1,"featured_media":43213,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"cybocfi_hide_featured_image":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[3,4,748,1],"tags":[],"class_list":["post-43212","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cidade","category-cultura","category-distritos","category-raiz"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2021\/02\/izinaldo.jpg","jetpack_shortlink":"https:\/\/wp.me\/p3niVf-beY","jetpack_sharing_enabled":true,"jetpack-related-posts":[{"id":59404,"url":"https:\/\/blogdafeira.com.br\/home\/2023\/09\/19\/feito-em-aco-patinavel-escultura-do-vaqueiro-pesa-cerca-de-500kg\/","url_meta":{"origin":43212,"position":0},"title":"Feita em a\u00e7o patin\u00e1vel, escultura do Vaqueiro pesa cerca de 500kg","author":"Secom\/FSA","date":"19\/09\/2023","format":false,"excerpt":"A escultura confeccionada em a\u00e7o contorcido e de autoria do arquiteto Danilo Freitas finalmente foi colocada no in\u00edcio da avenida\u00a0 Ol\u00edmpio Vital, em Feira de Santana. O novo Vaqueiro foi inaugurado ontem pelo prefeito Colbert Filho(MDB) no dia em que a cidade completa 190 anos. Na obra, o artista buscou\u2026","rel":"","context":"Em &quot;Cidade&quot;","block_context":{"text":"Cidade","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/cidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2023\/09\/IMG_20230918_123920840_HDR-scaled.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2023\/09\/IMG_20230918_123920840_HDR-scaled.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2023\/09\/IMG_20230918_123920840_HDR-scaled.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2023\/09\/IMG_20230918_123920840_HDR-scaled.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2023\/09\/IMG_20230918_123920840_HDR-scaled.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2023\/09\/IMG_20230918_123920840_HDR-scaled.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":59381,"url":"https:\/\/blogdafeira.com.br\/home\/2023\/09\/15\/nova-escultura-do-vaqueiro-chega-a-avenida-olimpio-vital-no-aniversario-de-feira\/","url_meta":{"origin":43212,"position":1},"title":"Nova escultura do Vaqueiro chega \u00e0 avenida Ol\u00edmpio Vital no anivers\u00e1rio de Feira","author":"Secom\/FSA","date":"15\/09\/2023","format":false,"excerpt":"O Monumento ao Vaqueiro homenageia o prim\u00f3rdios da hist\u00f3ria de Feira de Santana, quando os vaqueiros e as boiadas tinham o munic\u00edpio como ponto de parada. A escultura\u00a0 ser\u00e1 instalada no canteiro central da rua Ol\u00edmpio Vital - prolongamento da avenida Get\u00falio Vargas e entregue pelo prefeito Colbert Filho(MDB) nesta\u2026","rel":"","context":"Em &quot;Colunistas&quot;","block_context":{"text":"Colunistas","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/colunistas\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2023\/09\/Monumento-ao-Vaqueiro-Foto-ACM-3-1.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2023\/09\/Monumento-ao-Vaqueiro-Foto-ACM-3-1.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2023\/09\/Monumento-ao-Vaqueiro-Foto-ACM-3-1.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2023\/09\/Monumento-ao-Vaqueiro-Foto-ACM-3-1.jpeg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":53427,"url":"https:\/\/blogdafeira.com.br\/home\/2022\/07\/25\/vaqueiro-na-praca-dos-remedios-escultura-ganhou-concurso-da-prefeitura-de-feira\/","url_meta":{"origin":43212,"position":2},"title":"Vaqueiro na Pra\u00e7a dos Rem\u00e9dios: escultura ganhou concurso da Prefeitura de Feira","author":"Secom\/FSA","date":"25\/07\/2022","format":false,"excerpt":"Bote o Vaqueiro na Pra\u00e7a dos Rem\u00e9dios. \"O Vaqueiro\", escultura em ferro do artista Danilo Freitas foi escolhida atrav\u00e9s de concurso p\u00fablico aberto pela Secretaria Municipal de Cultura, na gest\u00e3o do jornalista Edson Borges, atual secret\u00e1rio de Comunica\u00e7\u00e3o do governo de Feira de Santana. O concurso atendeu a um apelo\u2026","rel":"","context":"Em &quot;Colunistas&quot;","block_context":{"text":"Colunistas","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/colunistas\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2022\/07\/Nova-escutura-do-vaqueiro-Danilo-Freitas-28-01-2021-Foto-Izinaldo-Barreto-10-1.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2022\/07\/Nova-escutura-do-vaqueiro-Danilo-Freitas-28-01-2021-Foto-Izinaldo-Barreto-10-1.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2022\/07\/Nova-escutura-do-vaqueiro-Danilo-Freitas-28-01-2021-Foto-Izinaldo-Barreto-10-1.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2022\/07\/Nova-escutura-do-vaqueiro-Danilo-Freitas-28-01-2021-Foto-Izinaldo-Barreto-10-1.jpeg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2022\/07\/Nova-escutura-do-vaqueiro-Danilo-Freitas-28-01-2021-Foto-Izinaldo-Barreto-10-1.jpeg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":59119,"url":"https:\/\/blogdafeira.com.br\/home\/2023\/08\/17\/camara-de-feira-quer-escultura-do-vaqueiro-na-praca-dos-remedios\/","url_meta":{"origin":43212,"position":3},"title":"C\u00e2mara de Feira quer escultura do Vaqueiro na Pra\u00e7a dos Rem\u00e9dios","author":"Secom\/FSA","date":"17\/08\/2023","format":false,"excerpt":"A C\u00e2mara de Vereadores de Feira de Santana quer saber onde est\u00e1 a escultura do Vaqueiro, ganhadora o pr\u00eamio de concurso oficial promovido pela Secretaria Municipal da Cultura h\u00e1 mais de dois anos. Os vereadores aprovaram, por unanimidade, um requerimento solicitando o paradeiro e sugerindo que a obra de arte\u2026","rel":"","context":"Em &quot;Cidade&quot;","block_context":{"text":"Cidade","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/cidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2023\/08\/64de4ad0694b3.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2023\/08\/64de4ad0694b3.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2023\/08\/64de4ad0694b3.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2023\/08\/64de4ad0694b3.jpeg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2023\/08\/64de4ad0694b3.jpeg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":53574,"url":"https:\/\/blogdafeira.com.br\/home\/2022\/08\/01\/jornal-na-balada-e-o-vaqueiro-na-praca-dos-remedios\/","url_meta":{"origin":43212,"position":4},"title":"Jornal &#8216;Na Balada&#8217; e o Vaqueiro na Pra\u00e7a dos Rem\u00e9dios","author":"Secom\/FSA","date":"01\/08\/2022","format":false,"excerpt":"Ruy Barcellos tinha uma movimentada p\u00e1gina no face, dirigia uma ag\u00eancia de modelos, e editava esse jornal 'Na Balada'. No exerc\u00edcio do meu desapego a pap\u00e9is velhos, anota\u00e7\u00f5es mi\u00fadas, preju\u00edzos e contas pagas e n\u00e3o pagas, esse passado recicl\u00e1vel de tempos em tempos,\u00a0 encontrei essa pe\u00e7a valiosa, que n\u00e3o me\u2026","rel":"","context":"Em &quot;Colunistas&quot;","block_context":{"text":"Colunistas","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/colunistas\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2022\/08\/ruyd.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2022\/08\/ruyd.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2022\/08\/ruyd.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2022\/08\/ruyd.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":36287,"url":"https:\/\/blogdafeira.com.br\/home\/2020\/03\/16\/premio-de-15-mil-reais-em-feira-de-santana-para-a-melhor-escultura-do-vaqueiro\/","url_meta":{"origin":43212,"position":5},"title":"Pr\u00eamio de 15 mil reais em Feira para a melhor &#8216;escultura do vaqueiro&#8217;","author":"Secom\/FSA","date":"16\/03\/2020","format":false,"excerpt":"A Prefeitura de Feira de Santana abriu um edital de concurso que oferece um pr\u00eamio de 15 mil reais ao artista que apresentar o melhor projeto para uma 'escultura do vaqueiro', a ser colocada no in\u00edcio da avenida Ol\u00edmpio Vital, no centro da cidade, em substitui\u00e7\u00e3o a uma que havia\u2026","rel":"","context":"Em &quot;Cidade&quot;","block_context":{"text":"Cidade","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/cidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2015\/08\/vaqueirooo.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2015\/08\/vaqueirooo.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2015\/08\/vaqueirooo.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2015\/08\/vaqueirooo.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/posts\/43212","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/comments?post=43212"}],"version-history":[{"count":5,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/posts\/43212\/revisions"}],"predecessor-version":[{"id":43224,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/posts\/43212\/revisions\/43224"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/media\/43213"}],"wp:attachment":[{"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/media?parent=43212"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/categories?post=43212"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/tags?post=43212"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}