{"id":45826,"date":"2021-06-14T11:39:05","date_gmt":"2021-06-14T14:39:05","guid":{"rendered":"https:\/\/blogdafeira.com.br\/home\/?p=45826"},"modified":"2021-06-17T12:18:47","modified_gmt":"2021-06-17T15:18:47","slug":"rio-jacuipe-e-exaltado-em-videoclipe-do-grupo-africania","status":"publish","type":"post","link":"https:\/\/blogdafeira.com.br\/home\/2021\/06\/14\/rio-jacuipe-e-exaltado-em-videoclipe-do-grupo-africania\/","title":{"rendered":"Rio Jacu\u00edpe \u00e9 exaltado em videoclipe do grupo Africania"},"content":{"rendered":"<div id=\"blogd-733281071\" class=\"blogd-fim-do-post-mobile blogd-entity-placement\" style=\"margin-left: auto;margin-right: auto;text-align: center;\"><a href=\"https:\/\/www.feiradesantana.ba.gov.br\/servico.asp?s=a&titulo=Prefeitura-de-Feira-lan%C3%A7a-programa-Rem%C3%A9dio-em-Casa-e-transforma-acesso-a-medicamentos-em-pol%C3%ADtica-p%C3%BAblica-de-cuidados.html&id=14&link=secom\/noticias.asp&idn=43684#noticias\" target=_blank><picture>\r\n  <source media=\"(min-width: 768px)\" srcset=\"https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2026\/03\/980x150.gif\">\r\n  \r\n  <img decoding=\"async\" src=\"https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2021\/01\/350x2002.gif\" alt=\"Publicidade\" style=\"width: 100%; max-width: 100%; height: auto; display: block; margin: 0 auto;\">\r\n\t<\/picture><\/a><\/div><p style=\"text-align: justify;\">No m\u00eas dedicado \u00e0 consci\u00eancia mundial sobre o meio ambiente, o grupo Africania traz Jacu\u00edpe Gemedeira, uma homenagem ao Rio Jacu\u00edpe.<\/p>\n<p style=\"text-align: justify;\">Esta \u00e1 a segunda can\u00e7\u00e3o do \u00e1lbum O Curador do Museu do Imagin\u00e1rio que ganha um videoclipe e j\u00e1 se encontra dispon\u00edvel no canal do youtube e nas redes sociais do grupo, @bandaafricania.<\/p>\n<p style=\"text-align: justify;\">O trabalho traduz a grandiosidade Rio Jacu\u00edpe que se estende por mais de 400 km de extens\u00e3o, al\u00e9m de tocar nas quest\u00f5es relacionadas \u00e0 sua polui\u00e7\u00e3o.<\/p>\n<p style=\"text-align: justify;\">Link\u00a0<a href=\"https:\/\/www.youtube.com\/watch?v=XivINfAXIOY\" target=\"_blank\" rel=\"noopener noreferrer\" data-saferedirecturl=\"https:\/\/www.google.com\/url?q=https:\/\/www.youtube.com\/watch?v%3DXivINfAXIOY&amp;source=gmail&amp;ust=1623767452948000&amp;usg=AFQjCNFRX7EfN0EaQgHziN0GUBtL2LJQNg\">https:\/\/www.youtube.com\/<wbr \/>watch?v=XivINfAXIOY<\/a><\/p>\n<p style=\"text-align: justify;\">As grava\u00e7\u00f5es do videoclipe foram iniciadas em fevereiro, com filmagens nas principais regi\u00f5es at\u00e9 chegar em Feira de Santana, destacando a sua nascente em Morro do Chap\u00e9u.<\/p>\n<p style=\"text-align: justify;\">Al\u00e9m do audiovisual, o trabalho traz tamb\u00e9m um cat\u00e1logo fotogr\u00e1fico que busca traduzir um pouco da riqueza cultural e ambiental do Rio Jacu\u00edpe, assim como a sua import\u00e2ncia para Feira de Santana e regi\u00e3o.<\/p>\n<p style=\"text-align: justify;\">Al\u00e9m de Morro do Chap\u00e9u, regi\u00f5es como Gavi\u00e3o, Quixabeira e Jaguara ganharam destaques na produ\u00e7\u00e3o audiovisual, locais em que parte dos artistas envolvidos nasceram, respectivamente, Bel da Bonita, Daniel Penha da Quixabeira e Cesinha dos Olhos. \u201cAl\u00e9m de destacar a riqueza e as dificuldades do Rio Jacu\u00edpe, escolhemos gravar em locais onde nascemos, conhecemos e que fazem parte das nossas mem\u00f3rias\u201d, mencionou Bel da Bonita, o idealizador do projeto.<\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-medium wp-image-45828\" src=\"https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2021\/06\/018-346x190.png\" alt=\"\" width=\"346\" height=\"190\" srcset=\"https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2021\/06\/018-346x190.png 346w, https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2021\/06\/018-1024x563.png 1024w, https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2021\/06\/018-170x93.png 170w, https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2021\/06\/018-768x422.png 768w, https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2021\/06\/018-1536x844.png 1536w, https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2021\/06\/018-280x154.png 280w, https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2021\/06\/018-1170x643.png 1170w, https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2021\/06\/018.png 1822w\" sizes=\"auto, (max-width: 346px) 100vw, 346px\" \/>O trabalho tem a participa\u00e7\u00e3o do grupo feirense Chu\u00e1 de Caba\u00e7a, com os artistas Arquimedes Nascimento e Cesinha dos Olhos D&#8217;\u00c1gua. O videoclipe teve a dire\u00e7\u00e3o do cineasta Daniel Dourado, a dire\u00e7\u00e3o de fotografia de Jaime Sampaio e a coordena\u00e7\u00e3o do jornalista Cid Fiuza.<\/p>\n<div id=\"blogd-3858004490\" class=\"blogd-final-post blogd-entity-placement\"><a href=\"https:\/\/www.feiradesantana.ba.leg.br\/\" target=\"_blank\" aria-label=\"JUNHO-VERMELHO_CA\u0302MARA-DE-FEIRA\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2026\/03\/JUNHO-VERMELHO_CAMARA-DE-FEIRA.gif\" alt=\"\"  class=\"no-lazyload\" width=\"728\" height=\"90\"   \/><\/a><\/div><p style=\"text-align: justify;\"><strong>Equipe<\/strong>:<br \/>\nLudmilla Dourado na dire\u00e7\u00e3o executiva \/ Daniel Dourado na dire\u00e7\u00e3o geral \/ Jaime Sampaio na dire\u00e7\u00e3o de fotografia \/ Ananda Rocha na produ\u00e7\u00e3o \/ Cl\u00e1udio Camperlingo na produ\u00e7\u00e3o \/ Ramiro Barbosa na propon\u00eancia e produ\u00e7\u00e3o \/ Cid Fiuza na coordena\u00e7\u00e3o e comunica\u00e7\u00e3o.<br \/>\nGrupo Africania: Bel da Bonita, Daniel Penha da Quixabeira, Cid Fiuza e Ramiro Barbosa.<br \/>\nChu\u00e1 de Caba\u00e7a: Arquimedes Nascimento e Cesinha dos Olhos D&#8217;\u00c1gua<br \/>\nCan\u00e7\u00e3o: Jacu\u00edpe Gemedeira, de Bel da Bonita e Daniel Penha da Quixabeira<br \/>\nGrava\u00e7\u00e3o e mixagem: Anselmo Roberto\/Est\u00fadio Via Sonora<br \/>\nEsse projeto tem o apoio financeiro da Prefeitura de Feira de Santana, atrav\u00e9s da Secretaria Municipal de Cultura, Esporte e Lazer, via Lei Aldir Blanc. Direcionado pela Secretaria Especial da Cultura, Minist\u00e9rio do Turismo e Governo Federal.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>No m\u00eas dedicado \u00e0 consci\u00eancia mundial sobre o meio ambiente, o grupo Africania traz Jacu\u00edpe Gemedeira, uma homenagem ao Rio Jacu\u00edpe. Esta \u00e1 a segunda can\u00e7\u00e3o do \u00e1lbum O Curador do Museu do Imagin\u00e1rio que ganha um videoclipe e j\u00e1 se encontra dispon\u00edvel no canal do youtube e nas redes sociais do grupo, @bandaafricania. O<\/p>\n","protected":false},"author":1,"featured_media":45827,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"cybocfi_hide_featured_image":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[4,748,1],"tags":[],"class_list":["post-45826","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultura","category-distritos","category-raiz"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2021\/06\/032.png","jetpack_shortlink":"https:\/\/wp.me\/p3niVf-bV8","jetpack_sharing_enabled":true,"jetpack-related-posts":[{"id":40152,"url":"https:\/\/blogdafeira.com.br\/home\/2020\/09\/05\/africania-e-o-samba-de-batuque-na-bacia-do-jacuipe\/","url_meta":{"origin":45826,"position":0},"title":"Africania e o Samba de Batuque na bacia do Jacu\u00edpe","author":"oCordel Assessoria","date":"05\/09\/2020","format":false,"excerpt":"As mem\u00f3rias do 'Samba de Batuque' da regi\u00e3o da bacia do Rio Jacu\u00edpe', est\u00e3o em v\u00eddeoclipe\u00a0 da can\u00e7\u00e3o\u00a0 \u201cDa Quixabeira pro Gavi\u00e3o\u201d , do grupo Africania, dispon\u00edvel no Youtube (clique) A can\u00e7\u00e3o faz parte do album \"O Curador do Museu Imagin\u00e1rio' que presta uma homenagem aos sambadores e sambadoras dessa\u2026","rel":"","context":"Em &quot;Cidade&quot;","block_context":{"text":"Cidade","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/cidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2020\/09\/Grupo-Africania-Tag-1.png?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2020\/09\/Grupo-Africania-Tag-1.png?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2020\/09\/Grupo-Africania-Tag-1.png?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2020\/09\/Grupo-Africania-Tag-1.png?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2020\/09\/Grupo-Africania-Tag-1.png?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2020\/09\/Grupo-Africania-Tag-1.png?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":45674,"url":"https:\/\/blogdafeira.com.br\/home\/2021\/06\/02\/roberto-kuelho-lanca-namoridos-e-antecipa-dia-dos-namorados\/","url_meta":{"origin":45826,"position":1},"title":"Roberto Kuelho lan\u00e7a Namoridos e antecipa dia dos namorados","author":"oCordel Assessoria","date":"02\/06\/2021","format":false,"excerpt":"Em comemora\u00e7\u00e3o ao m\u00eas dos namorados, o cantor Roberto Kuelho inicia junho lan\u00e7ando o clipe \"Namoridos\". O novo trabalho musical vai ao ar nesta quinta-feira (03) e para dividir com ele as cenas do videoclipe, Kuelho convidou a atriz e modelo Aninha Pinheiro. O enredo visa inspirar as pessoas a\u2026","rel":"","context":"Em &quot;Cultura&quot;","block_context":{"text":"Cultura","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/cultura\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2021\/06\/Roberto-Kuelho-Namoridos.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2021\/06\/Roberto-Kuelho-Namoridos.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2021\/06\/Roberto-Kuelho-Namoridos.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2021\/06\/Roberto-Kuelho-Namoridos.jpeg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2021\/06\/Roberto-Kuelho-Namoridos.jpeg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":7855,"url":"https:\/\/blogdafeira.com.br\/home\/2014\/01\/02\/br-116-construcao-da-ponte-sobre-rio-jacuipe-em-feira-completa-1-ano\/","url_meta":{"origin":45826,"position":2},"title":"BR-116: constru\u00e7\u00e3o da ponte sobre rio Jacuipe em Feira completa 1 ano","author":"oCordel Assessoria","date":"02\/01\/2014","format":false,"excerpt":"As obras de constru\u00e7\u00e3o da ponte sobre o rio Jacuipe v\u00e3o completar um ano de iniciadas. A foto acima foi tirada no \u00faltimo dia do m\u00eas de dezembro e em compara\u00e7\u00e3o com as que est\u00e3o abaixo (tiradas em mar\u00e7o e julho, respectivamente) mostram o ritmo das obras da duplica\u00e7\u00e3o da\u2026","rel":"","context":"Em &quot;Home&quot;","block_context":{"text":"Home","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/raiz\/"},"img":{"alt_text":"PONTE JACUIPE","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2014\/01\/PONTE-JACUIPE.jpg?resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2014\/01\/PONTE-JACUIPE.jpg?resize=350%2C200 1x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2014\/01\/PONTE-JACUIPE.jpg?resize=525%2C300 1.5x"},"classes":[]},{"id":2025,"url":"https:\/\/blogdafeira.com.br\/home\/2013\/05\/28\/alphaville-vai-lancar-novo-residencial-as-margens-do-rio-jacuipe-em-feira\/","url_meta":{"origin":45826,"position":3},"title":"Alphaville vai lan\u00e7ar novo residencial \u00e0s margens do rio Jacuipe em Feira","author":"oCordel Assessoria","date":"28\/05\/2013","format":false,"excerpt":"A empresa Alphaville resolveu ampliar os investimentos em Feira de Santana e vai lan\u00e7ar a segunda etapa do Alphaville Feira de Santana, \u00e0s margens do rio Jacuipe e da BR-116 Norte. Esta semana o\u00a0\u00a0diretor Comercial e\u00a0Novos\u00a0Neg\u00f3cios da Alphaville, F\u00e1bio Valle, confirmou a inten\u00e7\u00e3o da empresa de investir em Feira. E\u2026","rel":"","context":"Em &quot;Home&quot;","block_context":{"text":"Home","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/raiz\/"},"img":{"alt_text":"a rio jacuipe","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2013\/05\/a-rio-jacuipe-170x127.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":47874,"url":"https:\/\/blogdafeira.com.br\/home\/2021\/10\/27\/selo-educadora-fm-promove-album-da-banda-africania\/","url_meta":{"origin":45826,"position":4},"title":"Selo Educadora FM promove \u00e1lbum da banda Africania","author":"oCordel Assessoria","date":"27\/10\/2021","format":false,"excerpt":"A banda Africania, composta por m\u00fasicos da regi\u00e3o do Rio Jacu\u00edpe no interior da Bahia, ter\u00e1 seu \u00e1lbum \u201cO Curador do Museu do Imagin\u00e1rio\u201d promovido pelo Selo Educadora FM Independente. A iniciativa divulga lan\u00e7amentos independentes de \u00e1lbuns ou EPs, atrav\u00e9s da articula\u00e7\u00e3o entre a R\u00e1dio Educadora FM, a TVE e\u2026","rel":"","context":"Em &quot;Cultura&quot;","block_context":{"text":"Cultura","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/cultura\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2021\/10\/Selo_Educadora_FM_Africania.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2021\/10\/Selo_Educadora_FM_Africania.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2021\/10\/Selo_Educadora_FM_Africania.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2021\/10\/Selo_Educadora_FM_Africania.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2021\/10\/Selo_Educadora_FM_Africania.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":46678,"url":"https:\/\/blogdafeira.com.br\/home\/2021\/07\/26\/roberto-kuelho-planeja-fazer-videoclipe-na-ponte-da-matinha\/","url_meta":{"origin":45826,"position":5},"title":"Roberto Kuelho planeja fazer videoclipe na Ponte da Matinha","author":"oCordel Assessoria","date":"26\/07\/2021","format":false,"excerpt":"O sucesso do videoclipe da m\u00fasica Namoridos(clique) ainda est\u00e1 no ar mas ao conhecer a Ponte da Matinha, o cantor e compositor Roberto Kuelho logo expressou o desejo de fazer \"alguma coisa em v\u00eddeo...um clipe nesse lugar po\u00e9tico\". Roberto Kuelho foi at\u00e9 o rio POJUCA, na divisa entre os Munic\u00edpios\u2026","rel":"","context":"Em &quot;Cultura&quot;","block_context":{"text":"Cultura","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/cultura\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2021\/07\/Screenshot_20210726-1930253-1.png?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2021\/07\/Screenshot_20210726-1930253-1.png?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2021\/07\/Screenshot_20210726-1930253-1.png?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2021\/07\/Screenshot_20210726-1930253-1.png?resize=700%2C400&ssl=1 2x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/posts\/45826","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/comments?post=45826"}],"version-history":[{"count":3,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/posts\/45826\/revisions"}],"predecessor-version":[{"id":45879,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/posts\/45826\/revisions\/45879"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/media\/45827"}],"wp:attachment":[{"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/media?parent=45826"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/categories?post=45826"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/tags?post=45826"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}