{"id":47315,"date":"2021-09-09T15:43:26","date_gmt":"2021-09-09T18:43:26","guid":{"rendered":"https:\/\/blogdafeira.com.br\/home\/?p=47315"},"modified":"2021-09-11T20:14:22","modified_gmt":"2021-09-11T23:14:22","slug":"acm-neto-vem-a-feira-de-santana-neste-sabado-11","status":"publish","type":"post","link":"https:\/\/blogdafeira.com.br\/home\/2021\/09\/09\/acm-neto-vem-a-feira-de-santana-neste-sabado-11\/","title":{"rendered":"ACM Neto vem a Feira de Santana neste s\u00e1bado, 11"},"content":{"rendered":"<div id=\"blogd-2191634441\" class=\"blogd-fim-do-post-mobile blogd-entity-placement\" style=\"margin-left: auto;margin-right: auto;text-align: center;\"><a href=\"https:\/\/www.feiradesantana.ba.gov.br\/servico.asp?s=a&titulo=Prefeitura-de-Feira-lan%C3%A7a-programa-Rem%C3%A9dio-em-Casa-e-transforma-acesso-a-medicamentos-em-pol%C3%ADtica-p%C3%BAblica-de-cuidados.html&id=14&link=secom\/noticias.asp&idn=43684#noticias\" target=_blank><picture>\r\n  <source media=\"(min-width: 768px)\" srcset=\"https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2026\/03\/980x150.gif\">\r\n  \r\n  <img decoding=\"async\" src=\"https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2021\/01\/350x2002.gif\" alt=\"Publicidade\" style=\"width: 100%; max-width: 100%; height: auto; display: block; margin: 0 auto;\">\r\n\t<\/picture><\/a><\/div><p style=\"text-align: justify;\">Ex-prefeito de Salvador e candidato de oposi\u00e7\u00e3o ao Governo da Bahia no pr\u00f3ximo ano, ACM Neto vem a Feira neste s\u00e1bado, 11, participar de um curso de forma\u00e7\u00e3o pol\u00edtica que acontece na Faculdades An\u00edsio Teixeira. (cartaz).<\/p>\n<div id=\"blogd-3775136265\" class=\"blogd-final-post blogd-entity-placement\"><a href=\"https:\/\/www.feiradesantana.ba.leg.br\/\" target=\"_blank\" aria-label=\"JUNHO-VERMELHO_CA\u0302MARA-DE-FEIRA\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2026\/03\/JUNHO-VERMELHO_CAMARA-DE-FEIRA.gif\" alt=\"\"  class=\"no-lazyload\" width=\"728\" height=\"90\"   \/><\/a><\/div><p style=\"text-align: justify;\">O presidente do DEM nacional concede uma entrevista coletiva \u00e0 imprensa, marcada para as 10:30h.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-47318 aligncenter\" src=\"https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2021\/09\/Screenshot_20210909-1539442-298x300.png\" alt=\"\" width=\"298\" height=\"300\" srcset=\"https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2021\/09\/Screenshot_20210909-1539442-298x300.png 298w, https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2021\/09\/Screenshot_20210909-1539442-149x150.png 149w, https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2021\/09\/Screenshot_20210909-1539442-185x187.png 185w, https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2021\/09\/Screenshot_20210909-1539442.png 720w\" sizes=\"auto, (max-width: 298px) 100vw, 298px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ex-prefeito de Salvador e candidato de oposi\u00e7\u00e3o ao Governo da Bahia no pr\u00f3ximo ano, ACM Neto vem a Feira neste s\u00e1bado, 11, participar de um curso de forma\u00e7\u00e3o pol\u00edtica que acontece na Faculdades An\u00edsio Teixeira. (cartaz). O presidente do DEM nacional concede uma entrevista coletiva \u00e0 imprensa, marcada para as 10:30h.<\/p>\n","protected":false},"author":1,"featured_media":47316,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"cybocfi_hide_featured_image":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[1,631],"tags":[],"class_list":["post-47315","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-raiz","category-politica"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2021\/09\/images-3.jpeg","jetpack_shortlink":"https:\/\/wp.me\/p3niVf-cj9","jetpack_sharing_enabled":true,"jetpack-related-posts":[{"id":52520,"url":"https:\/\/blogdafeira.com.br\/home\/2022\/05\/23\/mdb-de-feira-promove-encontro-com-colbert-e-acm-neto-nesta-quinta-feira\/","url_meta":{"origin":47315,"position":0},"title":"MDB de Feira promove encontro com Colbert e ACM Neto nesta quinta-feira","author":"Blog da Feira","date":"23\/05\/2022","format":false,"excerpt":"O pr\u00e9-candidato ao governo da Bahia, ACM Neto (UB) vem a Feira de Santana nesta quinta-feira, 26, participar de uma reuni\u00e3o promovida pelo MDB local, \u00e0s 12 horas, na CDL, pra\u00e7a da Matriz. Em Feira o MDB \u00e9 liderado pelo prefeito Colbert Filho (MDB) que j\u00e1 declarou apoio \u00e0 candidatura\u2026","rel":"","context":"Em &quot;Home&quot;","block_context":{"text":"Home","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/raiz\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2022\/05\/Campo-Formoso-2022-05-22.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2022\/05\/Campo-Formoso-2022-05-22.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2022\/05\/Campo-Formoso-2022-05-22.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2022\/05\/Campo-Formoso-2022-05-22.jpeg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":42002,"url":"https:\/\/blogdafeira.com.br\/home\/2020\/11\/22\/colbert-acm-neto-e-uma-forca-politica-pronta-para-2022\/","url_meta":{"origin":47315,"position":1},"title":"Colbert :  ACM Neto \u00e9 uma for\u00e7a pol\u00edtica  pronta para 2022","author":"Blog da Feira","date":"22\/11\/2020","format":false,"excerpt":"ACM Neto \u00e9 o candidato natural a governador do estado, \u00e9 uma for\u00e7a pol\u00edtica extremamente pronta, organizada e efetivamente forte para ganhar as elei\u00e7\u00f5es, disse o prefeito Colbert Filho que ontem (s\u00e1bado)\u00a0 andou pela cidade de Feira de Santana em carreata eleitoral com o prefeito de Salvador. \"Ele tem efetivamente\u2026","rel":"","context":"Em &quot;Elei\u00e7\u00f5es 2020&quot;","block_context":{"text":"Elei\u00e7\u00f5es 2020","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/eleicoes-2020\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2020\/11\/images-11.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2020\/11\/images-11.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2020\/11\/images-11.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2020\/11\/images-11.jpeg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":47369,"url":"https:\/\/blogdafeira.com.br\/home\/2021\/09\/11\/acm-neto-em-feira-ze-ronaldo-e-excelente-mestre-de-cerimonia\/","url_meta":{"origin":47315,"position":2},"title":"ACM Neto em Feira: Z\u00e9 Ronaldo \u00e9 excelente &#8216;mestre de cerim\u00f4nia&#8217;","author":"Blog da Feira","date":"11\/09\/2021","format":false,"excerpt":"O ex-prefeito de Salvador ACM Neto (DEM) disse neste s\u00e1bado, 11, em Feira de Santana que o ex-prefeito Z\u00e9 Ronaldo (DEM) tem se mostrado, nas viagens pelo interior da Bahia \"um excelente mestre de cerim\u00f4nia\". ACM participou de um evento promovido pelo secret\u00e1rio municipal\u00a0 e vereador licenciado Pablo Roberto, pr\u00e9\u2026","rel":"","context":"Em &quot;Home&quot;","block_context":{"text":"Home","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/raiz\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2021\/09\/Screenshot_20210911-1952022.png?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2021\/09\/Screenshot_20210911-1952022.png?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2021\/09\/Screenshot_20210911-1952022.png?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":54910,"url":"https:\/\/blogdafeira.com.br\/home\/2022\/10\/15\/desafio-de-ze-ronaldo-e-ampliar-vantagem-de-acm-neto-sobre-jeronimo-em-feira\/","url_meta":{"origin":47315,"position":3},"title":"Desafio de Z\u00e9 Ronaldo \u00e9 ampliar vantagem de ACM Neto sobre Jer\u00f4nimo em Feira","author":"Blog da Feira","date":"15\/10\/2022","format":false,"excerpt":"Foram apenas 5 mil e poucos votos a diferen\u00e7a entre ACM Neto e Jer\u00f4nimo no primeiro turno em Feira de Santana. \u00c9 essa margem de vantagem aqui no munic\u00edpio de Feira e outros da regi\u00e3o que o ex-prefeito Z\u00e9 Ronaldo tem o desafio de ampliar neste segundo turno. Terreiro eleitoral\u2026","rel":"","context":"Em &quot;Home&quot;","block_context":{"text":"Home","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/raiz\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2022\/10\/Artigo-Destaque_01203006_00.webp?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2022\/10\/Artigo-Destaque_01203006_00.webp?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2022\/10\/Artigo-Destaque_01203006_00.webp?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2022\/10\/Artigo-Destaque_01203006_00.webp?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":55279,"url":"https:\/\/blogdafeira.com.br\/home\/2022\/11\/07\/jeronimo-maquiavel-e-o-pai-da-vitoria-de-acm-neto-em-feira-de-santana\/","url_meta":{"origin":47315,"position":4},"title":"Jer\u00f4nimo, Maquiavel e o &#8216;pai&#8217; da vit\u00f3ria de ACM Neto em Feira de Santana","author":"J\u00e2nio R\u00eago","date":"07\/11\/2022","format":false,"excerpt":"Mesmo que a inten\u00e7\u00e3o n\u00e3o tenha sido essa, e a ressalva at\u00e9\u00a0 tenha sido feita (\"Mas, existe o respeito pelo povo de Feira de Santana sim\u201d), a afirmativa\u00a0 de Jer\u00f4nimo sobre como ser\u00e1 o tratamento a Feira de Santana, atrav\u00e9s do prefeito Colbert, soou como um sentimento de revanche, um\u2026","rel":"","context":"Em &quot;Colunistas&quot;","block_context":{"text":"Colunistas","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/colunistas\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2022\/11\/images-1.jpeg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":38009,"url":"https:\/\/blogdafeira.com.br\/home\/2020\/05\/22\/acm-neto-enfrenta-a-febraban-os-bancos-cobram-juros-absurdos\/","url_meta":{"origin":47315,"position":5},"title":"ACM Neto enfrenta a Febraban: &#8220;deveria ter vergonha&#8221;","author":"Blog da Feira","date":"22\/05\/2020","format":false,"excerpt":"O prefeito de Salvador, ACM Neto, incorporou a\u00a0 'entidade' pol\u00edtica\u00a0 que j\u00e1 carrega no nome,\u00a0 e rebateu no\u00a0 estilo do av\u00f4 ACM uma\u00a0 propaganda da poderosa Federa\u00e7\u00e3o Brasileira dos Bancos (Febraban) falando sobre a import\u00e2ncia das institui\u00e7\u00f5es banc\u00e1rias nesta pandemia. \"Ela deveria ter vergonha\", bradou o prefeito em sua p\u00e1gina\u2026","rel":"","context":"Em &quot;Bahia&quot;","block_context":{"text":"Bahia","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/bahia\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2020\/05\/IMAGEM_NOTICIA_1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2020\/05\/IMAGEM_NOTICIA_1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2020\/05\/IMAGEM_NOTICIA_1.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2020\/05\/IMAGEM_NOTICIA_1.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/posts\/47315","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/comments?post=47315"}],"version-history":[{"count":4,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/posts\/47315\/revisions"}],"predecessor-version":[{"id":47378,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/posts\/47315\/revisions\/47378"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/media\/47316"}],"wp:attachment":[{"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/media?parent=47315"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/categories?post=47315"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/tags?post=47315"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}