{"id":47345,"date":"2021-09-11T00:01:39","date_gmt":"2021-09-11T03:01:39","guid":{"rendered":"https:\/\/blogdafeira.com.br\/home\/?p=47345"},"modified":"2021-09-15T23:04:59","modified_gmt":"2021-09-16T02:04:59","slug":"o-11-de-setembro-de-2001-na-feira","status":"publish","type":"post","link":"https:\/\/blogdafeira.com.br\/home\/2021\/09\/11\/o-11-de-setembro-de-2001-na-feira\/","title":{"rendered":"O 11 de Setembro de 2001 na Feira"},"content":{"rendered":"<div id=\"blogd-3658073497\" class=\"blogd-fim-do-post-mobile blogd-entity-placement\" style=\"margin-left: auto;margin-right: auto;text-align: center;\"><a href=\"https:\/\/www.feiradesantana.ba.gov.br\/servico.asp?s=a&titulo=Prefeitura-de-Feira-lan%C3%A7a-programa-Rem%C3%A9dio-em-Casa-e-transforma-acesso-a-medicamentos-em-pol%C3%ADtica-p%C3%BAblica-de-cuidados.html&id=14&link=secom\/noticias.asp&idn=43684#noticias\" target=_blank><picture>\r\n  <source media=\"(min-width: 768px)\" srcset=\"https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2026\/03\/980x150.gif\">\r\n  \r\n  <img decoding=\"async\" src=\"https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2021\/01\/350x2002.gif\" alt=\"Publicidade\" style=\"width: 100%; max-width: 100%; height: auto; display: block; margin: 0 auto;\">\r\n\t<\/picture><\/a><\/div><p style=\"text-align: justify;\">\u2013 Um avi\u00e3o bateu contra o <em>World Trade Center<\/em> l\u00e1 em Nova Iorque&#8230;<\/p>\n<p style=\"text-align: justify;\">A not\u00edcia chegou no fim da sess\u00e3o da C\u00e2mara Municipal aqui da Feira de Santana. Quem a trouxe, nem recordo. Mas sei que n\u00e3o atribuiu grande import\u00e2ncia. Assim, julguei o fato um acidente, talvez um avi\u00e3ozinho qualquer tivesse se chocado por acaso contra uma das Torres G\u00eameas. Naquela \u00e9poca, o frenesi pela busca por informa\u00e7\u00f5es nos aparelhos celulares ainda estava distante. Segui a rotina, despreocupado.<\/p>\n<p style=\"text-align: justify;\">Por alguma raz\u00e3o, fui \u00e0 avenida Get\u00falio Vargas naquela manh\u00e3 ensolarada, t\u00edpica do fim do inverno. L\u00e1, recebi a liga\u00e7\u00e3o de um amigo fornecendo detalhes, informando que fora um atentado de grandes propor\u00e7\u00f5es. Descreveu as cenas vividamente, sua agita\u00e7\u00e3o ao telefone contrastava com os pios tranquilos dos pardais nos oitis das cercanias da Pra\u00e7a de Alimenta\u00e7\u00e3o. Apressei o passo em busca de uma tev\u00ea.<\/p>\n<p style=\"text-align: justify;\">Muita gente fez o mesmo, naquele e nos dias seguintes. Embora pouco afeito ao notici\u00e1rio internacional, o feirense parou defronte \u00e0s tev\u00eas das lojas de eletrodom\u00e9sticos, dos bares, das farm\u00e1cias, das lojas e de qualquer lugar que dispusesse de um aparelho. Osama Bin Laden, a Al Qaeda, o Talib\u00e3 e o Afeganist\u00e3o tornaram-se populares at\u00e9 entre quem mercadejava na Marechal Deodoro, na Sales Barbosa.<\/p>\n<p style=\"text-align: justify;\">\u00c0 \u00e9poca, a internet ainda era pouco difundida. Nela, o acesso ao notici\u00e1rio apenas engatinhava. Da\u00ed a necessidade da tev\u00ea, do r\u00e1dio, dos jornais impressos que se esgotaram rapidamente na manh\u00e3 seguinte. Lembro que at\u00e9 tentei adquirir um exemplar da Folha de S\u00e3o Paulo numa banca do centro da Feira de Santana. O vendedor ficou indignado com minha pretens\u00e3o:<\/p>\n<p style=\"text-align: justify;\">\u2013 S\u00f3 v\u00e3o chegar dez exemplares e j\u00e1 tem uma fila de espera com mais de 15 pessoas!<\/p>\n<p style=\"text-align: justify;\">Desisti. Tive que disputar um exemplar quase no tapa na Biblioteca Central da Uefs, \u00e0 noite. Mas consegui ler boa parte da edi\u00e7\u00e3o especial. Em volta da tev\u00ea, no <em>hall<\/em> da biblioteca, dezenas de estudantes acompanhando, atentos, o notici\u00e1rio. Foram dias febris. Ali, todos sabiam que o mundo estava mudando.<\/p>\n<p style=\"text-align: justify;\">Pelas ruas, como sempre, n\u00e3o faltou quem enxergasse mais um sinal do fim dos tempos, do Apocalipse, da volta de Jesus Cristo. O que sempre acontece nestas ocasi\u00f5es, ali\u00e1s. At\u00e9 ent\u00e3o, s\u00f3 quem lia jornais sabia das atrocidades do Talib\u00e3 no Afeganist\u00e3o ou do recrudescimento do terrorismo isl\u00e2mico na \u00c1sia e na \u00c1frica.<\/p>\n<p style=\"text-align: justify;\">O t\u00e9trico 11 de Setembro tornou costumeiras no notici\u00e1rio as imagens dos combatentes com seus fuzis, seus trajes t\u00edpicos e suas convic\u00e7\u00f5es obscurantistas na arenosa paisagem afeg\u00e3. Irreverente, o feirense tratou de apelidar de \u201cBin Laden\u201d ou \u201cOsama\u201d os raros barbudos daqueles tempos. Muitos, obviamente, ficavam indignados. Outros, at\u00e9 temerosos, assustados com a novidade do terrorismo.<\/p>\n<div id=\"blogd-1436569948\" class=\"blogd-final-post blogd-entity-placement\"><a href=\"https:\/\/www.feiradesantana.ba.leg.br\/\" target=\"_blank\" aria-label=\"JUNHO-VERMELHO_CA\u0302MARA-DE-FEIRA\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2026\/03\/JUNHO-VERMELHO_CAMARA-DE-FEIRA.gif\" alt=\"\"  class=\"no-lazyload\" width=\"728\" height=\"90\"   \/><\/a><\/div><p style=\"text-align: justify;\">L\u00e1 se v\u00e3o 20 anos. O mundo mudou muito desde ent\u00e3o. O mais impressionante, por\u00e9m, foram as mudan\u00e7as nas formas de produ\u00e7\u00e3o e de dissemina\u00e7\u00e3o de not\u00edcias, o car\u00e1ter quase instant\u00e2neo do acesso \u00e0s informa\u00e7\u00f5es na atualidade. Lembro que o telefonema do colega mencionado acima foi atendido com um daqueles aparelhos celulares que, basicamente, serviam s\u00f3 para chamadas de voz&#8230;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u2013 Um avi\u00e3o bateu contra o World Trade Center l\u00e1 em Nova Iorque&#8230; A not\u00edcia chegou no fim da sess\u00e3o da C\u00e2mara Municipal aqui da Feira de Santana. Quem a trouxe, nem recordo. Mas sei que n\u00e3o atribuiu grande import\u00e2ncia. Assim, julguei o fato um acidente, talvez um avi\u00e3ozinho qualquer tivesse se chocado por acaso<\/p>\n","protected":false},"author":13,"featured_media":47350,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"cybocfi_hide_featured_image":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[592,1],"tags":[],"class_list":["post-47345","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-colunistas","category-raiz"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2021\/09\/wtc-11-setembro-atentado-terrorista-ny34.jpg","jetpack_shortlink":"https:\/\/wp.me\/p3niVf-cjD","jetpack_sharing_enabled":true,"jetpack-related-posts":[{"id":52499,"url":"https:\/\/blogdafeira.com.br\/home\/2022\/05\/23\/como-esta-a-vacinacao-contra-a-covid-19-em-feira\/","url_meta":{"origin":47345,"position":0},"title":"Como est\u00e1 a vacina\u00e7\u00e3o contra a Covid-19 em Feira?","author":"Andr\u00e9 Pomponet","date":"23\/05\/2022","format":false,"excerpt":"V\u00e1 l\u00e1 que os casos de Covid-19 ca\u00edram na Feira de Santana nos \u00faltimos meses: dados da Secretaria Municipal de Sa\u00fade da quinta-feira (19) indicam que, naquele dia, havia apenas um paciente internado e foram registrados somente sete novos casos. Mas a situa\u00e7\u00e3o j\u00e1 foi mais favor\u00e1vel e o n\u00famero\u2026","rel":"","context":"Em &quot;Colunistas&quot;","block_context":{"text":"Colunistas","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/colunistas\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2021\/12\/20122021160108.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2021\/12\/20122021160108.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2021\/12\/20122021160108.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2021\/12\/20122021160108.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2021\/12\/20122021160108.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":52079,"url":"https:\/\/blogdafeira.com.br\/home\/2022\/05\/04\/quantidade-de-recem-nascidos-caiu-em-2020\/","url_meta":{"origin":47345,"position":1},"title":"Quantidade de rec\u00e9m-nascidos caiu em 2020","author":"Andr\u00e9 Pomponet","date":"04\/05\/2022","format":false,"excerpt":"No texto anterior abordamos a quest\u00e3o da morte aqui na Feira de Santana em 2020. Em grande medida, o aumento foi um desdobramento da pandemia da Covid-19. Mas \u2013 apesar das densas energias da morte, altamente mal\u00e9ficas, que pairam no ar \u2013 \u00e9 bom n\u00e3o se contaminar com o Tanatos:\u2026","rel":"","context":"Em &quot;Colunistas&quot;","block_context":{"text":"Colunistas","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/colunistas\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2022\/05\/pexels-jonathan-borba-3259629-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2022\/05\/pexels-jonathan-borba-3259629-1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2022\/05\/pexels-jonathan-borba-3259629-1.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2022\/05\/pexels-jonathan-borba-3259629-1.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2022\/05\/pexels-jonathan-borba-3259629-1.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":41926,"url":"https:\/\/blogdafeira.com.br\/home\/2020\/11\/20\/as-vibrantes-eleicoes-de-1996-em-feira-2\/","url_meta":{"origin":47345,"position":2},"title":"As vibrantes elei\u00e7\u00f5es de 1996 em Feira (2)","author":"Andr\u00e9 Pomponet","date":"20\/11\/2020","format":false,"excerpt":"Leia a parte 1, clique aqui Como mencionei no texto anterior, em 1996 as urnas eletr\u00f4nicas estrearam aqui na Feira de Santana. Boa parte dos eleitores utilizou o novo recurso, mas as c\u00e9dulas de papel foram necess\u00e1rias nas se\u00e7\u00f5es em que o equipamento n\u00e3o funcionou. Houve, ent\u00e3o, a coexist\u00eancia dos\u2026","rel":"","context":"Em &quot;Colunistas&quot;","block_context":{"text":"Colunistas","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/colunistas\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2020\/11\/FALCAAO-E-JOSUE.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2020\/11\/FALCAAO-E-JOSUE.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2020\/11\/FALCAAO-E-JOSUE.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":37871,"url":"https:\/\/blogdafeira.com.br\/home\/2020\/05\/17\/bate-papo-com-bolsonarista-motorista-de-aplicativo\/","url_meta":{"origin":47345,"position":3},"title":"Bate-papo com bolsonarista motorista de aplicativo","author":"Andr\u00e9 Pomponet","date":"17\/05\/2020","format":false,"excerpt":"\u2013 T\u00e1 tudo errado! E deu uma pancada no volante do autom\u00f3vel para real\u00e7ar a indigna\u00e7\u00e3o. Discorria sobre o recesso de julho em escolas e faculdades. \u201cOnde j\u00e1 se viu? Duas f\u00e9rias por ano!\u201d, exasperava-se. E recorria ao bord\u00e3o: \u201cT\u00e1 tudo errado!\u201d. Era motorista de aplicativo. Presumi que sem nenhuma\u2026","rel":"","context":"Em &quot;Colunistas&quot;","block_context":{"text":"Colunistas","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/colunistas\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":38499,"url":"https:\/\/blogdafeira.com.br\/home\/2020\/06\/17\/a-fake-news-do-traficante-robertinho-de-lucas-morando-em-feira\/","url_meta":{"origin":47345,"position":4},"title":"A fake news do traficante &#8220;Robertinho de Lucas&#8221; morando em Feira","author":"Andr\u00e9 Pomponet","date":"17\/06\/2020","format":false,"excerpt":"Em janeiro de 1997 causou alvoro\u00e7o na Feira de Santana a not\u00edcia de que o traficante carioca Jos\u00e9 Roberto da Silva, o \u201cRobertinho de Lucas\u201d, estava residindo na cidade havia dois anos. Mas n\u00e3o apenas isso: ele at\u00e9 se estabelecera como comerciante por aqui. Naquela \u00e9poca, \u201cRobertinho de Lucas\u201d era\u2026","rel":"","context":"Em &quot;Home&quot;","block_context":{"text":"Home","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/raiz\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2020\/06\/robertinho-de-lucas.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2020\/06\/robertinho-de-lucas.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2020\/06\/robertinho-de-lucas.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":29051,"url":"https:\/\/blogdafeira.com.br\/home\/2018\/02\/03\/touro-do-sertao-avanca-na-copa-do-brasil-por-andre-pomponet\/","url_meta":{"origin":47345,"position":5},"title":"Touro do Sert\u00e3o avan\u00e7a na Copa do Brasil, por Andr\u00e9 Pomponet","author":"Andr\u00e9 Pomponet","date":"03\/02\/2018","format":false,"excerpt":"Demorou 27 anos, mas o Fluminense de Feira avan\u00e7ou de fase na Copa do Brasil, depois de vencer o Santa Cruz no Joia da Princesa por dois a zero, na quarta-feira (31). De quebra, a equipe feirense quebrou um tabu contra os pernambucanos: venceu o tricolor do Arruda pela primeira\u2026","rel":"","context":"Em &quot;Colunistas&quot;","block_context":{"text":"Colunistas","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/colunistas\/"},"img":{"alt_text":"images-3","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2018\/02\/images-3.jpeg?resize=350%2C200","width":350,"height":200},"classes":[]}],"_links":{"self":[{"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/posts\/47345","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/comments?post=47345"}],"version-history":[{"count":5,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/posts\/47345\/revisions"}],"predecessor-version":[{"id":47351,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/posts\/47345\/revisions\/47351"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/media\/47350"}],"wp:attachment":[{"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/media?parent=47345"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/categories?post=47345"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/tags?post=47345"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}