{"id":47651,"date":"2021-10-05T14:04:02","date_gmt":"2021-10-05T17:04:02","guid":{"rendered":"https:\/\/blogdafeira.com.br\/home\/?p=47651"},"modified":"2021-10-15T22:40:47","modified_gmt":"2021-10-16T01:40:47","slug":"meu-chao","status":"publish","type":"post","link":"https:\/\/blogdafeira.com.br\/home\/2021\/10\/05\/meu-chao\/","title":{"rendered":"Meu ch\u00e3o&#8230;"},"content":{"rendered":"<div id=\"blogd-3084114118\" class=\"blogd-fim-do-post-mobile blogd-entity-placement\" style=\"margin-left: auto;margin-right: auto;text-align: center;\"><a href=\"https:\/\/www.feiradesantana.ba.gov.br\/servico.asp?s=a&titulo=Prefeitura-de-Feira-lan%C3%A7a-programa-Rem%C3%A9dio-em-Casa-e-transforma-acesso-a-medicamentos-em-pol%C3%ADtica-p%C3%BAblica-de-cuidados.html&id=14&link=secom\/noticias.asp&idn=43684#noticias\" target=_blank><picture>\r\n  <source media=\"(min-width: 768px)\" srcset=\"https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2026\/03\/980x150.gif\">\r\n  \r\n  <img decoding=\"async\" src=\"https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2021\/01\/350x2002.gif\" alt=\"Publicidade\" style=\"width: 100%; max-width: 100%; height: auto; display: block; margin: 0 auto;\">\r\n\t<\/picture><\/a><\/div><p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Quando menina tinha um ch\u00e3o absoluto, de certezas inabal\u00e1veis, que mais parecia um tapete de pedras, postas ali por algu\u00e9ns e ningu\u00e9ns, menos eu! At\u00e9 que aparentava s\u00f3lido, mas se rachou!<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Cresci, e meu ch\u00e3o de pedra se fez de terra, daquelas que quando se avolumam as perturba\u00e7\u00f5es, sobe o poeir\u00e3o!\u00a0 Afinal , tormento pouco \u00e9 bobagem! Tem que arder os olhos, empigarrar a goela, encrespar os cabelos e rachar a pele! S\u00f3 n\u00e3o me resseque a alma&#8230;<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Cresci mais ou de novo, ou envelheci&#8230; E mais uma vez,\u00a0 meu ch\u00e3o mudou!<\/span><\/p>\n<div id=\"blogd-1447282632\" class=\"blogd-final-post blogd-entity-placement\"><a href=\"https:\/\/www.feiradesantana.ba.leg.br\/\" target=\"_blank\" aria-label=\"JUNHO-VERMELHO_CA\u0302MARA-DE-FEIRA\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2026\/03\/JUNHO-VERMELHO_CAMARA-DE-FEIRA.gif\" alt=\"\"  class=\"no-lazyload\" width=\"728\" height=\"90\"   \/><\/a><\/div><p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">E se fez de barro! Com medo que endure\u00e7a e se torne s\u00f3lido outra vez, vivo a molh\u00e1-lo com minhas incertezas!<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Quando menina tinha um ch\u00e3o absoluto, de certezas inabal\u00e1veis, que mais parecia um tapete de pedras, postas ali por algu\u00e9ns e ningu\u00e9ns, menos eu! At\u00e9 que aparentava s\u00f3lido, mas se rachou! Cresci, e meu ch\u00e3o de pedra se fez de terra, daquelas que quando se avolumam as perturba\u00e7\u00f5es, sobe o poeir\u00e3o!\u00a0 Afinal , tormento pouco<\/p>\n","protected":false},"author":22,"featured_media":47654,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"cybocfi_hide_featured_image":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[592,1],"tags":[],"class_list":["post-47651","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-colunistas","category-raiz"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2021\/10\/images-1.jpeg","jetpack_shortlink":"https:\/\/wp.me\/p3niVf-coz","jetpack_sharing_enabled":true,"jetpack-related-posts":[{"id":2392,"url":"https:\/\/blogdafeira.com.br\/home\/2013\/06\/07\/cordel-e-o-tema-do-cha-deste-mes\/","url_meta":{"origin":47651,"position":0},"title":"Cordel \u00e9 o tema do Ch\u00e1 deste m\u00eas","author":"Blog da Feira","date":"07\/06\/2013","format":false,"excerpt":"Na pr\u00f3xima quinta-feira (13 de junho), dia de Santo Ant\u00f4nio, ser\u00e1 realizada mais uma edi\u00e7\u00e3o do projeto Ch\u00e1 de Conversa e Som, a partir das 19h30, na Cidade da Cultura, em Feira de Santana. O tema deste m\u00eas \u00e9 \u201cEu sou cordelista de Feira\u201d e contaremos com a participa\u00e7\u00e3o especial\u2026","rel":"","context":"Em &quot;Home&quot;","block_context":{"text":"Home","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/raiz\/"},"img":{"alt_text":"Seu Jurivaldo _ Pedro cem","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2013\/06\/Seu-Jurivaldo-_-Pedro-cem-199x300.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":61025,"url":"https:\/\/blogdafeira.com.br\/home\/2024\/02\/02\/casa-de-pedra\/","url_meta":{"origin":47651,"position":1},"title":"Casa-de-pedra","author":"J\u00e2nio R\u00eago","date":"02\/02\/2024","format":false,"excerpt":"Elas me impressionam bastante quando viajo pelo Serid\u00f3. Dessa vez pude parar para olhar de perto. E fotografar. Elas me trazem de volta \u00e0 mem\u00f3ria a casa-de-pedra de meus av\u00f3s. Havia tamb\u00e9m naquele caminho secular um resqu\u00edcio de cerca enroscada com a caatinga ribeirinha de Pau dos Ferros. Da casa-de-pedra\u2026","rel":"","context":"Em &quot;Colunistas&quot;","block_context":{"text":"Colunistas","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/colunistas\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2024\/02\/IMG_20240123_121556438-scaled.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2024\/02\/IMG_20240123_121556438-scaled.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2024\/02\/IMG_20240123_121556438-scaled.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2024\/02\/IMG_20240123_121556438-scaled.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2024\/02\/IMG_20240123_121556438-scaled.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2024\/02\/IMG_20240123_121556438-scaled.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":45327,"url":"https:\/\/blogdafeira.com.br\/home\/2021\/05\/09\/a-guerra-das-mamonas\/","url_meta":{"origin":47651,"position":2},"title":"A Guerra das Mamonas","author":"Ant\u00f4nio Brasileiro","date":"09\/05\/2021","format":false,"excerpt":"Quando Bode veio do mato afivelando o cinto, j\u00e1 foi aos berros: \u2013 Quem \u00e9 o ladr\u00e3o que est\u00e1 mexendo nas minhas mamonas? Biziu respondeu na tampa: \u2013 Mamona, \u00e9? E isso aqui? E isso aqui? \u00c9 s\u00f3 mamona, \u00e9? \u2013 E ia despejando a capanga e separando as pedras.\u2026","rel":"","context":"Em &quot;Colunistas&quot;","block_context":{"text":"Colunistas","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/colunistas\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2021\/05\/images-6.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2021\/05\/images-6.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2021\/05\/images-6.jpeg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":4364,"url":"https:\/\/blogdafeira.com.br\/home\/2013\/08\/16\/hoje-tem-cha-no-mac\/","url_meta":{"origin":47651,"position":3},"title":"Hoje tem Ch\u00e1 no MAC","author":"Blog da Feira","date":"16\/08\/2013","format":false,"excerpt":"","rel":"","context":"Em &quot;Home&quot;","block_context":{"text":"Home","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/raiz\/"},"img":{"alt_text":"ch\u00e1","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2013\/08\/ch%C3%A1.jpg?resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2013\/08\/ch%C3%A1.jpg?resize=350%2C200 1x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2013\/08\/ch%C3%A1.jpg?resize=525%2C300 1.5x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2013\/08\/ch%C3%A1.jpg?resize=700%2C400 2x"},"classes":[]},{"id":1738,"url":"https:\/\/blogdafeira.com.br\/home\/2013\/05\/19\/quinta-tem-cha-de-conversa-e-som-na-cidade-da-cultura\/","url_meta":{"origin":47651,"position":4},"title":"Quinta tem Ch\u00e1 de Conversa e Som na Cidade da Cultura","author":"Blog da Feira","date":"19\/05\/2013","format":false,"excerpt":"Na pr\u00f3xima quinta-feira (23), a partir das 19h30, ser\u00e1 realizada mais uma edi\u00e7\u00e3o do Ch\u00e1 de Conversa e Som, desta vez com o tema \u00e9 \u201cO que \u00e9 Conselho de Cultura Mesmo?\u201d. Como convidado especial, o produtor cultural e jornalista Roberto Martins. Martins \u00e9 militante em v\u00e1rios movimentos socioculturais de\u2026","rel":"","context":"Em &quot;Home&quot;","block_context":{"text":"Home","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/raiz\/"},"img":{"alt_text":"945536_501796879874658_1807972608_n","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2013\/05\/945536_501796879874658_1807972608_n1.jpg?resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2013\/05\/945536_501796879874658_1807972608_n1.jpg?resize=350%2C200 1x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2013\/05\/945536_501796879874658_1807972608_n1.jpg?resize=525%2C300 1.5x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2013\/05\/945536_501796879874658_1807972608_n1.jpg?resize=700%2C400 2x"},"classes":[]},{"id":70183,"url":"https:\/\/blogdafeira.com.br\/home\/2025\/11\/13\/cha-com-ze-promove-conversa-na-matinha-sobre-saude-da-populacao-negra-com-ervas-medicinais\/","url_meta":{"origin":47651,"position":5},"title":"&#8220;Ch\u00e1 com Z\u00e9&#8221; promove conversa na Matinha sobre sa\u00fade da popula\u00e7\u00e3o negra com ervas medicinais","author":"Blog da Feira","date":"13\/11\/2025","format":false,"excerpt":"O programa \"Ch\u00e1 com Z\u00e9\"\u00a0 se destaca, principalmente no distrito da Matinha, pela intera\u00e7\u00e3o com a comunidade e os temas que aborda e nos quais se envolve diretamente. \u00c9 o que vai ocorrer mais uma vez nesta sexta-feira-feira, dia 14 (amanh\u00e3) , quando o radialista Z\u00e9 das Virgens vai conduzir\u2026","rel":"","context":"Em &quot;Distritos&quot;","block_context":{"text":"Distritos","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/distritos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2025\/11\/IMG-20251113-WA0025.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2025\/11\/IMG-20251113-WA0025.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2025\/11\/IMG-20251113-WA0025.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2025\/11\/IMG-20251113-WA0025.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2025\/11\/IMG-20251113-WA0025.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/posts\/47651","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/comments?post=47651"}],"version-history":[{"count":3,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/posts\/47651\/revisions"}],"predecessor-version":[{"id":47721,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/posts\/47651\/revisions\/47721"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/media\/47654"}],"wp:attachment":[{"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/media?parent=47651"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/categories?post=47651"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/tags?post=47651"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}