{"id":48557,"date":"2021-11-18T18:49:28","date_gmt":"2021-11-18T21:49:28","guid":{"rendered":"https:\/\/blogdafeira.com.br\/home\/?p=48557"},"modified":"2021-11-22T20:11:30","modified_gmt":"2021-11-22T23:11:30","slug":"a-moqueca-frustrada-no-presidio","status":"publish","type":"post","link":"https:\/\/blogdafeira.com.br\/home\/2021\/11\/18\/a-moqueca-frustrada-no-presidio\/","title":{"rendered":"A moqueca frustrada no pres\u00eddio"},"content":{"rendered":"<div id=\"blogd-4131622148\" class=\"blogd-fim-do-post-mobile blogd-entity-placement\" style=\"margin-left: auto;margin-right: auto;text-align: center;\"><a href=\"https:\/\/www.feiradesantana.ba.gov.br\/servico.asp?s=a&titulo=Prefeitura-de-Feira-lan%C3%A7a-programa-Rem%C3%A9dio-em-Casa-e-transforma-acesso-a-medicamentos-em-pol%C3%ADtica-p%C3%BAblica-de-cuidados.html&id=14&link=secom\/noticias.asp&idn=43684#noticias\" target=_blank><picture>\r\n  <source media=\"(min-width: 768px)\" srcset=\"https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2026\/03\/980x150.gif\">\r\n  \r\n  <img decoding=\"async\" src=\"https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2021\/01\/350x2002.gif\" alt=\"Publicidade\" style=\"width: 100%; max-width: 100%; height: auto; display: block; margin: 0 auto;\">\r\n\t<\/picture><\/a><\/div><p style=\"text-align: justify;\">A not\u00edcia n\u00e3o passou de uma mera notinha, destas que, noutros tempos, iam para os rodap\u00e9s dos jornais impressos. Na verdade, quem divulgou praticamente reproduziu o texto da ocorr\u00eancia, inclusive com os jarg\u00f5es t\u00edpicos da linguagem policial. Mas a not\u00edcia, de t\u00e3o pitoresca, merecia abordagem melhor, texto mais extenso, compat\u00edvel com sua singularidade: em Salvador, policiais militares apreenderam 12 garrafas com frutos do mar e temperos, que seriam lan\u00e7adas no Complexo Penitenci\u00e1rio da Mata Escura.<\/p>\n<p style=\"text-align: justify;\">A apreens\u00e3o foi mais ampla: al\u00e9m dos frutos do mar e dos temperos, os policiais do Batalh\u00e3o de Guardas da Pol\u00edcia Militar aprenderam aparelhos celulares, maconha, <em>chips<\/em> para os celulares, carregadores e cabos de carregadores e embalagens de papel de cigarro. A dupla que pretendia lan\u00e7ar os produtos embrenhou-se no matagal e desapareceu, abandonando a encomenda.<\/p>\n<p style=\"text-align: justify;\">Quase todos os itens s\u00e3o banais em apreens\u00f5es semelhantes \u2013 a maconha, os celulares e seus acess\u00f3rios \u2013 e, com frequ\u00eancia, s\u00e3o apanhados em opera\u00e7\u00f5es policiais. Mas os frutos do mar e os temperos, n\u00e3o. No passado, uma apreens\u00e3o do g\u00eanero colocaria rep\u00f3rteres e editores de pol\u00edcia em polvorosa: necess\u00e1rio apurar, porque a not\u00edcia poderia render manchete de p\u00e1gina, chamada de capa.<\/p>\n<p style=\"text-align: justify;\">Imagino que, desolados com o insosso card\u00e1pio do sistema penitenci\u00e1rio e saudosos da apetitosa culin\u00e1ria baiana, alguns presos reuniram-se e encaminharem a encomenda para seus parceiros na rua. Calculo que os frutos do mar \u2013 Camar\u00f5es? Siris? Polvos? \u2013 misturados aos temperos \u2013 deduzo que havia azeite de dend\u00ea \u2013renderiam uma moqueca que apaziguaria esp\u00edritos e resgataria uma ef\u00eamera sensa\u00e7\u00e3o de liberdade.<\/p>\n<p style=\"text-align: justify;\">N\u00e3o deve ser f\u00e1cil fazer moqueca na clandestinidade, numa cela de pres\u00eddio. Talvez pretendessem improvisar um fog\u00e3o, usando resist\u00eancia de chuveiro e tijolo. Os presos brasileiros s\u00e3o inventivos, o notici\u00e1rio frequentemente atesta. Mas o fato \u00e9 que, provavelmente, a moqueca n\u00e3o ficaria no padr\u00e3o daquelas que se comem nos restaurantes da orla soteropolitana. Cogito que, prudentes, n\u00e3o pretendiam preparar um bob\u00f3 de camar\u00e3o, prato mais sofisticado.<\/p>\n<p style=\"text-align: justify;\">Todas estas especula\u00e7\u00f5es \u2013 trata-se de meras especula\u00e7\u00f5es \u2013 talvez encontrassem respostas caso os rep\u00f3rteres investissem numa apura\u00e7\u00e3o mais robusta, como se fazia noutros tempos. Hoje o notici\u00e1rio policial, basicamente, se limita \u00e0 reprodu\u00e7\u00e3o da vers\u00e3o oficial dos fatos. Replicam at\u00e9 aquelas express\u00f5es t\u00e9cnicas, pouco comuns ao jornalismo e \u00e0 sociedade. Flagranteio \u2013 o termo faz sucesso \u2013 essas palavras com muita frequ\u00eancia.<\/p>\n<div id=\"blogd-2183146227\" class=\"blogd-final-post blogd-entity-placement\"><a href=\"https:\/\/www.feiradesantana.ba.leg.br\/\" target=\"_blank\" aria-label=\"JUNHO-VERMELHO_CA\u0302MARA-DE-FEIRA\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2026\/03\/JUNHO-VERMELHO_CAMARA-DE-FEIRA.gif\" alt=\"\"  class=\"no-lazyload\" width=\"728\" height=\"90\"   \/><\/a><\/div><p style=\"text-align: justify;\">O fato \u00e9 que a moqueca de frutos do mar no Complexo Penitenci\u00e1rio da Mata Escura frustrou-se. Tamb\u00e9m n\u00e3o entrou a maconha que renderia baseados para abrir o apetite, nem os celulares que registrariam o rega-bofe. Mas, mesmo assim, merecia mat\u00e9ria, como aquelas que se faziam noutras \u00e9pocas&#8230;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A not\u00edcia n\u00e3o passou de uma mera notinha, destas que, noutros tempos, iam para os rodap\u00e9s dos jornais impressos. Na verdade, quem divulgou praticamente reproduziu o texto da ocorr\u00eancia, inclusive com os jarg\u00f5es t\u00edpicos da linguagem policial. Mas a not\u00edcia, de t\u00e3o pitoresca, merecia abordagem melhor, texto mais extenso, compat\u00edvel com sua singularidade: em Salvador,<\/p>\n","protected":false},"author":13,"featured_media":48577,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"cybocfi_hide_featured_image":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[592,1],"tags":[],"class_list":["post-48557","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-colunistas","category-raiz"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2021\/11\/WhatsApp-Image-2021-07-01-at-13.14.09.jpeg","jetpack_shortlink":"https:\/\/wp.me\/p3niVf-cDb","jetpack_sharing_enabled":true,"jetpack-related-posts":[{"id":4741,"url":"https:\/\/blogdafeira.com.br\/home\/2013\/09\/03\/pacto-da-feira-instala-modulos-policiais-no-centro-la-vem-o-rapa\/","url_meta":{"origin":48557,"position":0},"title":"&#8216;Pacto da Feira&#8217; instala m\u00f3dulos policiais no centro: l\u00e1 vem o rapa!","author":"Blog da Feira","date":"03\/09\/2013","format":false,"excerpt":"O chamado 'Pacto da Feira', projeto lan\u00e7ado pelo Governo municipal no in\u00edcio do ano com o objetivo de 'ordenar' o com\u00e9rcio ambulante no centro comercial de Feira de Santana, come\u00e7ou a 'mostrar servi\u00e7o'. Dois 'toldos', devidamente identificados com a logomarca do projeto, da Prefeitura Municipal e da Pol\u00edcia Militar da\u2026","rel":"","context":"Em &quot;Home&quot;","block_context":{"text":"Home","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/raiz\/"},"img":{"alt_text":"pacto da feira","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2013\/09\/pacto-da-feira.jpg?resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2013\/09\/pacto-da-feira.jpg?resize=350%2C200 1x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2013\/09\/pacto-da-feira.jpg?resize=525%2C300 1.5x"},"classes":[]},{"id":8743,"url":"https:\/\/blogdafeira.com.br\/home\/2014\/01\/29\/abordagem-policial-caes-farejadores-de-aparelho-celular\/","url_meta":{"origin":48557,"position":1},"title":"Abordagem Policial: c\u00e3es farejadores de aparelho celular","author":"Blog da Feira","date":"29\/01\/2014","format":false,"excerpt":"A utiliza\u00e7\u00e3o de c\u00e3es farejadores no servi\u00e7o policial pode proporcionar v\u00e1rios efeitos positivos, principalmente no campo da redu\u00e7\u00e3o do uso da for\u00e7a pelos agentes policiais, que podem se antecipar \u00e0 presen\u00e7a de objetos suspeitos e\/ou fruto de crime. Um grande exemplo do uso desses animais\u00a0\u00e9 a detec\u00e7\u00e3o de aparelhos celulares\u00a0atrav\u00e9s\u2026","rel":"","context":"Em &quot;Home&quot;","block_context":{"text":"Home","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/raiz\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":50108,"url":"https:\/\/blogdafeira.com.br\/home\/2022\/01\/13\/cinco-mil-soldados-vao-reforcar-policiamento-nos-municipios-da-bahia\/","url_meta":{"origin":48557,"position":2},"title":"Cinco mil soldados v\u00e3o refor\u00e7ar policiamento nos munic\u00edpios da Bahia","author":"Blog da Feira","date":"13\/01\/2022","format":false,"excerpt":"A Pol\u00edcia Militar da Bahia intensificou o policiamento nos 417 munic\u00edpios baianos com o in\u00edcio da primeira edi\u00e7\u00e3o da Opera\u00e7\u00e3o For\u00e7a Total. A cerim\u00f4nia de lan\u00e7amento ocorreu nesta quinta-feira (13), em Salvador, no bairro da Boca do Rio, e contou com a presen\u00e7a do comandante geral da PM, coronel Paulo\u2026","rel":"","context":"Em &quot;Geral&quot;","block_context":{"text":"Geral","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/geral\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2022\/01\/pmbahia.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2022\/01\/pmbahia.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2022\/01\/pmbahia.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":53490,"url":"https:\/\/blogdafeira.com.br\/home\/2022\/07\/27\/inquerito-sobre-troca-de-tiros-que-matou-marcelinho-continua-inconcluso\/","url_meta":{"origin":48557,"position":3},"title":"Inqu\u00e9rito sobre &#8216;troca-de-tiros&#8217; que matou &#8216;Marcelinho&#8217; continua inconcluso","author":"Blog da Feira","date":"27\/07\/2022","format":false,"excerpt":"O inqu\u00e9rito \u00e9 um dos poucos onde familiares da v\u00edtima contestam as frequentes \"trocas-de-tiros\" com que a Pol\u00edcia justifica os alvejados e mortos \"em confronto\". A apura\u00e7\u00e3o da Pol\u00edcia sobre o envolvimento dos policiais militares j\u00e1 mudou de delegado e de promotor e j\u00e1 foi e voltou para o Minist\u00e9rio\u2026","rel":"","context":"Em &quot;Geral&quot;","block_context":{"text":"Geral","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/geral\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2022\/07\/Marcelo-Felipe-Guerra-dos-Santos-Rocha_-jovem-morto-em-intervencao-policial-768x507-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2022\/07\/Marcelo-Felipe-Guerra-dos-Santos-Rocha_-jovem-morto-em-intervencao-policial-768x507-1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2022\/07\/Marcelo-Felipe-Guerra-dos-Santos-Rocha_-jovem-morto-em-intervencao-policial-768x507-1.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2022\/07\/Marcelo-Felipe-Guerra-dos-Santos-Rocha_-jovem-morto-em-intervencao-policial-768x507-1.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":7660,"url":"https:\/\/blogdafeira.com.br\/home\/2013\/12\/23\/a-morte-de-policiais-baianos-em-um-teste-fisico\/","url_meta":{"origin":48557,"position":4},"title":"A morte de policiais baianos em um teste f\u00edsico","author":"Blog da Feira","date":"23\/12\/2013","format":false,"excerpt":"Teve repercuss\u00e3o nacional o triste caso de dois policiais militares baianos que morreram ap\u00f3s realizarem o Teste de Habilidades Espec\u00edficas (THE) do Curso de Opera\u00e7\u00f5es Especiais (COPES). Como ocorre em toda trag\u00e9dia, o\u00a0momento \u00e9 de especula\u00e7\u00e3o e conjecturas a respeito da responsabilidade das mortes: teria havido abuso durante a atividade?\u2026","rel":"","context":"Em &quot;Home&quot;","block_context":{"text":"Home","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/raiz\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":41262,"url":"https:\/\/blogdafeira.com.br\/home\/2020\/10\/20\/pastor-isidorio-faz-projeto-em-defesa-dos-ambulantes\/","url_meta":{"origin":48557,"position":5},"title":"Pastor Isid\u00f3rio faz projeto em defesa dos ambulantes","author":"Blog da Feira","date":"20\/10\/2020","format":false,"excerpt":"O Projeto de Lei 4867\/20 pro\u00edbe o confisco de mercadorias legais ofertadas por camel\u00f4s ou vendedores ambulantes ou informais em vias p\u00fablicas. A medida abrange itens de consumo imediato, perec\u00edveis e baixo valor, entre outras caracter\u00edsticas similares. O texto em tramita\u00e7\u00e3o na C\u00e2mara dos Deputados estabelece a proibi\u00e7\u00e3o em \u00e2mbito\u2026","rel":"","context":"Em &quot;Cidade&quot;","block_context":{"text":"Cidade","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/cidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2020\/10\/img20191210230634241-768x512-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2020\/10\/img20191210230634241-768x512-1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2020\/10\/img20191210230634241-768x512-1.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2020\/10\/img20191210230634241-768x512-1.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/posts\/48557","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/comments?post=48557"}],"version-history":[{"count":3,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/posts\/48557\/revisions"}],"predecessor-version":[{"id":48578,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/posts\/48557\/revisions\/48578"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/media\/48577"}],"wp:attachment":[{"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/media?parent=48557"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/categories?post=48557"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/tags?post=48557"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}