{"id":49009,"date":"2021-12-01T07:36:19","date_gmt":"2021-12-01T10:36:19","guid":{"rendered":"https:\/\/blogdafeira.com.br\/home\/?p=49009"},"modified":"2021-12-03T16:18:31","modified_gmt":"2021-12-03T19:18:31","slug":"a-marechal","status":"publish","type":"post","link":"https:\/\/blogdafeira.com.br\/home\/2021\/12\/01\/a-marechal\/","title":{"rendered":"A Marechal"},"content":{"rendered":"<div id=\"blogd-2459254535\" class=\"blogd-final-post blogd-entity-placement\"><a href=\"https:\/\/www.feiradesantana.ba.leg.br\/\" target=\"_blank\" aria-label=\"JUNHO-VERMELHO_CA\u0302MARA-DE-FEIRA\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2026\/03\/JUNHO-VERMELHO_CAMARA-DE-FEIRA.gif\" alt=\"\"  class=\"no-lazyload\" width=\"728\" height=\"90\"   \/><\/a><\/div><div dir=\"auto\" style=\"text-align: justify;\">Foquei na vendedora de ma\u00e7\u00e3s sempre deliciosas nas ruas mas o zoom n\u00e3o abriu e terminei clicando essa cena urbana composta profundamente comum nessa esquina onde come\u00e7a a Marechal, a Rua Mal. Deodoro como est\u00e1 escrito na placa vermelha ao fundo. A van e o cobrador na porta grita o percurso e o destino, a kombi dobra no sentido do G. Barbosa, o homem de bon\u00e9 quer atravessar a rua e as duas baianas batem pernas no com\u00e9rcio do centro hist\u00f3rico da cidade da Feira.<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Foquei na vendedora de ma\u00e7\u00e3s sempre deliciosas nas ruas mas o zoom n\u00e3o abriu e terminei clicando essa cena urbana composta profundamente comum nessa esquina onde come\u00e7a a Marechal, a Rua Mal. Deodoro como est\u00e1 escrito na placa vermelha ao fundo. A van e o cobrador na porta grita o percurso e o destino, a<\/p>\n","protected":false},"author":8,"featured_media":49010,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"cybocfi_hide_featured_image":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[592,1],"tags":[],"class_list":["post-49009","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-colunistas","category-raiz"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2021\/12\/foto.jpg","jetpack_shortlink":"https:\/\/wp.me\/p3niVf-cKt","jetpack_sharing_enabled":true,"jetpack-related-posts":[{"id":45775,"url":"https:\/\/blogdafeira.com.br\/home\/2021\/06\/09\/lajedinho-marcio-punk-e-as-transformacoes-da-marechal\/","url_meta":{"origin":49009,"position":0},"title":"Lajedinho, M\u00e1rcio Punk e as transforma\u00e7\u00f5es da Marechal","author":"J\u00e2nio R\u00eago","date":"09\/06\/2021","format":false,"excerpt":"O historiador feirense Antonio de Lajedinho conheceu j\u00e1 em ru\u00ednas um est\u00e1dio de futebol na rua Marechal Deodoro, que ent\u00e3o se chamava rua Manoel Vitorino. Lajedinho morreu no m\u00eas passado com quase 100 anos de idade e lucidez. \u00a0\"O seu nome era Est\u00e1dio Leolindo Ramos e ocupava todo o \u00faltimo\u2026","rel":"","context":"Em &quot;Colunistas&quot;","block_context":{"text":"Colunistas","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/colunistas\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2017\/02\/IMG_20170217_113303.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2017\/02\/IMG_20170217_113303.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2017\/02\/IMG_20170217_113303.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2017\/02\/IMG_20170217_113303.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2017\/02\/IMG_20170217_113303.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2017\/02\/IMG_20170217_113303.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":39711,"url":"https:\/\/blogdafeira.com.br\/home\/2020\/08\/20\/centro-de-feira-em-obras-transito-interditado-na-marechal\/","url_meta":{"origin":49009,"position":1},"title":"Centro de Feira em obras; tr\u00e2nsito interditado na Marechal","author":"Blog da Feira","date":"20\/08\/2020","format":false,"excerpt":"A rua Marechal Deodoro, uma das mais movimentadas do centro comercial de Feira de Santana, est\u00e1 parcialmente interditada ao tr\u00e2nsito desde a manh\u00e3 desta quinta-feira, 20. Nas pr\u00f3ximas semanas a rua vai ficar temporariamente fechada para a circula\u00e7\u00e3o de carros e motocicletas devido \u00e0 instala\u00e7\u00e3o da rede de drenagem pluvial,\u2026","rel":"","context":"Em &quot;Cidade&quot;","block_context":{"text":"Cidade","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/cidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2020\/08\/marechal-fsfsf.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2020\/08\/marechal-fsfsf.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2020\/08\/marechal-fsfsf.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2020\/08\/marechal-fsfsf.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2020\/08\/marechal-fsfsf.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":25749,"url":"https:\/\/blogdafeira.com.br\/home\/2017\/02\/20\/a-marechal-de-feira-de-santana\/","url_meta":{"origin":49009,"position":2},"title":"&#8216;A Marechal&#8217; de Feira de Santana","author":"Blog da Feira","date":"20\/02\/2017","format":false,"excerpt":"O historiador feirense Antonio de Lajedinho, 91 , conheceu j\u00e1 em ru\u00ednas, na d\u00e9cada de 30 do s\u00e9culo passado, \u00a0um est\u00e1dio de futebol na rua Marechal Deodoro, que ent\u00e3o se chamava Manoel Vitorino. \u00a0\"O seu nome era Est\u00e1dio Leolindo Ramos e ocupava todo o \u00faltimo quarteir\u00e3o da Rua Manoel Vitorino\u2026","rel":"","context":"Em &quot;Home&quot;","block_context":{"text":"Home","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/raiz\/"},"img":{"alt_text":"img_20170217_091556420","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2017\/02\/IMG_20170217_091556420-1024x576.jpg?resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2017\/02\/IMG_20170217_091556420-1024x576.jpg?resize=350%2C200 1x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2017\/02\/IMG_20170217_091556420-1024x576.jpg?resize=525%2C300 1.5x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2017\/02\/IMG_20170217_091556420-1024x576.jpg?resize=700%2C400 2x"},"classes":[]},{"id":45481,"url":"https:\/\/blogdafeira.com.br\/home\/2021\/05\/19\/feirantes-pedem-ajuda-a-vereadores-para-salvar-a-feirinha-da-marechal\/","url_meta":{"origin":49009,"position":3},"title":"Feirantes pedem ajuda a vereadores para salvar a feirinha da Marechal","author":"Blog da Feira","date":"19\/05\/2021","format":false,"excerpt":"As feirantes Sheyla dos Santos Silva e S\u00f4nia Pereira de Jesus (foto) utilizaram a 'Tribuna Livre' da C\u00e2mara de Vereadores de Feira de Santana\u00a0 para pedir o apoio do Legislativo para\u00a0 manuten\u00e7\u00e3o de suas barracas de frutas e legumes na Marechal, no centro da cidade. A feirinha vai sair da\u2026","rel":"","context":"Em &quot;Cidade&quot;","block_context":{"text":"Cidade","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/cidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2021\/05\/Screenshot_20210519-1847552.png?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2021\/05\/Screenshot_20210519-1847552.png?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2021\/05\/Screenshot_20210519-1847552.png?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":50643,"url":"https:\/\/blogdafeira.com.br\/home\/2022\/02\/10\/obras-na-marechal-provocam-a-queda-de-arvore\/","url_meta":{"origin":49009,"position":4},"title":"Obras na Marechal provocam a queda de \u00e1rvore","author":"Blog da Feira","date":"10\/02\/2022","format":false,"excerpt":"Caiu uma antiga \u00e1rvore que sombreava parte da cal\u00e7ada da rua\u00a0 Marechal Deodoro, no centro de Feira de Santana, devido \u00e0s obras que a Prefeitura vem realizando no local. A falta de isolamento do vegetal exposto ao uso de m\u00e1quinas pesadas revolvendo terra, provocou a queda da \u00e1rvore. Ao longo\u2026","rel":"","context":"Em &quot;Cidade&quot;","block_context":{"text":"Cidade","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/cidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2022\/02\/Rua-Marechal-interditada-arvore-caida-10-02-2022-Foto-Izinaldo-Barreto-6-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2022\/02\/Rua-Marechal-interditada-arvore-caida-10-02-2022-Foto-Izinaldo-Barreto-6-1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2022\/02\/Rua-Marechal-interditada-arvore-caida-10-02-2022-Foto-Izinaldo-Barreto-6-1.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2022\/02\/Rua-Marechal-interditada-arvore-caida-10-02-2022-Foto-Izinaldo-Barreto-6-1.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2022\/02\/Rua-Marechal-interditada-arvore-caida-10-02-2022-Foto-Izinaldo-Barreto-6-1.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":68209,"url":"https:\/\/blogdafeira.com.br\/home\/2025\/07\/10\/transformar-a-marechal-em-calcadao-para-pedestres-esta-se-tornando-um-consenso-cadai\/","url_meta":{"origin":49009,"position":5},"title":"Transformar a Marechal em Cal\u00e7ad\u00e3o para pedestres est\u00e1 se tornando um consenso","author":"Blog da Feira","date":"10\/07\/2025","format":false,"excerpt":"A maioria das pessoas que participaram do podcast \"Ch\u00e1 com Z\u00e9\" na Feira da Marechal, nesta manh\u00e3 de quinta-feira,10, se posicionou favor\u00e1vel a que a rua seja transformada em um Cal\u00e7ad\u00e3o exclusivo para pedestres ficarem \u00e0 vontade no com\u00e9rcio local. Do secret\u00e1rio municipal de Agricultura a lideran\u00e7as populares e t\u00e9cnicos,\u2026","rel":"","context":"Em &quot;Cidade&quot;","block_context":{"text":"Cidade","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/cidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2025\/07\/Screenshot_20250710-094805.png?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2025\/07\/Screenshot_20250710-094805.png?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2025\/07\/Screenshot_20250710-094805.png?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2025\/07\/Screenshot_20250710-094805.png?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2025\/07\/Screenshot_20250710-094805.png?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2025\/07\/Screenshot_20250710-094805.png?resize=1400%2C800&ssl=1 4x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/posts\/49009","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/comments?post=49009"}],"version-history":[{"count":3,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/posts\/49009\/revisions"}],"predecessor-version":[{"id":49013,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/posts\/49009\/revisions\/49013"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/media\/49010"}],"wp:attachment":[{"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/media?parent=49009"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/categories?post=49009"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/tags?post=49009"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}