{"id":49342,"date":"2021-12-13T09:57:52","date_gmt":"2021-12-13T12:57:52","guid":{"rendered":"https:\/\/blogdafeira.com.br\/home\/?p=49342"},"modified":"2021-12-15T20:33:01","modified_gmt":"2021-12-15T23:33:01","slug":"prefeitura-de-feira-arboriza-trecho-final-da-avenida-ayrton-sena","status":"publish","type":"post","link":"https:\/\/blogdafeira.com.br\/home\/2021\/12\/13\/prefeitura-de-feira-arboriza-trecho-final-da-avenida-ayrton-sena\/","title":{"rendered":"Prefeitura de Feira arboriza trecho final da avenida Ayrton Sena"},"content":{"rendered":"<div id=\"blogd-1172124908\" class=\"blogd-fim-do-post-mobile blogd-entity-placement\" style=\"margin-left: auto;margin-right: auto;text-align: center;\"><a href=\"https:\/\/www.feiradesantana.ba.gov.br\/servico.asp?s=a&titulo=Prefeitura-de-Feira-lan%C3%A7a-programa-Rem%C3%A9dio-em-Casa-e-transforma-acesso-a-medicamentos-em-pol%C3%ADtica-p%C3%BAblica-de-cuidados.html&id=14&link=secom\/noticias.asp&idn=43684#noticias\" target=_blank><picture>\r\n  <source media=\"(min-width: 768px)\" srcset=\"https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2026\/03\/980x150.gif\">\r\n  \r\n  <img decoding=\"async\" src=\"https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2021\/01\/350x2002.gif\" alt=\"Publicidade\" style=\"width: 100%; max-width: 100%; height: auto; display: block; margin: 0 auto;\">\r\n\t<\/picture><\/a><\/div><p style=\"text-align: justify;\">O prolongamento da avenida Ayrton Sena foi o local escolhido pela Prefeitura de Feira para dar in\u00edcio, na manh\u00e3 deste domingo, 11, ao projeto de arboriza\u00e7\u00e3o \u201cViva a Natureza\u201d, que prev\u00ea o plantio \u2013 somente na primeira etapa \u2013 de mil \u00e1rvores em toda a cidade.<\/p>\n<p style=\"text-align: justify;\">As mudas foram plantadas no canteiro central da avenida, a partir do Cemit\u00e9rio S\u00e3o Jo\u00e3o Batista at\u00e9 o contorno que d\u00e1 acesso a Mantiba.\u00a0Somente neste trecho foram 97 mudas, sendo 55 da esp\u00e9cie Jacarand\u00e1 Mimoso, 20 de Fel\u00edcio, 20 da esp\u00e9cie Resed\u00e1 e duas Sibipirunas.<\/p>\n<p style=\"text-align: justify;\">O prefeito Colbert Filho enfatizou a import\u00e2ncia do projeto, observando ser uma a\u00e7\u00e3o tamb\u00e9m para amenizar os impactos das mudan\u00e7as clim\u00e1ticas e o aquecimento global.<\/p>\n<blockquote><p>&#8220;<em>Al\u00e9m de combater \u00e0 polui\u00e7\u00e3o, uma vez que as \u00e1rvores absorvem gases, transformando-os em oxig\u00eanio, elas proporcionam sombra&#8221;,<\/em> afirma.<\/p><\/blockquote>\n<p style=\"text-align: justify;\">A iniciativa est\u00e1 sendo coordenada pela Secretaria Municipal do Meio Ambiente (SEMMAM) com o apoio da Secretaria Municipal de Servi\u00e7os P\u00fablicos (SESP), por meio do Departamento de \u00c1reas Verdes.<\/p>\n<p style=\"text-align: justify;\">De acordo com o secret\u00e1rio de Meio Ambiente, Jos\u00e9 Carneiro,\u00a0o projeto vai contemplar ainda outras localidades. &#8220;<em>Esse projeto ser\u00e1 levado para outros locais da cidade, incluindo os distritos. Vamos plantar inicialmente mil \u00e1rvores, mas a expectativa \u00e9 atingir, a longo prazo, o percentual de pelo menos tr\u00eas \u00e1rvores por habitante<\/em>&#8220;, destacou.<\/p>\n<p style=\"text-align: justify;\">No local tamb\u00e9m foram distribu\u00eddas para a comunidade mudas que podem ser plantadas em jardins e quintais, como Escova de Garrafa, Aroeira Chorona, Pata de Vaca, Quaresmeira e Ip\u00ea, nas cores amarelo e rosa, para a comunidade.<\/p>\n<div id=\"blogd-1382811009\" class=\"blogd-final-post blogd-entity-placement\"><a href=\"https:\/\/www.feiradesantana.ba.leg.br\/\" target=\"_blank\" aria-label=\"JUNHO-VERMELHO_CA\u0302MARA-DE-FEIRA\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2026\/03\/JUNHO-VERMELHO_CAMARA-DE-FEIRA.gif\" alt=\"\"  class=\"no-lazyload\" width=\"728\" height=\"90\"   \/><\/a><\/div><p style=\"text-align: justify;\"><em>foto:Cau Preto\/Secom<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O prolongamento da avenida Ayrton Sena foi o local escolhido pela Prefeitura de Feira para dar in\u00edcio, na manh\u00e3 deste domingo, 11, ao projeto de arboriza\u00e7\u00e3o \u201cViva a Natureza\u201d, que prev\u00ea o plantio \u2013 somente na primeira etapa \u2013 de mil \u00e1rvores em toda a cidade. As mudas foram plantadas no canteiro central da avenida,<\/p>\n","protected":false},"author":1,"featured_media":49343,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"cybocfi_hide_featured_image":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[3,1],"tags":[],"class_list":["post-49342","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cidade","category-raiz"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2021\/12\/Plantio-de-arvores-Foto-Cau-Preto-10-1.jpg","jetpack_shortlink":"https:\/\/wp.me\/p3niVf-cPQ","jetpack_sharing_enabled":true,"jetpack-related-posts":[{"id":49302,"url":"https:\/\/blogdafeira.com.br\/home\/2021\/12\/11\/projeto-viva-a-natureza-tem-plantio-de-arvores-neste-domingo\/","url_meta":{"origin":49342,"position":0},"title":"Projeto Viva a Natureza tem plantio de \u00e1rvores neste domingo","author":"Secom\/FSA","date":"11\/12\/2021","format":false,"excerpt":"A avenida Ayrton Senna vai ficar ainda mais verde. Novas esp\u00e9cies de \u00e1rvores ser\u00e3o plantadas neste domingo, 12, a partir das 8h, incrementando o paisagismo. A arboriza\u00e7\u00e3o faz parte do projeto Viva a Natureza, desenvolvido pela Prefeitura de Feira. O plantio ser\u00e1 feito no trecho entre o Cemit\u00e9rio S\u00e3o Jo\u00e3o\u2026","rel":"","context":"Em &quot;Cidade&quot;","block_context":{"text":"Cidade","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/cidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2021\/12\/Plantio-de-arvores-Foto-ACM-3.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2021\/12\/Plantio-de-arvores-Foto-ACM-3.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2021\/12\/Plantio-de-arvores-Foto-ACM-3.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2021\/12\/Plantio-de-arvores-Foto-ACM-3.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2021\/12\/Plantio-de-arvores-Foto-ACM-3.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":28234,"url":"https:\/\/blogdafeira.com.br\/home\/2017\/09\/22\/prefeitura-planta-arvores-frutiferas-em-parques-e-avenidas-de-feira-de-santana\/","url_meta":{"origin":49342,"position":1},"title":"Prefeitura planta \u00e1rvores frut\u00edferas em parques e avenidas de Feira de Santana","author":"Secom\/FSA","date":"22\/09\/2017","format":false,"excerpt":"At\u00e9 o final desta semana, parques e avenidas de Feira de Santana ganhar\u00e3o mais de mil novas \u00e1rvores, sendo que aproximadamente 40% s\u00e3o frut\u00edferas e os 60% tem caracter\u00edsticas de arboriza\u00e7\u00e3o e revegeta\u00e7\u00e3o. Nesta quinta-feira, 21, comemorou-se o Dia da \u00c1rvore. As \u00e1rvores ser\u00e3o plantadas no Parque da Cidade Frei\u2026","rel":"","context":"Em &quot;Home&quot;","block_context":{"text":"Home","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/raiz\/"},"img":{"alt_text":"_rvores-sesp-5","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2017\/09\/rvores-Sesp-5.jpg?resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2017\/09\/rvores-Sesp-5.jpg?resize=350%2C200 1x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2017\/09\/rvores-Sesp-5.jpg?resize=525%2C300 1.5x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2017\/09\/rvores-Sesp-5.jpg?resize=700%2C400 2x"},"classes":[]},{"id":41092,"url":"https:\/\/blogdafeira.com.br\/home\/2020\/10\/09\/arborizacao-da-avenida-fraga-maia-ganha-380-mudas-de-ipes\/","url_meta":{"origin":49342,"position":2},"title":"Arboriza\u00e7\u00e3o da avenida Fraga Maia ganha 380 mudas de ip\u00eas","author":"Secom\/FSA","date":"09\/10\/2020","format":false,"excerpt":"As mudas de ip\u00eas foram plantadas na extens\u00e3o da avenida Fraga Maia, entre os bairros Papagaio e o conjunto Jo\u00e3o Paulo. Esp\u00e9cie facilmente adaptada \u00e0 regi\u00e3o, dentro de mais alguns anos, dar\u00e3o flores, sombra, al\u00e9m de contribuir com as quest\u00f5es ambientais. Elas s\u00e3o nas cores amarelo, roxo, rosa e branco.\u2026","rel":"","context":"Em &quot;Cidade&quot;","block_context":{"text":"Cidade","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/cidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2020\/10\/Plantio-de-mudas-de-Ipe-na-Av-Fraga-Maia-foto-Jorge-Magalhaes-26-scaled.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2020\/10\/Plantio-de-mudas-de-Ipe-na-Av-Fraga-Maia-foto-Jorge-Magalhaes-26-scaled.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2020\/10\/Plantio-de-mudas-de-Ipe-na-Av-Fraga-Maia-foto-Jorge-Magalhaes-26-scaled.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2020\/10\/Plantio-de-mudas-de-Ipe-na-Av-Fraga-Maia-foto-Jorge-Magalhaes-26-scaled.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2020\/10\/Plantio-de-mudas-de-Ipe-na-Av-Fraga-Maia-foto-Jorge-Magalhaes-26-scaled.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2020\/10\/Plantio-de-mudas-de-Ipe-na-Av-Fraga-Maia-foto-Jorge-Magalhaes-26-scaled.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":45052,"url":"https:\/\/blogdafeira.com.br\/home\/2021\/04\/21\/prefeitura-desaprova-uso-da-arvore-nim-para-arborizacao-de-feira\/","url_meta":{"origin":49342,"position":3},"title":"Prefeitura desaprova uso da \u00e1rvore &#8216;Nim&#8217; para arboriza\u00e7\u00e3o de Feira","author":"Secom\/FSA","date":"21\/04\/2021","format":false,"excerpt":"\u00c1rvores da esp\u00e9cie Nim foram plantadas de forma indevida no passeio da avenida Noide Cerqueira, nas proximidades do viaduto, que liga a Get\u00falio Vargas. A avalia\u00e7\u00e3o \u00e9 do Departamento de \u00c1reas Verdes da Sesp (Secretaria de Servi\u00e7os P\u00fablicos), que produziu um laudo t\u00e9cnico sugerindo substitu\u00ed-las por outras \u00e1rvores ornamentais. O\u2026","rel":"","context":"Em &quot;Cidade&quot;","block_context":{"text":"Cidade","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/cidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2021\/04\/7-14.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":51885,"url":"https:\/\/blogdafeira.com.br\/home\/2022\/04\/20\/prefeitura-solicita-a-camara-autorizacao-de-emprestimo-para-obras-de-saneamento-e-mobilidade\/","url_meta":{"origin":49342,"position":4},"title":"Prefeitura solicita \u00e0 C\u00e2mara autoriza\u00e7\u00e3o de empr\u00e9stimo para obras de saneamento e mobilidade","author":"Secom\/FSA","date":"20\/04\/2022","format":false,"excerpt":"A Prefeitura de Feira de Santana encaminhou nesta quarta-feira, 20, o projeto de autoriza\u00e7\u00e3o \u00e0 C\u00e2mara Municipal para empr\u00e9stimo no valor de\u00a0R$ 246 milh\u00f5es e 100 mil\u00a0para a execu\u00e7\u00e3o de\u00a0obras de saneamento, meio ambiente e mobilidade na sede e nos distritos. Os locais e ideias de como ser\u00e3o feitas as\u2026","rel":"","context":"Em &quot;Cidade&quot;","block_context":{"text":"Cidade","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/cidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2022\/04\/Limpeza-do-canal-prato-raso-foto-divulgacao-sesp-74.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2022\/04\/Limpeza-do-canal-prato-raso-foto-divulgacao-sesp-74.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2022\/04\/Limpeza-do-canal-prato-raso-foto-divulgacao-sesp-74.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2022\/04\/Limpeza-do-canal-prato-raso-foto-divulgacao-sesp-74.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2022\/04\/Limpeza-do-canal-prato-raso-foto-divulgacao-sesp-74.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":5434,"url":"https:\/\/blogdafeira.com.br\/home\/2013\/10\/04\/avenida-ayrton-sena-em-feira-expoe-conflito-entre-governos-municipal-e-estadual\/","url_meta":{"origin":49342,"position":5},"title":"Avenida Ayrton Sena em Feira exp\u00f5e conflito entre governos municipal e estadual","author":"Secom\/FSA","date":"04\/10\/2013","format":false,"excerpt":"'\u00c9 mentira', disse taxativamente o prefeito de Feira de Santana, Jos\u00e9 Ronaldo(DEM) , desmentindo afirma\u00e7\u00f5es do l\u00edder do governo Wagner na Assembleia Legislativa, o deputado Z\u00e9 Neto(PT), acerca da avenida Ayrton Sena. Neto declarou que a continuidade das obras daquela avenida dependiam de licen\u00e7as da Prefeitura de Feira, garantindo que\u2026","rel":"","context":"Em &quot;Home&quot;","block_context":{"text":"Home","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/raiz\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"_links":{"self":[{"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/posts\/49342","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/comments?post=49342"}],"version-history":[{"count":2,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/posts\/49342\/revisions"}],"predecessor-version":[{"id":49396,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/posts\/49342\/revisions\/49396"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/media\/49343"}],"wp:attachment":[{"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/media?parent=49342"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/categories?post=49342"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/tags?post=49342"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}