{"id":49387,"date":"2021-12-14T18:37:26","date_gmt":"2021-12-14T21:37:26","guid":{"rendered":"https:\/\/blogdafeira.com.br\/home\/?p=49387"},"modified":"2021-12-16T23:18:06","modified_gmt":"2021-12-17T02:18:06","slug":"decoracao-natalina-virou-genero-de-primeira-necessidade","status":"publish","type":"post","link":"https:\/\/blogdafeira.com.br\/home\/2021\/12\/14\/decoracao-natalina-virou-genero-de-primeira-necessidade\/","title":{"rendered":"Decora\u00e7\u00e3o natalina virou g\u00eanero de primeira necessidade"},"content":{"rendered":"<div id=\"blogd-1958459890\" class=\"blogd-fim-do-post-mobile blogd-entity-placement\" style=\"margin-left: auto;margin-right: auto;text-align: center;\"><a href=\"https:\/\/www.feiradesantana.ba.gov.br\/servico.asp?s=a&titulo=Prefeitura-de-Feira-lan%C3%A7a-programa-Rem%C3%A9dio-em-Casa-e-transforma-acesso-a-medicamentos-em-pol%C3%ADtica-p%C3%BAblica-de-cuidados.html&id=14&link=secom\/noticias.asp&idn=43684#noticias\" target=_blank><picture>\r\n  <source media=\"(min-width: 768px)\" srcset=\"https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2026\/03\/980x150.gif\">\r\n  \r\n  <img decoding=\"async\" src=\"https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2021\/01\/350x2002.gif\" alt=\"Publicidade\" style=\"width: 100%; max-width: 100%; height: auto; display: block; margin: 0 auto;\">\r\n\t<\/picture><\/a><\/div><p style=\"text-align: justify;\">Decora\u00e7\u00e3o natalina virou g\u00eanero de primeira necessidade no Brasil. Pelo menos \u00e9 o que denota a ansiedade e a expectativa que tomam conta das pessoas \u00e0 espera das luzes e cores dos pisca-piscas. Quem acompanha as m\u00eddias sociais de prefeituras fica impressionado: as inaugura\u00e7\u00f5es s\u00e3o apote\u00f3ticas, provocam aglomera\u00e7\u00e3o \u2013 embora boa parte do p\u00fablico tenha l\u00e1 seus v\u00ednculos com o prefeito de plant\u00e3o \u2013 e o que se v\u00ea s\u00e3o elogios, gente feliz fazendo <em>selfie, <\/em>exultante com mais um Natal.<\/p>\n<p style=\"text-align: justify;\">No fundo, \u00e9 isso: a decora\u00e7\u00e3o natalina serve para as <em>selfies<\/em>, que v\u00e3o ficar em permanente exibi\u00e7\u00e3o nas m\u00eddias sociais. Quanto mais decorada a cidade \u2013 j\u00e1 h\u00e1 disputa at\u00e9 entre prefeituras \u2013 mais fotos, mais repercuss\u00e3o e mais elogios. Reunir familiares, amigos, conhecidos, colegas de trabalho para o tradicional autorretrato se tornou um ritual. Quem n\u00e3o o faz \u00e9 um insens\u00edvel, n\u00e3o registra os bons momentos da vida.<\/p>\n<p style=\"text-align: justify;\">No interior do Brasil a ilumina\u00e7\u00e3o \u00e0 noite costuma ser tristonha, at\u00e9 melanc\u00f3lica. Focos esparsos de luz espantam precariamente a escurid\u00e3o que sitia os pequenos lugarejos. Da\u00ed, talvez, a ilumina\u00e7\u00e3o generosa, o \u00eaxtase de crian\u00e7as e adultos \u2013 muita gente grande infantiliza-se diante dos pisca-piscas \u2013 e as entusiasmadas congratula\u00e7\u00f5es aos prefeitos no Natal de luzes e cores.<\/p>\n<p style=\"text-align: justify;\">Mas mesmo as metr\u00f3poles profusamente iluminadas rendem-se aos apelos das <em>selfies<\/em> sob as l\u00e2mpadas natalinas. \u00c9 o caso de S\u00e3o Paulo, do Rio de Janeiro, mesmo das demais metr\u00f3poles brasileiras. Parece que as silhuetas iluminadas das \u00e1rvores, dos anjos, dos reis magos, do Papai Noel, despertam um desejo irreprim\u00edvel pelo autorretrato. E revertem-se em popularidade para os prefeitos.<\/p>\n<p style=\"text-align: justify;\">A pandemia que permanece a\u00ed e n\u00e3o acabou, os brasileiros fam\u00e9licos garimpando restos de comida, os biscateiros rotulados como empreendedores, os desempregados e a iniquidade no Planalto Central, nada disso comove ou mobiliza o brasileiro. S\u00f3 a decora\u00e7\u00e3o natalina para emprestar um ar de novidade \u00e0s irreprim\u00edveis <em>selfies<\/em>.<\/p>\n<p style=\"text-align: justify;\">Nesses insanos dezembros, daqui a pouco come\u00e7am a classificar decora\u00e7\u00e3o natalina como pol\u00edtica p\u00fablica. Nos parlamentos, deputados apresentar\u00e3o emendas, esfregando gostosamente as pan\u00e7as nos balc\u00f5es do toma-l\u00e1-d\u00e1-c\u00e1; prefeitos alicer\u00e7ar\u00e3o suas campanhas reeleitorais com a decora\u00e7\u00e3o natalina; o povo, feliz, tratar\u00e1 de providenciar cr\u00e9ditos para os celulares, afoito para renovar seu repert\u00f3rio de autorretratos nas m\u00eddias sociais.<\/p>\n<div id=\"blogd-1991546332\" class=\"blogd-final-post blogd-entity-placement\"><a href=\"https:\/\/www.feiradesantana.ba.leg.br\/\" target=\"_blank\" aria-label=\"JUNHO-VERMELHO_CA\u0302MARA-DE-FEIRA\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2026\/03\/JUNHO-VERMELHO_CAMARA-DE-FEIRA.gif\" alt=\"\"  class=\"no-lazyload\" width=\"728\" height=\"90\"   \/><\/a><\/div><p style=\"text-align: justify;\">N\u00e3o falta quem enxergue vazio e vacuidade nessa moda de filmar-se ou fotografar-se feito estrela de cinema o tempo todo. Tudo bem. Mas, pelo que se percebe, o povo est\u00e1 marcado l\u00e1 nas m\u00eddias sociais, mas est\u00e1 feliz, conforme a cl\u00e1ssica can\u00e7\u00e3o de Z\u00e9 Ramalho&#8230;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Decora\u00e7\u00e3o natalina virou g\u00eanero de primeira necessidade no Brasil. Pelo menos \u00e9 o que denota a ansiedade e a expectativa que tomam conta das pessoas \u00e0 espera das luzes e cores dos pisca-piscas. Quem acompanha as m\u00eddias sociais de prefeituras fica impressionado: as inaugura\u00e7\u00f5es s\u00e3o apote\u00f3ticas, provocam aglomera\u00e7\u00e3o \u2013 embora boa parte do p\u00fablico tenha<\/p>\n","protected":false},"author":13,"featured_media":7484,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"cybocfi_hide_featured_image":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[592,1],"tags":[],"class_list":["post-49387","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-colunistas","category-raiz"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2013\/12\/NATAL.jpg","jetpack_shortlink":"https:\/\/wp.me\/p3niVf-cQz","jetpack_sharing_enabled":true,"jetpack-related-posts":[{"id":64692,"url":"https:\/\/blogdafeira.com.br\/home\/2024\/11\/25\/manifesto-por-mais-decoracao-natalina\/","url_meta":{"origin":49387,"position":0},"title":"Manifesto por mais decora\u00e7\u00e3o natalina","author":"Andr\u00e9 Pomponet","date":"25\/11\/2024","format":false,"excerpt":"Vai chegando o Natal e os prefeitos \u2013 os reeleitos \u2013 come\u00e7am a se mexer para garantir a decora\u00e7\u00e3o natalina. Afinal, a popula\u00e7\u00e3o espera capricho em luzes e adere\u00e7os para garantir aquelas selfies que v\u00e3o circular entre amigos, nos grupos familiares e tamb\u00e9m viralizar nas m\u00eddias digitais. Decora\u00e7\u00e3o natalina aumenta\u2026","rel":"","context":"Em &quot;Colunistas&quot;","block_context":{"text":"Colunistas","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/colunistas\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2024\/11\/images-10.jpeg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":55842,"url":"https:\/\/blogdafeira.com.br\/home\/2022\/12\/12\/colbert-inaugura-decoracao-natalina-no-centro-historico-de-feira\/","url_meta":{"origin":49387,"position":1},"title":"Colbert inaugura decora\u00e7\u00e3o natalina no centro hist\u00f3rico de Feira","author":"Blog da Feira","date":"12\/12\/2022","format":false,"excerpt":"As luzes e o sentimento natalino tomaram conta do Cal\u00e7ad\u00e3o da Sales Babosa com a inaugura\u00e7\u00e3o da decora\u00e7\u00e3o na noite desta segunda-feira (12), depois que o prefeito de Feira de Santana, Colbert Filho (MDB) inaugurou os modernos cen\u00e1rios em Led e totalmente instagram\u00e1veis - espa\u00e7os pensados para despertar no feirense\u2026","rel":"","context":"Em &quot;Cidade&quot;","block_context":{"text":"Cidade","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/cidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2022\/12\/thumbnail_Inauguracao-da-iluminacao-de-natal-12-2-2022-Foto-Izinaldo-Barreto-38.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2022\/12\/thumbnail_Inauguracao-da-iluminacao-de-natal-12-2-2022-Foto-Izinaldo-Barreto-38.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2022\/12\/thumbnail_Inauguracao-da-iluminacao-de-natal-12-2-2022-Foto-Izinaldo-Barreto-38.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2022\/12\/thumbnail_Inauguracao-da-iluminacao-de-natal-12-2-2022-Foto-Izinaldo-Barreto-38.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2022\/12\/thumbnail_Inauguracao-da-iluminacao-de-natal-12-2-2022-Foto-Izinaldo-Barreto-38.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":55752,"url":"https:\/\/blogdafeira.com.br\/home\/2022\/12\/06\/decoracao-natalina-no-centro-de-feira-tem-tunel-de-led-e-arvore-de-9-metros\/","url_meta":{"origin":49387,"position":2},"title":"Decora\u00e7\u00e3o natalina no centro de Feira tem t\u00fanel de LED e \u00e1rvore de 9 metros","author":"Blog da Feira","date":"06\/12\/2022","format":false,"excerpt":"O cal\u00e7ad\u00e3o da Sales Barbosa vai ganhar um t\u00fanel vermelho com l\u00e2mpadas LED, cujas estruturas b\u00e1sicas j\u00e1 est\u00e3o no lugar, pr\u00f3ximo ao Mercado de Arte Popular (MAP) . Os postes ser\u00e3o decorados com arandelas, enquanto as palmeiras receber\u00e3o mangueiras em LED. Em frente \u00e0 Igreja dos Rem\u00e9dios ser\u00e1 montada uma\u2026","rel":"","context":"Em &quot;Cidade&quot;","block_context":{"text":"Cidade","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/cidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2022\/12\/WhatsApp-Image-2022-12-06-at-11_40_31.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2022\/12\/WhatsApp-Image-2022-12-06-at-11_40_31.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2022\/12\/WhatsApp-Image-2022-12-06-at-11_40_31.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2022\/12\/WhatsApp-Image-2022-12-06-at-11_40_31.jpeg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":64897,"url":"https:\/\/blogdafeira.com.br\/home\/2024\/12\/16\/prefeitura-de-lencois-criticada-por-ausencia-de-programacao-e-decoracao-natalinas\/","url_meta":{"origin":49387,"position":3},"title":"Prefeitura de Len\u00e7\u00f3is criticada por aus\u00eancia de programa\u00e7\u00e3o e decora\u00e7\u00e3o natalinas","author":"Blog da Feira","date":"16\/12\/2024","format":false,"excerpt":"A cidade de Len\u00e7\u00f3is, um dos principais destinos tur\u00edsticos da Bahia, est\u00e1 enfrentando duras cr\u00edticas por parte de comerciantes e moradores devido \u00e0 aus\u00eancia de programa\u00e7\u00e3o e decora\u00e7\u00e3o natalina neste fim de ano. Faltando poucos dias para o Natal e o R\u00e9veillon, n\u00e3o h\u00e1 informa\u00e7\u00f5es oficiais sobre celebra\u00e7\u00f5es ou iniciativas\u2026","rel":"","context":"Em &quot;Cidade&quot;","block_context":{"text":"Cidade","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/cidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2024\/12\/IMG-20241215-WA0028.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2024\/12\/IMG-20241215-WA0028.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2024\/12\/IMG-20241215-WA0028.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2024\/12\/IMG-20241215-WA0028.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2024\/12\/IMG-20241215-WA0028.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":60424,"url":"https:\/\/blogdafeira.com.br\/home\/2023\/12\/12\/decoracao-natalina-vermelha-e-verde-no-centro-de-feira\/","url_meta":{"origin":49387,"position":4},"title":"Decora\u00e7\u00e3o natalina vermelha e verde no centro de Feira","author":"J\u00e2nio R\u00eago","date":"12\/12\/2023","format":false,"excerpt":"Feira de Santana se prepara para as comemora\u00e7\u00f5es natalinas e de final de ano. A cidade recebe pe\u00e7as decorativas com os tradicionais s\u00edmbolos da \u00e9poca, que enfeitam a avenida Get\u00falio Vargas, o Cal\u00e7ad\u00e3o da Sales Barbosa e o Pa\u00e7o Municipal Maria Quit\u00e9ria (sede da Prefeitura). A decora\u00e7\u00e3o tem\u00e1tica nas cores\u2026","rel":"","context":"Em &quot;Cidade&quot;","block_context":{"text":"Cidade","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/cidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2023\/12\/DECORACAO-DE-NATAL-FOTO-VALDENIR-LIMA-122.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2023\/12\/DECORACAO-DE-NATAL-FOTO-VALDENIR-LIMA-122.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2023\/12\/DECORACAO-DE-NATAL-FOTO-VALDENIR-LIMA-122.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2023\/12\/DECORACAO-DE-NATAL-FOTO-VALDENIR-LIMA-122.jpeg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2023\/12\/DECORACAO-DE-NATAL-FOTO-VALDENIR-LIMA-122.jpeg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":5931,"url":"https:\/\/blogdafeira.com.br\/home\/2013\/11\/06\/decoracao-natalina-do-boulevard-de-feira-e-uma-estacao-de-trem\/","url_meta":{"origin":49387,"position":5},"title":"Decora\u00e7\u00e3o natalina do Boulevard de Feira \u00e9 uma Esta\u00e7\u00e3o de Trem","author":"Blog da Feira","date":"06\/11\/2013","format":false,"excerpt":"A decora\u00e7\u00e3o natalina que o Boulevard Shopping inaugura nesta quinta-feira, 7, \u00e0s 16 horas, com a festiva \u2018Chegada de Papai Noel\u2019 \u00a0tem 120m\u00b2 de \u00e1rea, e representar\u00e1 o m\u00e1gico ambiente de uma \u2018Esta\u00e7\u00e3o de Trem\u2019. A pe\u00e7a principal da decora\u00e7\u00e3o \u00e9 um vag\u00e3o de 5 metros de comprimento que solta\u2026","rel":"","context":"Em &quot;Home&quot;","block_context":{"text":"Home","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/raiz\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"_links":{"self":[{"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/posts\/49387","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/comments?post=49387"}],"version-history":[{"count":2,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/posts\/49387\/revisions"}],"predecessor-version":[{"id":49395,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/posts\/49387\/revisions\/49395"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/media\/7484"}],"wp:attachment":[{"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/media?parent=49387"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/categories?post=49387"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/tags?post=49387"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}