{"id":49769,"date":"2022-01-02T19:32:36","date_gmt":"2022-01-02T22:32:36","guid":{"rendered":"https:\/\/blogdafeira.com.br\/home\/?p=49769"},"modified":"2022-01-04T19:33:19","modified_gmt":"2022-01-04T22:33:19","slug":"oito-casos-de-covid19-em-feira-confirmados-neste-domingo","status":"publish","type":"post","link":"https:\/\/blogdafeira.com.br\/home\/2022\/01\/02\/oito-casos-de-covid19-em-feira-confirmados-neste-domingo\/","title":{"rendered":"Oito casos de Covid19 em Feira confirmados neste domingo"},"content":{"rendered":"<div id=\"blogd-2352696686\" class=\"blogd-fim-do-post-mobile blogd-entity-placement\" style=\"margin-left: auto;margin-right: auto;text-align: center;\"><a href=\"https:\/\/www.feiradesantana.ba.gov.br\/servico.asp?s=a&titulo=Prefeitura-de-Feira-lan%C3%A7a-programa-Rem%C3%A9dio-em-Casa-e-transforma-acesso-a-medicamentos-em-pol%C3%ADtica-p%C3%BAblica-de-cuidados.html&id=14&link=secom\/noticias.asp&idn=43684#noticias\" target=_blank><picture>\r\n  <source media=\"(min-width: 768px)\" srcset=\"https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2026\/03\/980x150.gif\">\r\n  \r\n  <img decoding=\"async\" src=\"https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2021\/01\/350x2002.gif\" alt=\"Publicidade\" style=\"width: 100%; max-width: 100%; height: auto; display: block; margin: 0 auto;\">\r\n\t<\/picture><\/a><\/div><p style=\"text-align: justify;\">Neste domingo (02), Feira de Santana registrou apenas oito casos positivos da Covid-19 e manteve a marca de 48.888 curados da doen\u00e7a, \u00edndice que representa 93,8% dos casos confirmados. Enquanto isso, mais 174 exames foram negativos.<\/p>\n<p style=\"text-align: justify;\">Os resultados positivos de hoje s\u00e3o em rela\u00e7\u00e3o a libera\u00e7\u00e3o dos exames acumulados que haviam realizado coleta entre os dias 28 de novembro e 31 de dezembro que estavam aguardando resultado do laborat\u00f3rio.<br \/>\nO boletim epidemiol\u00f3gico contabiliza ainda 12 pacientes internados no munic\u00edpio. As informa\u00e7\u00f5es s\u00e3o da Vigil\u00e2ncia Epidemiol\u00f3gica da Secretaria de Sa\u00fade.<\/p>\n<p style=\"text-align: justify;\">Relat\u00f3rio sobre Covid-19 em Feira de Santana<br \/>\n*N\u00daMEROS DESTE DOMINGO*<br \/>\n02 de janeiro de 2022<\/p>\n<p style=\"text-align: justify;\">Casos confirmados no dia: 8<br \/>\nPacientes recuperados no dia: 0<br \/>\nResultados negativos no dia: 174<br \/>\nTotal de pacientes hospitalizados no munic\u00edpio: 12<br \/>\n\u00d3bito comunicado no dia: 0<\/p>\n<p style=\"text-align: justify;\">*N\u00daMEROS TOTAIS*<\/p>\n<p style=\"text-align: justify;\">Total de pacientes ativos: 145 (Dados da Sesab)<br \/>\nTotal de casos confirmados no munic\u00edpio: 52.124 (Per\u00edodo de 06 de mar\u00e7o de 2020 a 02 de janeiro de 2022)<br \/>\nTotal de pacientes em isolamento domiciliar: 2.211<br \/>\nTotal de recuperados no munic\u00edpio: 48.888<br \/>\nTotal de exames negativos: 86.066 (Per\u00edodo de 06 de mar\u00e7o de 2020 a 02 de janeiro de 2022)<br \/>\nAguardando resultado do exame: 142<br \/>\nTotal de \u00f3bitos: 1.013<\/p>\n<p style=\"text-align: justify;\">*INFORMA\u00c7\u00d5ES TESTES R\u00c1PIDOS*<\/p>\n<p style=\"text-align: justify;\">Total de testes r\u00e1pidos realizados: 26.221 (Per\u00edodo de 06 de mar\u00e7o de 2020 a 02 de janeiro de 2022)<br \/>\nResultado positivo: 5.142 (Per\u00edodo de 06 de mar\u00e7o de 2020 a 02 de janeiro de 2022)<br \/>\nEm isolamento domiciliar: 0<br \/>\nResultado negativo: 21.079 (Per\u00edodo de 06 de mar\u00e7o de 2020 a 02 de janeiro de 2022)<\/p>\n<div id=\"blogd-3208248405\" class=\"blogd-final-post blogd-entity-placement\"><a href=\"https:\/\/www.feiradesantana.ba.leg.br\/\" target=\"_blank\" aria-label=\"JUNHO-VERMELHO_CA\u0302MARA-DE-FEIRA\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2026\/03\/JUNHO-VERMELHO_CAMARA-DE-FEIRA.gif\" alt=\"\"  class=\"no-lazyload\" width=\"728\" height=\"90\"   \/><\/a><\/div><p style=\"text-align: justify;\">O teste r\u00e1pido isoladamente n\u00e3o confirma nem exclui completamente o diagn\u00f3stico para Covid-19, devendo ser usado como um teste para aux\u00edlio diagn\u00f3stico, conforme a nota t\u00e9cnica COE Sa\u00fade N\u00ba 54 de 08 de abril de 2020 (atualizada em 04\/06\/20).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Neste domingo (02), Feira de Santana registrou apenas oito casos positivos da Covid-19 e manteve a marca de 48.888 curados da doen\u00e7a, \u00edndice que representa 93,8% dos casos confirmados. Enquanto isso, mais 174 exames foram negativos. Os resultados positivos de hoje s\u00e3o em rela\u00e7\u00e3o a libera\u00e7\u00e3o dos exames acumulados que haviam realizado coleta entre os<\/p>\n","protected":false},"author":1,"featured_media":49489,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"cybocfi_hide_featured_image":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[3,1],"tags":[],"class_list":["post-49769","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cidade","category-raiz"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2021\/12\/vacnanan.jpg","jetpack_shortlink":"https:\/\/wp.me\/p3niVf-cWJ","jetpack_sharing_enabled":true,"jetpack-related-posts":[{"id":46497,"url":"https:\/\/blogdafeira.com.br\/home\/2021\/07\/18\/covid-19-feira-registra-mais-156-casos-neste-domingo\/","url_meta":{"origin":49769,"position":0},"title":"Covid-19: Feira registra mais 156 casos neste domingo","author":"Secom\/FSA","date":"18\/07\/2021","format":false,"excerpt":"*Covid-19: Feira de Santana registra mais 156 casos neste domingo (18)* Feira de Santana n\u00e3o registrou nenhuma morte por Covid-19, nas \u00faltimas 24h. O munic\u00edpio atingiu a marca de 41.140 curados da doen\u00e7a, \u00edndice que representa 85,3% dos casos confirmados. Enquanto isso, 36 exames foram negativos e 156 positivos. Os\u2026","rel":"","context":"Em &quot;Cidade&quot;","block_context":{"text":"Cidade","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/cidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2021\/06\/corona-420x280_c-420x280_c.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":45330,"url":"https:\/\/blogdafeira.com.br\/home\/2021\/05\/09\/covid-19-mais-95-casos-confirmados-neste-domingo\/","url_meta":{"origin":49769,"position":1},"title":"Covid-19: mais 95 casos confirmados neste domingo","author":"Secom\/FSA","date":"09\/05\/2021","format":false,"excerpt":"Feira de Santana est\u00e1 perto de superar a marca de 31 mil recuperados da Covid-19. At\u00e9 agora, s\u00e3o exatamente 30.967 pacientes livres da doen\u00e7a, \u00edndice que representa 82,5% dos casos confirmados. Al\u00e9m disso, nas \u00faltimas 24h foram registrados 163 exames negativos para o v\u00edrus e 95 casos positivos. O boletim\u2026","rel":"","context":"Em &quot;Geral&quot;","block_context":{"text":"Geral","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/geral\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2021\/05\/corona-420x280_c.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":45550,"url":"https:\/\/blogdafeira.com.br\/home\/2021\/05\/23\/mais-de-30-mil-pacientes-com-covid19-recuperados-em-feira\/","url_meta":{"origin":49769,"position":2},"title":"Mais de 30 mil pacientes com Covid19 recuperados em Feira","author":"Secom\/FSA","date":"23\/05\/2021","format":false,"excerpt":"Feira de Santana n\u00e3o registrou nenhuma morte por Covid-19, nas \u00faltimas 24h. At\u00e9 agora s\u00e3o exatamente 33.720 pacientes recuperados, \u00edndice que representa 87,3% dos casos confirmados. Enquanto isso, 51 exames foram negativos e 48 positivos. O boletim epidemiol\u00f3gico contabiliza ainda 126 pacientes internados no munic\u00edpio e 4.170 casos ativos, ou\u2026","rel":"","context":"Em &quot;Cidade&quot;","block_context":{"text":"Cidade","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/cidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2021\/05\/corona-420x280_c.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":39434,"url":"https:\/\/blogdafeira.com.br\/home\/2020\/08\/07\/covid19-feira-tem-7-641-casos-confirmados-com-1-705-ativos\/","url_meta":{"origin":49769,"position":3},"title":"Covid19: Feira tem 7.641 casos confirmados, com 1.705 ativos","author":"Secom\/FSA","date":"07\/08\/2020","format":false,"excerpt":"A Prefeitura de Feira de Santana, atrav\u00e9s da Divis\u00e3o de Vigil\u00e2ncia Epidemiol\u00f3gica da Secretaria Municipal de Sa\u00fade, divulgou os dados do boletim epidemiol\u00f3gico da Covid-19 no Munic\u00edpio nesta sexta-feira (07). Nas \u00faltimas 24h, 73 novos casos foram confirmados e outras 35 pessoas est\u00e3o recuperadas da doen\u00e7a. Apesar do munic\u00edpio alcan\u00e7ar\u2026","rel":"","context":"Em &quot;Cidade&quot;","block_context":{"text":"Cidade","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/cidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2020\/06\/campanha.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2020\/06\/campanha.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2020\/06\/campanha.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2020\/06\/campanha.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2020\/06\/campanha.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":47978,"url":"https:\/\/blogdafeira.com.br\/home\/2021\/11\/01\/apenas-um-caso-positivo-de-covid-19-registrado-nesta-segunda-1-em-feira\/","url_meta":{"origin":49769,"position":4},"title":"Apenas um caso positivo de Covid-19 registrado nesta segunda (1) em Feira","author":"Secom\/FSA","date":"01\/11\/2021","format":false,"excerpt":"Feira de Santana registrou apenas um caso positivo da Covid-19 nesta segunda-feira (01). O munic\u00edpio manteve a marca de 48.242 curados da doen\u00e7a, \u00edndice que representa 94,7% dos casos confirmados. Enquanto isso, mais tr\u00eas exames foram negativos. Os resultados positivos de hoje s\u00e3o em rela\u00e7\u00e3o a libera\u00e7\u00e3o dos exames acumulados\u2026","rel":"","context":"Em &quot;Cidade&quot;","block_context":{"text":"Cidade","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/cidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2021\/11\/01112021182651.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2021\/11\/01112021182651.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2021\/11\/01112021182651.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2021\/11\/01112021182651.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2021\/11\/01112021182651.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":49499,"url":"https:\/\/blogdafeira.com.br\/home\/2021\/12\/20\/48-854-pessoas-curadas-de-covid19-na-feira-de-santana\/","url_meta":{"origin":49769,"position":5},"title":"48.854 pessoas curadas de Covid19 na Feira de Santana","author":"Secom\/FSA","date":"20\/12\/2021","format":false,"excerpt":"Nesta segunda-feira (20), Feira de Santana registrou 69 pacientes recuperados da Covid-19 e atingiu a marca de 48.854 curados da doen\u00e7a, \u00edndice que representa 94% dos casos confirmados. Exames da Covid-19 coletados entre os dias 15 de novembro e 18 de dezembro, ou seja, mais de um m\u00eas, confirmaram 42\u2026","rel":"","context":"Em &quot;Cidade&quot;","block_context":{"text":"Cidade","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/cidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2021\/12\/20122021160108.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2021\/12\/20122021160108.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2021\/12\/20122021160108.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2021\/12\/20122021160108.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2021\/12\/20122021160108.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/posts\/49769","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/comments?post=49769"}],"version-history":[{"count":2,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/posts\/49769\/revisions"}],"predecessor-version":[{"id":49824,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/posts\/49769\/revisions\/49824"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/media\/49489"}],"wp:attachment":[{"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/media?parent=49769"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/categories?post=49769"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/tags?post=49769"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}