{"id":49966,"date":"2022-01-09T17:58:11","date_gmt":"2022-01-09T20:58:11","guid":{"rendered":"https:\/\/blogdafeira.com.br\/home\/?p=49966"},"modified":"2022-01-12T13:09:54","modified_gmt":"2022-01-12T16:09:54","slug":"jornalismo-feirense-perde-socorro-pitombo-uma-de-suas-maiores-referencias","status":"publish","type":"post","link":"https:\/\/blogdafeira.com.br\/home\/2022\/01\/09\/jornalismo-feirense-perde-socorro-pitombo-uma-de-suas-maiores-referencias\/","title":{"rendered":"Jornalismo feirense perde Socorro Pitombo, uma de suas maiores refer\u00eancias"},"content":{"rendered":"<div id=\"blogd-1366456593\" class=\"blogd-fim-do-post-mobile blogd-entity-placement\" style=\"margin-left: auto;margin-right: auto;text-align: center;\"><a href=\"https:\/\/www.feiradesantana.ba.gov.br\/servico.asp?s=a&titulo=Prefeitura-de-Feira-lan%C3%A7a-programa-Rem%C3%A9dio-em-Casa-e-transforma-acesso-a-medicamentos-em-pol%C3%ADtica-p%C3%BAblica-de-cuidados.html&id=14&link=secom\/noticias.asp&idn=43684#noticias\" target=_blank><picture>\r\n  <source media=\"(min-width: 768px)\" srcset=\"https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2026\/03\/980x150.gif\">\r\n  \r\n  <img decoding=\"async\" src=\"https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2021\/01\/350x2002.gif\" alt=\"Publicidade\" style=\"width: 100%; max-width: 100%; height: auto; display: block; margin: 0 auto;\">\r\n\t<\/picture><\/a><\/div><p style=\"text-align: justify;\">Grande refer\u00eancia do jornalismo feirense e baiano, a jornalista Socorro Pitombo Cristo faleceu na manh\u00e3 deste domingo (9), aos 78 anos, em decorr\u00eancia de problemas cardiorrespirat\u00f3rios.<\/p>\n<p style=\"text-align: justify;\">Ela estava internada h\u00e1 cerca de 20 dias no Hospital da Bahia, em Salvador, onde passou por um procedimento cir\u00fargico. A jornalista deixa tr\u00eas filhos \u2013 Renata, Lara e Raphael Pitombo \u2013 e uma legi\u00e3o de amigos.<\/p>\n<p style=\"text-align: justify;\">Por onde passou, em sua trajet\u00f3ria profissional, Socorro deixou marcas indel\u00e9veis. Fazia do jornalismo a sua vida, o que inspirou muitas gera\u00e7\u00f5es de comunicadores. Passou por reda\u00e7\u00f5es de jornais, que definia como as verdadeiras escolas de jornalismo, e pelas assessorias de comunica\u00e7\u00e3o da Universidade Estadual de Feira de Santana (Uefs) e da UniFTC que se destacou no exerc\u00edcio da profiss\u00e3o que amava e, sobretudo, acreditava.<\/p>\n<p style=\"text-align: justify;\">O corpo da jornalista ser\u00e1 velado no Centro de Vel\u00f3rios Pax Bahia, no bairro SIM, e o sepultamento est\u00e1 marcado para as 11h desta segunda-feira (10), no Cemit\u00e9rio Piedade, centro da cidade.<\/p>\n<p style=\"text-align: justify;\"><em><strong>Madalena de Jesus \u00e9 jornalista e amiga<\/strong>.<\/em><\/p>\n<p style=\"text-align: justify;\"><em>Nota do BF<strong>: A jornalista Socorro Pitombo era nossa colaboradora, assinando uma coluna de opini\u00e3o. Abaixo, o \u00faltimo texto de Socorro publicado aqui no BF:<\/strong><\/em><\/p>\n<div id=\"blogd-2282085306\" class=\"blogd-final-post blogd-entity-placement\"><a href=\"https:\/\/www.feiradesantana.ba.leg.br\/\" target=\"_blank\" aria-label=\"JUNHO-VERMELHO_CA\u0302MARA-DE-FEIRA\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2026\/03\/JUNHO-VERMELHO_CAMARA-DE-FEIRA.gif\" alt=\"\"  class=\"no-lazyload\" width=\"728\" height=\"90\"   \/><\/a><\/div><blockquote class=\"wp-embedded-content\" data-secret=\"7VYnCtzV3Q\"><p><a href=\"https:\/\/blogdafeira.com.br\/home\/2021\/08\/22\/reminiscencias-de-uma-reporter-como-se-fazia-jornalismo-sem-internet-por-socorro-pitombo\/\">Reminisc\u00eancias de uma rep\u00f3rter: como se fazia jornalismo sem internet<\/a><\/p><\/blockquote>\n<p><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; clip: rect(1px, 1px, 1px, 1px);\" title=\"&#8220;Reminisc\u00eancias de uma rep\u00f3rter: como se fazia jornalismo sem internet&#8221; &#8212; Blog da Feira\" src=\"https:\/\/blogdafeira.com.br\/home\/2021\/08\/22\/reminiscencias-de-uma-reporter-como-se-fazia-jornalismo-sem-internet-por-socorro-pitombo\/embed\/#?secret=7VYnCtzV3Q\" data-secret=\"7VYnCtzV3Q\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe><\/p>\n\n","protected":false},"excerpt":{"rendered":"<p>Grande refer\u00eancia do jornalismo feirense e baiano, a jornalista Socorro Pitombo Cristo faleceu na manh\u00e3 deste domingo (9), aos 78 anos, em decorr\u00eancia de problemas cardiorrespirat\u00f3rios. Ela estava internada h\u00e1 cerca de 20 dias no Hospital da Bahia, em Salvador, onde passou por um procedimento cir\u00fargico. A jornalista deixa tr\u00eas filhos \u2013 Renata, Lara e<\/p>\n","protected":false},"author":1,"featured_media":49967,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"cybocfi_hide_featured_image":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[3,1],"tags":[],"class_list":["post-49966","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cidade","category-raiz"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2022\/01\/Screenshot_20220109-1753182.png","jetpack_shortlink":"https:\/\/wp.me\/p3niVf-cZU","jetpack_sharing_enabled":true,"jetpack-related-posts":[{"id":32390,"url":"https:\/\/blogdafeira.com.br\/home\/2019\/08\/16\/jornalista-socorro-pitombo-integra-o-time-de-colunistas-no-blog-da-feira\/","url_meta":{"origin":49966,"position":0},"title":"Jornalista Socorro Pitombo integra o time de colunistas no Blog da Feira","author":"Madalena de Jesus","date":"16\/08\/2019","format":false,"excerpt":"Socorro Pitombo nasceu em Feira de Santana. \u00c9 jornalista, forma\u00e7\u00e3o conferida pela Universidade Federal da Bahia (UFBA). Como profissional de imprensa passou pelo Jornal A Tarde e Jornal da Bahia, este \u00faltimo extinto h\u00e1 muitos anos. Atuou na Universidade Estadual de Feira de Santana (UEFS), como Assessora de Comunica\u00e7\u00e3o, e\u2026","rel":"","context":"Em &quot;Home&quot;","block_context":{"text":"Home","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/raiz\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2019\/08\/FB_IMG_1565981256509-300x300.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":49988,"url":"https:\/\/blogdafeira.com.br\/home\/2022\/01\/10\/nota-de-pesar-da-facom-da-ufba-pelo-falecimento-de-socorro-pitombo\/","url_meta":{"origin":49966,"position":1},"title":"Nota de pesar da Facom da UFBA pelo falecimento de Socorro Pitombo","author":"Madalena de Jesus","date":"10\/01\/2022","format":false,"excerpt":"NOTA DE PESAR A Faculdade de Comunica\u00e7\u00e3o vem por meio desta nota demonstrar seu profundo pesar pelo falecimento da jornalista Maria do Socorro Pitombo. Egressa do curso de Jornalismo da UFBA na \u00e9poca da antiga Escola de Biblioteconomia e Comunica\u00e7\u00e3o, Maria do Socorro Pitombo construiu uma respeitada e brilhante carreira.\u2026","rel":"","context":"Em &quot;Cidade&quot;","block_context":{"text":"Cidade","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/cidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2022\/01\/Faculdade-de-Comunicacao.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":16864,"url":"https:\/\/blogdafeira.com.br\/home\/2015\/09\/29\/ftc-em-feira-faz-homenagens-a-terezinha-mamoma-e-socorro-pitombo\/","url_meta":{"origin":49966,"position":2},"title":"FTC em Feira faz homenagens a Terezinha Mamoma e Socorro Pitombo","author":"Madalena de Jesus","date":"29\/09\/2015","format":false,"excerpt":"Emo\u00e7\u00e3o. Este foi o sentimento predominante na solenidade de inaugura\u00e7\u00e3o do Audit\u00f3rio Professora Terezinha Mamona, na FTC Feira de Santana, na tarde de sexta-feira (25). \u00c9 que, al\u00e9m da professora que d\u00e1 nome ao espa\u00e7o, a Institui\u00e7\u00e3o prestou homenagem tamb\u00e9m \u00e0 jornalista Socorro Pitombo, que deixa a unidade ap\u00f3s 12\u2026","rel":"","context":"Em &quot;Home&quot;","block_context":{"text":"Home","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/raiz\/"},"img":{"alt_text":"Homenagens e Inaugura\u00e7\u00e3o na FTC-Fotos Jorge Magalh\u00e3es (9)","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2015\/09\/Homenagens-e-Inaugura%C3%A7%C3%A3o-na-FTC-Fotos-Jorge-Magalh%C3%A3es-9.jpg?resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2015\/09\/Homenagens-e-Inaugura%C3%A7%C3%A3o-na-FTC-Fotos-Jorge-Magalh%C3%A3es-9.jpg?resize=350%2C200 1x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2015\/09\/Homenagens-e-Inaugura%C3%A7%C3%A3o-na-FTC-Fotos-Jorge-Magalh%C3%A3es-9.jpg?resize=525%2C300 1.5x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2015\/09\/Homenagens-e-Inaugura%C3%A7%C3%A3o-na-FTC-Fotos-Jorge-Magalh%C3%A3es-9.jpg?resize=700%2C400 2x"},"classes":[]},{"id":58551,"url":"https:\/\/blogdafeira.com.br\/home\/2023\/07\/06\/o-bando-e-os-becos\/","url_meta":{"origin":49966,"position":3},"title":"O Bando e os Becos","author":"Madalena de Jesus","date":"06\/07\/2023","format":false,"excerpt":"Em mem\u00f3ria da amiga jornalista Socorro Pitombo. Os Pitombos viveram e moraram ali pelo Beco do Moc\u00f3. Beto, o cantor, poeta, cujo corpo e alma vivem no mar de\u00a0 Imbassahy mas um dos cora\u00e7\u00f5es (ele tem muitos) est\u00e1 navegando sempre por aqui clique aqui; Dival, o ensa\u00edsta, pioneiro da UEFS,\u2026","rel":"","context":"Em &quot;Colunistas&quot;","block_context":{"text":"Colunistas","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/colunistas\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2023\/07\/Screenshot_20230706-082329.png?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2023\/07\/Screenshot_20230706-082329.png?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2023\/07\/Screenshot_20230706-082329.png?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2023\/07\/Screenshot_20230706-082329.png?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2023\/07\/Screenshot_20230706-082329.png?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":55386,"url":"https:\/\/blogdafeira.com.br\/home\/2022\/11\/15\/livro-e-desfile-colocam-moda-e-critica-em-debate\/","url_meta":{"origin":49966,"position":4},"title":"Livro e desfile colocam moda e cr\u00edtica em debate","author":"Madalena de Jesus","date":"15\/11\/2022","format":false,"excerpt":"Como avaliar o campo da moda, seus produtos e fluxos? Esta foi a indaga\u00e7\u00e3o inicial que deflagrou a reflex\u00e3o sobre a cr\u00edtica de moda e a realiza\u00e7\u00e3o do livro Moda e Cr\u00edtica: Prazer, Julgamento e Avalia\u00e7\u00e3o, da jornalista e pesquisadora Renata Pitombo Cidreira. O livro tem o selo da EDUFBA\u2026","rel":"","context":"Em &quot;Cultura&quot;","block_context":{"text":"Cultura","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/cultura\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2022\/11\/IMG-20221115-WA00292.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2022\/11\/IMG-20221115-WA00292.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2022\/11\/IMG-20221115-WA00292.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":26337,"url":"https:\/\/blogdafeira.com.br\/home\/2017\/03\/30\/tabuleiro-da-maria-livro-da-jornalista-madalena-de-jesus-lancado-hoje-no-cuca\/","url_meta":{"origin":49966,"position":5},"title":"&#8220;Tabuleiro da Maria&#8221;, livro da jornalista Madalena de Jesus lan\u00e7ado hoje no Cuca","author":"Madalena de Jesus","date":"30\/03\/2017","format":false,"excerpt":"\u201cCr\u00f4nicas s\u00e3o sobre fatos do cotidiano, mas estas falam sobre a alma humana\u201d. Esta \u00e9 a defini\u00e7\u00e3o do livro Tabuleiro da Maria, para o jornalista e escritor Marcondes Ara\u00fajo que aceitou a irrecus\u00e1vel tarefa de selecionar 50 textos tecidos com o talento de quem possui hist\u00f3rias no olhar. O t\u00edtulo\u2026","rel":"","context":"Em &quot;Home&quot;","block_context":{"text":"Home","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/raiz\/"},"img":{"alt_text":"madalena-de-jesus-autora-tabuleiro-da-maria","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2017\/03\/MADALENA-DE-JESUS-AUTORA-TABULEIRO-DA-MARIA-177x300.jpg?resize=350%2C200","width":350,"height":200},"classes":[]}],"_links":{"self":[{"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/posts\/49966","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/comments?post=49966"}],"version-history":[{"count":6,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/posts\/49966\/revisions"}],"predecessor-version":[{"id":50047,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/posts\/49966\/revisions\/50047"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/media\/49967"}],"wp:attachment":[{"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/media?parent=49966"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/categories?post=49966"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/tags?post=49966"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}