{"id":50122,"date":"2022-01-14T18:40:48","date_gmt":"2022-01-14T21:40:48","guid":{"rendered":"https:\/\/blogdafeira.com.br\/home\/?p=50122"},"modified":"2022-01-18T18:32:07","modified_gmt":"2022-01-18T21:32:07","slug":"vacinados-mas-sem-mascara","status":"publish","type":"post","link":"https:\/\/blogdafeira.com.br\/home\/2022\/01\/14\/vacinados-mas-sem-mascara\/","title":{"rendered":"Vacinados, mas sem m\u00e1scara"},"content":{"rendered":"<div id=\"blogd-2287249088\" class=\"blogd-fim-do-post-mobile blogd-entity-placement\" style=\"margin-left: auto;margin-right: auto;text-align: center;\"><a href=\"https:\/\/www.feiradesantana.ba.gov.br\/servico.asp?s=a&titulo=Prefeitura-de-Feira-lan%C3%A7a-programa-Rem%C3%A9dio-em-Casa-e-transforma-acesso-a-medicamentos-em-pol%C3%ADtica-p%C3%BAblica-de-cuidados.html&id=14&link=secom\/noticias.asp&idn=43684#noticias\" target=_blank><picture>\r\n  <source media=\"(min-width: 768px)\" srcset=\"https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2026\/03\/980x150.gif\">\r\n  \r\n  <img decoding=\"async\" src=\"https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2021\/01\/350x2002.gif\" alt=\"Publicidade\" style=\"width: 100%; max-width: 100%; height: auto; display: block; margin: 0 auto;\">\r\n\t<\/picture><\/a><\/div><p style=\"text-align: justify;\">Por um lado, o feirense est\u00e1 de parab\u00e9ns por se vacinar contra a Covid-19, apesar de todo o boicote da extrema-direita no poder l\u00e1 em Bras\u00edlia. Por outro lado, cuidados essenciais como o uso de m\u00e1scaras em ambientes externos \u2013 e at\u00e9 internos \u2013 est\u00e3o sendo abandonados, o que \u00e9 preocupante em fun\u00e7\u00e3o do avan\u00e7o da variante \u00d4micron, que j\u00e1 circula no munic\u00edpio. Para evitar press\u00f5es sobre os servi\u00e7os de sa\u00fade \u2013 alertam autoridades m\u00e9dicas \u2013 \u00e9 necess\u00e1rio manter os cuidados.<\/p>\n<p style=\"text-align: justify;\">At\u00e9 ontem (13) o vacin\u00f4metro da prefeitura feirense indicava que exatas 506.279 pessoas tomaram a primeira dose de alguma das vacinas. Estimativa do IBGE aponta que, no munic\u00edpio, residem 624.107 pessoas. Percentualmente, portanto, 81,12% dos feirenses deram in\u00edcio ao ciclo vacinal.<\/p>\n<p style=\"text-align: justify;\">Quem completou este ciclo vacinal \u2013 com as duas doses ou com a vacina de dose \u00fanica \u2013 correspondem a 71,75% da popula\u00e7\u00e3o ou 447.200 pessoas. \u00c9 um percentual respeit\u00e1vel, sobretudo quando se considera as incessantes campanhas antivacina conduzidas por matilhas de alucinados.<\/p>\n<p style=\"text-align: justify;\">O mesmo vacin\u00f4metro informa, tamb\u00e9m, que 80.427 pessoas j\u00e1 receberam a dose de refor\u00e7o. O n\u00famero equivale a 12,88% da popula\u00e7\u00e3o. Como a prote\u00e7\u00e3o mais efetiva contra a variante \u00d4micron depende desta terceira dose, \u00e9 bom intensificar a campanha para incentivar a dose de refor\u00e7o, advertindo sobre os riscos em caso de contamina\u00e7\u00e3o. A vacina protege \u2013 quem tem ju\u00edzo sabe \u2013 mas \u00e9 necess\u00e1rio estar em dia com a imuniza\u00e7\u00e3o.<\/p>\n<p style=\"text-align: justify;\">O cen\u00e1rio favor\u00e1vel em rela\u00e7\u00e3o \u00e0 vacina\u00e7\u00e3o talvez induza \u2013 erroneamente \u2013 as pessoas a relaxar nas medidas de prote\u00e7\u00e3o. Nos bairros feirenses quase n\u00e3o se v\u00ea gente com m\u00e1scara pelas ruas. Em muitos estabelecimentos comerciais os pr\u00f3prios trabalhadores n\u00e3o utilizam, penduram no queixo ou deixam o nariz de fora. No centro da cidade, o cen\u00e1rio \u00e9 um pouco melhor.<\/p>\n<p style=\"text-align: justify;\">\u00c9 claro que o come\u00e7o da vacina\u00e7\u00e3o infantil \u2013 a prefeitura j\u00e1 anunciou que come\u00e7a na segunda-feira (17) para o p\u00fablico de 5 a 11 anos \u2013 vai alavancar os percentuais de imuniza\u00e7\u00e3o, contribuindo para reduzir interna\u00e7\u00f5es, casos graves e mortes. Mas \u00e9 necess\u00e1rio manter a disciplina, sobretudo em rela\u00e7\u00e3o ao uso da m\u00e1scara, essencial para a prote\u00e7\u00e3o individual e coletiva.<\/p>\n<div id=\"blogd-1310868260\" class=\"blogd-final-post blogd-entity-placement\"><a href=\"https:\/\/www.feiradesantana.ba.leg.br\/\" target=\"_blank\" aria-label=\"JUNHO-VERMELHO_CA\u0302MARA-DE-FEIRA\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2026\/03\/JUNHO-VERMELHO_CAMARA-DE-FEIRA.gif\" alt=\"\"  class=\"no-lazyload\" width=\"728\" height=\"90\"   \/><\/a><\/div><p style=\"text-align: justify;\">O in\u00edcio da imuniza\u00e7\u00e3o infantil \u00e9 uma excelente not\u00edcia para come\u00e7ar o final de semana.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por um lado, o feirense est\u00e1 de parab\u00e9ns por se vacinar contra a Covid-19, apesar de todo o boicote da extrema-direita no poder l\u00e1 em Bras\u00edlia. Por outro lado, cuidados essenciais como o uso de m\u00e1scaras em ambientes externos \u2013 e at\u00e9 internos \u2013 est\u00e3o sendo abandonados, o que \u00e9 preocupante em fun\u00e7\u00e3o do avan\u00e7o<\/p>\n","protected":false},"author":13,"featured_media":50135,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"cybocfi_hide_featured_image":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[592,1],"tags":[],"class_list":["post-50122","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-colunistas","category-raiz"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2022\/01\/mascara-mika-baumeister-unsplash-scaled.jpg","jetpack_shortlink":"https:\/\/wp.me\/p3niVf-d2q","jetpack_sharing_enabled":true,"jetpack-related-posts":[{"id":50641,"url":"https:\/\/blogdafeira.com.br\/home\/2022\/02\/10\/vacinacao-avanca-mas-a-variante-omicron-tambem\/","url_meta":{"origin":50122,"position":0},"title":"Vacina\u00e7\u00e3o avan\u00e7a, mas a variante \u00f4micron tamb\u00e9m","author":"Andr\u00e9 Pomponet","date":"10\/02\/2022","format":false,"excerpt":"Analisando-se os dados recentes da Covid-19 na Feira de Santana, percebe-se que o munic\u00edpio segue na mesma toada. Por um lado, a vacina\u00e7\u00e3o avan\u00e7a e os n\u00fameros s\u00e3o superiores at\u00e9 \u00e0 m\u00e9dia nacional. Por outro lado, a altamente contagiosa variante \u00f4micron espalha-se com velocidade impressionante, embora a quantidade de \u00f3bitos\u2026","rel":"","context":"Em &quot;Colunistas&quot;","block_context":{"text":"Colunistas","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/colunistas\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2022\/02\/omicron.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2022\/02\/omicron.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2022\/02\/omicron.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2022\/02\/omicron.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2022\/02\/omicron.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":50446,"url":"https:\/\/blogdafeira.com.br\/home\/2022\/02\/01\/com-a-omicron-e-salve-se-quem-puder\/","url_meta":{"origin":50122,"position":1},"title":"Com a \u00f4micron, \u00e9 salve-se quem puder","author":"Andr\u00e9 Pomponet","date":"01\/02\/2022","format":false,"excerpt":"Impressionante o avan\u00e7o da variante \u00f4micron da Covid-19. Fico sabendo de casos de pessoas infectadas todos os dias. Felizmente, at\u00e9 aqui, n\u00e3o soube de nenhum fato mais grave. At\u00e9 porque boa parte da popula\u00e7\u00e3o j\u00e1 se vacinou \u2013 a aplica\u00e7\u00e3o da dose de refor\u00e7o vem acontecendo de maneira mais t\u00edmida\u2026","rel":"","context":"Em &quot;Colunistas&quot;","block_context":{"text":"Colunistas","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/colunistas\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2022\/02\/omicron.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2022\/02\/omicron.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2022\/02\/omicron.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2022\/02\/omicron.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2022\/02\/omicron.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":48872,"url":"https:\/\/blogdafeira.com.br\/home\/2021\/11\/25\/governador-apela-a-populacao-para-completar-esquema-vacinal-contra-a-covid-19\/","url_meta":{"origin":50122,"position":2},"title":"Governador apela \u00e0 popula\u00e7\u00e3o para completar esquema vacinal contra Covid-19","author":"Blog da Feira","date":"25\/11\/2021","format":false,"excerpt":"Em agenda na cidade de Bom Jesus da Serra, no sudoeste da Bahia, o governador Rui Costa refor\u00e7ou, ontem, quarta-feira (24), a necessidade de que a popula\u00e7\u00e3o tome a vacina contra a Covid-19. Quem j\u00e1 se vacinou com a primeira e a segunda doses, e est\u00e1 apto, deve retornar aos\u2026","rel":"","context":"Em &quot;Home&quot;","block_context":{"text":"Home","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/raiz\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2021\/11\/IMAGEM_NOTICIA_1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2021\/11\/IMAGEM_NOTICIA_1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2021\/11\/IMAGEM_NOTICIA_1.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2021\/11\/IMAGEM_NOTICIA_1.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":48902,"url":"https:\/\/blogdafeira.com.br\/home\/2021\/11\/26\/deputado-reforca-apelo-de-rui-aos-baianos-pelo-ciclo-vacinal-completo\/","url_meta":{"origin":50122,"position":3},"title":"Deputado refor\u00e7a apelo de Rui aos baianos pelo ciclo vacinal completo","author":"Blog da Feira","date":"26\/11\/2021","format":false,"excerpt":"O deputado estadual Robinson Almeida (PT) refor\u00e7ou, ontem, quinta-feira (25), o apelo do governador Rui Costa (PT) para que a popula\u00e7\u00e3o complete o ciclo vacinal contra o Coronav\u00edrus. Segundo a Secretaria da Sa\u00fade na Bahia h\u00e1 quase 3 milh\u00f5es de baianos que n\u00e3o completaram o ciclo vacinal. Na capital do\u2026","rel":"","context":"Em &quot;Home&quot;","block_context":{"text":"Home","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/raiz\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2021\/11\/Screenshot_20211125-2014202.png?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2021\/11\/Screenshot_20211125-2014202.png?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2021\/11\/Screenshot_20211125-2014202.png?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2021\/11\/Screenshot_20211125-2014202.png?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":52499,"url":"https:\/\/blogdafeira.com.br\/home\/2022\/05\/23\/como-esta-a-vacinacao-contra-a-covid-19-em-feira\/","url_meta":{"origin":50122,"position":4},"title":"Como est\u00e1 a vacina\u00e7\u00e3o contra a Covid-19 em Feira?","author":"Andr\u00e9 Pomponet","date":"23\/05\/2022","format":false,"excerpt":"V\u00e1 l\u00e1 que os casos de Covid-19 ca\u00edram na Feira de Santana nos \u00faltimos meses: dados da Secretaria Municipal de Sa\u00fade da quinta-feira (19) indicam que, naquele dia, havia apenas um paciente internado e foram registrados somente sete novos casos. Mas a situa\u00e7\u00e3o j\u00e1 foi mais favor\u00e1vel e o n\u00famero\u2026","rel":"","context":"Em &quot;Colunistas&quot;","block_context":{"text":"Colunistas","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/colunistas\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2021\/12\/20122021160108.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2021\/12\/20122021160108.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2021\/12\/20122021160108.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2021\/12\/20122021160108.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2021\/12\/20122021160108.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":46597,"url":"https:\/\/blogdafeira.com.br\/home\/2021\/07\/23\/pandemia-ja-matou-mais-de-mil-na-feira\/","url_meta":{"origin":50122,"position":5},"title":"Pandemia j\u00e1 matou mais de mil na Feira","author":"Andr\u00e9 Pomponet","date":"23\/07\/2021","format":false,"excerpt":"O ritmo de mortes confirmadas ou sob suspeita por Covid-19 caiu na Feira de Santana em julho, embora ainda faltem alguns dias para o final do m\u00eas. At\u00e9 hoje (23), de acordo com a Central de Informa\u00e7\u00f5es de Registro Civil \u2013 CRC Nacional, foram contabilizados 52 \u00f3bitos suspeitos ou confirmados.\u2026","rel":"","context":"Em &quot;Cidade&quot;","block_context":{"text":"Cidade","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/cidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2021\/07\/whatsapp-image-2020-06-04-at-21.25.53.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2021\/07\/whatsapp-image-2020-06-04-at-21.25.53.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2021\/07\/whatsapp-image-2020-06-04-at-21.25.53.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2021\/07\/whatsapp-image-2020-06-04-at-21.25.53.jpeg?resize=700%2C400&ssl=1 2x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/posts\/50122","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/comments?post=50122"}],"version-history":[{"count":2,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/posts\/50122\/revisions"}],"predecessor-version":[{"id":50173,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/posts\/50122\/revisions\/50173"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/media\/50135"}],"wp:attachment":[{"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/media?parent=50122"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/categories?post=50122"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/tags?post=50122"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}