{"id":50138,"date":"2022-01-15T08:02:09","date_gmt":"2022-01-15T11:02:09","guid":{"rendered":"https:\/\/blogdafeira.com.br\/home\/?p=50138"},"modified":"2022-01-21T02:16:02","modified_gmt":"2022-01-21T05:16:02","slug":"vereadores-nao-aprovam-orcamento-e-atingem-em-cheio-a-populacao-diz-secretario","status":"publish","type":"post","link":"https:\/\/blogdafeira.com.br\/home\/2022\/01\/15\/vereadores-nao-aprovam-orcamento-e-atingem-em-cheio-a-populacao-diz-secretario\/","title":{"rendered":"Vereadores n\u00e3o aprovam Or\u00e7amento e atingem em cheio a popula\u00e7\u00e3o, diz secret\u00e1rio"},"content":{"rendered":"<div id=\"blogd-3252287109\" class=\"blogd-fim-do-post-mobile blogd-entity-placement\" style=\"margin-left: auto;margin-right: auto;text-align: center;\"><a href=\"https:\/\/www.feiradesantana.ba.gov.br\/servico.asp?s=a&titulo=Prefeitura-de-Feira-lan%C3%A7a-programa-Rem%C3%A9dio-em-Casa-e-transforma-acesso-a-medicamentos-em-pol%C3%ADtica-p%C3%BAblica-de-cuidados.html&id=14&link=secom\/noticias.asp&idn=43684#noticias\" target=_blank><picture>\r\n  <source media=\"(min-width: 768px)\" srcset=\"https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2026\/03\/980x150.gif\">\r\n  \r\n  <img decoding=\"async\" src=\"https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2021\/01\/350x2002.gif\" alt=\"Publicidade\" style=\"width: 100%; max-width: 100%; height: auto; display: block; margin: 0 auto;\">\r\n\t<\/picture><\/a><\/div><p>Impedimento total de realizar melhorias, inclusive na Sa\u00fade e na Educa\u00e7\u00e3o. Impossibilidade total de realizar qualquer obra, por menor que seja. Esta \u00e9 a situa\u00e7\u00e3o, atualmente, do Governo Municipal de Feira de Santana, diante da decis\u00e3o da C\u00e2mara Municipal em devolver o projeto de Lei do Or\u00e7amento 2022, conforme alerta o secret\u00e1rio de Planejamento, Carlos Brito.<\/p>\n<p>Em of\u00edcio enviado ao prefeito Colbert Martins, o Poder Legislativo alega que a devolu\u00e7\u00e3o da Lei Or\u00e7ament\u00e1ria e da Lei de Diretrizes Or\u00e7ament\u00e1rias (LDO) \u00e9 <em>&#8220;para que sejam efetuadas as readequa\u00e7\u00f5es se fazem necess\u00e1rias&#8221;.<\/em><\/p>\n<p>&#8220;<em>Enquanto o or\u00e7amento de 2022 n\u00e3o for aprovado, o governo s\u00f3 pode fazer o m\u00ednimo para manter a m\u00e1quina funcionando, mas n\u00e3o pode fazer qualquer novo investimento que vise qualquer tipo de melhorias para munic\u00edpio, seja em obras ou servi\u00e7os. Ou seja, no popular, dir\u00edamos que o governo est\u00e1 travado em sua a\u00e7\u00f5es, o que prejudica, \u00e9 claro, a popula\u00e7\u00e3o de Feira de Santana<\/em>&#8220;, adverte o secret\u00e1rio.<\/p>\n<div id=\"blogd-2819506772\" class=\"blogd-final-post blogd-entity-placement\"><a href=\"https:\/\/www.feiradesantana.ba.leg.br\/\" target=\"_blank\" aria-label=\"JUNHO-VERMELHO_CA\u0302MARA-DE-FEIRA\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2026\/03\/JUNHO-VERMELHO_CAMARA-DE-FEIRA.gif\" alt=\"\"  class=\"no-lazyload\" width=\"728\" height=\"90\"   \/><\/a><\/div><p>Ano passado os vereadores tamb\u00e9m n\u00e3o aprovaram a forma\u00e7\u00e3o do Conselho do Fundeb, <strong><a href=\"https:\/\/blogdafeira.com.br\/home\/2020\/12\/30\/feira-de-santana-deixa-de-receber-milhoes-do-fundeb\/\">prejudicando tamb\u00e9m\u00a0 o munic\u00edpio que deixa de receber recursos.<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Impedimento total de realizar melhorias, inclusive na Sa\u00fade e na Educa\u00e7\u00e3o. Impossibilidade total de realizar qualquer obra, por menor que seja. Esta \u00e9 a situa\u00e7\u00e3o, atualmente, do Governo Municipal de Feira de Santana, diante da decis\u00e3o da C\u00e2mara Municipal em devolver o projeto de Lei do Or\u00e7amento 2022, conforme alerta o secret\u00e1rio de Planejamento, Carlos<\/p>\n","protected":false},"author":1,"featured_media":49369,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"cybocfi_hide_featured_image":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[1,631],"tags":[],"class_list":["post-50138","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-raiz","category-politica"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2021\/12\/images-1.jpeg","jetpack_shortlink":"https:\/\/wp.me\/p3niVf-d2G","jetpack_sharing_enabled":true,"jetpack-related-posts":[{"id":50164,"url":"https:\/\/blogdafeira.com.br\/home\/2022\/01\/18\/governo-de-feira-traca-quadro-de-caos-com-nao-aprovacao-do-orcamento\/","url_meta":{"origin":50138,"position":0},"title":"Governo de Feira tra\u00e7a quadro de caos com n\u00e3o aprova\u00e7\u00e3o do Or\u00e7amento","author":"Secom\/FSA","date":"18\/01\/2022","format":false,"excerpt":"O Governo Municipal de Feira de Santana - Prefeito e diversos secret\u00e1rios - pintaram um quadro de caos administrativo hoje em uma explana\u00e7\u00e3o atrav\u00e9s da internet sobre as consequ\u00eancias da n\u00e3o vota\u00e7\u00e3o da Lei Or\u00e7ament\u00e1ria Anual (LOA) pela C\u00e2mara Municipal de Vereadores. Cada um dos secret\u00e1rios que participou da \"coletiva\u2026","rel":"","context":"Em &quot;Cidade&quot;","block_context":{"text":"Cidade","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/cidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2022\/01\/Screenshot_20220118-1534092.png?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2022\/01\/Screenshot_20220118-1534092.png?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2022\/01\/Screenshot_20220118-1534092.png?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2022\/01\/Screenshot_20220118-1534092.png?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":50787,"url":"https:\/\/blogdafeira.com.br\/home\/2022\/02\/16\/stj-acaba-impasse-juridico-do-orcamento-de-feira\/","url_meta":{"origin":50138,"position":1},"title":"STJ acaba impasse jur\u00eddico do Or\u00e7amento de Feira","author":"Secom\/FSA","date":"16\/02\/2022","format":false,"excerpt":"O Superior Tribunal de Justi\u00e7a decidiu nesta ter\u00e7a (15) manter\u00a0 a\u00a0 prerrogativa da C\u00e2mara de Feira de Santana para legislar sobre a Lei de Diretrizes Or\u00e7ament\u00e1rias 2022. A medida \u00e9 uma negativa ao recurso do Poder Executivo pedindo\u00a0 que fossem desconsideradas emendas \u00e0 LDO aprovadas no plen\u00e1rio da Casa da\u2026","rel":"","context":"Em &quot;Home&quot;","block_context":{"text":"Home","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/raiz\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2022\/02\/veredor-ddd-2.png?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":50532,"url":"https:\/\/blogdafeira.com.br\/home\/2022\/02\/04\/colbert-devolve-a-camara-de-vereadores-lei-do-orcamento-2022-sem-alteracoes\/","url_meta":{"origin":50138,"position":2},"title":"Impasse continua: Colbert devolve \u00e0 C\u00e2mara Lei do Or\u00e7amento sem altera\u00e7\u00f5es","author":"Secom\/FSA","date":"04\/02\/2022","format":false,"excerpt":"Pelo jeito vai come\u00e7ar tudo de novo, o impasse entre a Prefeitura de Feira e a C\u00e2mara de Vereadores por causa do Or\u00e7amento 2022.. O prefeito de Feira de Santana, Colbert Filho (MDB), atrav\u00e9s da Procuradoria Geral do Munic\u00edpio, devolveu hoje \u00e0 C\u00e2mara de Vereadores a Lei Or\u00e7ament\u00e1ria Anual, sem\u2026","rel":"","context":"Em &quot;Home&quot;","block_context":{"text":"Home","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/raiz\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2022\/02\/veredor-ddd-2.png?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":56078,"url":"https:\/\/blogdafeira.com.br\/home\/2023\/01\/06\/jhonatas-critica-projeto-do-orcamento-municipal-e-tudo-muito-generico\/","url_meta":{"origin":50138,"position":3},"title":"Vereadores criticam projeto do or\u00e7amento municipal: &#8220;\u00c9 tudo muito gen\u00e9rico&#8221;, diz Jhonatas","author":"Secom\/FSA","date":"06\/01\/2023","format":false,"excerpt":"A falta de detalhamento das a\u00e7\u00f5es, por parte do Poder Executivo, \u00e9 uma das principais defici\u00eancias no Projeto de Lei Or\u00e7ament\u00e1ria - a estimativa de receita e despesa do Munic\u00edpio para 2023 -, reclamou o vereador Jhonatas Monteiro (PSOL) na sess\u00e3o desta quinta-feira (5). Segundo ele, a pe\u00e7a tem os\u2026","rel":"","context":"Em &quot;Cidade&quot;","block_context":{"text":"Cidade","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/cidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2023\/01\/05012023173019.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2023\/01\/05012023173019.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2023\/01\/05012023173019.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2023\/01\/05012023173019.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2023\/01\/05012023173019.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":55238,"url":"https:\/\/blogdafeira.com.br\/home\/2022\/11\/03\/orcamento-de-feira-vereadores-ouvem-secretarios-mas-querem-ver-as-contas\/","url_meta":{"origin":50138,"position":4},"title":"Or\u00e7amento de Feira: vereadores ouvem secret\u00e1rios mas querem &#8220;ver as contas&#8221;","author":"Secom\/FSA","date":"03\/11\/2022","format":false,"excerpt":"Rep\u00f3rteres veteranos na cobertura jornal\u00edstica na C\u00e2mara de Vereadores de Feira de Santana ficaram hoje impressionados, n\u00e3o s\u00f3 com a presen\u00e7a maci\u00e7a de Secret\u00e1rios do Governo Colbert, mas tamb\u00e9m de pessoas do segundo escal\u00e3o na mais longa sess\u00e3o dessa legislatura. Come\u00e7ou \u00e0s 10 horas, aproximadamente, e terminou por volta de\u2026","rel":"","context":"Em &quot;Home&quot;","block_context":{"text":"Home","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/raiz\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2022\/11\/03112022181258.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2022\/11\/03112022181258.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2022\/11\/03112022181258.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2022\/11\/03112022181258.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2022\/11\/03112022181258.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":49503,"url":"https:\/\/blogdafeira.com.br\/home\/2021\/12\/20\/deputado-adolfo-menezes-reclama-de-defasagem-no-orcamento-da-assembleia\/","url_meta":{"origin":50138,"position":5},"title":"Deputado Adolfo Menezes reclama de &#8220;defasagem&#8221; no or\u00e7amento da Assembleia","author":"Secom\/FSA","date":"20\/12\/2021","format":false,"excerpt":"O presidente da Assembleia Legislativa da Bahia \u2013 ALBA, deputado Adolfo Menezes, afirmou, em sess\u00e3o extraordin\u00e1ria mista (presencial e remota) nesta segunda-feira (20.12), que vai conversar com o governador Rui Costa para que a quest\u00e3o do or\u00e7amento do Poder Legislativo seja equacionada em 2022. \u201cTodos os anos o or\u00e7amento da\u2026","rel":"","context":"Em &quot;Home&quot;","block_context":{"text":"Home","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/raiz\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2021\/12\/IMG-20211220-WA0028.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2021\/12\/IMG-20211220-WA0028.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2021\/12\/IMG-20211220-WA0028.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2021\/12\/IMG-20211220-WA0028.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2021\/12\/IMG-20211220-WA0028.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2021\/12\/IMG-20211220-WA0028.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/posts\/50138","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/comments?post=50138"}],"version-history":[{"count":1,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/posts\/50138\/revisions"}],"predecessor-version":[{"id":50140,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/posts\/50138\/revisions\/50140"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/media\/49369"}],"wp:attachment":[{"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/media?parent=50138"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/categories?post=50138"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/tags?post=50138"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}