{"id":50164,"date":"2022-01-18T15:35:47","date_gmt":"2022-01-18T18:35:47","guid":{"rendered":"https:\/\/blogdafeira.com.br\/home\/?p=50164"},"modified":"2022-01-24T10:46:53","modified_gmt":"2022-01-24T13:46:53","slug":"governo-de-feira-traca-quadro-de-caos-com-nao-aprovacao-do-orcamento","status":"publish","type":"post","link":"https:\/\/blogdafeira.com.br\/home\/2022\/01\/18\/governo-de-feira-traca-quadro-de-caos-com-nao-aprovacao-do-orcamento\/","title":{"rendered":"Governo de Feira tra\u00e7a quadro de caos com n\u00e3o aprova\u00e7\u00e3o do Or\u00e7amento"},"content":{"rendered":"<div id=\"blogd-805054255\" class=\"blogd-fim-do-post-mobile blogd-entity-placement\" style=\"margin-left: auto;margin-right: auto;text-align: center;\"><a href=\"https:\/\/www.feiradesantana.ba.gov.br\/servico.asp?s=a&titulo=Prefeitura-de-Feira-lan%C3%A7a-programa-Rem%C3%A9dio-em-Casa-e-transforma-acesso-a-medicamentos-em-pol%C3%ADtica-p%C3%BAblica-de-cuidados.html&id=14&link=secom\/noticias.asp&idn=43684#noticias\" target=_blank><picture>\r\n  <source media=\"(min-width: 768px)\" srcset=\"https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2026\/03\/980x150.gif\">\r\n  \r\n  <img decoding=\"async\" src=\"https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2021\/01\/350x2002.gif\" alt=\"Publicidade\" style=\"width: 100%; max-width: 100%; height: auto; display: block; margin: 0 auto;\">\r\n\t<\/picture><\/a><\/div><p style=\"text-align: justify;\">O Governo Municipal de Feira de Santana &#8211; Prefeito e diversos secret\u00e1rios &#8211; pintaram um quadro de caos administrativo hoje em uma explana\u00e7\u00e3o atrav\u00e9s da internet sobre as consequ\u00eancias da n\u00e3o vota\u00e7\u00e3o da Lei Or\u00e7ament\u00e1ria Anual (LOA) pela C\u00e2mara Municipal de Vereadores.<\/p>\n<p style=\"text-align: justify;\">Cada um dos secret\u00e1rios que participou da &#8220;coletiva de imprensa&#8221; relatou projetos e investimentos que ser\u00e3o prejudicados pela situa\u00e7\u00e3o.\u00a0Palavras como &#8220;caos&#8221;, &#8220;terra arrasada&#8221; e outras foram usadas para descrever a situa\u00e7\u00e3o.<\/p>\n<p style=\"text-align: justify;\">Abaixo, a \u00edntegra da coletiva:<\/p>\n<p><span class=\"embed-youtube\" style=\"text-align:center; display: block;\"><iframe loading=\"lazy\" class=\"youtube-player\" width=\"1170\" height=\"659\" src=\"https:\/\/www.youtube.com\/embed\/wwZQt8zv1Xo?version=3&#038;rel=1&#038;showsearch=0&#038;showinfo=1&#038;iv_load_policy=1&#038;fs=1&#038;hl=pt-BR&#038;autohide=2&#038;wmode=transparent\" allowfullscreen=\"true\" style=\"border:0;\" sandbox=\"allow-scripts allow-same-origin allow-popups allow-presentation allow-popups-to-escape-sandbox\"><\/iframe><\/span><\/p>\n<div id=\"blogd-1379492062\" class=\"blogd-final-post blogd-entity-placement\"><a href=\"https:\/\/www.feiradesantana.ba.leg.br\/\" target=\"_blank\" aria-label=\"JUNHO-VERMELHO_CA\u0302MARA-DE-FEIRA\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2026\/03\/JUNHO-VERMELHO_CAMARA-DE-FEIRA.gif\" alt=\"\"  class=\"no-lazyload\" width=\"728\" height=\"90\"   \/><\/a><\/div><blockquote class=\"wp-embedded-content\" data-secret=\"Ic2RUzep92\"><p><a href=\"https:\/\/blogdafeira.com.br\/home\/2022\/01\/19\/justica-invalida-ldo-da-camara-e-impoe-mais-uma-derrota-a-fernando-torres\/\">Justi\u00e7a invalida LDO da C\u00e2mara e imp\u00f5e mais uma derrota a Fernando Torres<\/a><\/p><\/blockquote>\n<p><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; clip: rect(1px, 1px, 1px, 1px);\" title=\"&#8220;Justi\u00e7a invalida LDO da C\u00e2mara e imp\u00f5e mais uma derrota a Fernando Torres&#8221; &#8212; Blog da Feira\" src=\"https:\/\/blogdafeira.com.br\/home\/2022\/01\/19\/justica-invalida-ldo-da-camara-e-impoe-mais-uma-derrota-a-fernando-torres\/embed\/#?secret=Ic2RUzep92\" data-secret=\"Ic2RUzep92\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Governo Municipal de Feira de Santana &#8211; Prefeito e diversos secret\u00e1rios &#8211; pintaram um quadro de caos administrativo hoje em uma explana\u00e7\u00e3o atrav\u00e9s da internet sobre as consequ\u00eancias da n\u00e3o vota\u00e7\u00e3o da Lei Or\u00e7ament\u00e1ria Anual (LOA) pela C\u00e2mara Municipal de Vereadores. Cada um dos secret\u00e1rios que participou da &#8220;coletiva de imprensa&#8221; relatou projetos e<\/p>\n","protected":false},"author":1,"featured_media":50166,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"cybocfi_hide_featured_image":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[3,1,631],"tags":[],"class_list":["post-50164","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cidade","category-raiz","category-politica"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2022\/01\/Screenshot_20220118-1534092.png","jetpack_shortlink":"https:\/\/wp.me\/p3niVf-d36","jetpack_sharing_enabled":true,"jetpack-related-posts":[{"id":47155,"url":"https:\/\/blogdafeira.com.br\/home\/2021\/08\/26\/transporte-coletivo-da-crise-intermitente-ao-caos-permanente\/","url_meta":{"origin":50164,"position":0},"title":"Transporte coletivo: da crise intermitente ao caos permanente","author":"Andr\u00e9 Pomponet","date":"26\/08\/2021","format":false,"excerpt":"A semana come\u00e7ou com mais um cap\u00edtulo da intermin\u00e1vel crise que envolve o transporte coletivo na Feira de Santana. Greve dos rodovi\u00e1rios reivindicando reajuste salarial, \u00f4nibus retirados das garagens pelas empresas, acusa\u00e7\u00f5es, nota aqui, nota ali... enfim, um quiproqu\u00f3 terr\u00edvel. Desde o come\u00e7o da pandemia, ali\u00e1s, que a situa\u00e7\u00e3o se\u2026","rel":"","context":"Em &quot;Cidade&quot;","block_context":{"text":"Cidade","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/cidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2021\/08\/24082021092142.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2021\/08\/24082021092142.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2021\/08\/24082021092142.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2021\/08\/24082021092142.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2021\/08\/24082021092142.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":31514,"url":"https:\/\/blogdafeira.com.br\/home\/2019\/05\/28\/vereadores-governistas-de-feira-de-santana-nao-explicam-caos-na-saude-apenas-fazem-elogios-a-ze-ronaldo\/","url_meta":{"origin":50164,"position":1},"title":"Vereadores governistas de Feira de Santana n\u00e3o explicam caos na sa\u00fade; apenas fazem elogios a Z\u00e9 Ronaldo","author":"J\u00e2nio R\u00eago","date":"28\/05\/2019","format":false,"excerpt":"'Um bom pai de fam\u00edlia, um bom amigo, um homem honrado, do bem, sens\u00edvel com os mais necesitados....\" foi com elogios desse tipo ao ex-prefeito Jos\u00e9 Ronaldo de Carvalho que os vereadores governistas 'defenderam' o governo do munic\u00edp\u00edo das den\u00fancias de caos na sa\u00fade p\u00fablica, apresentadas durante um pronunciamento do\u2026","rel":"","context":"Em &quot;Home&quot;","block_context":{"text":"Home","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/raiz\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2019\/05\/Vereador-Roberto-Tourinho.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":50138,"url":"https:\/\/blogdafeira.com.br\/home\/2022\/01\/15\/vereadores-nao-aprovam-orcamento-e-atingem-em-cheio-a-populacao-diz-secretario\/","url_meta":{"origin":50164,"position":2},"title":"Vereadores n\u00e3o aprovam Or\u00e7amento e atingem em cheio a popula\u00e7\u00e3o, diz secret\u00e1rio","author":"Blog da Feira","date":"15\/01\/2022","format":false,"excerpt":"Impedimento total de realizar melhorias, inclusive na Sa\u00fade e na Educa\u00e7\u00e3o. Impossibilidade total de realizar qualquer obra, por menor que seja. Esta \u00e9 a situa\u00e7\u00e3o, atualmente, do Governo Municipal de Feira de Santana, diante da decis\u00e3o da C\u00e2mara Municipal em devolver o projeto de Lei do Or\u00e7amento 2022, conforme alerta\u2026","rel":"","context":"Em &quot;Home&quot;","block_context":{"text":"Home","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/raiz\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2021\/12\/images-1.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2021\/12\/images-1.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2021\/12\/images-1.jpeg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":56911,"url":"https:\/\/blogdafeira.com.br\/home\/2023\/03\/15\/vereador-sugere-suspender-micareta-de-feira\/","url_meta":{"origin":50164,"position":3},"title":"Vereadora sugere suspender Micareta de Feira","author":"Blog da Feira","date":"15\/03\/2023","format":false,"excerpt":"Uma vereadora de Feira de Santana, Lu de Rony sugere suspender a Micareta por causa da situa\u00e7\u00e3o da sa\u00fade e seguran\u00e7a p\u00fabicas no munic\u00edpio. Filiada ao MDB, mesmo partido do prefeito Colbert Filho, a vereadora \u00e9 no entanto da oposi\u00e7\u00e3o ao governo municipal. Enfermeira,ela focou suas cr\u00edticas ao \"caos da\u2026","rel":"","context":"Em &quot;Home&quot;","block_context":{"text":"Home","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/raiz\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2023\/03\/presidente-do-mdb-de-feira-de-santana-critica-veto-construcao-do-hospital-municipal-infeliz_widelg.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2023\/03\/presidente-do-mdb-de-feira-de-santana-critica-veto-construcao-do-hospital-municipal-infeliz_widelg.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2023\/03\/presidente-do-mdb-de-feira-de-santana-critica-veto-construcao-do-hospital-municipal-infeliz_widelg.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2023\/03\/presidente-do-mdb-de-feira-de-santana-critica-veto-construcao-do-hospital-municipal-infeliz_widelg.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":10019,"url":"https:\/\/blogdafeira.com.br\/home\/2014\/04\/02\/governo-wagner-tambem-amansa-medicos-e-hgca-continua-funcionando\/","url_meta":{"origin":50164,"position":4},"title":"Governo Wagner tamb\u00e9m &#8216;amansa&#8217; m\u00e9dicos e HGCA continua funcionando","author":"Blog da Feira","date":"02\/04\/2014","format":false,"excerpt":"Assim como o prefeito de Feira, Jos\u00e9 Ronaldo com o IPTU e os comerciantes da Associa\u00e7\u00e3o Comercial e CDL, o Governo Wagner tamb\u00e9m conseguiu 'amansar' uma categoria que amea\u00e7ava ampliar o que alguns chamam de 'caos' no Hospital Geral Cl\u00e9riston Andrade. Cirurgi\u00f5es e ortopedistas daquele hospital amea\u00e7aram parar suas atividades\u2026","rel":"","context":"Em &quot;Home&quot;","block_context":{"text":"Home","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/raiz\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":45211,"url":"https:\/\/blogdafeira.com.br\/home\/2021\/04\/29\/oscilacoes-no-clima-e-caos-na-politica-feirense\/","url_meta":{"origin":50164,"position":5},"title":"Oscila\u00e7\u00f5es no clima e caos na pol\u00edtica feirense","author":"Andr\u00e9 Pomponet","date":"29\/04\/2021","format":false,"excerpt":"A atmosfera feirense amanheceu cinza mais uma vez. Abril talvez seja o m\u00eas em que essas altern\u00e2ncias clim\u00e1ticas costumem ser mais constantes. Lembro de duas ou tr\u00eas manh\u00e3s radiosas no come\u00e7o do m\u00eas, de c\u00e9u azul e luz pur\u00edssima. Depois, vieram as chuvas \u2013 caudalosas, castigando as fachadas fustigadas pelo\u2026","rel":"","context":"Em &quot;Cidade&quot;","block_context":{"text":"Cidade","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/cidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2021\/02\/IMG_2946-scaled.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2021\/02\/IMG_2946-scaled.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2021\/02\/IMG_2946-scaled.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2021\/02\/IMG_2946-scaled.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2021\/02\/IMG_2946-scaled.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2021\/02\/IMG_2946-scaled.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/posts\/50164","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/comments?post=50164"}],"version-history":[{"count":3,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/posts\/50164\/revisions"}],"predecessor-version":[{"id":50232,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/posts\/50164\/revisions\/50232"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/media\/50166"}],"wp:attachment":[{"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/media?parent=50164"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/categories?post=50164"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/tags?post=50164"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}