{"id":50192,"date":"2022-01-19T14:36:17","date_gmt":"2022-01-19T17:36:17","guid":{"rendered":"https:\/\/blogdafeira.com.br\/home\/?p=50192"},"modified":"2022-01-24T10:46:53","modified_gmt":"2022-01-24T13:46:53","slug":"justica-invalida-ldo-da-camara-e-impoe-mais-uma-derrota-a-fernando-torres","status":"publish","type":"post","link":"https:\/\/blogdafeira.com.br\/home\/2022\/01\/19\/justica-invalida-ldo-da-camara-e-impoe-mais-uma-derrota-a-fernando-torres\/","title":{"rendered":"Justi\u00e7a invalida LDO da C\u00e2mara e imp\u00f5e mais uma derrota a Fernando Torres"},"content":{"rendered":"<div id=\"blogd-563271007\" class=\"blogd-fim-do-post-mobile blogd-entity-placement\" style=\"margin-left: auto;margin-right: auto;text-align: center;\"><a href=\"https:\/\/www.feiradesantana.ba.gov.br\/servico.asp?s=a&titulo=Prefeitura-de-Feira-lan%C3%A7a-programa-Rem%C3%A9dio-em-Casa-e-transforma-acesso-a-medicamentos-em-pol%C3%ADtica-p%C3%BAblica-de-cuidados.html&id=14&link=secom\/noticias.asp&idn=43684#noticias\" target=_blank><picture>\r\n  <source media=\"(min-width: 768px)\" srcset=\"https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2026\/03\/980x150.gif\">\r\n  \r\n  <img decoding=\"async\" src=\"https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2021\/01\/350x2002.gif\" alt=\"Publicidade\" style=\"width: 100%; max-width: 100%; height: auto; display: block; margin: 0 auto;\">\r\n\t<\/picture><\/a><\/div><p>Em 24 horas a Justi\u00e7a imp\u00f4s duas derrotas ao vereador presidente da C\u00e2mara, Fernando Torres (PSD), na &#8220;briga&#8221; que ele alimenta com o prefeito Colbert Martins Filho (MDB) desde o in\u00edcio do ano passado quando assumiu o cargo de Chefe do Legislativo.<\/p>\n<p><strong><a href=\"https:\/\/blogdafeira.com.br\/home\/2022\/01\/19\/justica-obriga-fernando-torres-colocar-em-votacao-lei-que-cria-conselho-do-fundeb\/\">A primeira foi a que o obrigou a colocar em pauta a aprova\u00e7\u00e3o da lei que cria o Conselho do Fundeb<\/a> <\/strong>e hoje o mesmo juiz, Nunisvaldo dos Santos, determinou que o presidente invalide a Lei de Diretrizes Or\u00e7ament\u00e1rias que promulgou \u00e0 revelia da que j\u00e1 existia e foi publicada pelo Poder Executivo em agosto de 2021.<\/p>\n<p>&#8220;<em>A C\u00e2mara tem prazo m\u00e1ximo de 03 (tr\u00eas dias) para tornar sem efeitos a publica\u00e7\u00e3o realizada no Di\u00e1rio Oficial do Poder Legislativo, no dia 10 de dezembro de 2021, &#8220;a qual promulgou fora do prazo a lei n\u00b0 4.065\/2021 (LDO), mantendo em sua integralidade o texto da LDO publicado pelo Poder Executivo no Di\u00e1rio Oficial do Munic\u00edpio no dia 26 de agosto de 2021, sob pena de multa di\u00e1ria, a qual arbitro em R$ 10.000,00 (Dez mil reais) em caso de descumprimento da medida&#8221;<\/em>, conclui o juiz.<\/p>\n<div id=\"blogd-3344412905\" class=\"blogd-final-post blogd-entity-placement\"><a href=\"https:\/\/www.feiradesantana.ba.leg.br\/\" target=\"_blank\" aria-label=\"JUNHO-VERMELHO_CA\u0302MARA-DE-FEIRA\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2026\/03\/JUNHO-VERMELHO_CAMARA-DE-FEIRA.gif\" alt=\"\"  class=\"no-lazyload\" width=\"728\" height=\"90\"   \/><\/a><\/div><p><strong><a href=\"https:\/\/pje.tjba.jus.br\/pje\/ConsultaPublica\/DetalheProcessoConsultaPublica\/documentoSemLoginHTML.seam?ca=b5d06572fae9e0e4ee6a60796ebd1f8cf444c94005c801ec91b6c855e4be10ac5d922177a81017198dc40a7b65035a680d08342b63690bd7&amp;idProcessoDoc=176835062\">Leia na \u00edntegra a decis\u00e3o da Justi\u00e7a clique aqui<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Em 24 horas a Justi\u00e7a imp\u00f4s duas derrotas ao vereador presidente da C\u00e2mara, Fernando Torres (PSD), na &#8220;briga&#8221; que ele alimenta com o prefeito Colbert Martins Filho (MDB) desde o in\u00edcio do ano passado quando assumiu o cargo de Chefe do Legislativo. A primeira foi a que o obrigou a colocar em pauta a aprova\u00e7\u00e3o<\/p>\n","protected":false},"author":1,"featured_media":49369,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"cybocfi_hide_featured_image":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[1,631],"tags":[],"class_list":["post-50192","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-raiz","category-politica"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2021\/12\/images-1.jpeg","jetpack_shortlink":"https:\/\/wp.me\/p3niVf-d3y","jetpack_sharing_enabled":true,"jetpack-related-posts":[{"id":50424,"url":"https:\/\/blogdafeira.com.br\/home\/2022\/01\/31\/tribunal-suspende-liminar-e-mantem-ldo-da-camara\/","url_meta":{"origin":50192,"position":0},"title":"Tribunal suspende liminar e mant\u00e9m LDO da C\u00e2mara","author":"Blog da Feira","date":"31\/01\/2022","format":false,"excerpt":"O desembargador Lourival de Almeida Trindade, presidente do Tribunal de Justi\u00e7a da Bahia, suspendeu nesta segunda-feira (31) a liminar que invalidava a promulga\u00e7\u00e3o da Lei de Diretrizes Or\u00e7ament\u00e1rias (LDO) pela C\u00e2mara Municipal de Feira de Santana. Segundo o desembargador, a decis\u00e3o proferida pelo juiz Nunisvaldo dos Santos no dia 19\u2026","rel":"","context":"Em &quot;Cidade&quot;","block_context":{"text":"Cidade","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/cidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2022\/01\/tj-ba-1.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2022\/01\/tj-ba-1.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2022\/01\/tj-ba-1.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2022\/01\/tj-ba-1.jpeg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":50787,"url":"https:\/\/blogdafeira.com.br\/home\/2022\/02\/16\/stj-acaba-impasse-juridico-do-orcamento-de-feira\/","url_meta":{"origin":50192,"position":1},"title":"STJ acaba impasse jur\u00eddico do Or\u00e7amento de Feira","author":"Blog da Feira","date":"16\/02\/2022","format":false,"excerpt":"O Superior Tribunal de Justi\u00e7a decidiu nesta ter\u00e7a (15) manter\u00a0 a\u00a0 prerrogativa da C\u00e2mara de Feira de Santana para legislar sobre a Lei de Diretrizes Or\u00e7ament\u00e1rias 2022. A medida \u00e9 uma negativa ao recurso do Poder Executivo pedindo\u00a0 que fossem desconsideradas emendas \u00e0 LDO aprovadas no plen\u00e1rio da Casa da\u2026","rel":"","context":"Em &quot;Home&quot;","block_context":{"text":"Home","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/raiz\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2022\/02\/veredor-ddd-2.png?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":50177,"url":"https:\/\/blogdafeira.com.br\/home\/2022\/01\/19\/justica-obriga-fernando-torres-colocar-em-votacao-lei-que-cria-conselho-do-fundeb\/","url_meta":{"origin":50192,"position":2},"title":"Justi\u00e7a obriga Fernando Torres colocar em vota\u00e7\u00e3o lei que forma Conselho do Fundeb","author":"Blog da Feira","date":"19\/01\/2022","format":false,"excerpt":"O Tribunal de Justi\u00e7a da Bahia concedeu, ontem, 18, liminar requerida pela Prefeitura de Feira de Santana determinando que o presidente da C\u00e2mara de Vereadores de Feira de Santana, vereador Fernando Torres \"coloque em delibera\u00e7\u00e3o e vota\u00e7\u00e3o pelo plen\u00e1rio da C\u00e2mara de Vereadores, no prazo m\u00e1ximo de 20 dias, o\u2026","rel":"","context":"Em &quot;Home&quot;","block_context":{"text":"Home","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/raiz\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2022\/01\/feira-de-santana-fernando-torres.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2022\/01\/feira-de-santana-fernando-torres.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2022\/01\/feira-de-santana-fernando-torres.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":50291,"url":"https:\/\/blogdafeira.com.br\/home\/2022\/01\/24\/saiba-quais-sao-e-porque-colbert-vetou-17-emendas-legislativas-a-ldo-de-feira\/","url_meta":{"origin":50192,"position":3},"title":"Saiba quais s\u00e3o os vetos que provocaram o impasse do Or\u00e7amento de Feira","author":"Blog da Feira","date":"24\/01\/2022","format":false,"excerpt":"S\u00e3o 17 emendas distribu\u00eddas em artigos e par\u00e1grafos da Lei de Diretrizes Or\u00e7ament\u00e1rias 2022 de Feira de Santana, que foram vetadas pelo prefeito Colbert Filho (MDB) que deram origem \u00e0 maior crise pol\u00edtica entre o Legislativo e o Executivo j\u00e1 vistas no Munic\u00edpio. Todas as raz\u00f5es apresentadas s\u00e3o de que\u2026","rel":"","context":"Em &quot;Cidade&quot;","block_context":{"text":"Cidade","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/cidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2022\/01\/images-3.jpeg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":50671,"url":"https:\/\/blogdafeira.com.br\/home\/2022\/02\/11\/camara-do-tj-decide-pela-validade-do-orcamento-de-feira-sem-as-emendas\/","url_meta":{"origin":50192,"position":4},"title":"C\u00e2mara do TJ decide pela validade do Or\u00e7amento de Feira sem as emendas","author":"Blog da Feira","date":"11\/02\/2022","format":false,"excerpt":"Na decis\u00e3o de quarta-feira, 9, a Primeira C\u00e2mara C\u00edvel, do Tribunal de Justi\u00e7a da Bahias, atrav\u00e9s da relatora do recurso (agravo de instrumento), desembargadora Maria de Lourdes Pinho Medauar, dediciu reconhecer como v\u00e1lida a LDO (Lei de Diretrizes Or\u00e7ament\u00e1ria), sancionada pelo prefeito Colbert Filho com os vetos a emendas inconstitucionais\u2026","rel":"","context":"Em &quot;Cidade&quot;","block_context":{"text":"Cidade","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/cidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2022\/01\/tj-ba-1.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2022\/01\/tj-ba-1.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2022\/01\/tj-ba-1.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2022\/01\/tj-ba-1.jpeg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":46853,"url":"https:\/\/blogdafeira.com.br\/home\/2021\/08\/04\/a-pendenga-da-ldo-no-legislativo-feirense\/","url_meta":{"origin":50192,"position":5},"title":"A pendenga da LDO no Legislativo feirense","author":"Andr\u00e9 Pomponet","date":"04\/08\/2021","format":false,"excerpt":"Impressionante a pendenga envolvendo a aprova\u00e7\u00e3o da Lei de Diretrizes Or\u00e7ament\u00e1rias (LDO) na C\u00e2mara Municipal aqui da Feira de Santana. Pelo jeito, a atual legislatura \u00e9 traquejada em temas \u00e1ridos como planejamento e or\u00e7amento. Provavelmente no segundo semestre o caldo vai entornar ainda mais. \u00c9 que, nele, ser\u00e1 apreciada a\u2026","rel":"","context":"Em &quot;Cidade&quot;","block_context":{"text":"Cidade","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/cidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2021\/08\/13072021173857.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2021\/08\/13072021173857.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2021\/08\/13072021173857.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2021\/08\/13072021173857.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2021\/08\/13072021173857.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/posts\/50192","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/comments?post=50192"}],"version-history":[{"count":2,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/posts\/50192\/revisions"}],"predecessor-version":[{"id":50194,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/posts\/50192\/revisions\/50194"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/media\/49369"}],"wp:attachment":[{"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/media?parent=50192"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/categories?post=50192"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/tags?post=50192"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}