{"id":50261,"date":"2022-01-23T04:33:26","date_gmt":"2022-01-23T07:33:26","guid":{"rendered":"https:\/\/blogdafeira.com.br\/home\/?p=50261"},"modified":"2022-01-31T16:22:07","modified_gmt":"2022-01-31T19:22:07","slug":"a-desculpa-de-clovis-lima","status":"publish","type":"post","link":"https:\/\/blogdafeira.com.br\/home\/2022\/01\/23\/a-desculpa-de-clovis-lima\/","title":{"rendered":"A desculpa de Cl\u00f3vis Lima"},"content":{"rendered":"<div id=\"blogd-1439971355\" class=\"blogd-fim-do-post-mobile blogd-entity-placement\" style=\"margin-left: auto;margin-right: auto;text-align: center;\"><a href=\"https:\/\/www.feiradesantana.ba.gov.br\/servico.asp?s=a&titulo=Prefeitura-de-Feira-lan%C3%A7a-programa-Rem%C3%A9dio-em-Casa-e-transforma-acesso-a-medicamentos-em-pol%C3%ADtica-p%C3%BAblica-de-cuidados.html&id=14&link=secom\/noticias.asp&idn=43684#noticias\" target=_blank><picture>\r\n  <source media=\"(min-width: 768px)\" srcset=\"https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2026\/03\/980x150.gif\">\r\n  \r\n  <img decoding=\"async\" src=\"https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2021\/01\/350x2002.gif\" alt=\"Publicidade\" style=\"width: 100%; max-width: 100%; height: auto; display: block; margin: 0 auto;\">\r\n\t<\/picture><\/a><\/div><p style=\"text-align: justify;\">Nas elei\u00e7\u00f5es proporcionais de 1974 em Feira de Santana, para substituir Chico Pinto, processado pelo regime militar, o MDB lan\u00e7ou o vereador Noide Cerqueira candidato a deputado federal.<\/p>\n<p style=\"text-align: justify;\">O prefeito Jos\u00e9 Falc\u00e3o reuniu a equipe e avisou que seriam demitidos os que n\u00e3o seguissem a decis\u00e3o partid\u00e1ria.<\/p>\n<p style=\"text-align: justify;\">Terminada a elei\u00e7\u00e3o e por ter votado em Domingos Leonelli, o secret\u00e1rio Clovis Lima, decidiu n\u00e3o voltar ao gabinete.<\/p>\n<p style=\"text-align: justify;\">Falc\u00e3o o chamou de volta, mas Clovis disse que precisava de uma justificativa para os rep\u00f3rteres que cobriam a prefeitura.<\/p>\n<p style=\"text-align: justify;\">Falc\u00e3o lambeu os l\u00e1bios:<\/p>\n<div id=\"blogd-1894886278\" class=\"blogd-final-post blogd-entity-placement\"><a href=\"https:\/\/www.feiradesantana.ba.leg.br\/\" target=\"_blank\" aria-label=\"JUNHO-VERMELHO_CA\u0302MARA-DE-FEIRA\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2026\/03\/JUNHO-VERMELHO_CAMARA-DE-FEIRA.gif\" alt=\"\"  class=\"no-lazyload\" width=\"728\" height=\"90\"   \/><\/a><\/div><p style=\"text-align: justify;\">&#8211; <em>Diga que esteve ausente porque estava de papeira&#8230;<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nas elei\u00e7\u00f5es proporcionais de 1974 em Feira de Santana, para substituir Chico Pinto, processado pelo regime militar, o MDB lan\u00e7ou o vereador Noide Cerqueira candidato a deputado federal. O prefeito Jos\u00e9 Falc\u00e3o reuniu a equipe e avisou que seriam demitidos os que n\u00e3o seguissem a decis\u00e3o partid\u00e1ria. Terminada a elei\u00e7\u00e3o e por ter votado em<\/p>\n","protected":false},"author":40,"featured_media":50264,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"cybocfi_hide_featured_image":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[592,1],"tags":[],"class_list":["post-50261","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-colunistas","category-raiz"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2022\/01\/images-5-1.jpeg","jetpack_shortlink":"https:\/\/wp.me\/p3niVf-d4F","jetpack_sharing_enabled":true,"jetpack-related-posts":[{"id":27527,"url":"https:\/\/blogdafeira.com.br\/home\/2017\/07\/18\/prefeito-jose-falcao-quero-saber-e-quando-eu-vou-fazer-o-gol-por-adilson-simas\/","url_meta":{"origin":50261,"position":0},"title":"&#8216;Prefeito Jos\u00e9 Falc\u00e3o, quero saber \u00e9 quando eu vou fazer o gol&#8217;, por Adilson Simas","author":"Blog da Feira","date":"18\/07\/2017","format":false,"excerpt":"Rec\u00e9m-empossado, no come\u00e7o de 1973, antes mesmo de entrar no Gabinete para mais um dia de trabalho, o prefeito Jos\u00e9 Falc\u00e3o \u00e9 interrompido por um eleitor que diz estar precisando de uma ajuda da Prefeitura de Feira de Santana. Falc\u00e3o explica que qualquer ajuda passa pelo processo burocr\u00e1tico, dentro da\u2026","rel":"","context":"Em &quot;Home&quot;","block_context":{"text":"Home","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/raiz\/"},"img":{"alt_text":"prefeito-jose-falcao-v","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2017\/07\/PREFEITO-JOS%C3%89-FALC%C3%83O-V.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":14998,"url":"https:\/\/blogdafeira.com.br\/home\/2015\/05\/16\/morreu-o-advogado-feirense-clovis-ribeiro-daltro\/","url_meta":{"origin":50261,"position":1},"title":"Morreu o advogado feirense Cl\u00f3vis Ribeiro Daltro","author":"Blog da Feira","date":"16\/05\/2015","format":false,"excerpt":"Faleceu na madrugada de s\u00e1bado, 16, o advogado\u00a0\u00a0Cl\u00f3vis Ribeiro Daltro, 69, profissional de larga milit\u00e2ncia, membro do diret\u00f3rio municipal do PMDB em Feira de Santana.O corpo \u00e9\u00a0velado na capela do Dom Pedro de Alc\u00e2ntara.O sepultamento acontece \u00e0s 16 horas no Cemit\u00e9rio Jardim Celestial. Cl\u00f3via \u00e9 irm\u00e3o do advogado Celso Ribeiro\u2026","rel":"","context":"Em &quot;Home&quot;","block_context":{"text":"Home","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/raiz\/"},"img":{"alt_text":"CLOVIS DALTRO","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2015\/05\/CLOVIS-DALTRO.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":13617,"url":"https:\/\/blogdafeira.com.br\/home\/2014\/11\/21\/neste-mes-completa-1-ano-da-prisao-do-lider-pacifista-clovis-nunes\/","url_meta":{"origin":50261,"position":2},"title":"Neste m\u00eas completa 1 ano da pris\u00e3o do l\u00edder pacifista Cl\u00f3vis Nunes","author":"Blog da Feira","date":"21\/11\/2014","format":false,"excerpt":"https:\/\/www.youtube.com\/watch?v=Bi0dQ66yNas Completa no pr\u00f3ximo dia 28, um ano da pris\u00e3o do l\u00edder pacifista, idealizador e criador da Passeata Paz Pela Paz' , o baiano de Feira de Santana, Clovis Nunes. Cl\u00f3vis foi preso em Fortaleza, numa opera\u00e7\u00e3o da Pol\u00edcia Federal envolvendo programa nacional de Desarmamento do qual Clovis foi tamb\u00e9m\u2026","rel":"","context":"Em &quot;Home&quot;","block_context":{"text":"Home","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/raiz\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/img.youtube.com\/vi\/Bi0dQ66yNas\/0.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":6657,"url":"https:\/\/blogdafeira.com.br\/home\/2013\/12\/01\/clovis-nunes-deve-sair-do-presidio-de-feira-esta-semana\/","url_meta":{"origin":50261,"position":3},"title":"Cl\u00f3vis Nunes deve sair do Pres\u00eddio de Feira esta semana","author":"Blog da Feira","date":"01\/12\/2013","format":false,"excerpt":"O diretor do MovPaz, Cl\u00f3vis Nunes, deve sair do Pres\u00eddio de Feira esta semana, quando expira o prazo da 'pris\u00e3o tempor\u00e1ria' a que est\u00e1 submetido.\u00a0A\u00a0'pris\u00e3o tempor\u00e1ria'\u00a0tem o prazo de cinco dias, mas pode ser prorrogada por decis\u00e3o da Justi\u00e7a Cl\u00f3vis Nunes foi preso pela Pol\u00edcia Federal em Fortaleza e est\u00e1\u2026","rel":"","context":"Em &quot;Home&quot;","block_context":{"text":"Home","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/raiz\/"},"img":{"alt_text":"clovisnunes","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2013\/11\/clovisnunes-170x113.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":6538,"url":"https:\/\/blogdafeira.com.br\/home\/2013\/11\/28\/feira-surpresa-com-prisao-de-clovis-nunes-pela-policia-federal-em-fortaleza\/","url_meta":{"origin":50261,"position":4},"title":"Feira surpresa com pris\u00e3o de Cl\u00f3vis Nunes pela Pol\u00edcia Federal em Fortaleza","author":"Blog da Feira","date":"28\/11\/2013","format":false,"excerpt":"O coordenador do Movimento Nacional pela Paz e criador das Passeatas pela Paz que hoje acontecem em todo o Brasil, o feirense Cl\u00f3vis Nunes foi preso hoje em Fortaleza pela Pol\u00edcia Federal acusado de fraude no programa de desarmamento. Nunes \u00e9 dirigente de uma ong que participa desse programa e\u2026","rel":"","context":"Em &quot;Home&quot;","block_context":{"text":"Home","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/raiz\/"},"img":{"alt_text":"clovisnunes","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2013\/11\/clovisnunes.jpg?resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2013\/11\/clovisnunes.jpg?resize=350%2C200 1x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2013\/11\/clovisnunes.jpg?resize=525%2C300 1.5x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2013\/11\/clovisnunes.jpg?resize=700%2C400 2x"},"classes":[]},{"id":574,"url":"https:\/\/blogdafeira.com.br\/home\/2013\/04\/17\/feira-de-santana-representada-no-conselho-nacional-de-seguranca-publica\/","url_meta":{"origin":50261,"position":5},"title":"Feira de Santana representada no Conselho Nacional de Seguran\u00e7a P\u00fablica.","author":"Blog da Feira","date":"17\/04\/2013","format":false,"excerpt":"O feirense Cl\u00f3vis Nunes tomou posse no Conselho Nacional de Seguran\u00e7a P\u00fablica- CONASP em Bras\u00edlia. A solenidade contou com a presen\u00e7a Ministro da Justi\u00e7a, \u00a0Jos\u00e9 Eduardo Cardozo, \u00a0e representantes de 34 entidades ligadas \u00e0 seguran\u00e7a p\u00fablica no pa\u00eds. Cl\u00f3vis Nunes, assume o cargo como representante da Rede Desarma Brasil, um\u2026","rel":"","context":"Em &quot;Home&quot;","block_context":{"text":"Home","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/raiz\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"_links":{"self":[{"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/posts\/50261","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/users\/40"}],"replies":[{"embeddable":true,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/comments?post=50261"}],"version-history":[{"count":2,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/posts\/50261\/revisions"}],"predecessor-version":[{"id":50322,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/posts\/50261\/revisions\/50322"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/media\/50264"}],"wp:attachment":[{"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/media?parent=50261"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/categories?post=50261"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/tags?post=50261"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}