{"id":50448,"date":"2022-02-01T15:40:07","date_gmt":"2022-02-01T18:40:07","guid":{"rendered":"https:\/\/blogdafeira.com.br\/home\/?p=50448"},"modified":"2022-02-03T19:16:14","modified_gmt":"2022-02-03T22:16:14","slug":"morreu-gerson-bulos-fundador-da-casa-esportiva-em-feira","status":"publish","type":"post","link":"https:\/\/blogdafeira.com.br\/home\/2022\/02\/01\/morreu-gerson-bulos-fundador-da-casa-esportiva-em-feira\/","title":{"rendered":"Morreu Gerson Bulos, fundador da &#8216;Casa Esportiva&#8217; em Feira"},"content":{"rendered":"<div id=\"blogd-2973735867\" class=\"blogd-fim-do-post-mobile blogd-entity-placement\" style=\"margin-left: auto;margin-right: auto;text-align: center;\"><a href=\"https:\/\/www.feiradesantana.ba.gov.br\/servico.asp?s=a&titulo=Prefeitura-de-Feira-lan%C3%A7a-programa-Rem%C3%A9dio-em-Casa-e-transforma-acesso-a-medicamentos-em-pol%C3%ADtica-p%C3%BAblica-de-cuidados.html&id=14&link=secom\/noticias.asp&idn=43684#noticias\" target=_blank><picture>\r\n  <source media=\"(min-width: 768px)\" srcset=\"https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2026\/03\/980x150.gif\">\r\n  \r\n  <img decoding=\"async\" src=\"https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2021\/01\/350x2002.gif\" alt=\"Publicidade\" style=\"width: 100%; max-width: 100%; height: auto; display: block; margin: 0 auto;\">\r\n\t<\/picture><\/a><\/div><p>Gerson Vasconcelos de Bulos, da Casa Esportiva, partiu deste plano hoje, acometido da Covid 19.Era um dos mais tradicionais comerciantes de Feira de Santana. Foi um grande incentivador do esporte amador da cidade.Faria amanh\u00e3\u00a0 98 anos de idade.<\/p>\n<p>Quando fui rep\u00f3rter do Jornal da Bahia, na d\u00e9cada de 70, consegui que a sucursal de Feira, tivesse o fornecimento de material fotogr\u00e1fico da Casa Esportiva.<\/p>\n<div id=\"blogd-3542683295\" class=\"blogd-final-post blogd-entity-placement\"><a href=\"https:\/\/www.feiradesantana.ba.leg.br\/\" target=\"_blank\" aria-label=\"JUNHO-VERMELHO_CA\u0302MARA-DE-FEIRA\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2026\/03\/JUNHO-VERMELHO_CAMARA-DE-FEIRA.gif\" alt=\"\"  class=\"no-lazyload\" width=\"728\" height=\"90\"   \/><\/a><\/div><p>Nos \u00faltimos anos Bulos ficava sentado, no interior da loja, da rua Conselheiro Franco, observando os clientes e vendo a movimento comercial da cidade.No dia de Yemanj\u00e1, nasceu Gerson Bulos e parte deixando saudades!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Gerson Vasconcelos de Bulos, da Casa Esportiva, partiu deste plano hoje, acometido da Covid 19.Era um dos mais tradicionais comerciantes de Feira de Santana. Foi um grande incentivador do esporte amador da cidade.Faria amanh\u00e3\u00a0 98 anos de idade. Quando fui rep\u00f3rter do Jornal da Bahia, na d\u00e9cada de 70, consegui que a sucursal de Feira,<\/p>\n","protected":false},"author":1,"featured_media":50450,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"cybocfi_hide_featured_image":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[3,592,1],"tags":[],"class_list":["post-50448","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cidade","category-colunistas","category-raiz"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2022\/02\/Screenshot_20220201-1508352.png","jetpack_shortlink":"https:\/\/wp.me\/p3niVf-d7G","jetpack_sharing_enabled":true,"jetpack-related-posts":[{"id":64771,"url":"https:\/\/blogdafeira.com.br\/home\/2024\/12\/05\/mostra-de-cinema-na-casa-noise-nesta-sexta-feira-a-vida-de-bule-bule\/","url_meta":{"origin":50448,"position":0},"title":"Mostra de cinema na Casa Noise nesta sexta-feira: a vida de Bule-Bule","author":"Wilson M\u00e1rio","date":"05\/12\/2024","format":false,"excerpt":"Nesta sexta-feira (06), a partir das 19h30, mais dois filmes, destacando personagens marcantes da Bahia, ser\u00e3o apresentados em uma nova sess\u00e3o do projeto Cine Noise no espa\u00e7o cultural Casa Noise, em Feira de Santana. A entrada \u00e9 gratuita. Na primeira exibi\u00e7\u00e3o da noite, o repentista, m\u00fasico, compositor, escritor e pesquisador\u2026","rel":"","context":"Em &quot;Cultura&quot;","block_context":{"text":"Cultura","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/cultura\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2024\/12\/IMG-20241204-WA0074.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2024\/12\/IMG-20241204-WA0074.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2024\/12\/IMG-20241204-WA0074.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2024\/12\/IMG-20241204-WA0074.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2024\/12\/IMG-20241204-WA0074.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":23334,"url":"https:\/\/blogdafeira.com.br\/home\/2016\/08\/30\/bule-bule-e-caboquinho-divertem-plateia-com-sextilhas-sobre-a-vida-de-dadinho\/","url_meta":{"origin":50448,"position":1},"title":"Bule Bule e Caboquinho divertem plat\u00e9ia com sextilhas sobre a vida de Dadinho","author":"Wilson M\u00e1rio","date":"30\/08\/2016","format":false,"excerpt":"\u00a0 O poeta cantador, mestre Bule Bule com o experiente violeiro Caboquinho deram o tom do riso e da brincadeira ao 42\u00ba Festival de Violeiros em Feira de Santana ao cantarem \u00a0versos sobre a vida de Dadinho da Bahia, violeiro criador do Festival. Bule Bule come\u00e7ou e Caboquinho n\u00e3o deixou\u2026","rel":"","context":"Em &quot;Home&quot;","block_context":{"text":"Home","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/raiz\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2020\/05\/Screenshot_2020-05-20-11-07-35-e1589983949666.png?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2020\/05\/Screenshot_2020-05-20-11-07-35-e1589983949666.png?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2020\/05\/Screenshot_2020-05-20-11-07-35-e1589983949666.png?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":28801,"url":"https:\/\/blogdafeira.com.br\/home\/2017\/12\/14\/assista-bule-bule-hoje-no-programa-soteropolis-da-tve-bahia\/","url_meta":{"origin":50448,"position":2},"title":"Assista Bule-Bule hoje no programa Soter\u00f3polis da TVE Bahia","author":"Wilson M\u00e1rio","date":"14\/12\/2017","format":false,"excerpt":"O programa Soter\u00f3polis desta quinta-feira (14), \u00e0s 22h, na TVE (Canal 10.1), homenageia o artista Bule Bule, que comemorou 70 anos de idade e 50 anos de carreira no m\u00eas de novembro atrav\u00e9s e dois shows intitulados \u201cAnt\u00f4nio 70, Bule Bule 50\u201d. Esta figura emblem\u00e1tica da cultura popular, conhecido como\u2026","rel":"","context":"Em &quot;Home&quot;","block_context":{"text":"Home","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/raiz\/"},"img":{"alt_text":"bule-bule","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2016\/11\/bule-bule.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":597,"url":"https:\/\/blogdafeira.com.br\/home\/2013\/04\/17\/documentario-sobre-bule-bule-esta-sendo-filmado-em-feira-de-santana\/","url_meta":{"origin":50448,"position":3},"title":"Document\u00e1rio sobre Bule-Bule est\u00e1 sendo filmado em Feira de Santana","author":"Wilson M\u00e1rio","date":"17\/04\/2013","format":false,"excerpt":"Est\u00e1 sendo gravado em Feira de Santana um document\u00e1rio sobre o famoso repentista Bule Bule. O epis\u00f3dio \u201cO Trovador, o Cabra e os Mundos\u201d faz parte da s\u00e9rie Visceral Brasil \u2013 as veias abertas da m\u00fasica, uma s\u00e9rie de 13 document\u00e1rios que ser\u00e1 exibido pela TV Brasil.\u00a0 As primeiras imagens\u2026","rel":"","context":"Em &quot;Home&quot;","block_context":{"text":"Home","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/raiz\/"},"img":{"alt_text":"bule","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2013\/04\/bule-147x150.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":27447,"url":"https:\/\/blogdafeira.com.br\/home\/2017\/07\/14\/bule-bule-abre-a-cortina-da-lembranca-e-fala-sobre-a-arte-em-videos-curtos\/","url_meta":{"origin":50448,"position":4},"title":"Bule-Bule abre a &#8216;cortina da lembran\u00e7a&#8217; e fala sobre a arte em v\u00eddeos curtos","author":"Wilson M\u00e1rio","date":"14\/07\/2017","format":false,"excerpt":"O poeta Bule Bule divulgou o primeiro de uma s\u00e9rie de v\u00eddeos curtos onde ele vai contando a hist\u00f3ria da arte popular misturada com a vida dele que chega aos 70 anos de idade em plena e criativa atividade. Cantador, cordelista, sambador, tiraneiro, mestre da cultura popular nordestina, ele nasceu\u2026","rel":"","context":"Em &quot;Home&quot;","block_context":{"text":"Home","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/raiz\/"},"img":{"alt_text":"IMG_20160827_202717077","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2016\/08\/IMG_20160827_202717077-576x1024.jpg?resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2016\/08\/IMG_20160827_202717077-576x1024.jpg?resize=350%2C200 1x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2016\/08\/IMG_20160827_202717077-576x1024.jpg?resize=525%2C300 1.5x"},"classes":[]},{"id":27293,"url":"https:\/\/blogdafeira.com.br\/home\/2017\/07\/01\/nenem-do-acordeon-hoje-no-sao-pedro-da-terra-de-bule-bule-antonio-cardoso-2\/","url_meta":{"origin":50448,"position":5},"title":"Nen\u00e9m do Acordeon hoje no S\u00e3o Pedro da &#8216;Terra de Bule-Bule&#8217;, Ant\u00f4nio Cardoso","author":"Wilson M\u00e1rio","date":"01\/07\/2017","format":false,"excerpt":"O sanfoneiro Nen\u00e9m do Acordeon, Jota Sobrinho e o Trio Barnab\u00e9, \u00a0animam hoje o S\u00e3o Pedro na cidade de Ant\u00f4nio Cardoso, (a 30 km de Feira de Santana), que encerra o per\u00edodo junino que este ano\u00a0homenageou os 70 anos do mestre de cultura popular Bule-Bule. Os eventos juninos \u00a0come\u00e7aram com\u2026","rel":"","context":"Em &quot;Home&quot;","block_context":{"text":"Home","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/raiz\/"},"img":{"alt_text":"antonio-cardoso-bule-bule","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2017\/07\/Antonio-cardoso-bule-bule.jpg?resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2017\/07\/Antonio-cardoso-bule-bule.jpg?resize=350%2C200 1x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2017\/07\/Antonio-cardoso-bule-bule.jpg?resize=525%2C300 1.5x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/posts\/50448","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/comments?post=50448"}],"version-history":[{"count":1,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/posts\/50448\/revisions"}],"predecessor-version":[{"id":50451,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/posts\/50448\/revisions\/50451"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/media\/50450"}],"wp:attachment":[{"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/media?parent=50448"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/categories?post=50448"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/tags?post=50448"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}