{"id":50614,"date":"2022-02-09T13:00:08","date_gmt":"2022-02-09T16:00:08","guid":{"rendered":"https:\/\/blogdafeira.com.br\/home\/?p=50614"},"modified":"2022-02-15T00:25:09","modified_gmt":"2022-02-15T03:25:09","slug":"faleceu-helder-alencar-referencia-da-imprensa-feirense","status":"publish","type":"post","link":"https:\/\/blogdafeira.com.br\/home\/2022\/02\/09\/faleceu-helder-alencar-referencia-da-imprensa-feirense\/","title":{"rendered":"Faleceu H\u00e9lder Alencar, refer\u00eancia da imprensa feirense"},"content":{"rendered":"<div id=\"blogd-3037799679\" class=\"blogd-fim-do-post-mobile blogd-entity-placement\" style=\"margin-left: auto;margin-right: auto;text-align: center;\"><a href=\"https:\/\/www.feiradesantana.ba.gov.br\/servico.asp?s=a&titulo=Prefeitura-de-Feira-lan%C3%A7a-programa-Rem%C3%A9dio-em-Casa-e-transforma-acesso-a-medicamentos-em-pol%C3%ADtica-p%C3%BAblica-de-cuidados.html&id=14&link=secom\/noticias.asp&idn=43684#noticias\" target=_blank><picture>\r\n  <source media=\"(min-width: 768px)\" srcset=\"https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2026\/03\/980x150.gif\">\r\n  \r\n  <img decoding=\"async\" src=\"https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2021\/01\/350x2002.gif\" alt=\"Publicidade\" style=\"width: 100%; max-width: 100%; height: auto; display: block; margin: 0 auto;\">\r\n\t<\/picture><\/a><\/div><p style=\"text-align: justify\">Hoje a Feira de Santana amanheceu de luto e o jornalismo feirense ficou mais pobre. Faleceu o jornalista, procurador aposentado da Uefs e historiador H\u00e9lder Alencar. Fundador do extinto jornal Feira Hoje \u2013 um dos marcos do jornalismo impresso local durante quase tr\u00eas d\u00e9cadas \u2013, H\u00e9lder desempenhava a fun\u00e7\u00e3o de editor-chefe da publica\u00e7\u00e3o nos anos 1970, \u00e9poca em que os impressos alcan\u00e7aram seu auge mundo afora e tamb\u00e9m por aqui. Embora n\u00e3o o tenha vivido, sei que foi um per\u00edodo fervilhante.<\/p>\n<p style=\"text-align: justify\">Considero-me um dos legat\u00e1rios da iniciativa de H\u00e9lder Alencar e de Egberto Costa, dois dos jornalistas fundadores do Feira Hoje: em meados dos anos 1990, j\u00e1 na fase final do jornal, tive a oportunidade de trabalhar na reda\u00e7\u00e3o do Feira Hoje, \u00e0 \u00e9poca sob a chefia do jornalista Valdomiro Silva. Foi l\u00e1 que comecei esta j\u00e1 longa trajet\u00f3ria, foi l\u00e1 que cursei, no batente, o jornalismo na pr\u00e1tica. O d\u00e9bito com os pioneiros fundadores do jornal, portanto, \u00e9 imensur\u00e1vel.<\/p>\n<p style=\"text-align: justify\">S\u00f3 muito recentemente \u2013 a partir de 2017 \u2013 tive a oportunidade de conviver com H\u00e9lder, trabalhando na reitoria da Uefs. At\u00e9 ent\u00e3o, conhecia-o s\u00f3 de encontros eventuais com amigos jornalistas. H\u00e9lder era mestre na arte da conversa\u00e7\u00e3o, que podia se estender por horas sem que o interlocutor percebesse a passagem do tempo.<\/p>\n<p style=\"text-align: justify\">No curto, mas marcante conv\u00edvio profissional conversava com ele frequentemente. Aprendi muito sobre a Feira de Santana e suas personagens, me inspirei em sua serenidade e sabedoria para lidar melhor com os desafios que marcam a administra\u00e7\u00e3o p\u00fablica. Nos corredores da Uefs ou no estacionamento defronte ao pr\u00e9dio da Administra\u00e7\u00e3o Central, sempre parava para ouvi-lo. Era um prazer ouvi-lo. Quando dizia que ia almo\u00e7ar na casa do meu pai, ele fazia um coment\u00e1rio engra\u00e7ado:<\/p>\n<p style=\"text-align: justify\">\u2013 Vai filar o pir\u00e3o do velho, hein?<\/p>\n<p style=\"text-align: justify\">Infelizmente, no seu sepultamento, H\u00e9lder n\u00e3o pode receber as homenagens dos seus in\u00fameros amigos e admiradores, porque foi v\u00edtima da Covid-19 e n\u00e3o houve vel\u00f3rio. Para mim, vai-se uma das maiores refer\u00eancias jornal\u00edsticas, que admirava desde os tempos em que, pouco mais que adolescente, comecei a labutar na reda\u00e7\u00e3o inesquec\u00edvel do jornal Feira Hoje.<\/p>\n<div id=\"blogd-2657887775\" class=\"blogd-final-post blogd-entity-placement\"><a href=\"https:\/\/www.feiradesantana.ba.leg.br\/\" target=\"_blank\" aria-label=\"JUNHO-VERMELHO_CA\u0302MARA-DE-FEIRA\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2026\/03\/JUNHO-VERMELHO_CAMARA-DE-FEIRA.gif\" alt=\"\"  class=\"no-lazyload\" width=\"728\" height=\"90\"   \/><\/a><\/div><p style=\"text-align: justify\">H\u00e9lder Alencar, a partir de agora, \u00e9 parte da Hist\u00f3ria do jornalismo feirense. Diria mais: torna-se parte da pr\u00f3pria Hist\u00f3ria feirense. Pesaroso, fa\u00e7o este texto p\u00e1lido \u00e0 guisa de homenagem&#8230;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hoje a Feira de Santana amanheceu de luto e o jornalismo feirense ficou mais pobre. Faleceu o jornalista, procurador aposentado da Uefs e historiador H\u00e9lder Alencar. Fundador do extinto jornal Feira Hoje \u2013 um dos marcos do jornalismo impresso local durante quase tr\u00eas d\u00e9cadas \u2013, H\u00e9lder desempenhava a fun\u00e7\u00e3o de editor-chefe da publica\u00e7\u00e3o nos anos<\/p>\n","protected":false},"author":13,"featured_media":50631,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"cybocfi_hide_featured_image":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[3,592,1],"tags":[],"class_list":["post-50614","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cidade","category-colunistas","category-raiz"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2022\/02\/1644410319IMG_4051-1-scaled.jpeg","jetpack_shortlink":"https:\/\/wp.me\/p3niVf-dam","jetpack_sharing_enabled":true,"jetpack-related-posts":[{"id":50601,"url":"https:\/\/blogdafeira.com.br\/home\/2022\/02\/09\/morre-em-feira-o-jornalista-e-advogado-helder-alencar\/","url_meta":{"origin":50614,"position":0},"title":"Morre em Feira o jornalista e advogado Helder Alencar","author":"Blog da Feira","date":"09\/02\/2022","format":false,"excerpt":"\"Eu sou ex-jornalista, formado em advocacia mas exercendo procuradoria jur\u00eddica. Pauto toda a minha vida pela humildade. Todos os dias que eu acordo eu lembro do fil\u00f3sofo grego S\u00f3crates: \"s\u00f3 sei que nada sei\". \u00a0 Morreu nesta madrugada o jornalista, advogado e escritor feirense Helder Alencar. No pr\u00f3ximo dia 19\u2026","rel":"","context":"Em &quot;Cidade&quot;","block_context":{"text":"Cidade","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/cidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2022\/02\/helder-alencar-entrevista.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":71598,"url":"https:\/\/blogdafeira.com.br\/home\/2026\/03\/08\/helder-alencar-na-festa-de-tito\/","url_meta":{"origin":50614,"position":1},"title":"H\u00e9lder Alencar na festa de Tito","author":"J\u00e2nio R\u00eago","date":"08\/03\/2026","format":false,"excerpt":"Houve um momento que Helder Alencar parecia estar ali naquela roda de conversa de veteranos jornalistas profissionais de Feira. N\u00e3o citarei nomes para n\u00e3o comprometer a vaidade biol\u00f3gica de ningu\u00e9m. Mediunidade, incorpora\u00e7\u00e3o, for\u00e7a dos Orix\u00e1s, do Divino, ou imagina\u00e7\u00e3o humana, seja o que for, eis Helder tomando cerveja com a\u2026","rel":"","context":"Em &quot;Colunistas&quot;","block_context":{"text":"Colunistas","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/colunistas\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2026\/03\/IMG_20260307_183011803_HDR2-1-scaled.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2026\/03\/IMG_20260307_183011803_HDR2-1-scaled.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2026\/03\/IMG_20260307_183011803_HDR2-1-scaled.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2026\/03\/IMG_20260307_183011803_HDR2-1-scaled.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2026\/03\/IMG_20260307_183011803_HDR2-1-scaled.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2026\/03\/IMG_20260307_183011803_HDR2-1-scaled.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":29794,"url":"https:\/\/blogdafeira.com.br\/home\/2018\/06\/08\/biblioteca-julieta-carteado-da-uefs-tem-exemplar-do-livro-feira\/","url_meta":{"origin":50614,"position":2},"title":"Biblioteca &#8216;Julieta Carteado&#8217; da UEFS tem exemplar do livro &#8216;Feira&#8217;","author":"J\u00e2nio R\u00eago","date":"08\/06\/2018","format":false,"excerpt":"\u201cFeira\u201d, livro lan\u00e7ado recentemente pelo jornalista J\u00e2nio R\u00eago, j\u00e1 faz parte do acervo da Biblioteca Central Julieta Carteado da Universidade Estadual de Feira de Santana (Uefs). O autor protocolou a doa\u00e7\u00e3o do livro que compila textos do pr\u00f3prio J\u00e2nio e de autores diversos que, ao longo dos \u00faltimos anos, contribu\u00edram\u2026","rel":"","context":"Em &quot;Home&quot;","block_context":{"text":"Home","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/raiz\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2018\/06\/FB_IMG_1528489124936-223x300.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":66941,"url":"https:\/\/blogdafeira.com.br\/home\/2025\/04\/26\/jornalismo-que-se-aprendia-no-olhar-e-se-aperfeicoava-na-convivencia\/","url_meta":{"origin":50614,"position":3},"title":"Jornalismo que se aprendia no olhar e se aperfei\u00e7oava na conviv\u00eancia","author":"Blog da Feira","date":"26\/04\/2025","format":false,"excerpt":"A cena parece sa\u00edda de um filme: dois jornalistas, cansados, mas animados, sentam-se \u00e0 mesa de um bar de esquina, m\u00e1quinas de escrever ainda ecoando em suas mentes, enquanto a fuma\u00e7a dos cigarros e o tilintar das garrafas formam a trilha sonora da madrugada. Era assim que muitas hist\u00f3rias nasciam\u2026","rel":"","context":"Em &quot;Colunistas&quot;","block_context":{"text":"Colunistas","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/colunistas\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2025\/04\/FB_IMG_17456726139772.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2025\/04\/FB_IMG_17456726139772.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2025\/04\/FB_IMG_17456726139772.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2025\/04\/FB_IMG_17456726139772.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2025\/04\/FB_IMG_17456726139772.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":29766,"url":"https:\/\/blogdafeira.com.br\/home\/2018\/06\/03\/lancado-feira-livro-do-jornalista-janio-rego-por-andre-pomponet\/","url_meta":{"origin":50614,"position":4},"title":"Lan\u00e7ado &#8216;Feira&#8217;, livro do jornalista J\u00e2nio R\u00eago, por Andr\u00e9 Pomponet","author":"Andr\u00e9 Pomponet","date":"03\/06\/2018","format":false,"excerpt":"Finalmente veio a p\u00fablico \u201cFeira\u201d, do jornalista potiguar J\u00e2nio R\u00eago, longamente radicado na Feira de Santana. Parto dif\u00edcil, adiado por um ano ou mais, mas que chegou de repente, como essas intensas trovoadas aguardadas com ansiedade pelos sertanejos, que desabam de uma vez. \u201cFeira\u201d come\u00e7a feliz j\u00e1 pelo t\u00edtulo: n\u00e3o\u2026","rel":"","context":"Em &quot;Colunistas&quot;","block_context":{"text":"Colunistas","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/colunistas\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2018\/06\/IMG_20180602_203927_719-300x300.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":50626,"url":"https:\/\/blogdafeira.com.br\/home\/2022\/02\/09\/nosso-convidado-foi-dr-helder-alencar\/","url_meta":{"origin":50614,"position":5},"title":"Nosso convidado foi Dr. Helder Alencar","author":"Elismar Pond\u00e9","date":"09\/02\/2022","format":false,"excerpt":"No long\u00ednquo ano de 2010, a equipe do @blogdafeira, liderada por @janiorego, se reuniu para mais uma grande entrevista, nosso convidado foi Dr Helder Alencar. Neste registro: @MarciliotCosta, @OrisaGomes, Reginaldo Tracaj\u00e1, Everaldo Goes, @PaulaaMacedo e @Gislaine_Sena.Tamb\u00e9m temos nesta foto Crispina Paula, Daniel Rego e o saudoso Cl\u00e1udio Boaventura. A entrevista\u2026","rel":"","context":"Em &quot;Cidade&quot;","block_context":{"text":"Cidade","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/cidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2022\/02\/Screenshot_20220209-1023262.png?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2022\/02\/Screenshot_20220209-1023262.png?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2022\/02\/Screenshot_20220209-1023262.png?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2022\/02\/Screenshot_20220209-1023262.png?resize=700%2C400&ssl=1 2x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/posts\/50614","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/comments?post=50614"}],"version-history":[{"count":3,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/posts\/50614\/revisions"}],"predecessor-version":[{"id":50640,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/posts\/50614\/revisions\/50640"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/media\/50631"}],"wp:attachment":[{"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/media?parent=50614"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/categories?post=50614"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/tags?post=50614"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}