{"id":50737,"date":"2022-02-14T03:59:52","date_gmt":"2022-02-14T06:59:52","guid":{"rendered":"https:\/\/blogdafeira.com.br\/home\/?p=50737"},"modified":"2022-02-16T22:59:27","modified_gmt":"2022-02-17T01:59:27","slug":"voce-pode-pagar-o-iptu-em-feira-ate-marco-com-20-de-desconto","status":"publish","type":"post","link":"https:\/\/blogdafeira.com.br\/home\/2022\/02\/14\/voce-pode-pagar-o-iptu-em-feira-ate-marco-com-20-de-desconto\/","title":{"rendered":"Voc\u00ea pode pagar o IPTU em Feira at\u00e9 mar\u00e7o com 20% de desconto"},"content":{"rendered":"<div id=\"blogd-3807219243\" class=\"blogd-fim-do-post-mobile blogd-entity-placement\" style=\"margin-left: auto;margin-right: auto;text-align: center;\"><a href=\"https:\/\/www.feiradesantana.ba.gov.br\/servico.asp?s=a&titulo=Prefeitura-de-Feira-lan%C3%A7a-programa-Rem%C3%A9dio-em-Casa-e-transforma-acesso-a-medicamentos-em-pol%C3%ADtica-p%C3%BAblica-de-cuidados.html&id=14&link=secom\/noticias.asp&idn=43684#noticias\" target=_blank><picture>\r\n  <source media=\"(min-width: 768px)\" srcset=\"https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2026\/03\/980x150.gif\">\r\n  \r\n  <img decoding=\"async\" src=\"https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2021\/01\/350x2002.gif\" alt=\"Publicidade\" style=\"width: 100%; max-width: 100%; height: auto; display: block; margin: 0 auto;\">\r\n\t<\/picture><\/a><\/div><p>A Prefeitura de Feira decidiu prorrogar o pagamento o pagamento do IPTU (Imposto Predial e Territorial Urbano) e da Taxa de Fiscaliza\u00e7\u00e3o de Funcionamento &#8211; TFF, dos exerc\u00edcios de 2020 e 2021. Sendo assim, o feirense pode pagar em cota \u00fanica com desconto de 20% at\u00e9 25 de mar\u00e7o.<\/p>\n<p>A decis\u00e3o do prefeito Colbert Filho considera os efeitos colaterais e negativos que ainda v\u00eam sendo causados pela crise sanit\u00e1ria provocada pela Covid-19, al\u00e9m dos in\u00fameros pedidos de diversos segmentos da sociedade civil organizada.<\/p>\n<p>O contribuinte que optou pelo parcelamento do IPTU tamb\u00e9m poder\u00e1 quitar o saldo remanescente com desconto de 20% at\u00e9 essa data. O decreto foi publicado neste s\u00e1bado, 12, no Di\u00e1rio Oficial Eletr\u00f4nico do Munic\u00edpio.<\/p>\n<p>Vale lembrar que as guias para o pagamento do IPTU e da TFF podem ser obtidas na p\u00e1gina da Secretaria Municipal da Fazenda (Sefaz) na internet, acessando \u00a0<a href=\"http:\/\/www.sefaz.feiradesantana.ba.gov.br\/\">www.sefaz.feiradesantana.ba.gov.br<\/a>, assim como diretamente no CEAF, localizado na rua Bar\u00e3o de Cotegipe, n\u00ba 764, Centro, ou ainda, atrav\u00e9s de solicita\u00e7\u00e3o atrav\u00e9s do e-mail dat@sefaz.feiradesantana.ba.gov.br<\/p>\n<div id=\"blogd-1889414049\" class=\"blogd-final-post blogd-entity-placement\"><a href=\"https:\/\/www.feiradesantana.ba.leg.br\/\" target=\"_blank\" aria-label=\"JUNHO-VERMELHO_CA\u0302MARA-DE-FEIRA\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2026\/03\/JUNHO-VERMELHO_CAMARA-DE-FEIRA.gif\" alt=\"\"  class=\"no-lazyload\" width=\"728\" height=\"90\"   \/><\/a><\/div><p>Confira abaixo o decreto:<\/p>\n<p><a href=\"https:\/\/feiradesantana.ba.gov.br\/arquivos\/1FT61L11022022_-_IPTU.pdf\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" src=\"https:\/\/feiradesantana.ba.gov.br\/imagens\/baixar.jpg\" border=\"0\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Prefeitura de Feira decidiu prorrogar o pagamento o pagamento do IPTU (Imposto Predial e Territorial Urbano) e da Taxa de Fiscaliza\u00e7\u00e3o de Funcionamento &#8211; TFF, dos exerc\u00edcios de 2020 e 2021. Sendo assim, o feirense pode pagar em cota \u00fanica com desconto de 20% at\u00e9 25 de mar\u00e7o. A decis\u00e3o do prefeito Colbert Filho<\/p>\n","protected":false},"author":1,"featured_media":50738,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"cybocfi_hide_featured_image":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[3,1],"tags":[],"class_list":["post-50737","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cidade","category-raiz"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2022\/02\/ipt.jpg","jetpack_shortlink":"https:\/\/wp.me\/p3niVf-dcl","jetpack_sharing_enabled":true,"jetpack-related-posts":[{"id":55850,"url":"https:\/\/blogdafeira.com.br\/home\/2022\/12\/14\/iptu-em-feira-com-20-de-desconto-ate-o-dia-23\/","url_meta":{"origin":50737,"position":0},"title":"IPTU em Feira com 20% de desconto at\u00e9 o dia 23","author":"Secom\/FSA","date":"14\/12\/2022","format":false,"excerpt":"Os contribuintes de Feira de Santana podem utilizar a segunda parcela do 13\u00ba sal\u00e1rio para aproveitar o desconto de 20% no pagamento do Imposto Predial e Territorial Urbano (IPTU) e da Taxa de Fiscaliza\u00e7\u00e3o do funcionamento (TFF), referente ao exerc\u00edcio de 2022. O prazo vai at\u00e9 o dia 23 de\u2026","rel":"","context":"Em &quot;Economia&quot;","block_context":{"text":"Economia","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/economia\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2022\/12\/thumbnail_Desconto-IPTU-2022-GALERIA-Foto-Jorge-Magalhaes-31.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2022\/12\/thumbnail_Desconto-IPTU-2022-GALERIA-Foto-Jorge-Magalhaes-31.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2022\/12\/thumbnail_Desconto-IPTU-2022-GALERIA-Foto-Jorge-Magalhaes-31.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2022\/12\/thumbnail_Desconto-IPTU-2022-GALERIA-Foto-Jorge-Magalhaes-31.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2022\/12\/thumbnail_Desconto-IPTU-2022-GALERIA-Foto-Jorge-Magalhaes-31.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":64142,"url":"https:\/\/blogdafeira.com.br\/home\/2024\/10\/08\/prefeitura-prorroga-prazo-de-pagamento-do-iptu-e-tff-para-23-de-dezembro\/","url_meta":{"origin":50737,"position":1},"title":"Prefeitura prorroga prazo de pagamento do IPTU e TFF para 23 de dezembro","author":"Secom\/FSA","date":"08\/10\/2024","format":false,"excerpt":"A Prefeitura de Feira prorrogou o prazo para pagamento da cota \u00fanica do Imposto Predial e Territorial Urbano (IPTU), com desconto de 15%, para o dia 23 de dezembro. A medida publicada no Di\u00e1rio Oficial Eletr\u00f4nico nesta ter\u00e7a-feira (8) considera as recorrentes interpela\u00e7\u00f5es dos mais diversos segmentos da sociedade civil\u2026","rel":"","context":"Em &quot;Geral&quot;","block_context":{"text":"Geral","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/geral\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2024\/10\/CAPA-1-CARNE-DO-IPTU-FOTO-VALDENIR-LIMA-21211.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2024\/10\/CAPA-1-CARNE-DO-IPTU-FOTO-VALDENIR-LIMA-21211.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2024\/10\/CAPA-1-CARNE-DO-IPTU-FOTO-VALDENIR-LIMA-21211.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2024\/10\/CAPA-1-CARNE-DO-IPTU-FOTO-VALDENIR-LIMA-21211.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2024\/10\/CAPA-1-CARNE-DO-IPTU-FOTO-VALDENIR-LIMA-21211.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":58650,"url":"https:\/\/blogdafeira.com.br\/home\/2023\/07\/14\/iptu-em-feira-com-desconte-de-20-ate-proximo-dia-28\/","url_meta":{"origin":50737,"position":2},"title":"IPTU em Feira com desconto de 20% at\u00e9 pr\u00f3ximo dia 28","author":"Secom\/FSA","date":"14\/07\/2023","format":false,"excerpt":"O prazo para pagamento do IPTU (Imposto Predial e Territorial Urbano) 2023 em cota \u00fanica com desconto de 20% segue at\u00e9 o dia 28. O contribuinte que optou pelo parcelamento tamb\u00e9m poder\u00e1 quitar o saldo remanescente com desconto at\u00e9 essa data. \"\u00c9 importante que o contribuinte n\u00e3o perca esta oportunidade\u2026","rel":"","context":"Em &quot;Cidade&quot;","block_context":{"text":"Cidade","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/cidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2023\/07\/13072023152511.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2023\/07\/13072023152511.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2023\/07\/13072023152511.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2023\/07\/13072023152511.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2023\/07\/13072023152511.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":26580,"url":"https:\/\/blogdafeira.com.br\/home\/2017\/04\/18\/parcela-unica-do-iptu-em-feira-pode-ser-paga-ate-o-dia-15-de-maio\/","url_meta":{"origin":50737,"position":3},"title":"Parcela \u00fanica do IPTU em Feira pode ser paga at\u00e9 o dia 15 de maio","author":"Secom\/FSA","date":"18\/04\/2017","format":false,"excerpt":"Est\u00e1 prorrogado at\u00e9 o dia 15 de maio o prazo para pagamento em parcela \u00fanica do IPTU 2017, em Feira de Santana. A medida foi anunciada pelo secret\u00e1rio da Fazenda do Munic\u00edpio, Expedito Eloy. A quita\u00e7\u00e3o do imposto at\u00e9 esta data poder\u00e1 ser feita com desconto de 20 por cento,\u2026","rel":"","context":"Em &quot;Home&quot;","block_context":{"text":"Home","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/raiz\/"},"img":{"alt_text":"img_20170403_224754","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2017\/04\/IMG_20170403_224754-189x300.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":9221,"url":"https:\/\/blogdafeira.com.br\/home\/2014\/02\/19\/prefeitura-de-feira-distribui-carnes-do-iptu-no-proximo-mes\/","url_meta":{"origin":50737,"position":4},"title":"Prefeitura de Feira distribui carn\u00eas do IPTU no pr\u00f3ximo m\u00eas","author":"Secom\/FSA","date":"19\/02\/2014","format":false,"excerpt":"Os carn\u00eas para pagamento do Imposto sobre a Propriedade Predial e Territorial Urbana (IPTU) devem come\u00e7ar a ser distribu\u00eddos, a partir da primeira quinzena de mar\u00e7o. Antes, os contribuintes receber\u00e3o em suas resid\u00eancias um comunicado explicando, de forma detalhada, os motivos que justificam a adequa\u00e7\u00e3o na taxa cobrada. O valor\u2026","rel":"","context":"Em &quot;Home&quot;","block_context":{"text":"Home","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/raiz\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":31127,"url":"https:\/\/blogdafeira.com.br\/home\/2019\/04\/03\/pague-iptu-com-desconto-ate-esta-quinta-feira-em-feira-de-santana\/","url_meta":{"origin":50737,"position":5},"title":"Pague IPTU com desconto at\u00e9 esta quinta-feira em Feira de Santana","author":"Secom\/FSA","date":"03\/04\/2019","format":false,"excerpt":"O prazo para o pagamento do IPTU (Imposto Predial e Territorial Urbano) em Feira de Santana, do exerc\u00edcio deste ano, com desconto de 20%, em cota \u00fanica, ser\u00e1 encerrado no final da tarde desta quinta-feira, 4, quando os estabelecimentos autorizados a receber o tributo encerram suas atividades. A partir de\u2026","rel":"","context":"Em &quot;Home&quot;","block_context":{"text":"Home","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/raiz\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2019\/04\/feira-aerea.jpg?resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2019\/04\/feira-aerea.jpg?resize=350%2C200 1x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2019\/04\/feira-aerea.jpg?resize=525%2C300 1.5x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/posts\/50737","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/comments?post=50737"}],"version-history":[{"count":1,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/posts\/50737\/revisions"}],"predecessor-version":[{"id":50739,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/posts\/50737\/revisions\/50739"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/media\/50738"}],"wp:attachment":[{"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/media?parent=50737"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/categories?post=50737"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/tags?post=50737"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}