{"id":50861,"date":"2022-02-19T14:24:12","date_gmt":"2022-02-19T17:24:12","guid":{"rendered":"https:\/\/blogdafeira.com.br\/home\/?p=50861"},"modified":"2022-02-25T19:58:25","modified_gmt":"2022-02-25T22:58:25","slug":"sabado-na-feira","status":"publish","type":"post","link":"https:\/\/blogdafeira.com.br\/home\/2022\/02\/19\/sabado-na-feira\/","title":{"rendered":"Pandemia cruel apagou o samba na pra\u00e7a do Map"},"content":{"rendered":"<div id=\"blogd-3658022932\" class=\"blogd-fim-do-post-mobile blogd-entity-placement\" style=\"margin-left: auto;margin-right: auto;text-align: center;\"><a href=\"https:\/\/www.feiradesantana.ba.gov.br\/servico.asp?s=a&titulo=Prefeitura-de-Feira-lan%C3%A7a-programa-Rem%C3%A9dio-em-Casa-e-transforma-acesso-a-medicamentos-em-pol%C3%ADtica-p%C3%BAblica-de-cuidados.html&id=14&link=secom\/noticias.asp&idn=43684#noticias\" target=_blank><picture>\r\n  <source media=\"(min-width: 768px)\" srcset=\"https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2026\/03\/980x150.gif\">\r\n  \r\n  <img decoding=\"async\" src=\"https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2021\/01\/350x2002.gif\" alt=\"Publicidade\" style=\"width: 100%; max-width: 100%; height: auto; display: block; margin: 0 auto;\">\r\n\t<\/picture><\/a><\/div><p style=\"text-align: justify;\">A pedra vermelha est\u00e1 l\u00e1 ao p\u00e9 do oiti mas a sombra da \u00e1rvore n\u00e3o projeta mais o gingado e o batuque dos Angoleiros do Sert\u00e3o sob a batuta do mestre Cl\u00e1udio. Pandemia cruel apagou o samba dos capoeiristas na pra\u00e7a do Map aos s\u00e1bados. Feira \u00e9 movimento, \u00e9 passagem e as coisas mudam de lugar, sempre, o v\u00edrus s\u00f3 apressou. Manifesta\u00e7\u00f5es espont\u00e2neas e despretenciosas como aquela, nas ruas, p\u00fablicas, j\u00e1 eram raras tornam-se rar\u00edssimas a partir de agora. Surgiram, por exemplo, dois m\u00fasicos nas novas cal\u00e7adas do centro, mas n\u00e3o se trata da mesma motiva\u00e7\u00e3o nem demanda. O samba estava na pra\u00e7a como um preceito, uma obriga\u00e7\u00e3o com a cultura, tradi\u00e7\u00e3o e conhecimento popular.<\/p>\n<p style=\"text-align: justify;\">****<\/p>\n<div id=\"blogd-4107891577\" class=\"blogd-final-post blogd-entity-placement\"><a href=\"https:\/\/www.feiradesantana.ba.leg.br\/\" target=\"_blank\" aria-label=\"JUNHO-VERMELHO_CA\u0302MARA-DE-FEIRA\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2026\/03\/JUNHO-VERMELHO_CAMARA-DE-FEIRA.gif\" alt=\"\"  class=\"no-lazyload\" width=\"728\" height=\"90\"   \/><\/a><\/div><p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-50862\" src=\"https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2022\/02\/FL9_hqUWQBEm1NQ-259x300.png\" alt=\"\" width=\"259\" height=\"300\" srcset=\"https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2022\/02\/FL9_hqUWQBEm1NQ-259x300.png 259w, https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2022\/02\/FL9_hqUWQBEm1NQ-130x150.png 130w, https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2022\/02\/FL9_hqUWQBEm1NQ-162x187.png 162w, https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2022\/02\/FL9_hqUWQBEm1NQ.png 400w\" sizes=\"auto, (max-width: 259px) 100vw, 259px\" \/>Talvez quem more em Ipupiara, um pequeno munic\u00edpio baiano de pouco mais de 10 mil habitantes, talvez saiba porque o prefeito do lugar meteu uma camisa referenciando a bandeira dos EUA para receber na cidade e anunciar apoio ao candidato oposicionista a governador da Bahia, ACM Neto. O prefeito \u00e9 do PP, partido aliado ao atual governo do PT.<\/p>\n<p><span class=\"embed-youtube\" style=\"text-align:center; display: block;\"><iframe loading=\"lazy\" class=\"youtube-player\" width=\"1170\" height=\"659\" src=\"https:\/\/www.youtube.com\/embed\/on1euhFsqNc?version=3&#038;rel=1&#038;showsearch=0&#038;showinfo=1&#038;iv_load_policy=1&#038;fs=1&#038;hl=pt-BR&#038;autohide=2&#038;wmode=transparent\" allowfullscreen=\"true\" style=\"border:0;\" sandbox=\"allow-scripts allow-same-origin allow-popups allow-presentation allow-popups-to-escape-sandbox\"><\/iframe><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A pedra vermelha est\u00e1 l\u00e1 ao p\u00e9 do oiti mas a sombra da \u00e1rvore n\u00e3o projeta mais o gingado e o batuque dos Angoleiros do Sert\u00e3o sob a batuta do mestre Cl\u00e1udio. Pandemia cruel apagou o samba dos capoeiristas na pra\u00e7a do Map aos s\u00e1bados. Feira \u00e9 movimento, \u00e9 passagem e as coisas mudam de<\/p>\n","protected":false},"author":8,"featured_media":50864,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"cybocfi_hide_featured_image":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[592,1],"tags":[],"class_list":["post-50861","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-colunistas","category-raiz"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2022\/02\/Screenshot_20220219-142116.png","jetpack_shortlink":"https:\/\/wp.me\/p3niVf-del","jetpack_sharing_enabled":true,"jetpack-related-posts":[{"id":31500,"url":"https:\/\/blogdafeira.com.br\/home\/2019\/05\/27\/grupo-angoleiros-do-sertao-vai-mostrar-em-berlim-na-alemanha-a-capoeira-e-o-samba-rural-de-feira-de-santana\/","url_meta":{"origin":50861,"position":0},"title":"Angoleiros do Sert\u00e3o vai a Berlim levando capoeira e samba rural","author":"J\u00e2nio R\u00eago","date":"27\/05\/2019","format":false,"excerpt":"\u00a0 N\u00e3o estranhe se no pr\u00f3ximo dia 22 de junho,o mestre Claudio n\u00e3o estiver na roda de samba e capoeira que o grupo \"Angoleiros do Sert\u00e3o faz todos os sabados. na pra\u00e7a do MAP em Feira de Santana. \u00c9 que o mestre, l\u00edder e fundador do grupo \"Angoleiros do Sert\u00e3o\",\u2026","rel":"","context":"Em &quot;Home&quot;","block_context":{"text":"Home","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/raiz\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2019\/05\/june-event.jpg?resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2019\/05\/june-event.jpg?resize=350%2C200 1x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2019\/05\/june-event.jpg?resize=525%2C300 1.5x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2019\/05\/june-event.jpg?resize=700%2C400 2x"},"classes":[]},{"id":56714,"url":"https:\/\/blogdafeira.com.br\/home\/2023\/03\/01\/coitada-da-praca-do-tropeiro-viva-o-samba-de-luizinho\/","url_meta":{"origin":50861,"position":1},"title":"Coitada da pra\u00e7a do Tropeiro, viva o samba de Luizinho!","author":"J\u00e2nio R\u00eago","date":"01\/03\/2023","format":false,"excerpt":"\"E segunda-feira, vai l\u00e1?\" Fui, nunca mais tinha ido, Luizinho de Ipua\u00e7u nas oito baixos, caixa de som nova, som limpo e claro, instrumento afinado,\u00a0 repert\u00f3rio sincopado tem at\u00e9 hino de futebol e o de Georgina no jeito do forr\u00f3 e do samba chiado na sanfona; como os passos e\u2026","rel":"","context":"Em &quot;Cidade&quot;","block_context":{"text":"Cidade","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/cidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2023\/03\/IMG_20220905_115853_795-1-scaled.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2023\/03\/IMG_20220905_115853_795-1-scaled.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2023\/03\/IMG_20220905_115853_795-1-scaled.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2023\/03\/IMG_20220905_115853_795-1-scaled.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2023\/03\/IMG_20220905_115853_795-1-scaled.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2023\/03\/IMG_20220905_115853_795-1-scaled.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":36390,"url":"https:\/\/blogdafeira.com.br\/home\/2020\/03\/19\/sabado-nao-tem-samba-nem-comercio-no-centro-da-feira\/","url_meta":{"origin":50861,"position":2},"title":"S\u00e1bado n\u00e3o tem samba nem com\u00e9rcio no centro da Feira","author":"J\u00e2nio R\u00eago","date":"19\/03\/2020","format":false,"excerpt":"Feira em busca da transmiss\u00e3o zero do coronav\u00edrus fecha o com\u00e9rcio por sete dias. Neste s\u00e1bado n\u00e3o tem samba nem capoeira na pra\u00e7a do Map. O grande centro da cidade e o seu com\u00e9rcio radial, j\u00e1 estava desquecido desde as primeiras medidas tomadas pelos poderes p\u00fablicos. Hoje o prefeito Colbert\u2026","rel":"","context":"Em &quot;Cidade&quot;","block_context":{"text":"Cidade","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/cidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2020\/03\/20191123_111921_HDR.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2020\/03\/20191123_111921_HDR.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2020\/03\/20191123_111921_HDR.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2020\/03\/20191123_111921_HDR.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2020\/03\/20191123_111921_HDR.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2020\/03\/20191123_111921_HDR.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":38699,"url":"https:\/\/blogdafeira.com.br\/home\/2020\/06\/27\/sabado-na-feira-antes-da-pandemia\/","url_meta":{"origin":50861,"position":3},"title":"S\u00e1bado na Feira ou os especialistas em pandemia","author":"J\u00e2nio R\u00eago","date":"27\/06\/2020","format":false,"excerpt":"De repente nos tornamos especialistas em pandemia. \u00c9 parecido com o que ocorre, por exemplo, em copa do mundo, onde h\u00e1 t\u00e9cnicos de futebol em cada esquina. H\u00e1 os que analisam os n\u00fameros de infectados, mortos, hospitalizados,\u00a0 as taxas de transmiss\u00e3o, os n\u00edveis de isolamento, como verdadeiros estat\u00edsticos. Outros, se\u2026","rel":"","context":"Em &quot;Colunistas&quot;","block_context":{"text":"Colunistas","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/colunistas\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2020\/06\/sabado-2.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2020\/06\/sabado-2.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2020\/06\/sabado-2.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2020\/06\/sabado-2.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2020\/06\/sabado-2.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":68922,"url":"https:\/\/blogdafeira.com.br\/home\/2025\/08\/12\/obras-avancam-na-praca-do-tropeiro-mas-o-samba-nao-para\/","url_meta":{"origin":50861,"position":4},"title":"Obras avan\u00e7am na Pra\u00e7a do Tropeiro mas o Samba n\u00e3o p\u00e1ra","author":"Blog da Feira","date":"12\/08\/2025","format":false,"excerpt":"As obras da Prefeitura de Feira na Pra\u00e7a do Tropeiro avan\u00e7am na parte superior da pra\u00e7a,\u00a0 onde est\u00e3o as est\u00e1tuas do Tropeiro e da Mula-Madrinha. A \u00e1rea est\u00e1 isolada por tabiques de metal. Por enquanto todos os boxes est\u00e3o abertos e ontem, segunda-feira,11, o Samba de Luizinho dos 8 Baixos\u2026","rel":"","context":"Em &quot;Cultura&quot;","block_context":{"text":"Cultura","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/cultura\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2025\/08\/IMG_20250811_134250799_MP2-scaled.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2025\/08\/IMG_20250811_134250799_MP2-scaled.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2025\/08\/IMG_20250811_134250799_MP2-scaled.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2025\/08\/IMG_20250811_134250799_MP2-scaled.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2025\/08\/IMG_20250811_134250799_MP2-scaled.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2025\/08\/IMG_20250811_134250799_MP2-scaled.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":72069,"url":"https:\/\/blogdafeira.com.br\/home\/2026\/04\/20\/o-samba-da-praca-do-tropeiro-nao-pode-parar-2\/","url_meta":{"origin":50861,"position":5},"title":"O Samba da Pra\u00e7a do Tropeiro n\u00e3o pode parar (2)","author":"J\u00e2nio R\u00eago","date":"20\/04\/2026","format":false,"excerpt":"Esse samba popular nasceu depois que a feira-livre foi deslocada para o Centro de Abastecimento. Veio a urbaniza\u00e7\u00e3o da pra\u00e7a do Tropeiro e o samba continuou pelas barracas. No s\u00e9culo passado, o samba acontecia na\u00a0 de Dona B\u00e1rbara. Eu vi\u00a0 Baio do Acordeon, com um p\u00e9 no tamborete, debulhando a\u2026","rel":"","context":"Em &quot;Colunistas&quot;","block_context":{"text":"Colunistas","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/colunistas\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2026\/04\/Screenshot_20260420-0102283.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2026\/04\/Screenshot_20260420-0102283.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2026\/04\/Screenshot_20260420-0102283.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2026\/04\/Screenshot_20260420-0102283.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2026\/04\/Screenshot_20260420-0102283.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/posts\/50861","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/comments?post=50861"}],"version-history":[{"count":11,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/posts\/50861\/revisions"}],"predecessor-version":[{"id":50917,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/posts\/50861\/revisions\/50917"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/media\/50864"}],"wp:attachment":[{"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/media?parent=50861"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/categories?post=50861"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/tags?post=50861"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}