{"id":51142,"date":"2022-03-07T21:23:53","date_gmt":"2022-03-08T00:23:53","guid":{"rendered":"https:\/\/blogdafeira.com.br\/home\/?p=51142"},"modified":"2022-03-11T23:27:33","modified_gmt":"2022-03-12T02:27:33","slug":"camara-de-vereadores-de-feira-foi-instalada-onde-esta-hoje-ha-40-anos","status":"publish","type":"post","link":"https:\/\/blogdafeira.com.br\/home\/2022\/03\/07\/camara-de-vereadores-de-feira-foi-instalada-onde-esta-hoje-ha-40-anos\/","title":{"rendered":"C\u00e2mara de Vereadores de Feira foi instalada onde est\u00e1 hoje h\u00e1 40 anos"},"content":{"rendered":"<div id=\"blogd-3545081274\" class=\"blogd-fim-do-post-mobile blogd-entity-placement\" style=\"margin-left: auto;margin-right: auto;text-align: center;\"><a href=\"https:\/\/www.feiradesantana.ba.gov.br\/servico.asp?s=a&titulo=Prefeitura-de-Feira-lan%C3%A7a-programa-Rem%C3%A9dio-em-Casa-e-transforma-acesso-a-medicamentos-em-pol%C3%ADtica-p%C3%BAblica-de-cuidados.html&id=14&link=secom\/noticias.asp&idn=43684#noticias\" target=_blank><picture>\r\n  <source media=\"(min-width: 768px)\" srcset=\"https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2026\/03\/980x150.gif\">\r\n  \r\n  <img decoding=\"async\" src=\"https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2021\/01\/350x2002.gif\" alt=\"Publicidade\" style=\"width: 100%; max-width: 100%; height: auto; display: block; margin: 0 auto;\">\r\n\t<\/picture><\/a><\/div><p>H\u00e1 40 anos, setembro de 1982, em plena campanha para as elei\u00e7\u00f5es gerais, a \u00faltima, que aconteceria em novembro,\u00a0 o Poder Legislativo de Feira de Santana instalou-se no antigo pr\u00e9dio da Cadeia P\u00fablica onde funciona at\u00e9 hoje, na avenida Visconde do Rio Branco, no centro da cidade.<\/p>\n<p>A legislatura fez apenas a\u00a0 inaugura\u00e7\u00e3o mas praticamente quem iniciou o uso foi a legislatura seguinte (1983-88). Era presidente Renato S\u00e1 C\u00e2mara que n\u00e3o foi reeleito.<\/p>\n<p>Apenas tr\u00eas se reelegeram, lembra o advogado Celso Daltro <strong>(foto)<\/strong> que foi eleito vereador naquele ano. Celso \u00e9 o atual presidente municipal do MDB e assessor especial do prefeito Colbert Filho.<\/p>\n<p>Na \u00e9poca eram treze vereadores ao todo. Existe uma placa com o nome deles no hall de entrada.Daqueles\u00a0 vereadores apenas tr\u00eas\u00a0 continuam vivos.S\u00e3o eles:<\/p>\n<p>o cantor e compositor e hoteleiro Beto Pitombo, que mora e trabalha na praia de Imbassahy. Beto nem tentou continuar a carreira politica. Foi o primeiro e \u00fanico mandato;<\/p>\n<p>Ant\u00f4nio Carlos Daltro Coelho, (Coelhinho),atual presidente da Funda\u00e7\u00e3o Egberto Costa;<\/p>\n<p>e Nilton Bellas Vieira, advogado presidente do Instituto Hist\u00f3rico de Feira de Santana.<\/p>\n<div id=\"blogd-1480143330\" class=\"blogd-final-post blogd-entity-placement\"><a href=\"https:\/\/www.feiradesantana.ba.leg.br\/\" target=\"_blank\" aria-label=\"JUNHO-VERMELHO_CA\u0302MARA-DE-FEIRA\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2026\/03\/JUNHO-VERMELHO_CAMARA-DE-FEIRA.gif\" alt=\"\"  class=\"no-lazyload\" width=\"728\" height=\"90\"   \/><\/a><\/div><p>Em 1982 elegeu-se prefeito Jos\u00e9 Falc\u00e3o da Silva para um mandato de 6 (seis) anos, criado pelo governo federal para acabar com as elei\u00e7\u00f5es gerais, ou seja,\u00a0 &#8216;descoincidir&#8217; as duas elei\u00e7\u00f5es: estadual e nacional da municipal, como ainda \u00e9 hoje em dia.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>H\u00e1 40 anos, setembro de 1982, em plena campanha para as elei\u00e7\u00f5es gerais, a \u00faltima, que aconteceria em novembro,\u00a0 o Poder Legislativo de Feira de Santana instalou-se no antigo pr\u00e9dio da Cadeia P\u00fablica onde funciona at\u00e9 hoje, na avenida Visconde do Rio Branco, no centro da cidade. A legislatura fez apenas a\u00a0 inaugura\u00e7\u00e3o mas praticamente<\/p>\n","protected":false},"author":8,"featured_media":51145,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"cybocfi_hide_featured_image":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[592,1,631],"tags":[],"class_list":["post-51142","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-colunistas","category-raiz","category-politica"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2022\/03\/images.jpeg","jetpack_shortlink":"https:\/\/wp.me\/p3niVf-diS","jetpack_sharing_enabled":true,"jetpack-related-posts":[{"id":69896,"url":"https:\/\/blogdafeira.com.br\/home\/2025\/10\/21\/corpo-de-celso-daltro-esta-sendo-velado-na-camara-de-vereadores-de-feira-de-santana\/","url_meta":{"origin":51142,"position":0},"title":"Corpo de Celso Daltro \u00e9 velado na C\u00e2mara de Vereadores de Feira de Santana","author":"Blog da Feira","date":"21\/10\/2025","format":false,"excerpt":"A C\u00e2mara Municipal de Feira de Santana declarou Luto Oficial, por 3 (tr\u00eas) dias, em raz\u00e3o do falecimento do advogado e ex-vereador\u00a0 Celso Ribeiro Daltro, nesta ter\u00e7a-feira. O corporativo do advogado \u00e9 velado no sagu\u00e3o da C\u00e2mara Municipal de Feira de Santana, a partir das 8 h de amanh\u00e3, quando\u2026","rel":"","context":"Em &quot;Cidade&quot;","block_context":{"text":"Cidade","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/cidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2025\/10\/fcrxt.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":24547,"url":"https:\/\/blogdafeira.com.br\/home\/2016\/11\/23\/orcamento-de-feira-vai-ser-votado-nas-ultimas-sessoes-da-camara-de-vereadores\/","url_meta":{"origin":51142,"position":1},"title":"Or\u00e7amento de Feira vai ser votado nas \u00faltimas sess\u00f5es da C\u00e2mara de Vereadores","author":"Blog da Feira","date":"23\/11\/2016","format":false,"excerpt":"Quando faltarem tr\u00eas ou quatro sess\u00f5es para o t\u00e9rmino desta legislatura, em meados de dezembro, \u00e9 que a C\u00e2mara de Vereadores de Feira colocar\u00e1 em discuss\u00e3o e vota\u00e7\u00e3o o projeto da Lei Or\u00e7ament\u00e1ria Anual (LOA) que define \u00a0as a\u00e7\u00f5es e investimentos \u00a0do Governo para o ano de 2017. O Or\u00e7amento\u2026","rel":"","context":"Em &quot;Home&quot;","block_context":{"text":"Home","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/raiz\/"},"img":{"alt_text":"camara-de-veradores","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2016\/11\/camara-de-veradores.jpg?resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2016\/11\/camara-de-veradores.jpg?resize=350%2C200 1x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2016\/11\/camara-de-veradores.jpg?resize=525%2C300 1.5x"},"classes":[]},{"id":56201,"url":"https:\/\/blogdafeira.com.br\/home\/2023\/01\/16\/eremita-e-o-desafio-de-resgatar-a-credibilidade-da-camara-de-vereadores\/","url_meta":{"origin":51142,"position":2},"title":"Eremita e o desafio de resgatar a credibilidade da C\u00e2mara de Vereadores","author":"J\u00e2nio R\u00eago","date":"16\/01\/2023","format":false,"excerpt":"A vota\u00e7\u00e3o do Or\u00e7amento 2023\u00a0 de Feira de Santana, prevista para essa semana, \u00e9 o primeiro teste de equil\u00edbrio e lideran\u00e7a da presidente da C\u00e2mara, vereadora Eremita Mota (PSDB). Al\u00e9m da enorme quantidade de emendas ao Or\u00e7amento (cerca de 50), h\u00e1 um ponto crucial para a gest\u00e3o p\u00fablica que vai\u2026","rel":"","context":"Em &quot;Colunistas&quot;","block_context":{"text":"Colunistas","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/colunistas\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2023\/01\/images-2.jpeg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":42369,"url":"https:\/\/blogdafeira.com.br\/home\/2020\/12\/09\/vereadores-evangelicos-de-feira-de-olho-na-presidencia-da-camara\/","url_meta":{"origin":51142,"position":3},"title":"Vereadores evang\u00e9licos em Feira de olho na Presid\u00eancia da C\u00e2mara","author":"Blog da Feira","date":"09\/12\/2020","format":false,"excerpt":"Os vereadores evang\u00e9licos em Feira de Santana, eleitos e reeleitos, Josse Paulo (Paul\u00e3o do Caldeir\u00e3o), Valdemir Santos, Eli Ribeiro e Edvaldo Lima, fizeram uma reuni\u00e3o este m\u00eas\u00a0 para tratar\u00a0 de estrat\u00e9gias de mandato para \"impedir projetos contra a fam\u00edlia e os dogmas crist\u00e3os\", informou o Portal Cidade Gospel Na mesma\u2026","rel":"","context":"Em &quot;Home&quot;","block_context":{"text":"Home","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/raiz\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2020\/12\/evangelicos.png?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2020\/12\/evangelicos.png?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2020\/12\/evangelicos.png?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":47298,"url":"https:\/\/blogdafeira.com.br\/home\/2021\/09\/08\/xingamentos-e-insultos-viram-rotina-na-camara-de-vereadores-de-feira\/","url_meta":{"origin":51142,"position":4},"title":"Xingamentos e insultos viram rotina na C\u00e2mara de Vereadores de Feira","author":"Blog da Feira","date":"08\/09\/2021","format":false,"excerpt":"Os vereadores de Feira de Santana ofereceram aos mun\u00edcipes, nesta quarta-feira, 8, mais uma sess\u00e3o com xingamentos, insultos e baixaria. Esse estilo tem sido uma constante no Poder Legislativo de Feira desde o in\u00edcio dessa legislatura e o maior protagonista dos epis\u00f3dios mais indecorosos \u00e9 o pr\u00f3prio presidente da Casa,\u2026","rel":"","context":"Em &quot;Cidade&quot;","block_context":{"text":"Cidade","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/cidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2021\/09\/images-1.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2021\/09\/images-1.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2021\/09\/images-1.jpeg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":65514,"url":"https:\/\/blogdafeira.com.br\/home\/2025\/02\/05\/camara-de-feira-comeca-uma-nova-legislatura-com-uma-maioria-de-antigos-vereadores\/","url_meta":{"origin":51142,"position":5},"title":"C\u00e2mara de Feira come\u00e7a uma nova legislatura com uma maioria de antigos vereadores","author":"Blog da Feira","date":"05\/02\/2025","format":false,"excerpt":"N\u00e3o s\u00f3 o cen\u00e1rio, mas os atores aglomerados na 'Casa da Cidadania de Feira', para a reabertura do Legislativo e a tradicional mensagem do Executivo, eram praticamente as mesmas de outros come\u00e7os de legislatura municipal dos \u00faltimos 20 anos. Afora um in\u00e9dito hasteamento de bandeiras no p\u00e1tio de entrada da\u2026","rel":"","context":"Em &quot;Home&quot;","block_context":{"text":"Home","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/raiz\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2025\/02\/Abertura-do-Legislativo-2025-Foto-ACM-72.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2025\/02\/Abertura-do-Legislativo-2025-Foto-ACM-72.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2025\/02\/Abertura-do-Legislativo-2025-Foto-ACM-72.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2025\/02\/Abertura-do-Legislativo-2025-Foto-ACM-72.jpeg?resize=700%2C400&ssl=1 2x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/posts\/51142","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/comments?post=51142"}],"version-history":[{"count":6,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/posts\/51142\/revisions"}],"predecessor-version":[{"id":51150,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/posts\/51142\/revisions\/51150"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/media\/51145"}],"wp:attachment":[{"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/media?parent=51142"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/categories?post=51142"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/tags?post=51142"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}