{"id":51324,"date":"2022-03-16T16:09:40","date_gmt":"2022-03-16T19:09:40","guid":{"rendered":"https:\/\/blogdafeira.com.br\/home\/?p=51324"},"modified":"2022-03-23T14:27:13","modified_gmt":"2022-03-23T17:27:13","slug":"cid-daltro-no-andar-de-cima","status":"publish","type":"post","link":"https:\/\/blogdafeira.com.br\/home\/2022\/03\/16\/cid-daltro-no-andar-de-cima\/","title":{"rendered":"Cid Daltro no andar de cima"},"content":{"rendered":"<div id=\"blogd-4047425367\" class=\"blogd-fim-do-post-mobile blogd-entity-placement\" style=\"margin-left: auto;margin-right: auto;text-align: center;\"><a href=\"https:\/\/www.feiradesantana.ba.gov.br\/servico.asp?s=a&titulo=Prefeitura-de-Feira-lan%C3%A7a-programa-Rem%C3%A9dio-em-Casa-e-transforma-acesso-a-medicamentos-em-pol%C3%ADtica-p%C3%BAblica-de-cuidados.html&id=14&link=secom\/noticias.asp&idn=43684#noticias\" target=_blank><picture>\r\n  <source media=\"(min-width: 768px)\" srcset=\"https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2026\/03\/980x150.gif\">\r\n  \r\n  <img decoding=\"async\" src=\"https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2021\/01\/350x2002.gif\" alt=\"Publicidade\" style=\"width: 100%; max-width: 100%; height: auto; display: block; margin: 0 auto;\">\r\n\t<\/picture><\/a><\/div><p style=\"font-weight: 400;\">Foi ontem, lutando contra um c\u00e2ncer.O sepultamento ser\u00e1 hoje, no cemit\u00e9rio piedade.<\/p>\n<p style=\"font-weight: 400;\">Nos conhecemos \u00a0h\u00e1 59 anos, em 1963, estudando \u00a0no Gin\u00e1sio Municipal.No gin\u00e1sio, eu e o hoje advogado Celso Pereira criamos o jornal mural \u201cA Verdade\u201d.Convidamos o colega Eroncildes Paulo Daltro Barreto para assinar a coluna social. Criamos o pseud\u00f4nimo Cid Daltro para dificultar a identifica\u00e7\u00e3o.A partir de ent\u00e3o foi uma longa conviv\u00eancia<\/p>\n<p style=\"font-weight: 400;\">S\u00f3 no jornal Folha do Estado estivemos juntos ao longo de 21 anos.<\/p>\n<p style=\"font-weight: 400;\">A grandiosidade de Cid dispensa coment\u00e1rios.A festejada colunista \u201cBatatinha Quente\u201d, por exemplo, surgiu via Cid<\/p>\n<p style=\"font-weight: 400;\">Cid promoveu grandes eventos reunindo a \u201cfina flor\u201d da sociedade. Participou de tantos outros com famosos da televis\u00e3o e do cinema<\/p>\n<p style=\"font-weight: 400;\">Em 2016 autografou \u201cCid Daltro \u2013 50 Anos de Glamour\u201d.Livro editado por Brand\u00e3o contando parte de sua hist\u00f3ria.<\/p>\n<div id=\"blogd-3709169201\" class=\"blogd-final-post blogd-entity-placement\"><a href=\"https:\/\/www.feiradesantana.ba.leg.br\/\" target=\"_blank\" aria-label=\"JUNHO-VERMELHO_CA\u0302MARA-DE-FEIRA\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2026\/03\/JUNHO-VERMELHO_CAMARA-DE-FEIRA.gif\" alt=\"\"  class=\"no-lazyload\" width=\"728\" height=\"90\"   \/><\/a><\/div><p style=\"font-weight: 400;\">A viagem de Cid Daltro para o \u201candar de cima\u201dDeixa um grande espa\u00e7o vazio na cr\u00f4nica social de Feira de Santana<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Foi ontem, lutando contra um c\u00e2ncer.O sepultamento ser\u00e1 hoje, no cemit\u00e9rio piedade. Nos conhecemos \u00a0h\u00e1 59 anos, em 1963, estudando \u00a0no Gin\u00e1sio Municipal.No gin\u00e1sio, eu e o hoje advogado Celso Pereira criamos o jornal mural \u201cA Verdade\u201d.Convidamos o colega Eroncildes Paulo Daltro Barreto para assinar a coluna social. Criamos o pseud\u00f4nimo Cid Daltro para dificultar<\/p>\n","protected":false},"author":40,"featured_media":51325,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"cybocfi_hide_featured_image":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[592,1],"tags":[],"class_list":["post-51324","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-colunistas","category-raiz"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2022\/03\/IMG-20220316-WA0020.jpg","jetpack_shortlink":"https:\/\/wp.me\/p3niVf-dlO","jetpack_sharing_enabled":true,"jetpack-related-posts":[{"id":9994,"url":"https:\/\/blogdafeira.com.br\/home\/2014\/04\/01\/vote-pela-internet-no-rei-e-na-rainha-da-micareta-de-feira-de-santana\/","url_meta":{"origin":51324,"position":0},"title":"Vote  pela internet no Rei e na Rainha da Micareta de Feira de Santana","author":"Blog da Feira","date":"01\/04\/2014","format":false,"excerpt":"A escolha da Rainha e do Rei Momo da Micareta 2014 acontecer\u00e1 nesta quarta-feira (2), \u00e0s 19h, no Centro Universit\u00e1rio de Cultura e Arte (Cuca). Est\u00e3o participando do concurso 10 candidatas. Mas o internauta pode votar pela internet at\u00e9 as 23h59 de hoje (1\u00ba): clique aqui e vote. A vota\u00e7\u00e3o\u2026","rel":"","context":"Em &quot;Home&quot;","block_context":{"text":"Home","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/raiz\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":69908,"url":"https:\/\/blogdafeira.com.br\/home\/2025\/10\/21\/em-uma-tarde-cinza-e-chuvosa\/","url_meta":{"origin":51324,"position":1},"title":"Em uma tarde cinza e chuvosa","author":"Camila Rego","date":"21\/10\/2025","format":false,"excerpt":"Em uma tarde cinza e chuvosa, recebi com tristeza a not\u00edcia do falecimento do meu padrinho, Dr. Celso Daltro. Uma pessoa simples, uma biblioteca viva, advogado de excel\u00eancia que advogava com excel\u00eancia para quem podia e n\u00e3o podia pagar. Cada conversa que t\u00ednhamos era uma aula que eu recebia, Defensor\u2026","rel":"","context":"Em &quot;Colunistas&quot;","block_context":{"text":"Colunistas","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/colunistas\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2025\/10\/IMG-20251021-WA00992.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2025\/10\/IMG-20251021-WA00992.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2025\/10\/IMG-20251021-WA00992.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2025\/10\/IMG-20251021-WA00992.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2025\/10\/IMG-20251021-WA00992.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":28314,"url":"https:\/\/blogdafeira.com.br\/home\/2017\/10\/03\/cid-moreira-conversou-com-imprensa-no-parque-do-saber-em-feira-de-santana\/","url_meta":{"origin":51324,"position":2},"title":"Cid Moreira conversou com imprensa no Parque do Saber em Feira de Santana","author":"Blog da Feira","date":"03\/10\/2017","format":false,"excerpt":"A cidade de feira de Santana recebeu na manh\u00e3 desta segunda-feira, 02, Cid Moreira, um dos mais renomados jornalistas do pa\u00eds. O global foi convidado para participar do V Congresso Cient\u00edfico da Faculdade Adventista da Bahia, em Cachoeira, mas a Princesa do Sert\u00e3o foi a escolhida para receber a coletiva\u2026","rel":"","context":"Em &quot;Home&quot;","block_context":{"text":"Home","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/raiz\/"},"img":{"alt_text":"dscn9806","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2017\/10\/DSCN9806-1024x768.jpg?resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2017\/10\/DSCN9806-1024x768.jpg?resize=350%2C200 1x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2017\/10\/DSCN9806-1024x768.jpg?resize=525%2C300 1.5x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2017\/10\/DSCN9806-1024x768.jpg?resize=700%2C400 2x"},"classes":[]},{"id":63888,"url":"https:\/\/blogdafeira.com.br\/home\/2024\/09\/20\/muitos-vivas-a-biblioteca-do-professor-cid-teixeira-vai-permanecer-em-salvador\/","url_meta":{"origin":51324,"position":3},"title":"Muitos vivas! A biblioteca do professor Cid Teixeira vai permanecer em Salvador","author":"Blog da Feira","date":"20\/09\/2024","format":false,"excerpt":"\u201cLivros, discos, v\u00eddeos \u00e0 mancheia\/E deixa que digam,\/Que pensem, que falem\u201d (L\u00edngua, de Caetano Veloso) Diversas vezes subi a escada do modesto pr\u00e9dio na Avenida Paulo VI, em frente \u00e0 Pra\u00e7a Alfred Nobel, no bairro da Pituba, onde o professor Cid Teixeira mantinha sua biblioteca \u2013 um acervo de 18\u2026","rel":"","context":"Em &quot;Colunistas&quot;","block_context":{"text":"Colunistas","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/colunistas\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2024\/09\/professor-Cid-Teixeira.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2024\/09\/professor-Cid-Teixeira.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2024\/09\/professor-Cid-Teixeira.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2024\/09\/professor-Cid-Teixeira.jpeg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2024\/09\/professor-Cid-Teixeira.jpeg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":34336,"url":"https:\/\/blogdafeira.com.br\/home\/2019\/12\/04\/folhetim-em-duo-de-voz-e-cordas-com-lorena-porto-e-cid-fiuza-hoje-no-seriguela\/","url_meta":{"origin":51324,"position":4},"title":"&#8216;Folhetim em duo de voz e cordas&#8217;, com Lorena Porto e Cid Fiuza hoje no Seriguela","author":"J\u00e2nio R\u00eago","date":"04\/12\/2019","format":false,"excerpt":"A cantora Lorena Porto e o m\u00fasico Cid Fiuza com o show 'Folhetim - Chico Buarque em duo de voz e cordas, hoje (quarta, 4)\u00a0 na Seriguela Petiscaria (rua Fernando S\u00e3o Paulo, 499 - Ponto Central, Feira de Santana, Bahia), \u00e0s 20h. Os ingressos podem ser adquiridos por R$ 16\u2026","rel":"","context":"Em &quot;Home&quot;","block_context":{"text":"Home","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/raiz\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2019\/12\/Nesta-quarta-feira-04-tem-show-Folhetim-Chico-Buarque-em-duo-de-voz-e-cordas-com-Lorena-Porto-e-Cid-Fiuza-1024x1024.jpg?resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2019\/12\/Nesta-quarta-feira-04-tem-show-Folhetim-Chico-Buarque-em-duo-de-voz-e-cordas-com-Lorena-Porto-e-Cid-Fiuza-1024x1024.jpg?resize=350%2C200 1x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2019\/12\/Nesta-quarta-feira-04-tem-show-Folhetim-Chico-Buarque-em-duo-de-voz-e-cordas-com-Lorena-Porto-e-Cid-Fiuza-1024x1024.jpg?resize=525%2C300 1.5x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2019\/12\/Nesta-quarta-feira-04-tem-show-Folhetim-Chico-Buarque-em-duo-de-voz-e-cordas-com-Lorena-Porto-e-Cid-Fiuza-1024x1024.jpg?resize=700%2C400 2x"},"classes":[]},{"id":49547,"url":"https:\/\/blogdafeira.com.br\/home\/2021\/12\/21\/rip-cid-teixeira-por-alana-freitas\/","url_meta":{"origin":51324,"position":5},"title":"RIP Cid Teixeira! por Alana Freitas","author":"Alana Freitas","date":"21\/12\/2021","format":false,"excerpt":"RIP Cid Teixeira! Um Historiador \u00edmpar! Tive a honra de entrevist\u00e1-lo em sua casa h\u00e1 20 anos por ocasi\u00e3o da minha pesquisa de mestrado sobre Lulu Parola. Por interm\u00e9dio de Aleilton Fonseca , meu orientador, passei uma manh\u00e3 conversando com essa biblioteca! No dia me perdi na Pituba e n\u00e3o\u2026","rel":"","context":"Em &quot;Colunistas&quot;","block_context":{"text":"Colunistas","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/colunistas\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2021\/12\/FB_IMG_1640110322945.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]}],"_links":{"self":[{"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/posts\/51324","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/users\/40"}],"replies":[{"embeddable":true,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/comments?post=51324"}],"version-history":[{"count":2,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/posts\/51324\/revisions"}],"predecessor-version":[{"id":51327,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/posts\/51324\/revisions\/51327"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/media\/51325"}],"wp:attachment":[{"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/media?parent=51324"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/categories?post=51324"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/tags?post=51324"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}