{"id":51363,"date":"2022-03-18T19:53:15","date_gmt":"2022-03-18T22:53:15","guid":{"rendered":"https:\/\/blogdafeira.com.br\/home\/?p=51363"},"modified":"2022-03-23T14:27:13","modified_gmt":"2022-03-23T17:27:13","slug":"padre-ovidio-era-pra-ser-canonizado","status":"publish","type":"post","link":"https:\/\/blogdafeira.com.br\/home\/2022\/03\/18\/padre-ovidio-era-pra-ser-canonizado\/","title":{"rendered":"A Matriz precisa de uma guaribada"},"content":{"rendered":"<div id=\"blogd-451836376\" class=\"blogd-fim-do-post-mobile blogd-entity-placement\" style=\"margin-left: auto;margin-right: auto;text-align: center;\"><a href=\"https:\/\/www.feiradesantana.ba.gov.br\/servico.asp?s=a&titulo=Prefeitura-de-Feira-lan%C3%A7a-programa-Rem%C3%A9dio-em-Casa-e-transforma-acesso-a-medicamentos-em-pol%C3%ADtica-p%C3%BAblica-de-cuidados.html&id=14&link=secom\/noticias.asp&idn=43684#noticias\" target=_blank><picture>\r\n  <source media=\"(min-width: 768px)\" srcset=\"https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2026\/03\/980x150.gif\">\r\n  \r\n  <img decoding=\"async\" src=\"https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2021\/01\/350x2002.gif\" alt=\"Publicidade\" style=\"width: 100%; max-width: 100%; height: auto; display: block; margin: 0 auto;\">\r\n\t<\/picture><\/a><\/div><div id=\"blogd-1115597909\" class=\"blogd-final-post blogd-entity-placement\"><a href=\"https:\/\/www.feiradesantana.ba.leg.br\/\" target=\"_blank\" aria-label=\"JUNHO-VERMELHO_CA\u0302MARA-DE-FEIRA\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2026\/03\/JUNHO-VERMELHO_CAMARA-DE-FEIRA.gif\" alt=\"\"  class=\"no-lazyload\" width=\"728\" height=\"90\"   \/><\/a><\/div><p><em>A Matriz t\u00e1 precisando de uma guaribada. <\/em>Me lembrei do jornalista Geraldo Lima falando com aquela voz grave e muita seriedade no rosto que pode explodir numa risada a qualquer momento. Se algu\u00e9m o vir, diga que o abra\u00e7o daqui. Pois bem, de fato, toda ela est\u00e1 precisando mesmo de uma <em>guaribada. A<\/em> Igreja, pra\u00e7a, jardim e a est\u00e1tua do Padre Ov\u00eddio Alves de S\u00e3o Boaventura, ali\u00e1s, est\u00e1tuas, pois h\u00e1 a crian\u00e7a pegada ao casaco napole\u00f4nico que vestia o santo vig\u00e1rio da Catedral naqueles idos mon\u00e1rquicos. O conjunto \u00e9 uma rel\u00edquia e est\u00e1 em perfeito estado, falo do pedestal\u00a0 met\u00e1lico que inclusive\u00a0 \u00e9 arte recente. Corro\u00eddo mais uma vez aquela meia-bola(?) que tamb\u00e9m \u00e9 arte. H\u00e1 fotos com o pedestal original, inclusive em outro lugar do largo que se estendia at\u00e9&#8230;o casar\u00e3o hoje do Sesc. O pedestal met\u00e1lico deu-lhe\u00a0 impon\u00eancia mas colocou o p\u00e1roco distante da venera\u00e7\u00e3o popular. Quem a encomendou ao escultor franc\u00eas, um coronel Intendente,claro,\u00a0 queria torn\u00e1-lo um santo\u00a0 pelas <em>obras aos pequeninos.<\/em> Tamb\u00e9m queria notoriedade e espalhou que pagou a escultura com recursos pr\u00f3prios at\u00e9 hoje repetido pela hist\u00f3ria oficial. \u00c9 problema seu acreditar. Mas o fato \u00e9 que Padre Ov\u00eddio teve tudo\u00a0 pra ser santo e se n\u00e3o sabemos algum dos seus milagres \u00e9 porque esse tipo de f\u00e9 e religiosidade cat\u00f3lica em Feira n\u00e3o pegou, n\u00e3o vende muito bem, apesar de nossa profunda f\u00e9 em coisas mais passageiras e cotidianas como a pol\u00edtica. Mas esse n\u00e3o \u00e9 o\u00a0 assunto dessa extensa legenda. Sextou.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Matriz t\u00e1 precisando de uma guaribada. Me lembrei do jornalista Geraldo Lima falando com aquela voz grave e muita seriedade no rosto que pode explodir numa risada a qualquer momento. Se algu\u00e9m o vir, diga que o abra\u00e7o daqui. Pois bem, de fato, toda ela est\u00e1 precisando mesmo de uma guaribada. A Igreja, pra\u00e7a,<\/p>\n","protected":false},"author":8,"featured_media":51364,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"cybocfi_hide_featured_image":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[592,1],"tags":[],"class_list":["post-51363","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-colunistas","category-raiz"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2022\/03\/IMG_20220318_142025_047-scaled.jpg","jetpack_shortlink":"https:\/\/wp.me\/p3niVf-dmr","jetpack_sharing_enabled":true,"jetpack-related-posts":[{"id":27956,"url":"https:\/\/blogdafeira.com.br\/home\/2017\/08\/25\/pedestal-da-estatua-de-padre-ovidio-esta-apodrecendo-praca-foi-reformada-ha-dois-anos\/","url_meta":{"origin":51363,"position":0},"title":"Pedestal da est\u00e1tua de Padre Ov\u00eddio est\u00e1 apodrecendo; pra\u00e7a foi reformada h\u00e1 dois anos","author":"Blog da Feira","date":"25\/08\/2017","format":false,"excerpt":"A Prefeitura de Feira de Santana gastou, h\u00e1 cerca de dois anos, mais de R$1 milh\u00e3o de reais para reformar a pra\u00e7a Padre Ov\u00eddio, localizada ao lado da Igreja Matriz onde nasceu a cidade. A obra do governo municipal foi recebida com entusiasmo e pelo alto custo foi at\u00e9 considerada\u2026","rel":"","context":"Em &quot;Home&quot;","block_context":{"text":"Home","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/raiz\/"},"img":{"alt_text":"img_20170825_113526944","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2017\/08\/IMG_20170825_113526944-576x1024.jpg?resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2017\/08\/IMG_20170825_113526944-576x1024.jpg?resize=350%2C200 1x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2017\/08\/IMG_20170825_113526944-576x1024.jpg?resize=525%2C300 1.5x"},"classes":[]},{"id":30277,"url":"https:\/\/blogdafeira.com.br\/home\/2018\/09\/27\/pedestal-vazio-vira-o-tumulo-do-vaqueiro-em-protesto-de-marcio-punk-no-centro-de-feira-de-santana\/","url_meta":{"origin":51363,"position":1},"title":"Pedestal vazio vira o &#8216;T\u00famulo do Vaqueiro&#8217; em protesto de M\u00e1rcio Punk no centro de Feira","author":"J\u00e2nio R\u00eago","date":"27\/09\/2018","format":false,"excerpt":"O artista pl\u00e1stico e ativista cultural M\u00e1rcio Punk fez novo protesto no pedestal vazio da est\u00e1tua do vaqueiro no in\u00edcio da avenida Ol\u00edmpio Vital, no centro de Feira de Santana. Dessa vez M\u00e1rcio Punk colocou cruzes de madeira com as datas do 'nascimento e morte' da obra de arte que\u2026","rel":"","context":"Em &quot;Home&quot;","block_context":{"text":"Home","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/raiz\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2018\/09\/20180927_092455_HDR-1024x768.jpg?resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2018\/09\/20180927_092455_HDR-1024x768.jpg?resize=350%2C200 1x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2018\/09\/20180927_092455_HDR-1024x768.jpg?resize=525%2C300 1.5x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2018\/09\/20180927_092455_HDR-1024x768.jpg?resize=700%2C400 2x"},"classes":[]},{"id":61141,"url":"https:\/\/blogdafeira.com.br\/home\/2024\/02\/15\/padre-ovidio-e-padre-ovidio-e-o-historiador-carlos-mello\/","url_meta":{"origin":51363,"position":2},"title":"Padre Ov\u00eddio e Padre Ov\u00eddio e o historiador Carlos Mello","author":"J\u00e2nio R\u00eago","date":"15\/02\/2024","format":false,"excerpt":"Padre Ov\u00eddio, at\u00e9 a chegada do Almirante Tamandar\u00e9, era a \u00fanica est\u00e1tua de corpo inteiro da Feira. O almirante, est\u00e1 ao lado da pl\u00e1cida Lagoa do Geladinho, e o Padre continua onde est\u00e1, ao lado da Matriz de Sant'Anna. Onde ele est\u00e1 hoje, sobre essa esfera concavada, era um olho\u2026","rel":"","context":"Em &quot;Colunistas&quot;","block_context":{"text":"Colunistas","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/colunistas\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2024\/02\/Polish_20240215_154456702-scaled.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2024\/02\/Polish_20240215_154456702-scaled.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2024\/02\/Polish_20240215_154456702-scaled.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2024\/02\/Polish_20240215_154456702-scaled.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2024\/02\/Polish_20240215_154456702-scaled.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2024\/02\/Polish_20240215_154456702-scaled.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":26668,"url":"https:\/\/blogdafeira.com.br\/home\/2017\/04\/25\/poeta-olliver-brasil-tambem-faz-performance-de-protesto-no-pedestal-do-vaqueiro-em-feira\/","url_meta":{"origin":51363,"position":3},"title":"Poeta Olliver Brasil tamb\u00e9m faz &#8216;performance de protesto&#8217; no pedestal do Vaqueiro em Feira","author":"Blog da Feira","date":"25\/04\/2017","format":false,"excerpt":"Olliver Brasil \u00e9 \u00a0filho de \u00a0poeta, \u00a0tem\u00a0 fortes ra\u00edzes nordestinas, \u00a0e al\u00e9m de artista diversificado \u00e9 um inquieto produtor e \u00a0ativista cultural. Este n\u00e3o \u00e9 o primeiro protesto art\u00edstico feito neste local, depois que a escultura do Vaqueiro caiu destru\u00edda pelo tempo e foi levada pela Prefeitura. O artista M\u00e1rcio\u2026","rel":"","context":"Em &quot;Home&quot;","block_context":{"text":"Home","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/raiz\/"},"img":{"alt_text":"oliver-brasill","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2017\/04\/Oliver-Brasill.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":25400,"url":"https:\/\/blogdafeira.com.br\/home\/2017\/01\/16\/cade-o-vaqueiro-da-olimpio-vital\/","url_meta":{"origin":51363,"position":4},"title":"Cad\u00ea o vaqueiro da Ol\u00edmpio Vital?","author":"Blog da Feira","date":"16\/01\/2017","format":false,"excerpt":"Segunda-feira ainda \u00e9 comum e natural a figura do vaqueiro nas ruas de Feira de Santana, vestido com jaleco e nesses tempos quase sempre montado numa moto cilindrada. O jaleco, especial e \u00fanico, \u00a0continua sendo indument\u00e1ria regional, principalmente nos meses frios e rurais de junho, julho e agosto. Quando houve\u2026","rel":"","context":"Em &quot;Home&quot;","block_context":{"text":"Home","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/raiz\/"},"img":{"alt_text":"vaqueiro","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2017\/01\/VAQUEIRO.jpg?resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2017\/01\/VAQUEIRO.jpg?resize=350%2C200 1x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2017\/01\/VAQUEIRO.jpg?resize=525%2C300 1.5x"},"classes":[]},{"id":16074,"url":"https:\/\/blogdafeira.com.br\/home\/2015\/08\/13\/escultura-do-vaqueiro-caiu-do-pedestal-no-centro-de-feira\/","url_meta":{"origin":51363,"position":5},"title":"Escultura do &#8216;Vaqueiro&#8217; caiu do pedestal no centro de Feira","author":"Blog da Feira","date":"13\/08\/2015","format":false,"excerpt":"A foto \u00e9 do produtor cultural Ruy Barcellos. A escultura d'O Vaqueiro fica no cruzamento da Get\u00falio Vargas\/Ol\u00edmpio Vital com a rua Conselheiro Franco, no centro da cidade de Feira de Santana. Pela foto, nota-se o bra\u00e7o quebrado. A escultura foi colocada quando da abertura da Ol\u00edmpio Vital que \u00e9\u2026","rel":"","context":"Em &quot;Home&quot;","block_context":{"text":"Home","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/raiz\/"},"img":{"alt_text":"vaqueirooo","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2015\/08\/vaqueirooo.jpg?resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2015\/08\/vaqueirooo.jpg?resize=350%2C200 1x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2015\/08\/vaqueirooo.jpg?resize=525%2C300 1.5x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2015\/08\/vaqueirooo.jpg?resize=700%2C400 2x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/posts\/51363","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/comments?post=51363"}],"version-history":[{"count":2,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/posts\/51363\/revisions"}],"predecessor-version":[{"id":51369,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/posts\/51363\/revisions\/51369"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/media\/51364"}],"wp:attachment":[{"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/media?parent=51363"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/categories?post=51363"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/tags?post=51363"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}