{"id":51376,"date":"2022-03-21T18:56:39","date_gmt":"2022-03-21T21:56:39","guid":{"rendered":"https:\/\/blogdafeira.com.br\/home\/?p=51376"},"modified":"2022-03-28T00:55:15","modified_gmt":"2022-03-28T03:55:15","slug":"orcamento-2022-de-feira-foi-publicado-por-colbert","status":"publish","type":"post","link":"https:\/\/blogdafeira.com.br\/home\/2022\/03\/21\/orcamento-2022-de-feira-foi-publicado-por-colbert\/","title":{"rendered":"Or\u00e7amento 2022 de Feira foi publicado por Colbert"},"content":{"rendered":"<div id=\"blogd-4124050171\" class=\"blogd-fim-do-post-mobile blogd-entity-placement\" style=\"margin-left: auto;margin-right: auto;text-align: center;\"><a href=\"https:\/\/www.feiradesantana.ba.gov.br\/servico.asp?s=a&titulo=Prefeitura-de-Feira-lan%C3%A7a-programa-Rem%C3%A9dio-em-Casa-e-transforma-acesso-a-medicamentos-em-pol%C3%ADtica-p%C3%BAblica-de-cuidados.html&id=14&link=secom\/noticias.asp&idn=43684#noticias\" target=_blank><picture>\r\n  <source media=\"(min-width: 768px)\" srcset=\"https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2026\/03\/980x150.gif\">\r\n  \r\n  <img decoding=\"async\" src=\"https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2021\/01\/350x2002.gif\" alt=\"Publicidade\" style=\"width: 100%; max-width: 100%; height: auto; display: block; margin: 0 auto;\">\r\n\t<\/picture><\/a><\/div><p>O prefeito Colbert Filho sancionou hoje, 21, a Lei Or\u00e7ament\u00e1ria Anual (LOA) que estima a receita e prev\u00ea a despesa para o exerc\u00edcio de 2022. Desta forma, o chefe do Executivo Municipal est\u00e1 cumprindo em onze dos 15 dias que estabelece o prazo legal para sancionar o documento, conforme a Lei Org\u00e2nica.<\/p>\n<p>A publica\u00e7\u00e3o consta em edi\u00e7\u00e3o extra do\u00a0Di\u00e1rio Oficial Eletr\u00f4nico nesta segunda-feira, 21.\u00a0A Prefeitura de Feira de Santana contar\u00e1 com um or\u00e7amento de R$ 1.653.172.890 para ser aplicado no exerc\u00edcio financeiro deste ano.<\/p>\n<p>Para a Sa\u00fade ser\u00e1 destinado R$ 486.669.448 dos recursos; Educa\u00e7\u00e3o R$ 402.965.645; Administra\u00e7\u00e3o R$268.625.060 e Servi\u00e7os P\u00fablicos R$ 119.787.971.<\/p>\n<p>J\u00e1 o or\u00e7amento para a pasta da Fazenda \u00e9 de R$ 87.129.132; Gabinete do Prefeito com R$ 75.528.232; Desenvolvimento Social R$ 43.182.544; Transporte e Tr\u00e2nsito R$ 27.270.500; Planejamento R$ 23.735.765 e a Secretaria de Cultura, Esporte e Lazer R$ 19.851.800.<\/p>\n<p>A Comunica\u00e7\u00e3o Social tem como or\u00e7amento R$ 12.145.000; Desenvolvimento Urbano R$ 11.814.530 e a Secretaria do Trabalho, Turismo e Desenvolvimento Econ\u00f4mico R$ 7.455.750. O or\u00e7amento da C\u00e2mara Municipal \u00e9 de R$ 35.277.404.<\/p>\n<div id=\"blogd-277088405\" class=\"blogd-final-post blogd-entity-placement\"><a href=\"https:\/\/www.feiradesantana.ba.leg.br\/\" target=\"_blank\" aria-label=\"JUNHO-VERMELHO_CA\u0302MARA-DE-FEIRA\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2026\/03\/JUNHO-VERMELHO_CAMARA-DE-FEIRA.gif\" alt=\"\"  class=\"no-lazyload\" width=\"728\" height=\"90\"   \/><\/a><\/div><p>O documento disp\u00f5e ainda de alguns vetos.\u00a0Leia\u00a0<a href=\"https:\/\/diariooficial.feiradesantana.ba.gov.br\/atos\/executivo\/1MGRRO21032022.pdf\"><strong>aqui\u00a0<\/strong><\/a>o conte\u00fado completo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O prefeito Colbert Filho sancionou hoje, 21, a Lei Or\u00e7ament\u00e1ria Anual (LOA) que estima a receita e prev\u00ea a despesa para o exerc\u00edcio de 2022. Desta forma, o chefe do Executivo Municipal est\u00e1 cumprindo em onze dos 15 dias que estabelece o prazo legal para sancionar o documento, conforme a Lei Org\u00e2nica. A publica\u00e7\u00e3o consta<\/p>\n","protected":false},"author":1,"featured_media":51240,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"cybocfi_hide_featured_image":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[3,1,631],"tags":[],"class_list":["post-51376","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cidade","category-raiz","category-politica"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2022\/03\/FB_IMG_1647013414847.jpg","jetpack_shortlink":"https:\/\/wp.me\/p3niVf-dmE","jetpack_sharing_enabled":true,"jetpack-related-posts":[{"id":56466,"url":"https:\/\/blogdafeira.com.br\/home\/2023\/02\/15\/colbert-sanciona-orcamento-2023-de-feira-r-19-bi\/","url_meta":{"origin":51376,"position":0},"title":"Colbert sanciona Or\u00e7amento 2023 de Feira: R$ 1,9 bi","author":"Secom\/FSA","date":"15\/02\/2023","format":false,"excerpt":"Foi publicada em edi\u00e7\u00e3o extra do Di\u00e1rio Oficial Eletr\u00f4nico do Munic\u00edpio nesta quarta-feira (15) a Lei 4.124 que estima a Receita e Fixa a Despesa do Munic\u00edpio de Feira de Santana para o Exerc\u00edcio Financeiro de 2023. A san\u00e7\u00e3o do prefeito Colbert Martins Filho ao Projeto da\u00a0Lei Or\u00e7ament\u00e1ria Anual foi\u2026","rel":"","context":"Em &quot;Economia&quot;","block_context":{"text":"Economia","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/economia\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2023\/01\/colbert_martins__divulgacao1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2023\/01\/colbert_martins__divulgacao1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2023\/01\/colbert_martins__divulgacao1.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2023\/01\/colbert_martins__divulgacao1.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2023\/01\/colbert_martins__divulgacao1.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":41392,"url":"https:\/\/blogdafeira.com.br\/home\/2020\/10\/27\/vereadores-aprovam-orcamento-de-feira-nos-proximos-dias15-bilhao-de-reais\/","url_meta":{"origin":51376,"position":1},"title":"Vereadores aprovam Or\u00e7amento de Feira nos pr\u00f3ximos dias:1,5 bilh\u00e3o de reais","author":"Secom\/FSA","date":"27\/10\/2020","format":false,"excerpt":"A C\u00e2mara de Vereadores de Feira de Santana iniciou oficialmente a discuss\u00e3o do Projeto do Poder Executivo que institui a Lei Or\u00e7ament\u00e1ria Anual (LOA) de 2021, ou seja, o Or\u00e7amento do Munic\u00edpio para este ano que est\u00e1 estimado em quase 1 bilh\u00e3o e 500 milh\u00f5es, exatamente R$ 1.486.022.038,00 (um bilh\u00e3o,\u2026","rel":"","context":"Em &quot;Cidade&quot;","block_context":{"text":"Cidade","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/cidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2020\/10\/IMG_20201017_153216_452-scaled.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2020\/10\/IMG_20201017_153216_452-scaled.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2020\/10\/IMG_20201017_153216_452-scaled.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2020\/10\/IMG_20201017_153216_452-scaled.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2020\/10\/IMG_20201017_153216_452-scaled.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2020\/10\/IMG_20201017_153216_452-scaled.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":60537,"url":"https:\/\/blogdafeira.com.br\/home\/2023\/12\/19\/prefeito-de-feira-sanciona-lei-de-reajuste-salarial-para-servidores-municipais\/","url_meta":{"origin":51376,"position":2},"title":"Prefeito de Feira sanciona lei de reajuste salarial para servidores municipais","author":"Secom\/FSA","date":"19\/12\/2023","format":false,"excerpt":"Em publica\u00e7\u00e3o realizada hoje,\u00a0 ter\u00e7a-feira (19), no Di\u00e1rio Oficial Eletr\u00f4nico do Munic\u00edpio, o prefeito Colbert Filho sancionou o Projeto de Lei 166\/2023, de autoria do Poder Executivo, que estabelece a Revis\u00e3o Anual dos Vencimentos dos Servidores P\u00fablicos Municipais em Feira de Santana. A Lei, identificada como N\u00ba 4.203, de 18\u2026","rel":"","context":"Em &quot;Cidade&quot;","block_context":{"text":"Cidade","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/cidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2023\/12\/Screenshot_20231219-1710322.png?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2023\/12\/Screenshot_20231219-1710322.png?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2023\/12\/Screenshot_20231219-1710322.png?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2023\/12\/Screenshot_20231219-1710322.png?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2023\/12\/Screenshot_20231219-1710322.png?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":28693,"url":"https:\/\/blogdafeira.com.br\/home\/2017\/11\/29\/orcamento-do-municipio-de-feira-de-santana-para-2018-passa-de-r-1-bilhao-de-reais\/","url_meta":{"origin":51376,"position":3},"title":"Or\u00e7amento do munic\u00edpio de Feira de Santana para 2018 passa de R$ 1 bilh\u00e3o de reais","author":"Secom\/FSA","date":"29\/11\/2017","format":false,"excerpt":"A C\u00e2mara Municipal de Feira de Santana aprovou, ontem, em primeira vota\u00e7\u00e3o e por unanimidade dos presentes, o Projeto de Lei de n\u00ba 180\/2017, de autoria do Poder Executivo, que estima a receita e fixa a despesa do munic\u00edpio de Feira de Santana para o exerc\u00edcio financeiro de 2018, em\u2026","rel":"","context":"Em &quot;Home&quot;","block_context":{"text":"Home","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/raiz\/"},"img":{"alt_text":"getuli-ovagas","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2017\/11\/getuli-ovagas.jpg?resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2017\/11\/getuli-ovagas.jpg?resize=350%2C200 1x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2017\/11\/getuli-ovagas.jpg?resize=525%2C300 1.5x"},"classes":[]},{"id":59688,"url":"https:\/\/blogdafeira.com.br\/home\/2023\/10\/11\/recursos-da-lei-paulo-gustavo-ja-fazem-parte-do-orcamento-municipal\/","url_meta":{"origin":51376,"position":4},"title":"Recursos da Lei Paulo Gustavo j\u00e1 fazem parte do or\u00e7amento municipal","author":"Secom\/FSA","date":"11\/10\/2023","format":false,"excerpt":"A Prefeitura de Feira de Santana j\u00e1 est\u00e1 apta a disponibilizar R$ 4,6 milh\u00f5es aos fazedores e produtores culturais que tiverem seus projetos aprovados pela Secretaria Municipal de Cultura (Secel), com base na Lei Paulo Gustavo. Foi aprovado nesta quarta-feira (dia 11), em segunda discuss\u00e3o, pela C\u00e2mara de Vereadores, o\u2026","rel":"","context":"Em &quot;Cidade&quot;","block_context":{"text":"Cidade","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/cidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2023\/10\/11102023162635.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2023\/10\/11102023162635.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2023\/10\/11102023162635.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2023\/10\/11102023162635.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2023\/10\/11102023162635.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":47591,"url":"https:\/\/blogdafeira.com.br\/home\/2021\/09\/29\/vlt-de-salvador-esta-entre-os-grandes-investimentos-previstos-no-orcamento-da-bahia\/","url_meta":{"origin":51376,"position":5},"title":"VLT de Salvador est\u00e1 entre os grandes investimentos previstos no Or\u00e7amento da Bahia","author":"Secom\/FSA","date":"29\/09\/2021","format":false,"excerpt":"O Projeto de Lei Or\u00e7ament\u00e1ria Anual (PLOA) da Bahia, para 2022, prev\u00ea um crescimento de 6,5% em rela\u00e7\u00e3o ao or\u00e7amento executado este ano. O documento foi entregue pelo vice-governador Jo\u00e3o Le\u00e3o, secret\u00e1rio do Planejamento, ao presidente da Assembleia Legislativa da Bahia (Alba), deputado Adolfo Menezes, nesta quarta-feira (29). O or\u00e7amento\u2026","rel":"","context":"Em &quot;Home&quot;","block_context":{"text":"Home","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/raiz\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2021\/09\/Foto_Seplan-1.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2021\/09\/Foto_Seplan-1.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2021\/09\/Foto_Seplan-1.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2021\/09\/Foto_Seplan-1.jpeg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2021\/09\/Foto_Seplan-1.jpeg?resize=1050%2C600&ssl=1 3x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/posts\/51376","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/comments?post=51376"}],"version-history":[{"count":1,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/posts\/51376\/revisions"}],"predecessor-version":[{"id":51378,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/posts\/51376\/revisions\/51378"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/media\/51240"}],"wp:attachment":[{"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/media?parent=51376"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/categories?post=51376"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/tags?post=51376"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}