{"id":51820,"date":"2022-04-15T14:08:32","date_gmt":"2022-04-15T17:08:32","guid":{"rendered":"https:\/\/blogdafeira.com.br\/home\/?p=51820"},"modified":"2022-04-22T20:52:06","modified_gmt":"2022-04-22T23:52:06","slug":"as-obras-e-os-obreiros","status":"publish","type":"post","link":"https:\/\/blogdafeira.com.br\/home\/2022\/04\/15\/as-obras-e-os-obreiros\/","title":{"rendered":"As obras e os obreiros"},"content":{"rendered":"<blockquote>\n<p style=\"text-align: justify;\">Deus! \u00f3 Deus! onde est\u00e1s que n\u00e3o respondes?<\/p>\n<p style=\"text-align: justify;\">Em que mundo, em qu&#8217;estrela tu t&#8217;escondes<\/p>\n<p style=\"text-align: justify;\">Embu\u00e7ado nos c\u00e9us?<\/p>\n<p style=\"text-align: justify;\">H\u00e1 dois mil anos te mandei meu grito,<\/p>\n<p style=\"text-align: justify;\">Que embalde desde ent\u00e3o corre o infinito&#8230;<\/p>\n<p style=\"text-align: justify;\">Onde est\u00e1s, Senhor Deus?&#8230;<\/p>\n<\/blockquote>\n<div id=\"blogd-1336892286\" class=\"blogd-fim-do-post-mobile blogd-entity-placement\" style=\"margin-left: auto;margin-right: auto;text-align: center;\"><a href=\"https:\/\/www.feiradesantana.ba.gov.br\/servico.asp?s=a&titulo=Prefeitura-de-Feira-lan%C3%A7a-programa-Rem%C3%A9dio-em-Casa-e-transforma-acesso-a-medicamentos-em-pol%C3%ADtica-p%C3%BAblica-de-cuidados.html&id=14&link=secom\/noticias.asp&idn=43684#noticias\" target=_blank><picture>\r\n  <source media=\"(min-width: 768px)\" srcset=\"https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2026\/03\/980x150.gif\">\r\n  \r\n  <img decoding=\"async\" src=\"https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2021\/01\/350x2002.gif\" alt=\"Publicidade\" style=\"width: 100%; max-width: 100%; height: auto; display: block; margin: 0 auto;\">\r\n\t<\/picture><\/a><\/div><p style=\"text-align: justify;\">O brado do poeta Castro Alves (foto) em sua obra \u201cVozes D\u00b4\u00c1frica\u201d \u00e9 quase um lamento adequado para os tempos atuais. Onde mesmo estar\u00e1 Deus que n\u00e3o est\u00e1 vendo o que os seus ministros e os ministros de Bolsonaro andam fazendo. Os de Bolsonaro a gente tenta dar ten\u00eancia. Mas os ministros do Senhor, o que fazer? Seus representantes nesta terra de Tup\u00e3 est\u00e3o usando seu santo nome em v\u00e3o e usando de tretas, mal\u00edcias, safadezas e malandragens. Seus pastores cada vez mais envolvidos em il\u00edcitos, em engodos ou matulagens.<\/p>\n<p style=\"text-align: justify;\">Deus, o Senhor lembra daquele pastor, seu ministro, que estava vendendo \u00e1gua \u201cconsagrada\u201d para curar a Covid-19 antes da Ci\u00eancia descobrir como fazer a vacina? E aquele outros que vendia p\u00edlulas feitas de trigo om o mesmo intuito? Isso sem falar em tantos que est\u00e3o usando Seu santo nome em v\u00e3o.<\/p>\n<p style=\"text-align: justify;\">Veja agora que seus obreiros, segundo est\u00e1 nos jornais, est\u00e3o se metendo at\u00e9 em obras que n\u00e3o s\u00e3o em louvor ao Senhor. S\u00e3o obras f\u00edsicas. Est\u00e3o pegando o que \u00e9 do governo, com anu\u00eancia a orienta\u00e7\u00e3o dele &#8211; portanto pegando do povo &#8211; o dinheiro para oferecer \u00e0s prefeituras de todo o Brasil. A\u00ed o Senhor me pergunta o que h\u00e1 de errado nisso, se trata-se de coisa boa, que leva obras para as popula\u00e7\u00f5es carentes. Mas eu respondo que n\u00e3o \u00e9 n\u00e3o. Os pastores que frequentam os bastidores do minist\u00e9rio da Educa\u00e7\u00e3o foram orientados a somente dar a verba ao prefeito que der o feedback. E s\u00f3 recebe quem pedir atrav\u00e9s do Seu representante aqui na Terra, que \u00e9 tamb\u00e9m do presidente Jair Bolsonaro.<\/p>\n<p style=\"text-align: justify;\">Mas, como o Diabo atenta, n\u00e3o \u00e9 que um dos prefeitos procurados pelos pastores gravou a conversa. Numa den\u00fancia o prefeito do munic\u00edpio de Lu\u00eds Domingues, no Maranh\u00e3o, Gilberto Braga, do PSDB, assegurou \u2013 e provou &#8211; que um dos Vossos pastores que controlam o gabinete paralelo no Minist\u00e9rio da Educa\u00e7\u00e3o demandou pagamentos em dinheiro. Uma parte. Por que a outra parte, quando a verba sa\u00edsse do minist\u00e9rio, teria que ser e ouro. O metal dourado e raro em troca da libera\u00e7\u00e3o de recursos para a constru\u00e7\u00e3o de escolas e creches. Seu pastor teria pedido 1 quilo, o que vale dizer que queria mais de 300 mil reais de \u201ccomiss\u00e3o\u201d e n\u00e3o existem evid\u00eancias de que ele j\u00e1 teria recebido de outros prefeitos e pior: n\u00e3o estaria propenso a oferecer o Seu d\u00edzimo.<\/p>\n<p style=\"text-align: justify;\">Senhor, esse neg\u00f3cio de ser pastor e \u201cobreiro\u201d de obras p\u00fablicas \u00e9 uma coisa boa. Bom emprego. Talvez o Senhor n\u00e3o saiba, mas no Brasil tem 5.568 munic\u00edpios. Multiplique por 300 reais. Deixa que eu mesmo fa\u00e7o. Rapaz, vai dar quase bilh\u00e3o e meio de reais. Mas vamos l\u00e1: se somente metade dos prefeitos aceitar? Se apenas 10 por cento aceitarem? \u00c9 melhor que Megasena. Pare e imagine Seu d\u00edzimo.<\/p>\n<p style=\"text-align: justify;\">Mas o ministro da Educa\u00e7\u00e3o explicou que a sua prioridade \u00e9 atender primeiro os munic\u00edpios que mais precisam e, em segundo, atender a todos os que s\u00e3o amigos do pastor Gilmar. Est\u00e1 escrito.<\/p>\n<p style=\"text-align: justify;\">&#8211; Foi um pedido especial que o presidente da Rep\u00fablica fez para mim \u2013 justificou entornando mais ainda o caldo do ouro derretido.<\/p>\n<div id=\"blogd-3473040349\" class=\"blogd-final-post blogd-entity-placement\"><a href=\"https:\/\/www.feiradesantana.ba.leg.br\/\" target=\"_blank\" aria-label=\"JUNHO-VERMELHO_CA\u0302MARA-DE-FEIRA\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2026\/03\/JUNHO-VERMELHO_CAMARA-DE-FEIRA.gif\" alt=\"\"  class=\"no-lazyload\" width=\"728\" height=\"90\"   \/><\/a><\/div><p style=\"text-align: justify;\">Senhor, o Diabo est\u00e1 solto.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Deus! \u00f3 Deus! onde est\u00e1s que n\u00e3o respondes? Em que mundo, em qu&#8217;estrela tu t&#8217;escondes Embu\u00e7ado nos c\u00e9us? H\u00e1 dois mil anos te mandei meu grito, Que embalde desde ent\u00e3o corre o infinito&#8230; Onde est\u00e1s, Senhor Deus?&#8230; O brado do poeta Castro Alves (foto) em sua obra \u201cVozes D\u00b4\u00c1frica\u201d \u00e9 quase um lamento adequado para<\/p>\n","protected":false},"author":23,"featured_media":51821,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"cybocfi_hide_featured_image":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[592,1,631],"tags":[],"class_list":["post-51820","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-colunistas","category-raiz","category-politica"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2022\/04\/Castro-Alves_home.jpeg","jetpack_shortlink":"https:\/\/wp.me\/p3niVf-dtO","jetpack_sharing_enabled":true,"jetpack-related-posts":[{"id":46426,"url":"https:\/\/blogdafeira.com.br\/home\/2021\/07\/13\/stf-nao-e-templo-religioso\/","url_meta":{"origin":51820,"position":0},"title":"STF n\u00e3o \u00e9 templo religioso","author":"Luis Santos","date":"13\/07\/2021","format":false,"excerpt":"O presidente da Rep\u00fablica Federativa do Brasil, Jair Messias Bolsonaro (sem partido), indicou o nome de Andr\u00e9 Luiz de Almeida Mendon\u00e7a para a vaga de ministro deixada pelo decano do Supremo Tribunal Federal (STF), Marco Aur\u00e9lio Mendes de Farias Mello. Aposentado, Marco Aur\u00e9lio deixou a Corte nesta segunda feira, 12,\u2026","rel":"","context":"Em &quot;Colunistas&quot;","block_context":{"text":"Colunistas","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/colunistas\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2021\/07\/stf-crucifixo.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2021\/07\/stf-crucifixo.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2021\/07\/stf-crucifixo.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2021\/07\/stf-crucifixo.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":68494,"url":"https:\/\/blogdafeira.com.br\/home\/2025\/07\/20\/quatro-novos-frades-capuchinhos-na-bahia-fazem-votos-de-castidade-pobreza-e-obediencia\/","url_meta":{"origin":51820,"position":1},"title":"Quatro novos frades capuchinhos na Bahia fazem votos de castidade, pobreza e obedi\u00eancia","author":"Blog da Feira","date":"20\/07\/2025","format":false,"excerpt":"Em uma cerim\u00f4nia realizada no Santu\u00e1rio Arquidiocesano Nossa Senhora da Piedade, em Salvador , quatro frades capuchinhos emitiram votos perp\u00e9tuos, ontem (s\u00e1bado,19). Frei Jorge Rocha, Superintendente da Funda\u00e7\u00e3o Santo Ant\u00f4nio, em Feira,\u00a0 e formador dos jovens frades, explicou que os votos perp\u00e9tuos s\u00e3o de castidade, pobreza e obedi\u00eancia. Os frades\u2026","rel":"","context":"Em &quot;Geral&quot;","block_context":{"text":"Geral","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/geral\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2025\/07\/IMG-20250720-WA0049.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2025\/07\/IMG-20250720-WA0049.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2025\/07\/IMG-20250720-WA0049.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2025\/07\/IMG-20250720-WA0049.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":51224,"url":"https:\/\/blogdafeira.com.br\/home\/2022\/03\/11\/bolsonaro-vem-a-feira-na-proxima-semana-com-o-ministro-joao-roma\/","url_meta":{"origin":51820,"position":2},"title":"Bolsonaro vem a Feira nesta semana com o ministro Jo\u00e3o Roma","author":"Blog da Feira","date":"11\/03\/2022","format":false,"excerpt":"O presidente Jair Bolsonaro vem a Feira de Santana visitar a obra de duplica\u00e7\u00e3o da BR-116 Norte, pr\u00f3xima quarta-feira,dia 16, acompanhado do ministro da Cidadania\u00a0 e pr\u00e9 candidato a governador da Bahia, Jo\u00e3o Roma. A informa\u00e7\u00e3o inicial \u00e9 que ele chega primeiro em Salvador onde visitar\u00e1 as Obras Sociais Irm\u00e3\u2026","rel":"","context":"Em &quot;Home&quot;","block_context":{"text":"Home","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/raiz\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2022\/03\/ROMA.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2022\/03\/ROMA.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2022\/03\/ROMA.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2022\/03\/ROMA.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":62283,"url":"https:\/\/blogdafeira.com.br\/home\/2024\/05\/27\/barreiras-eu-gosto-muito-de-voce\/","url_meta":{"origin":51820,"position":3},"title":"Barreiras, eu gosto muit\u00e3o de voc\u00ea!","author":"Blog da Feira","date":"27\/05\/2024","format":false,"excerpt":"Janio Rego e demais amigos e amigas . Sou doido de amor , por Feira , onde eu nasci , l\u00e1 na Pracinha 2 de Julho . Cresci e fui muito feliz , na Barroquinha e na Rua de Aurora . Convivi com pessoas maravilhosas e conservo afetos que o\u2026","rel":"","context":"Em &quot;Colunistas&quot;","block_context":{"text":"Colunistas","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/colunistas\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2024\/05\/images-31.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2024\/05\/images-31.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2024\/05\/images-31.jpeg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":44904,"url":"https:\/\/blogdafeira.com.br\/home\/2021\/04\/15\/entre-a-misera-e-a-disgrama\/","url_meta":{"origin":51820,"position":4},"title":"Entre a \u201cmis\u00e9ra\u201d e a \u201cdisgrama\u201d","author":"Jolivaldo Freitas","date":"15\/04\/2021","format":false,"excerpt":"A extrema-direita ficou ressabiada e a extrema-esquerda ficou aliviada quando o ministro do STF, Edson Fachin decidiu que estava tudo errado em Curitiba, que os ju\u00edzes n\u00e3o podiam ter julgado tudo de uma s\u00f3 vez e na mesma esfera o caso do ex-presidente Lula. A quest\u00e3o \u00e9 que nem a\u2026","rel":"","context":"Em &quot;Colunistas&quot;","block_context":{"text":"Colunistas","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/colunistas\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2021\/04\/bancoImagemFotoAudiencia_AP_444349.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2021\/04\/bancoImagemFotoAudiencia_AP_444349.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2021\/04\/bancoImagemFotoAudiencia_AP_444349.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2021\/04\/bancoImagemFotoAudiencia_AP_444349.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2021\/04\/bancoImagemFotoAudiencia_AP_444349.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2021\/04\/bancoImagemFotoAudiencia_AP_444349.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":35098,"url":"https:\/\/blogdafeira.com.br\/home\/2020\/02\/06\/o-virus-da-vez-por-jolivaldo-freitas\/","url_meta":{"origin":51820,"position":5},"title":"O v\u00edrus da vez","author":"Jolivaldo Freitas","date":"06\/02\/2020","format":false,"excerpt":"De lastimar a atitude do governo brasileiro em querer fazer economia de palito. Vale perguntar: quanto custa uma vida? Quanto vale a vida de um brasileiro?","rel":"","context":"Em &quot;Colunistas&quot;","block_context":{"text":"Colunistas","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/colunistas\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2020\/02\/images-3-346x216.jpeg?resize=350%2C200","width":350,"height":200},"classes":[]}],"_links":{"self":[{"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/posts\/51820","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/users\/23"}],"replies":[{"embeddable":true,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/comments?post=51820"}],"version-history":[{"count":2,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/posts\/51820\/revisions"}],"predecessor-version":[{"id":51823,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/posts\/51820\/revisions\/51823"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/media\/51821"}],"wp:attachment":[{"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/media?parent=51820"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/categories?post=51820"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/tags?post=51820"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}