{"id":52606,"date":"2022-05-26T15:41:58","date_gmt":"2022-05-26T18:41:58","guid":{"rendered":"https:\/\/blogdafeira.com.br\/home\/?p=52606"},"modified":"2022-06-01T20:36:21","modified_gmt":"2022-06-01T23:36:21","slug":"feira-diferente-apelidos-de-vereadores-de-feira","status":"publish","type":"post","link":"https:\/\/blogdafeira.com.br\/home\/2022\/05\/26\/feira-diferente-apelidos-de-vereadores-de-feira\/","title":{"rendered":"Feira diferente: &#8220;apelidos de vereadores de Feira&#8221;"},"content":{"rendered":"<div id=\"blogd-2863026791\" class=\"blogd-fim-do-post-mobile blogd-entity-placement\" style=\"margin-left: auto;margin-right: auto;text-align: center;\"><a href=\"https:\/\/www.feiradesantana.ba.gov.br\/servico.asp?s=a&#038;titulo=Alceu,-Paula-Fernandes,-Alcymar-Monteiro,-Fl%C3%A1vio-Jos%C3%A9-e-Ra%C3%A7a-Negra-animar%C3%A3o-o-Arrai%C3%A1-de%20Feira.html&#038;id=8&#038;link=secom\/noticias.asp&#038;idn=43073#noticias\" target=\"_blank\" aria-label=\"728&#215;90 (7)\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2026\/03\/728x90-7.gif\" alt=\"\"  class=\"no-lazyload\" width=\"728\" height=\"90\"  style=\"display: inline-block;\" \/><\/a><\/div><p>Apelidar as pessoas \u00e9 uma tradi\u00e7\u00e3o brasileira de Norte a Sul do pa\u00eds. O grande poeta, escritor e compositor Vin\u00edcius de Moraes escreveu que &#8220;<em>o g\u00eanio do apelido \u00e9 virtude brasileira&#8221;. <\/em>Disse ele:<em> N\u00e3o conhe\u00e7o, em outros povos, uma tal espontaneidade na caracteriza\u00e7\u00e3o de tipos atrav\u00e9s de apelidos.<\/em><\/p><div id=\"blogd-2462338378\" class=\"blogd-conteudo-2-mobile blogd-entity-placement\"><a href=\"https:\/\/feirenses.com.br\/\" target=\"_blank\" aria-label=\"feirenses\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2026\/04\/feirenses.png\" alt=\"\"  srcset=\"https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2026\/04\/feirenses.png 300w, https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2026\/04\/feirenses-170x45.png 170w, https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2026\/04\/feirenses-280x74.png 280w\" sizes=\"(max-width: 300px) 100vw, 300px\" class=\"no-lazyload\" width=\"300\" height=\"79\"  style=\"display: inline-block;\" \/><\/a><\/div>\n<p>O Blog da Feira, ap\u00f3s fazer men\u00e7\u00e3o em um twitter sobre um apelido que o vereador Jhonatas Monteiro ganhou nos bastidores da C\u00e2mara de Vereadores de Feira de Santana resolveu compilar os apelidos que eventualmente fazem parte das conversas informais naquela Casa, principalmente entre jornalistas e radialistas que fazem a cobertura profissional dos trabalhos legislativos e resultou nessa lista, que n\u00e3o abrange todos. Alguns s\u00e3o apelidos j\u00e1 p\u00fablicos, os demais tornam-se agora. Veja a lista:<\/p>\n<p><span style=\"font-weight: 400;\">Lu de Rony \u2013 <strong><em>Viuvinha<\/em><\/strong><\/span><\/p>\n<p><span style=\"font-weight: 400;\">Fernando Torres \u2013 <strong><em>Todo-Poderoso<\/em><\/strong><\/span><\/p>\n<p><span style=\"font-weight: 400;\">Silvio Dias \u2013 <strong><em>C\u00e2mara de G\u00e1s<\/em><\/strong><\/span><\/p>\n<p><span style=\"font-weight: 400;\">Jhonatas Monteiro \u2013 <strong><em>Garganta de Grilo<\/em><\/strong><\/span><\/p>\n<p><span style=\"font-weight: 400;\">Paul\u00e3o do Caldeir\u00e3o \u2013 <strong><em>Professor<\/em><\/strong><\/span><\/p>\n<p><span style=\"font-weight: 400;\">Edvaldo Lima \u2013 <strong><em>Pantera Cor-de-Rosa<\/em><\/strong><\/span><\/p>\n<p><span style=\"font-weight: 400;\">Eremita \u2013 <strong><em>Ana Karenina<\/em><\/strong><\/span><\/p>\n<p><span style=\"font-weight: 400;\">Luiz da Feira \u2013 <strong><em>Aquele abra\u00e7o<\/em><\/strong><\/span><\/p>\n<p><span style=\"font-weight: 400;\">Jurandy Carvalho \u2013 <strong><em>Pescador<\/em><\/strong><\/span><\/p>\n<p><span style=\"font-weight: 400;\">Lulinha da Concei\u00e7\u00e3 \u2013 <strong><em>Jo\u00e3o B\u00f4bo<\/em><\/strong><\/span><\/p>\n<p><span style=\"font-weight: 400;\">Z\u00e9 Carneiro \u2013 <strong><em>O Cego<\/em><\/strong><\/span><\/p>\n<p><span style=\"font-weight: 400;\">Ron do Povo \u2013 <strong><em>Cal\u00e7a Justa<\/em><\/strong><\/span><\/p>\n<p><span style=\"font-weight: 400;\">Z\u00e9 Curuca \u2013<strong><em> O Meu Primeiro<\/em><\/strong><\/span><\/p>\n<div id=\"blogd-477769833\" class=\"blogd-final-post blogd-entity-placement\"><a href=\"https:\/\/www.feiradesantana.ba.leg.br\/\" target=\"_blank\" aria-label=\"BANNER-SITE-ENTREGADECHEQUE-CAMARADEFEIRA\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2026\/03\/BANNER-SITE-ENTREGADECHEQUE-CAMARADEFEIRA.gif\" alt=\"\"  class=\"no-lazyload\" width=\"728\" height=\"90\"   \/><\/a><\/div><p><span style=\"font-weight: 400;\">Ivamberg &#8211; <strong><em>Risadinha<\/em><\/strong><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Apelidar as pessoas \u00e9 uma tradi\u00e7\u00e3o brasileira de Norte a Sul do pa\u00eds. O grande poeta, escritor e compositor Vin\u00edcius de Moraes escreveu que &#8220;o g\u00eanio do apelido \u00e9 virtude brasileira&#8221;. Disse ele: N\u00e3o conhe\u00e7o, em outros povos, uma tal espontaneidade na caracteriza\u00e7\u00e3o de tipos atrav\u00e9s de apelidos. O Blog da Feira, ap\u00f3s fazer men\u00e7\u00e3o<\/p>\n","protected":false},"author":1,"featured_media":52608,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"cybocfi_hide_featured_image":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[1,656,631],"tags":[],"class_list":["post-52606","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-raiz","category-humor","category-politica"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2022\/05\/FB_IMG_1653590378980.jpg","jetpack_shortlink":"https:\/\/wp.me\/p3niVf-dGu","jetpack_sharing_enabled":true,"jetpack-related-posts":[{"id":55638,"url":"https:\/\/blogdafeira.com.br\/home\/2022\/11\/28\/chuvas-em-feira-fazem-colbert-fazer-novo-apelo-a-camara-de-vereadores\/","url_meta":{"origin":52606,"position":0},"title":"Chuvas em Feira: Colbert faz novo apelo \u00e0 C\u00e2mara de Vereadores","author":"Blog da Feira","date":"28\/11\/2022","format":false,"excerpt":"Com as chuvas pesadas que caem sobre Feira de Santana emergiram diversos problemas no mapa urbano do munic\u00edpio, relativos principalmente \u00e0 drenagem das \u00e1guas. O prefeito de Feira, Colbert Filho (MDB) fez um v\u00eddeo sobre o assunto e mais um vez fez um apelo aos vereadores pela aprova\u00e7\u00e3o dos pedidos\u2026","rel":"","context":"Em &quot;Cidade&quot;","block_context":{"text":"Cidade","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/cidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2022\/11\/OIP-2.jpeg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":57685,"url":"https:\/\/blogdafeira.com.br\/home\/2023\/05\/17\/vereador-faz-apelo-a-aplb-de-feira-deixe-as-criancas-estudarem\/","url_meta":{"origin":52606,"position":1},"title":"Vereador faz apelo \u00e0 APLB de Feira: &#8220;deixe as crian\u00e7as estudarem&#8221;","author":"Blog da Feira","date":"17\/05\/2023","format":false,"excerpt":"Algu\u00e9m se rebelou contra a banaliza\u00e7\u00e3o das greves de professores das escolas p\u00fablicas em Feira de Santana promovidas pela APLB e a voz que se levantou vem do distrito de Jaguara atrav\u00e9s de relatos indignados do vereador Paul\u00e3o do Caldeir\u00e3o hoje na C\u00e2mara de Vereadores. Marlede (Oliveira, presidente da associa\u00e7\u00e3o)\u2026","rel":"","context":"Em &quot;Home&quot;","block_context":{"text":"Home","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/raiz\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2023\/05\/17052023193918.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2023\/05\/17052023193918.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2023\/05\/17052023193918.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2023\/05\/17052023193918.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2023\/05\/17052023193918.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":43267,"url":"https:\/\/blogdafeira.com.br\/home\/2021\/02\/04\/paulao-do-caldeirao-bota-apelido-em-colega-vereador\/","url_meta":{"origin":52606,"position":2},"title":"Paul\u00e3o do Caldeir\u00e3o bota apelido em colega vereador","author":"Blog da Feira","date":"04\/02\/2021","format":false,"excerpt":"O irreverente comunicador Paul\u00e3o do Caldeir\u00e3o, vereador em primeiro mandato na Camara de Feira de Santana inicia o mandato mantendo mesmo perfil que o tornou um dos mais populares homens de comunica\u00e7\u00e3o no munic\u00edpio e em uma das primeiras entrevistas, ao jornalista Comendador Girlanio Guirra tascou um apelido em Luiz\u2026","rel":"","context":"Em &quot;Cidade&quot;","block_context":{"text":"Cidade","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/cidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2021\/02\/Screenshot_20210204-1709133.png?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":57696,"url":"https:\/\/blogdafeira.com.br\/home\/2023\/05\/18\/colbert-faz-apelo-ao-presidente-da-cni-feira-nao-pode-perder-essa-escola\/","url_meta":{"origin":52606,"position":3},"title":"Colbert faz apelo ao presidente da CNI: &#8220;Feira n\u00e3o pode perder essa escola&#8221;","author":"Blog da Feira","date":"18\/05\/2023","format":false,"excerpt":"O prefeito de Feira de Santana, Colbert Filho (MDB) utilizou as redes sociais para fazer um apelo ao presidente da Confedera\u00e7\u00e3o Nacional da Agricultura, Jo\u00e3o Martins Junior, para que continue com o plano de implantar no Parque de Exposi\u00e7\u00f5es de Feira de Santana uma \"escola t\u00e9cnica de n\u00edvel superior\" voltada\u2026","rel":"","context":"Em &quot;Home&quot;","block_context":{"text":"Home","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/raiz\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2023\/05\/Screenshot_20230518-184204.png?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2023\/05\/Screenshot_20230518-184204.png?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2023\/05\/Screenshot_20230518-184204.png?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2023\/05\/Screenshot_20230518-184204.png?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2023\/05\/Screenshot_20230518-184204.png?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":58890,"url":"https:\/\/blogdafeira.com.br\/home\/2023\/08\/04\/vereador-mostra-poluicao-no-rio-jacuipe-com-lixo-jogado-nas-ruas-de-feira\/","url_meta":{"origin":52606,"position":4},"title":"Lixo jogado nas ruas de Feira polui o Rio Jacu\u00edpe: vereador apela por &#8216;consci\u00eancia&#8217;","author":"Blog da Feira","date":"04\/08\/2023","format":false,"excerpt":"O vereador Jurandy Carvalho abriu uma campanha de conscientiza\u00e7\u00e3o sobre o descarte do lixo residencial e comercial urbano ao anunciar a limpeza do Tr\u00eas Riachos, afluente do Rio Jacu\u00edpe que \u00e9 atingido nesse trecho pelo despejo das \u00e1guas pluviais da cidade acompanhada da enorme quantidade de lixo jogada nas ruas\u2026","rel":"","context":"Em &quot;Cidade&quot;","block_context":{"text":"Cidade","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/cidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2023\/08\/Screenshot_20230804-0000552.png?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2023\/08\/Screenshot_20230804-0000552.png?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2023\/08\/Screenshot_20230804-0000552.png?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2023\/08\/Screenshot_20230804-0000552.png?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":33147,"url":"https:\/\/blogdafeira.com.br\/home\/2019\/10\/02\/ze-neto-faz-apelo-a-colbert-para-resolver-problema-dos-camelos-com-o-shopping-popular\/","url_meta":{"origin":52606,"position":5},"title":"Z\u00e9 Neto faz apelo a Colbert para resolver problema dos camel\u00f4s com o shopping popular","author":"J\u00e2nio R\u00eago","date":"02\/10\/2019","format":false,"excerpt":"No plen\u00e1rio da C\u00e2mara dos Deputados o deputado Z\u00e9 Neto (PT)\u00a0 fez um apelo ao Prefeito de Feira de Santana, Colbert Martins (MDB), para que ele resolva o\u00a0 problema dos camel\u00f4s da cidade que est\u00e3o se manifestando h\u00e1 dias, sem obter aten\u00e7\u00e3o do Poder Executivo. Os camel\u00f4s, explicou Z\u00e9 Neto\u2026","rel":"","context":"Em &quot;Home&quot;","block_context":{"text":"Home","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/raiz\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2019\/10\/Nota-5-Foto-Gabriel-Paiva-2-799x491-346x213.jpg?resize=350%2C200","width":350,"height":200},"classes":[]}],"_links":{"self":[{"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/posts\/52606","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/comments?post=52606"}],"version-history":[{"count":1,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/posts\/52606\/revisions"}],"predecessor-version":[{"id":52609,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/posts\/52606\/revisions\/52609"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/media\/52608"}],"wp:attachment":[{"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/media?parent=52606"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/categories?post=52606"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/tags?post=52606"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}