{"id":58150,"date":"2023-06-13T16:32:47","date_gmt":"2023-06-13T19:32:47","guid":{"rendered":"https:\/\/blogdafeira.com.br\/home\/?p=58150"},"modified":"2023-10-10T00:14:59","modified_gmt":"2023-10-10T03:14:59","slug":"jeronimo-quer-ajudar-colbert-na-iluminacao-do-joia-da-princesa","status":"publish","type":"post","link":"https:\/\/blogdafeira.com.br\/home\/2023\/06\/13\/jeronimo-quer-ajudar-colbert-na-iluminacao-do-joia-da-princesa\/","title":{"rendered":"Jer\u00f4nimo quer ajudar Colbert na ilumina\u00e7\u00e3o do Joia da Princesa"},"content":{"rendered":"<div id=\"blogd-1651436839\" class=\"blogd-fim-do-post-mobile blogd-entity-placement\" style=\"margin-left: auto;margin-right: auto;text-align: center;\"><a href=\"https:\/\/www.feiradesantana.ba.gov.br\/servico.asp?s=a&#038;titulo=Alceu,-Paula-Fernandes,-Alcymar-Monteiro,-Fl%C3%A1vio-Jos%C3%A9-e-Ra%C3%A7a-Negra-animar%C3%A3o-o-Arrai%C3%A1-de%20Feira.html&#038;id=8&#038;link=secom\/noticias.asp&#038;idn=43073#noticias\" target=\"_blank\" aria-label=\"728&#215;90 (7)\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2026\/03\/728x90-7.gif\" alt=\"\"  class=\"no-lazyload\" width=\"728\" height=\"90\"  style=\"display: inline-block;\" \/><\/a><\/div><p>Durante coletiva em Salvador e em resposta ao rep\u00f3rter esportivo Jair Cezarinho, o governador Jer\u00f4nimo Rodrigues aproveitou para &#8220;pedir aqui e agora, em p\u00fablico, para que o Prefeito de Feira e eu, achemos uma forma de fazermos, juntos, uma ilumina\u00e7\u00e3o p\u00fablica de qualidade\u00a0 no Joia da Princesa&#8221;.<\/p><div id=\"blogd-651064038\" class=\"blogd-conteudo-2-mobile blogd-entity-placement\"><a href=\"https:\/\/feirenses.com.br\/\" target=\"_blank\" aria-label=\"feirenses\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2026\/04\/feirenses.png\" alt=\"\"  srcset=\"https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2026\/04\/feirenses.png 300w, https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2026\/04\/feirenses-170x45.png 170w, https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2026\/04\/feirenses-280x74.png 280w\" sizes=\"(max-width: 300px) 100vw, 300px\" class=\"no-lazyload\" width=\"300\" height=\"79\"  style=\"display: inline-block;\" \/><\/a><\/div>\n<p>O governador disse que quer voltar ao est\u00e1dio onde tantas vezes esteve com seu &#8220;radinho de pilha&#8221;.<\/p>\n<p>Jer\u00f4nimo referia-se ao epis\u00f3dio n partida entre o Fluminense de Feira e Juazeiro, pela 4\u00aa rodada da segunda quando por volta de 20 minutos do segundo-tempo, uma das torres de ilumina\u00e7\u00e3o n\u00e3o acendeu e o problema n\u00e3o foi resolvido.<\/p>\n<div id=\"blogd-485741182\" class=\"blogd-final-post blogd-entity-placement\"><a href=\"https:\/\/www.feiradesantana.ba.leg.br\/\" target=\"_blank\" aria-label=\"BANNER-SITE-ENTREGADECHEQUE-CAMARADEFEIRA\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2026\/03\/BANNER-SITE-ENTREGADECHEQUE-CAMARADEFEIRA.gif\" alt=\"\"  class=\"no-lazyload\" width=\"728\" height=\"90\"   \/><\/a><\/div><p>O rep\u00f3rter\u00a0 Cezarinho tamb\u00e9m aproveitou para &#8216;adivinhar&#8217; em qual posi\u00e7\u00e3o o governador &#8220;jogava bola&#8221;. O di\u00e1logo:\u00a0 <em>Zagueiro? \u00c9 isso mesmo.Esquerda? Direita.\u00a0<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Durante coletiva em Salvador e em resposta ao rep\u00f3rter esportivo Jair Cezarinho, o governador Jer\u00f4nimo Rodrigues aproveitou para &#8220;pedir aqui e agora, em p\u00fablico, para que o Prefeito de Feira e eu, achemos uma forma de fazermos, juntos, uma ilumina\u00e7\u00e3o p\u00fablica de qualidade\u00a0 no Joia da Princesa&#8221;. O governador disse que quer voltar ao est\u00e1dio<\/p>\n","protected":false},"author":1,"featured_media":58151,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"cybocfi_hide_featured_image":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[5,1,631],"tags":[],"class_list":["post-58150","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-esporte","category-raiz","category-politica"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2023\/06\/jCdX9nwoW5zlvzS9RnCi7OBbJ3UeXvDCIKFZ0oY8.jpg","jetpack_shortlink":"https:\/\/wp.me\/p3niVf-f7U","jetpack_sharing_enabled":true,"jetpack-related-posts":[{"id":61869,"url":"https:\/\/blogdafeira.com.br\/home\/2024\/04\/07\/jero-vem-e-vai-chegar-brocando-e-rasgando-na-micareta-de-feira-diz-jair-cezarinho\/","url_meta":{"origin":58150,"position":0},"title":"&#8220;Jero vem e vai chegar brocando e rasgando na Micareta de Feira&#8221;, diz Jair Cezarinho","author":"Blog da Feira","date":"07\/04\/2024","format":false,"excerpt":"\"Eu n\u00e3o sou o porta-voz oficial de Jero, mas ele vem, e vai chegar, de novo, brocando e rasgando, na Micareta de Feira\",\u00a0diz o radialista Jair Cezarinho, um dos mais antigos profissionais do r\u00e1dio jornalismo de Feira de Santana, em \u00e1udio que circula na internet. O radialista \u00e9 um admirador\u2026","rel":"","context":"Em &quot;Cidade&quot;","block_context":{"text":"Cidade","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/cidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2024\/04\/IMG-20240407-WA0017.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2024\/04\/IMG-20240407-WA0017.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2024\/04\/IMG-20240407-WA0017.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":26571,"url":"https:\/\/blogdafeira.com.br\/home\/2017\/04\/17\/e-o-touro-do-sertao-continua-fregues-do-bahia-3-x-0-no-joia-da-princesa\/","url_meta":{"origin":58150,"position":1},"title":"E o Touro do Sert\u00e3o continua &#8216;fregu\u00eas&#8217; do Bahia&#8230;3 x 0 no Joia da Princesa","author":"Blog da Feira","date":"17\/04\/2017","format":false,"excerpt":"Certa estava a TV Bahia que encerrou o jornal do Meio Dia ontem com um torcedor do 'Bah\u00eaa', em Salvador, lembrando ao rep\u00f3rter: ah, voc\u00ea n\u00e3o sabia n\u00e3o \u00e9? o Flu de Feira \u00e9 fregu\u00eas, fregues\u00e3o do Bah\u00eaa...! Bah\u00eaa minha p....porreta!\" O Fluminense de Feira de Santana, o Touro do\u2026","rel":"","context":"Em &quot;Home&quot;","block_context":{"text":"Home","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/raiz\/"},"img":{"alt_text":"ed-santos","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2017\/04\/ed-santos-346x195.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":61415,"url":"https:\/\/blogdafeira.com.br\/home\/2024\/03\/05\/jeronimo-anuncia-plano-urbanistico-para-os-proximos-50-anos-de-feira\/","url_meta":{"origin":58150,"position":2},"title":"Jer\u00f4nimo anuncia Plano Urban\u00edstico para os pr\u00f3ximos 50 anos de Feira","author":"Blog da Feira","date":"05\/03\/2024","format":false,"excerpt":"O governador Jer\u00f4nimo Rodrigues autorizou\u00a0 durante reuni\u00e3o com empres\u00e1rios feirenses e o deputado federal Z\u00e9 Neto (PT), em Salvador, a primeira etapa das obras de recupera\u00e7\u00e3o asf\u00e1ltica das vias internas no Centro Industrial do Suba\u00e9 (CIS) e a nova ilumina\u00e7\u00e3o da BA-502, entre Feira de Santana e S\u00e3o Gon\u00e7alo. O\u2026","rel":"","context":"Em &quot;Cidade&quot;","block_context":{"text":"Cidade","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/cidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2024\/03\/IMG-20240305-WA0026.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2024\/03\/IMG-20240305-WA0026.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2024\/03\/IMG-20240305-WA0026.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2024\/03\/IMG-20240305-WA0026.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2024\/03\/IMG-20240305-WA0026.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":22059,"url":"https:\/\/blogdafeira.com.br\/home\/2016\/06\/17\/domingo-tem-brasileirao-no-estadio-joia-da-princesa-em-feira\/","url_meta":{"origin":58150,"position":3},"title":"Domingo tem brasileir\u00e3o no est\u00e1dio Joia da Princesa em Feira","author":"Blog da Feira","date":"17\/06\/2016","format":false,"excerpt":"O verde, vermelho e o branco, as cores do Fluminense de Feira d\u00e3o vida ao Est\u00e1dio Municipal Alberto Oliveira, o nosso Joia da Princesa. O tapete verde est\u00e1 pronto para receber o Flu, o \u201ctime da casa\u201d, e o Murici, de Alagoas, na primeira partida que marcar\u00e1 a reabertura do\u2026","rel":"","context":"Em &quot;Home&quot;","block_context":{"text":"Home","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/raiz\/"},"img":{"alt_text":"estadio","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2016\/06\/estadio.jpg?resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2016\/06\/estadio.jpg?resize=350%2C200 1x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2016\/06\/estadio.jpg?resize=525%2C300 1.5x"},"classes":[]},{"id":57270,"url":"https:\/\/blogdafeira.com.br\/home\/2023\/04\/26\/colbert-festa-e-um-bom-investimento-mas-quer-conversar-com-jeronimo-sobre-prioridades\/","url_meta":{"origin":58150,"position":4},"title":"Colbert diz que aguarda convite de Jer\u00f4nimo para conversar sobre novos investimentos","author":"Blog da Feira","date":"26\/04\/2023","format":false,"excerpt":"Ap\u00f3s apresentar um balan\u00e7o positivo da Micareta de Feira, hoje, no Teatro Municipal Margarida Ribeiro, o prefeito de Feira de Santana, Colbert Filho disse, em coletiva \u00e0 imprensa, ao responder a uma pergunta do rep\u00f3rter Jota Bezerra que \"festa \u00e9 um bom investimento\", mas que ele aguarda \u00e9 ser chamado\u2026","rel":"","context":"Em &quot;Home&quot;","block_context":{"text":"Home","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/raiz\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2023\/04\/IMG-20230424-WA0181-1536x1147-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2023\/04\/IMG-20230424-WA0181-1536x1147-1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2023\/04\/IMG-20230424-WA0181-1536x1147-1.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2023\/04\/IMG-20230424-WA0181-1536x1147-1.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2023\/04\/IMG-20230424-WA0181-1536x1147-1.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2023\/04\/IMG-20230424-WA0181-1536x1147-1.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":70682,"url":"https:\/\/blogdafeira.com.br\/home\/2025\/12\/26\/jeronimo-a-folha-de-sao-paulo-que-vai-trabalhar-ate-o-ultimo-dia-para-reverter-pesquisas\/","url_meta":{"origin":58150,"position":5},"title":"Jer\u00f4nimo diz \u00e0 &#8216;Folha de S\u00e3o Paulo&#8217; que vai trabalhar &#8220;at\u00e9 o \u00faltimo dia&#8221; para reverter pesquisas","author":"Blog da Feira","date":"26\/12\/2025","format":false,"excerpt":"Em entrevista ao rep\u00f3rter Jo\u00e3o Pedro Pitombo, publicada hoje na 'Folha de S\u00e3o Paulo', o governador Jer\u00f4nimo Rodrigues disse que vai trabalhar \"at\u00e9 o \u00faltimo dia\" para fazer \"minhas entregas e reverter as pesquisas\". Jer\u00f4nimo aparece atr\u00e1s de seu principal advers\u00e1rio, ACM Neto (Uni\u00e3o Brasil), nas pesquisas \u2013 o ex-prefeito\u2026","rel":"","context":"Em &quot;Home&quot;","block_context":{"text":"Home","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/raiz\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2025\/12\/images-162.jpeg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]}],"_links":{"self":[{"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/posts\/58150","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/comments?post=58150"}],"version-history":[{"count":4,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/posts\/58150\/revisions"}],"predecessor-version":[{"id":58155,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/posts\/58150\/revisions\/58155"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/media\/58151"}],"wp:attachment":[{"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/media?parent=58150"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/categories?post=58150"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/tags?post=58150"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}