{"id":71986,"date":"2026-04-13T18:29:41","date_gmt":"2026-04-13T21:29:41","guid":{"rendered":"https:\/\/blogdafeira.com.br\/home\/?p=71986"},"modified":"2026-07-06T16:58:08","modified_gmt":"2026-07-06T19:58:08","slug":"cris-vaccarezza-lanca-novo-livro-na-bienal-bahia-2026","status":"publish","type":"post","link":"https:\/\/blogdafeira.com.br\/home\/2026\/04\/13\/cris-vaccarezza-lanca-novo-livro-na-bienal-bahia-2026\/","title":{"rendered":"Cris Vaccarezza lan\u00e7a novo livro na Bienal Bahia 2026"},"content":{"rendered":"<div id=\"blogd-1829600986\" class=\"blogd-fim-do-post-mobile blogd-entity-placement\" style=\"margin-left: auto;margin-right: auto;text-align: center;\"><a href=\"https:\/\/expofeira.ba.gov.br\/\" target=_blank><picture>\r\n  <source media=\"(min-width: 768px)\" srcset=\"https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2026\/08\/980x1503.gif\">\r\n  \r\n  <img decoding=\"async\" src=\"https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2026\/08\/350x2005.gif\" alt=\"Publicidade\" style=\"width: 100%; max-width: 100%; height: auto; display: block; margin: 0 auto;\">\r\n\t<\/picture><\/a><\/div><p>A autora Cris Vaccarezza lan\u00e7a na Bienal do livro Bahia 2026 seu novo livro. Em Carolina Libert\u00e1ria, ela presenteia os leitores com um suspense eletrizante, com muito regionalismo, personagens femininas fortes e destemidas e uma critica pertinente no momento atual: At\u00e9 quando as mulheres v\u00e3o ter que lidar com quest\u00f5es de viol\u00eancia de g\u00eanero?<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-71987\" src=\"https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2026\/04\/images-38.jpeg\" alt=\"\" width=\"180\" height=\"279\" srcset=\"https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2026\/04\/images-38.jpeg 180w, https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2026\/04\/images-38-97x150.jpeg 97w, https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2026\/04\/images-38-121x187.jpeg 121w\" sizes=\"auto, (max-width: 180px) 100vw, 180px\" \/><\/p>\n<p><strong>Carolina Libert\u00e1ria &#8211;\u00a0 <\/strong>Carolina nasceu do lado errado do amor. Cresceu entre o medo e o sil\u00eancio. No sert\u00e3o, onde muitas hist\u00f3rias de viol\u00eancia parecem condenadas a se repetir gera\u00e7\u00e3o ap\u00f3s gera\u00e7\u00e3o, ela aprendeu cedo que esperar pela justi\u00e7a nem sempre \u00e9 uma op\u00e7\u00e3o.<\/p>\n<p>Criada pela for\u00e7a silenciosa da m\u00e3e e pela f\u00e9 firme do av\u00f4, Carolina carregou por anos o peso de uma origem que ningu\u00e9m ousa contar. At\u00e9 o dia em que decidiu que nunca mais seria v\u00edtima. Quando a viol\u00eancia amea\u00e7a novamente quem ela ama, Carolina escolhe um caminho sem volta. Entre o amor e o \u00f3dio, entre o per &#8211; d\u00e3o e a vingan\u00e7a, ela atravessa o Brasil com um prop\u00f3sito: enfren &#8211; tar homens que acreditam que o sil\u00eanciomulheres \u00e9 eterno. Mas romper um ciclo de dor tem um pre\u00e7o \u2014 e cada escolha a aproxima de um confronto inevit\u00e1vel com o pr\u00f3prio passado. Carolina Libert\u00e1ria \u00e9 um romance intenso sobre coragem, justi\u00e7a e a for\u00e7a de uma mulher que decidiu que a hist\u00f3ria n\u00e3o terminaria como come\u00e7ou. Nem v\u00edtima, nem vil\u00e3.<\/p>\n<p><strong>Sobra a autora Cris Vaccarezza <\/strong><\/p>\n<p>Cris Vaccarezza \u00e9 escritora baiana, radiologista e psicanalista apaixonada por palavras que curam e provocam. Autora de Poesias Acidentais e Inimput\u00e1vel \u2013 \u00c0 margem da loucura, mescla cr\u00edtica social e profundidade emocional em sua obra.<\/p>\n<p>Saiba mais sobre a autora em suas redes sociais.<\/p>\n<p><strong>Agenda<\/strong>:<\/p>\n<p>17\/04 &#8211; ENCONTRO DE LEITORES DE SUSPENSE NO ESTANDE DA ESTANTE<\/p>\n<p>VIRTUAL: Andrea e Cris Vaccarezza s\u00e3o as autoras que est\u00e3o confirmadas no encontro! 17:30H na Estante Virtual, estande A64, Asa A.<\/p>\n<p>17\/04 &#8211; Roda de conversa \u201cDesafios e oportunidades da escrita feminina\u201d Na areninha do Escreva, Garota! 19H no estande C06 Asa A.<\/p>\n<p>18\/04 \u2013 Roda de conversa \u201cQuando a justi\u00e7a tarda, o que desperta nas mulheres ? \u2013<\/p>\n<p>Literatura, liberdade e empoderamento e reinven\u00e7\u00e3o do feminino\u201d10H Na areninha do<\/p>\n<p><strong>Escreva, Garota! no estande C06 Asa A. <\/strong><\/p>\n<p>Quadro especial em suas redes sociais. A autora tem em seu instagram um quadro chamado \u201cMulheres que por n\u00f3s falam\u201d. A\u00a0 cada v\u00eddeo ela apresenta e destaca uma mulher diferente para inspirar, compartilhar\u00a0 conhecimento e rever a hist\u00f3ria. Mulheres que ocupam espa\u00e7os importantes, que rompem barreiras sociais, trazem leveza atrav\u00e9s de sua arte.<\/p>\n<p>Em um dos seus epis\u00f3dios, Cris conta sobre Edite Mendes da Gama e Abreu, nascida em Feira de Santana ela foi a primeira mulher a ocupar uma cadeira em academia de letras no Brasil.<\/p>\n<div id=\"blogd-440616882\" class=\"blogd-final-post blogd-entity-placement\"><a href=\"https:\/\/www.feiradesantana.ba.leg.br\/\" target=\"_blank\" aria-label=\"BANNER-SITE_CA\u0302MARA_AGOSTO_728x90px\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2026\/03\/BANNER-SITE_CAMARA_AGOSTO_728x90px.gif\" alt=\"\"  class=\"no-lazyload\" width=\"728\" height=\"90\"   \/><\/a><\/div><p>Para conhecer o quadro, siga a autora no instagram. Para saber mais, marcar entrevistas ou a participa\u00e7\u00e3o da autora em seu evento, basta entrar em contato.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A autora Cris Vaccarezza lan\u00e7a na Bienal do livro Bahia 2026 seu novo livro. Em Carolina Libert\u00e1ria, ela presenteia os leitores com um suspense eletrizante, com muito regionalismo, personagens femininas fortes e destemidas e uma critica pertinente no momento atual: At\u00e9 quando as mulheres v\u00e3o ter que lidar com quest\u00f5es de viol\u00eancia de g\u00eanero? Carolina<\/p>\n","protected":false},"author":1,"featured_media":71989,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"cybocfi_hide_featured_image":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[4,1],"tags":[],"class_list":["post-71986","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultura","category-raiz"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2026\/04\/images-39.jpeg","jetpack_shortlink":"https:\/\/wp.me\/p3niVf-iJ4","jetpack_sharing_enabled":true,"jetpack-related-posts":[{"id":5746,"url":"https:\/\/blogdafeira.com.br\/home\/2013\/10\/24\/antonio-brasileiro-lanca-novo-livro-na-bienal-da-bahia-em-novembro\/","url_meta":{"origin":71986,"position":0},"title":"Ant\u00f4nio Brasileiro lan\u00e7a novo livro na Bienal da Bahia em novembro","author":"Ascom","date":"24\/10\/2013","format":false,"excerpt":"O escritor Ant\u00f4nio Brasileiro lan\u00e7a mais um novo livro. Mais conhecido pelas poesias, o novo trabalho liter\u00e1rio de Brasileiro s\u00e3o contos e novelas. 'As Mem\u00f3rias Miraculosas de Nestor QuatorzeVoltas' ser\u00e1 lan\u00e7ado na Bienal do Livro da Bahia, que acontece no pr\u00f3ximo m\u00eas de novembro, em Salvador. Brasileiro divulgou a capa\u2026","rel":"","context":"Em &quot;Home&quot;","block_context":{"text":"Home","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/raiz\/"},"img":{"alt_text":"BRASILEIRO F","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2013\/10\/BRASILEIRO-F.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":5911,"url":"https:\/\/blogdafeira.com.br\/home\/2013\/11\/06\/poetas-e-escritores-de-feira-participam-da-bienal-do-livro-em-salvador\/","url_meta":{"origin":71986,"position":1},"title":"Poetas e escritores de Feira participam da Bienal do Livro em Salvador","author":"Ascom","date":"06\/11\/2013","format":false,"excerpt":"Os poetas e escritores Ant\u00f4nio Brasileiro, Roberval Pereyr e Franklin Maxado participam da Bienal do Livro da Bahia, que come\u00e7a nesta sexta-feira em Salvador. Brasileiro lan\u00e7a um novo livro de contos e novelas intitulado\u00a0\u2018As Mem\u00f3rias Miraculosas de Nestor QuatorzeVoltas\u2019. Franklin Maxado lan\u00e7a a nova edi\u00e7\u00e3o pela Editora Queima-Bucha do festejado\u2026","rel":"","context":"Em &quot;Home&quot;","block_context":{"text":"Home","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/raiz\/"},"img":{"alt_text":"BRASILEIRO F","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2013\/10\/BRASILEIRO-F-208x300.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":72077,"url":"https:\/\/blogdafeira.com.br\/home\/2026\/04\/20\/jaqueline-el-chami-lancou-coletanea-na-bienal-sobre-saude-integral-nas-organizacoes\/","url_meta":{"origin":71986,"position":2},"title":"Jaqueline El Chami lan\u00e7ou colet\u00e2nea, na Bienal, sobre sa\u00fade integral nas organiza\u00e7\u00f5es","author":"Ascom","date":"20\/04\/2026","format":false,"excerpt":"Uma colet\u00e2nea com autores renomados, sobre sa\u00fade organizacional e o futuro das rela\u00e7\u00f5es de trabalho, organizada por Jaqueline El Chami, conselheira de Rela\u00e7\u00f5es Trabalhistas da Federa\u00e7\u00e3o das Ind\u00fastrias, foi lan\u00e7ado, domingo (ontem, 19) ,\u00a0 durante a Bienal do Livro, em Salvador. A colet\u00e2nea \u201cColaboradores Saud\u00e1veis, Empresas Fortes\u201d re\u00fane diferentes vozes\u2026","rel":"","context":"Em &quot;Economia&quot;","block_context":{"text":"Economia","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/economia\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2026\/04\/IMG-20260418-WA00582.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2026\/04\/IMG-20260418-WA00582.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2026\/04\/IMG-20260418-WA00582.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2026\/04\/IMG-20260418-WA00582.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":73783,"url":"https:\/\/blogdafeira.com.br\/home\/2026\/08\/29\/jornalista-participa-pela-segunda-vez-da-flifs-e-vai-a-bienal-de-sao-paulo-lancar-o-setimo-livro\/","url_meta":{"origin":71986,"position":3},"title":"Jornalista participa pela segunda vez da FLIFS e vai \u00e0 Bienal de S\u00e3o Paulo lan\u00e7ar o s\u00e9timo livro","author":"Ascom","date":"29\/08\/2026","format":false,"excerpt":"A jornalista Clara Pomponet, que atua no setor de R\u00e1dio Escuta, na Secretaria Municipal de Comunica\u00e7\u00e3o Social (Secom), na Prefeitura de Feira de Santana, participa pela segunda vez do Festival Liter\u00e1rio e Cultural de Feira (FLIFS) onde apresenta ao p\u00fablico parte das obras que marcam sua trajet\u00f3ria como escritora. Em\u2026","rel":"","context":"Em &quot;Cidade&quot;","block_context":{"text":"Cidade","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/cidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2026\/08\/Livro-de-Clara-Pamponet-Foto-Gabriel-Calazans-3.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2026\/08\/Livro-de-Clara-Pamponet-Foto-Gabriel-Calazans-3.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2026\/08\/Livro-de-Clara-Pamponet-Foto-Gabriel-Calazans-3.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2026\/08\/Livro-de-Clara-Pamponet-Foto-Gabriel-Calazans-3.jpeg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2026\/08\/Livro-de-Clara-Pamponet-Foto-Gabriel-Calazans-3.jpeg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":38178,"url":"https:\/\/blogdafeira.com.br\/home\/2020\/06\/02\/a-literatura-contudente-de-carolina-maria-de-jesus\/","url_meta":{"origin":71986,"position":4},"title":"A literatura contundente de Carolina Maria de Jesus","author":"Ascom","date":"02\/06\/2020","format":false,"excerpt":"\u201c2 DE JUNHO Amanheceu fazendo frio. Acendi o fogo e mandei o Jo\u00e3o ir comprar p\u00e3o e caf\u00e9. O p\u00e3o, o Chico do Mercadinho cortou um peda\u00e7o. Eu chinguei o Chico de ordin\u00e1rio, cachorro (...) O senhor Manuel apareceu dizendo que quer casar-se comigo. Mas eu n\u00e3o quero porque j\u00e1\u2026","rel":"","context":"Em &quot;Colunistas&quot;","block_context":{"text":"Colunistas","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/colunistas\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2020\/06\/periferias-carolina-maria-de-jesus-uma-escritora-presente-carolina-maria-3-1-scaled.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2020\/06\/periferias-carolina-maria-de-jesus-uma-escritora-presente-carolina-maria-3-1-scaled.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2020\/06\/periferias-carolina-maria-de-jesus-uma-escritora-presente-carolina-maria-3-1-scaled.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2020\/06\/periferias-carolina-maria-de-jesus-uma-escritora-presente-carolina-maria-3-1-scaled.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2020\/06\/periferias-carolina-maria-de-jesus-uma-escritora-presente-carolina-maria-3-1-scaled.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2020\/06\/periferias-carolina-maria-de-jesus-uma-escritora-presente-carolina-maria-3-1-scaled.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":61988,"url":"https:\/\/blogdafeira.com.br\/home\/2024\/04\/27\/escariz-tem-jolivaldo-freitas-raphael-montes-itamar-vieira-e-varios-autores-para-a-bienal-do-livro\/","url_meta":{"origin":71986,"position":5},"title":"Escariz tem Jolivaldo Freitas, Raphael Montes, Itamar Vieira e v\u00e1rios autores para a Bienal do Livro","author":"Ascom","date":"27\/04\/2024","format":false,"excerpt":"Importantes nomes da literatura baiana, brasileira e internacional fazem parte do acervo que a Escariz est\u00e1 levando para a Bienal do Livro Bahia, que acontece em Salvador entre o dia 26 de abril e 1 de maio no Centro de Conven\u00e7\u00f5es da Bahia. O evento liter\u00e1rio tem como tema \"Venha\u2026","rel":"","context":"Em &quot;Bahia&quot;","block_context":{"text":"Bahia","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/bahia\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2024\/04\/Capa-e-foto-Zuavos.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2024\/04\/Capa-e-foto-Zuavos.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2024\/04\/Capa-e-foto-Zuavos.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2024\/04\/Capa-e-foto-Zuavos.jpeg?resize=700%2C400&ssl=1 2x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/posts\/71986","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/comments?post=71986"}],"version-history":[{"count":1,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/posts\/71986\/revisions"}],"predecessor-version":[{"id":71990,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/posts\/71986\/revisions\/71990"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/media\/71989"}],"wp:attachment":[{"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/media?parent=71986"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/categories?post=71986"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/tags?post=71986"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}