{"id":72397,"date":"2026-05-13T10:10:54","date_gmt":"2026-05-13T13:10:54","guid":{"rendered":"https:\/\/blogdafeira.com.br\/home\/?p=72397"},"modified":"2026-05-13T10:10:54","modified_gmt":"2026-05-13T13:10:54","slug":"a-exaustao-dos-ambientes-digitais","status":"publish","type":"post","link":"https:\/\/blogdafeira.com.br\/home\/2026\/05\/13\/a-exaustao-dos-ambientes-digitais\/","title":{"rendered":"A exaust\u00e3o dos ambientes digitais"},"content":{"rendered":"<div id=\"blogd-2153249082\" class=\"blogd-fim-do-post-mobile blogd-entity-placement\" style=\"margin-left: auto;margin-right: auto;text-align: center;\"><a href=\"https:\/\/www.feiradesantana.ba.gov.br\/servico.asp?s=a&#038;titulo=Alceu,-Paula-Fernandes,-Alcymar-Monteiro,-Fl%C3%A1vio-Jos%C3%A9-e-Ra%C3%A7a-Negra-animar%C3%A3o-o-Arrai%C3%A1-de%20Feira.html&#038;id=8&#038;link=secom\/noticias.asp&#038;idn=43073#noticias\" target=\"_blank\" aria-label=\"728&#215;90 (7)\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2026\/03\/728x90-7.gif\" alt=\"\"  class=\"no-lazyload\" width=\"728\" height=\"90\"  style=\"display: inline-block;\" \/><\/a><\/div><p>Lembro do entusiasmo das pessoas com o Orkut h\u00e1 cerca de duas d\u00e9cadas. Foi a pioneira entre as chamadas redes sociais e, portanto, uma grande novidade. Atraiu a gente mais jovem, mas tamb\u00e9m pessoas mais maduras, encantadas com a possibilidade de reconectar-se a amizades antigas, pessoas que moravam longe ou que, simplesmente, tinham ficado estacionadas no passado. Come\u00e7ava, naquele tempo, o fen\u00f4meno que, hoje, ocupa posi\u00e7\u00e3o central na vida de muita gente.<\/p><div id=\"blogd-2055322239\" class=\"blogd-conteudo-2-mobile blogd-entity-placement\"><a href=\"https:\/\/feirenses.com.br\/\" target=\"_blank\" aria-label=\"feirenses\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2026\/04\/feirenses.png\" alt=\"\"  srcset=\"https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2026\/04\/feirenses.png 300w, https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2026\/04\/feirenses-170x45.png 170w, https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2026\/04\/feirenses-280x74.png 280w\" sizes=\"(max-width: 300px) 100vw, 300px\" class=\"no-lazyload\" width=\"300\" height=\"79\"  style=\"display: inline-block;\" \/><\/a><\/div>\n<p>Mais afeito \u00e0 vida real \u2013 era poss\u00edvel uma rotina anal\u00f3gica naqueles tempos \u2013 demorei a ingressar na plataforma. Usava pouco, at\u00e9 por \u00f3bvia falta de tempo. Mas n\u00e3o foi isso que despertou certa indiferen\u00e7a. \u00c9 que, basicamente, encontrava por ali bobagens infantis ou a nostalgia de um passado emoldurado. Nem t\u00e3o jovem, mas nem t\u00e3o velho, n\u00e3o enxergava atrativos.<\/p>\n<p>Pouco depois houve o boom de redes sociais. Surgiram plataformas mais aprimoradas, conectando os mesmos amigos em novos ambientes, surgiram plataformas de relacionamentos amorosos, de conex\u00f5es de trabalho, enfim, de tudo que pode representar afinidade entre pessoas e \u2013 mais que isso \u2013 lucro para os donos das plataformas. Por fim, com a evolu\u00e7\u00e3o dos aparelhos celulares, as m\u00eddias chegaram \u00e0 palma da m\u00e3o.<\/p>\n<p>Junto com tudo isso veio o \u00f3dio, no v\u00e1cuo do fortalecimento dos extremismos. \u00c9 claro que o \u00f3dio, o rancor, o ressentimento, a raiva e o niilismo sempre existiram nestes ambientes digitais. Mas, ap\u00f3s sua massifica\u00e7\u00e3o, veio um direcionamento assustador, certamente impulsionado pelos algoritmos, que foram se sofisticando. O \u00f3dio, nestes espa\u00e7os, s\u00f3 perde para as propagandas.<\/p>\n<p>\u00c0s vezes, na imprensa, v\u00ea-se alguma not\u00edcia alvissareira: as pessoas est\u00e3o cansadas do \u00f3dio, da disc\u00f3rdia, dos ressentimentos, dos algoritmos. \u00c9 bom saber: pensava que lidava sozinho com o desconforto. O que elas fazem, ent\u00e3o, para manter a sanidade, impedir que sua sa\u00fade mental seja ainda mais comprometida? Em grande medida e dentro do poss\u00edvel, desconectam-se.<\/p>\n<p>\u00c9 um exerc\u00edcio valioso. Faz\u00ea-lo d\u00e1 uma indescrit\u00edvel sensa\u00e7\u00e3o de liberdade. Sobretudo porque, em todos os lugares, o que se v\u00ea s\u00e3o pessoas ref\u00e9ns das telas, dos v\u00eddeos, dos \u00e1udios, do mundo inteiro que cabe no celular e na palma da m\u00e3o. \u00c9 de se imaginar qual a rela\u00e7\u00e3o ideal com a tecnologia, dados os excessos que se veem por a\u00ed. Inclusive os que atingem as crian\u00e7as.<\/p>\n<div id=\"blogd-1620275917\" class=\"blogd-final-post blogd-entity-placement\"><a href=\"https:\/\/www.feiradesantana.ba.leg.br\/\" target=\"_blank\" aria-label=\"BANNER-SITE-ENTREGADECHEQUE-CAMARADEFEIRA\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2026\/03\/BANNER-SITE-ENTREGADECHEQUE-CAMARADEFEIRA.gif\" alt=\"\"  class=\"no-lazyload\" width=\"728\" height=\"90\"   \/><\/a><\/div><p>Depois de tantos avan\u00e7os tecnol\u00f3gicos, alcan\u00e7\u00e1veis com uns poucos cliques, muitas pessoas tornaram-se ansiosas, nervosas, neur\u00f3ticas, adoecidas pela exposi\u00e7\u00e3o excessiva ao universo digital. Chegou, portanto, o momento de lidar de maneira equilibrada com as redes, seja no \u00e2mbito do trabalho, seja no das rela\u00e7\u00f5es pessoais. Passou o momento da \u00e2nsia de integrar-se ao digital e chegou a hora de equilibr\u00e1-lo com os muitos prazeres que a vida anal\u00f3gica oferece.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lembro do entusiasmo das pessoas com o Orkut h\u00e1 cerca de duas d\u00e9cadas. Foi a pioneira entre as chamadas redes sociais e, portanto, uma grande novidade. Atraiu a gente mais jovem, mas tamb\u00e9m pessoas mais maduras, encantadas com a possibilidade de reconectar-se a amizades antigas, pessoas que moravam longe ou que, simplesmente, tinham ficado estacionadas<\/p>\n","protected":false},"author":13,"featured_media":72398,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"cybocfi_hide_featured_image":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[592,4,603],"tags":[],"class_list":["post-72397","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-colunistas","category-cultura","category-destaques"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2026\/05\/PALMA-DA-MAO.png","jetpack_shortlink":"https:\/\/wp.me\/p3niVf-iPH","jetpack_sharing_enabled":true,"jetpack-related-posts":[{"id":21894,"url":"https:\/\/blogdafeira.com.br\/home\/2016\/06\/03\/feira-de-santana-das-aguas-e-os-40-anos-da-universidade-estadual\/","url_meta":{"origin":72397,"position":0},"title":"Feira das \u00c1guas","author":"Blog da Feira","date":"03\/06\/2016","format":false,"excerpt":"Foi o solo e a \u00e1gua que fez tropeiros e vaqueiros, quilombolas e mascates, andarilhos, mission\u00e1rios, ladr\u00f5es, peregrinos ou dona Ana Brandoa, \u00a0escolherem, cada um a seu tempo e jeito, essas paragens onde se ergue hoje a cidade da Feira de Santana. Principalmente a \u00e1gua, a proximidade e piscosidade dos\u2026","rel":"","context":"Em &quot;Home&quot;","block_context":{"text":"Home","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/raiz\/"},"img":{"alt_text":"lagoa grandegdgdfg","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2015\/10\/lagoa-grandegdgdfg.jpg?resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2015\/10\/lagoa-grandegdgdfg.jpg?resize=350%2C200 1x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2015\/10\/lagoa-grandegdgdfg.jpg?resize=525%2C300 1.5x"},"classes":[]},{"id":41463,"url":"https:\/\/blogdafeira.com.br\/home\/2020\/11\/01\/o-vale-da-sombra-da-morte-juvenil\/","url_meta":{"origin":72397,"position":1},"title":"O vale da sombra da morte juvenil","author":"Andr\u00e9 Pomponet","date":"01\/11\/2020","format":false,"excerpt":"Amanh\u00e3, 2 de novembro, \u00e9 dia de Finados. Imagino que a pandemia e o feriado prolongado v\u00e3o reduzir a frequ\u00eancia aos cemit\u00e9rios feirenses. Quem for, por\u00e9m, poder\u00e1 observar algo que notei h\u00e1 tempos nas necr\u00f3poles da cidade. Trata-se da mudan\u00e7a no perfil de quem \u00e9 sepultado. No passado \u2013 d\u00e9cadas\u2026","rel":"","context":"Em &quot;Colunistas&quot;","block_context":{"text":"Colunistas","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/colunistas\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2020\/11\/69282-3.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2020\/11\/69282-3.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2020\/11\/69282-3.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":66065,"url":"https:\/\/blogdafeira.com.br\/home\/2025\/03\/11\/filosofia-de-bar-e-etarismo\/","url_meta":{"origin":72397,"position":2},"title":"Filosofia de bar e etarismo","author":"Andr\u00e9 Pomponet","date":"11\/03\/2025","format":false,"excerpt":"N\u00e3o foi hoje, nem foi ontem. Mas o papo \u2013 por atemporal \u2013 merece ser resgatado. Como sempre, tratou-se de uma dessas conversas de botequim, sem prop\u00f3sito ou finalidade. \u00c0s vezes, algumas delas \u2013 estranhamente \u2013 ficam, depois, ressoando na mem\u00f3ria. Foi o caso. - Eu vinha de c\u00e1, o\u2026","rel":"","context":"Em &quot;Colunistas&quot;","block_context":{"text":"Colunistas","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/colunistas\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2025\/03\/images-6.jpeg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":45686,"url":"https:\/\/blogdafeira.com.br\/home\/2021\/06\/03\/confidencias-de-um-brasileiro-desolado\/","url_meta":{"origin":72397,"position":3},"title":"Confid\u00eancias de um brasileiro desolado","author":"Andr\u00e9 Pomponet","date":"03\/06\/2021","format":false,"excerpt":"\u2013 Olha, se eu pudesse, eu ia embora disso aqui. O problema \u00e9 que eu j\u00e1 passei dos quarenta, n\u00e3o tenho para onde ir e acho que ningu\u00e9m vai me aceitar l\u00e1 fora. Quando eu era mais jovem, acabei me empolgando, achando que isso aqui tinha jeito, que estava mudando,\u2026","rel":"","context":"Em &quot;Colunistas&quot;","block_context":{"text":"Colunistas","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/colunistas\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2021\/04\/WhatsApp-Image-2021-04-26-at-17.25.02-1.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2021\/04\/WhatsApp-Image-2021-04-26-at-17.25.02-1.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2021\/04\/WhatsApp-Image-2021-04-26-at-17.25.02-1.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2021\/04\/WhatsApp-Image-2021-04-26-at-17.25.02-1.jpeg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2021\/04\/WhatsApp-Image-2021-04-26-at-17.25.02-1.jpeg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":63571,"url":"https:\/\/blogdafeira.com.br\/home\/2024\/09\/02\/roda-viva-tocando-no-radio\/","url_meta":{"origin":72397,"position":4},"title":"Roda-Viva tocando no r\u00e1dio","author":"Andr\u00e9 Pomponet","date":"02\/09\/2024","format":false,"excerpt":"Durante a pandemia ouvia muito a programa\u00e7\u00e3o musical das emissoras de r\u00e1dio. As noites eram estranhas. Sobretudo nos primeiros meses do isolamento social, as not\u00edcias alarmantes sobre mortes se avolumando. O r\u00e1dio ligado, \u00e0 noite, afastava um pouco as apreens\u00f5es, os medos, a pr\u00f3pria solid\u00e3o, pitoresca, que n\u00e3o era individual,\u2026","rel":"","context":"Em &quot;Colunistas&quot;","block_context":{"text":"Colunistas","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/colunistas\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2024\/09\/images-45.jpeg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":43106,"url":"https:\/\/blogdafeira.com.br\/home\/2021\/01\/23\/catarse-em-mesa-de-bar\/","url_meta":{"origin":72397,"position":5},"title":"Catarse em mesa de bar","author":"Andr\u00e9 Pomponet","date":"23\/01\/2021","format":false,"excerpt":"Tempos atr\u00e1s, numa dessas despretensiosas cervejadas de uma ensolarada tarde de s\u00e1bado, um amigo \u00e0 mesa respirou fundo e cultivou um angustiante sil\u00eancio por alguns instantes. B\u00eabado? N\u00e3o consumira tanto, era resistente ao \u00e1lcool. Mas o olhar perdido, lan\u00e7ado sobre a cal\u00e7ada encardida, inquietava. At\u00e9 ali o papo flu\u00edra, banal.\u2026","rel":"","context":"Em &quot;Colunistas&quot;","block_context":{"text":"Colunistas","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/colunistas\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2021\/01\/pexels-kaboompics-com-5842.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2021\/01\/pexels-kaboompics-com-5842.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2021\/01\/pexels-kaboompics-com-5842.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2021\/01\/pexels-kaboompics-com-5842.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2021\/01\/pexels-kaboompics-com-5842.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/posts\/72397","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/comments?post=72397"}],"version-history":[{"count":1,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/posts\/72397\/revisions"}],"predecessor-version":[{"id":72399,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/posts\/72397\/revisions\/72399"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/media\/72398"}],"wp:attachment":[{"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/media?parent=72397"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/categories?post=72397"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/tags?post=72397"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}