{"id":72973,"date":"2026-06-27T18:22:39","date_gmt":"2026-06-27T21:22:39","guid":{"rendered":"https:\/\/blogdafeira.com.br\/home\/?p=72973"},"modified":"2026-07-06T16:58:03","modified_gmt":"2026-07-06T19:58:03","slug":"72973","status":"publish","type":"post","link":"https:\/\/blogdafeira.com.br\/home\/2026\/06\/27\/72973\/","title":{"rendered":"Governador Jer\u00f4nimo defende Wagner e diz que oposi\u00e7\u00e3o tenta atingir Lula"},"content":{"rendered":"<div id=\"blogd-178903221\" class=\"blogd-fim-do-post-mobile blogd-entity-placement\" style=\"margin-left: auto;margin-right: auto;text-align: center;\"><a href=\"https:\/\/expofeira.ba.gov.br\/\" target=_blank><picture>\r\n  <source media=\"(min-width: 768px)\" srcset=\"https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2026\/08\/980x1503.gif\">\r\n  \r\n  <img decoding=\"async\" src=\"https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2026\/08\/350x2005.gif\" alt=\"Publicidade\" style=\"width: 100%; max-width: 100%; height: auto; display: block; margin: 0 auto;\">\r\n\t<\/picture><\/a><\/div><p>O governador Jer\u00f4nimo Rodrigues (PT), pr\u00e9-candidato \u00e0 reelei\u00e7\u00e3o, saiu em defesa do senador Jaques Wagner (PT), neste s\u00e1bado (27), em Barreiras, antes da plen\u00e1ria do Programa de Governo Participativo (PGP). Em entrevista \u00e0 imprensa, Jer\u00f4nimo relacionou a emo\u00e7\u00e3o que demonstrou em agenda recente tanto \u00e0 entrega do servi\u00e7o de radioterapia no Hospital do Oeste quanto ao que classificou como uma injusti\u00e7a contra o senador.<\/p>\n<p>Para Jer\u00f4nimo, os ataques a Wagner fazem parte de uma estrat\u00e9gia maior, voltada a desgastar o presidente Lula. \u201c<em>Na verdade, querem pegar Lula primeiro. Usam a gente o tempo inteiro pra bater no Lula. Depois, pegam uma pessoa que \u00e9 um patrim\u00f4nio nosso\u201d, afirmou. Em defesa da trajet\u00f3ria do senador, completou: \u201cVoc\u00ea nunca ouviu em 20 anos dizer que ele era desonesto\u201d.<\/em><\/p>\n<p>O governador demonstrou confian\u00e7a na resposta de Wagner e fez quest\u00e3o de refor\u00e7ar que conta com o senador na constru\u00e7\u00e3o pol\u00edtica do grupo na Bahia. \u201c<em>A gente quer que Wagner continue firme e forte, fa\u00e7a sua defesa e possa ajudar a gente a continuar governando o Brasil e a Bahia<\/em>\u201d, afirmou.<\/p>\n<p>Aos advers\u00e1rios, Jer\u00f4nimo respondeu com o que considera sua melhor arma: o trabalho. \u201c<em>Eu vou usar meu tempo para mostrar o que n\u00f3s fazemos<\/em>\u201d, disse ao comentar cr\u00edticas da oposi\u00e7\u00e3o. Na sequ\u00eancia, listou estradas, hospitais, escolas de tempo integral e o novo servi\u00e7o de radioterapia como marcas de sua gest\u00e3o.<\/p>\n<p>O governador tamb\u00e9m comparou estilo de governar ao da pol\u00edtica do passado feita pela oposi\u00e7\u00e3o, lembrando que mant\u00e9m o di\u00e1logo institucional aberto inclusive com prefeitos de partidos advers\u00e1rios, como mostrou a agenda em Barreiras.<\/p>\n<div id=\"blogd-3627758168\" class=\"blogd-final-post blogd-entity-placement\"><a href=\"https:\/\/www.feiradesantana.ba.leg.br\/\" target=\"_blank\" aria-label=\"BANNER-SITE_CA\u0302MARA_AGOSTO_728x90px\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2026\/03\/BANNER-SITE_CAMARA_AGOSTO_728x90px.gif\" alt=\"\"  class=\"no-lazyload\" width=\"728\" height=\"90\"   \/><\/a><\/div><p>\u201c<em>Ontem voc\u00eas me viram sentar com o prefeito de Barreiras. Dessa forma que n\u00f3s tiramos a Bahia do atraso e da m\u00e3o do chicote<\/em>\u201d, falou. \u201cNo tempo do av\u00f4, o prefeito que n\u00e3o sentava na mesa e n\u00e3o abaixava a cabe\u00e7a, era retirado. N\u00f3s n\u00e3o aprendemos a fazer essa pol\u00edtica. Nossa pol\u00edtica \u00e9 a pol\u00edtica do bem\u201d, completou o governador.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O governador Jer\u00f4nimo Rodrigues (PT), pr\u00e9-candidato \u00e0 reelei\u00e7\u00e3o, saiu em defesa do senador Jaques Wagner (PT), neste s\u00e1bado (27), em Barreiras, antes da plen\u00e1ria do Programa de Governo Participativo (PGP). Em entrevista \u00e0 imprensa, Jer\u00f4nimo relacionou a emo\u00e7\u00e3o que demonstrou em agenda recente tanto \u00e0 entrega do servi\u00e7o de radioterapia no Hospital do Oeste quanto<\/p>\n","protected":false},"author":1,"featured_media":72974,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"cybocfi_hide_featured_image":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[680,1,631],"tags":[],"class_list":["post-72973","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bahia","category-raiz","category-politica"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/blogdafeira.com.br\/home\/wp-content\/uploads\/2026\/06\/IMG-20260627-WA0090.jpg","jetpack_shortlink":"https:\/\/wp.me\/s3niVf-72973","jetpack_sharing_enabled":true,"jetpack-related-posts":[{"id":51580,"url":"https:\/\/blogdafeira.com.br\/home\/2022\/04\/03\/wagner-diz-em-feira-que-jeronimo-conhece-a-bahia-como-a-palma-da-mao\/","url_meta":{"origin":72973,"position":0},"title":"Wagner diz em Feira que Jer\u00f4nimo conhece a Bahia como a palma da m\u00e3o","author":"Secom\/Gov.Ba","date":"03\/04\/2022","format":false,"excerpt":"A cidade de Feira de Santana recebeu o \"time de Lula\" neste domingo (3) para lan\u00e7amento do Programa de Governo Participativo (PGP) 2022. Os pr\u00e9-candidatos a governador, Jer\u00f4nimo Rodrigues (PT), vice-governador, Geraldo Junior (MDB), e senador, Otto Alencar (PSD), reuniram mais de 3 mil pessoas no evento, que teve a\u2026","rel":"","context":"Em &quot;Home&quot;","block_context":{"text":"Home","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/raiz\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2022\/04\/Screenshot_20220403-1429224.png?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2022\/04\/Screenshot_20220403-1429224.png?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2022\/04\/Screenshot_20220403-1429224.png?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2022\/04\/Screenshot_20220403-1429224.png?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":68290,"url":"https:\/\/blogdafeira.com.br\/home\/2025\/07\/13\/jeronimo-defende-rui-dos-ataques-do-senador-ciro-nogueira\/","url_meta":{"origin":72973,"position":1},"title":"Jer\u00f4nimo defende Rui dos ataques do senador Ciro Nogueira","author":"Secom\/Gov.Ba","date":"13\/07\/2025","format":false,"excerpt":"Ap\u00f3s o senador\u00a0 Ciro Nogueira, em defesa do governador de S\u00e3o Paulo,\u00a0 \"mandar\" o ministro Rui Costa trabalhar para \"tirar o Brasil da 'encrenca em que o radicalismo da diplomacia do PT enfiou o pa\u00eds\", o governador da Bahia foi pra cima do senador e desconstruiu a agressividade do senador\u2026","rel":"","context":"Em &quot;Home&quot;","block_context":{"text":"Home","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/raiz\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2025\/07\/20250713_101301.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":72156,"url":"https:\/\/blogdafeira.com.br\/home\/2026\/04\/29\/jeronimo-visita-ministerios-e-reune-se-com-wagner-e-lula-no-palacio-da-alvorada\/","url_meta":{"origin":72973,"position":2},"title":"Jer\u00f4nimo visita minist\u00e9rios e re\u00fane-se com Wagner e Lula no Pal\u00e1cio da Alvorada","author":"Secom\/Gov.Ba","date":"29\/04\/2026","format":false,"excerpt":"Cumprindo agenda em Bras\u00edlia, nesta quarta-feira (29), o governador da Bahia, Jer\u00f4nimo Rodrigues participou de uma s\u00e9rie de reuni\u00f5es com representantes do Governo Federal e do Judici\u00e1rio, tratando de temas de interesse do estado. Acompanhado de secret\u00e1rios e gestores estaduais, o primeiro compromisso foi no Minist\u00e9rio dos Transportes, em audi\u00eancia\u2026","rel":"","context":"Em &quot;Home&quot;","block_context":{"text":"Home","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/raiz\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2026\/04\/IMG-20260429-WA0149.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2026\/04\/IMG-20260429-WA0149.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2026\/04\/IMG-20260429-WA0149.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2026\/04\/IMG-20260429-WA0149.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2026\/04\/IMG-20260429-WA0149.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":56382,"url":"https:\/\/blogdafeira.com.br\/home\/2023\/02\/06\/jaques-wagner-lula-fala-o-que-a-maioria-dos-brasileiros-pensa-sobre-os-juros\/","url_meta":{"origin":72973,"position":3},"title":"Jaques Wagner: Lula fala o que a maioria dos brasileiros pensa sobre os juros","author":"Secom\/Gov.Ba","date":"06\/02\/2023","format":false,"excerpt":"O ex-governador da Bahia,\u00a0 senador Jaques Wagner (PT), l\u00edder do governo no Senado, disse \u00e0 Folha de S\u00e3o Paulo que as cr\u00edticas do presidente Lula \u00e0 taxa de juros refletem o que pensa a maior da popula\u00e7\u00e3o brasileira. \"O presidente est\u00e1 dizendo o que a maioria dos brasileiros acha: os\u2026","rel":"","context":"Em &quot;Home&quot;","block_context":{"text":"Home","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/raiz\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2023\/02\/OIP-8.jpeg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":52515,"url":"https:\/\/blogdafeira.com.br\/home\/2022\/05\/23\/ze-neto-eleicao-mais-importante-da-historia-do-pais\/","url_meta":{"origin":72973,"position":4},"title":"Z\u00e9 Neto: &#8220;elei\u00e7\u00e3o mais importante da hist\u00f3ria do pa\u00eds&#8221;","author":"Secom\/Gov.Ba","date":"23\/05\/2022","format":false,"excerpt":"Na luta pelo segundo Mandato de deputado federal, Z\u00e9 Neto (PT-BA) exaltou o legado dos governos \u00a0petistas na Bahia e no Brasil, e reafirmou que \u2018essa ser\u00e1 a elei\u00e7\u00e3o mais importante da hist\u00f3ria do pa\u00eds\u2019, ao oficializar sua pr\u00e9-candidatura \u00e0 reelei\u00e7\u00e3o no Ville Convention (Ville Goumert) em Feira de Santana,\u2026","rel":"","context":"Em &quot;Home&quot;","block_context":{"text":"Home","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/raiz\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2022\/05\/WhatsApp-Image-2022-05-23-at-13.43.34.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2022\/05\/WhatsApp-Image-2022-05-23-at-13.43.34.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2022\/05\/WhatsApp-Image-2022-05-23-at-13.43.34.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2022\/05\/WhatsApp-Image-2022-05-23-at-13.43.34.jpeg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":70973,"url":"https:\/\/blogdafeira.com.br\/home\/2026\/01\/19\/psd-movimenta-tabuleiro-eleitoral-baiano\/","url_meta":{"origin":72973,"position":5},"title":"PSD movimenta tabuleiro eleitoral baiano","author":"Secom\/Gov.Ba","date":"19\/01\/2026","format":false,"excerpt":"A semana come\u00e7a com uma tremenda novidade no cen\u00e1rio pol\u00edtico baiano: o senador Otto Alencar (PSD), em entrevista, garantiu que, caso deseje, o senador \u00c2ngelo Coronel (PSD) dispor\u00e1 da legenda para lan\u00e7ar candidatura avulsa ao Senado. Como se sabe, o petismo deseja rifar Coronel, lan\u00e7ando os nomes dos ex-governadores Jaques\u2026","rel":"","context":"Em &quot;Colunistas&quot;","block_context":{"text":"Colunistas","link":"https:\/\/blogdafeira.com.br\/home\/categoria\/colunistas\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2026\/01\/InShot_20260119_113520812.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2026\/01\/InShot_20260119_113520812.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2026\/01\/InShot_20260119_113520812.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2026\/01\/InShot_20260119_113520812.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2026\/01\/InShot_20260119_113520812.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/blogdafeira.com.br\/home\/wp-content\/uploads\/2026\/01\/InShot_20260119_113520812.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/posts\/72973","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/comments?post=72973"}],"version-history":[{"count":2,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/posts\/72973\/revisions"}],"predecessor-version":[{"id":72976,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/posts\/72973\/revisions\/72976"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/media\/72974"}],"wp:attachment":[{"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/media?parent=72973"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/categories?post=72973"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogdafeira.com.br\/home\/wp-json\/wp\/v2\/tags?post=72973"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}